{"id":23766,"date":"2023-11-19T15:22:00","date_gmt":"2023-11-19T15:22:00","guid":{"rendered":"https:\/\/www.africa-press.net\/benin\/politique\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique"},"modified":"2023-12-22T10:40:25","modified_gmt":"2023-12-22T10:40:25","slug":"quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique","title":{"rendered":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique"},"content":{"rendered":"<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Benin. <\/strong><\/span>Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largement secre\u0300te. Puis, subitement, est arrive\u0301e une de\u0301cision qui a plonge\u0301 la Libye et la vaste re\u0301gion du Sahel dans une spirale dont ils ne se sont jamais remis.<\/p>\n<p>\u00ab Nous sommes venus, nous avons vu, il est mort \u00bb, a plaisante\u0301 la secre\u0301taire d&rsquo;E\u0301tat Hillary Clinton apre\u0300s qu&rsquo;une campagne ae\u0301rienne de l&rsquo;OTAN mene\u0301e par les E\u0301tats-Unis ait contribue\u0301, en 2011, a\u0300 renverser le colonel Mouammar Kadhafi, qu\u2019ils conside\u0301raient comme \u00ab dictateur libyen de longue date \u00bb. Le pre\u0301sident Barack Obama avait qualifie\u0301 l&rsquo;intervention de succe\u0300s, mais la Libye glissa vers le statut d\u2019E\u0301tat quasiment en faillite. Obama admettra plus tard que \u00ab ne pas avoir planifie\u0301 le lendemain \u00bb de la de\u0301faite de Kadhafi, e\u0301tait la \u00ab pire erreur \u00bb de sa pre\u0301sidence.<\/p>\n<p>Dans ce contexte, nous sommes tombe\u0301s sur un long article publie\u0301 sur le site Internet \u00ab Counter Punch \u00bb qui est revenu plus ou moins profonde\u0301ment sur la guerre mene\u0301e par les E\u0301tats-Unis contre les groupes arme\u0301s en Afrique, et qui s&rsquo;appuie sur des chiffres ame\u0301ricains pour mettre l\u2019accent sur l&rsquo;e\u0301chec des ame\u0301ricains dans cette mission et comment le \u00ab terrorisme \u00bb s\u2019est de\u0301veloppe\u0301 ces dernie\u0300res anne\u0301es apre\u0300s le de\u0301but de cette guerre.<\/p>\n<p><b>Un conflit qui restera dans l&rsquo;infamie<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" class=\"alignnone wp-image-23760 size-full\" src=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228818.167372.jpg\" srcset=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228818.167372.jpg 1920w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228818.167372-300x169.jpg 300w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228818.167372-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228818.167372-768x432.jpg 768w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228818.167372-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>La guerre mondiale contre le terrorisme mene\u0301e par les E\u0301tats-Unis a connu son lot d\u2019impasses, de catastrophes et de de\u0301faites pures et simples, et au cours de plus de 20 ans d\u2019interventions militarise\u0301es, les E\u0301tats-Unis ont vu leurs efforts imploser de fac\u0327on spectaculaire, sachant que le plus grand e\u0301chec de leurs \u00ab guerres e\u0301ternelles \u00bb contre ce fle\u0301au n\u2019e\u0301tait probablement pas au Moyen-Orient, mais pluto\u0302t en Afrique.<\/p>\n<p>Toutefois, le pre\u0301sident ame\u0301ricain Joe Biden semble avoir donne\u0301 corps a\u0300 sa promesse en ouvrant le porte-monnaie US : \u00ab Les E\u0301tats-Unis ont engage\u0301 des ressources supple\u0301mentaires au Sahel, pour soutenir les efforts de lutte contre le terrorisme \u00bb.<\/p>\n<p>Mais, finalement, les efforts ame\u0301ricains de vouloir e\u0301radiquer le terrorisme en Afrique ont e\u0301te\u0301 toutes vaines, car ce fle\u0301au n\u2019a fait que s\u2019encrer davantage.<\/p>\n<p>Il importe de rappeler, dans cette me\u0302le\u0301e, que s\u2019adressant au peuple ame\u0301ricain au lendemain des ce\u0301le\u0300bres attentats du 11 septembre 2001, le pre\u0301sident ame\u0301ricain George W. Bush avait de\u0301clare\u0301 a\u0300 l\u2019e\u0301poque : \u00ab La guerre contre le terrorisme a commence\u0301 avec Al-Qai\u0308da, mais elle ne s&rsquo;arre\u0302tera pas la\u0300 tant que tous les groupes terroristes d&rsquo;envergure mondiale n&rsquo;auront pas e\u0301te\u0301 de\u0301masque\u0301s, arre\u0302te\u0301s et vaincus \u00bb notant, en particulier, que ces groupes arme\u0301s envisagent de s&rsquo;e\u0301tendre dans de vastes re\u0301gions d&rsquo;Afrique.<\/p>\n<p>Bush avait souligne\u0301 e\u0301galement que \u00ab la seule fac\u0327on de vaincre le terrorisme est de l&rsquo;e\u0301liminer et de le de\u0301truire la\u0300 ou\u0300 il se de\u0301veloppe \u00bb. Cependant, il s\u2019est de\u0301veloppe\u0301 et e\u0301tendu, et un grand nombre de nouveaux groupes arme\u0301s ont e\u0301merge\u0301, en particulier sur le continent brun.<\/p>\n<p>Ceci dit, les E\u0301tats-Unis ont donc de\u0301cide\u0301 de renforcer ce front, en entamant un effort de plusieurs de\u0301cennies pour :<br \/>\n\u2022 fournir une aide abondante en matie\u0300re de se\u0301curite\u0301,<br \/>\n\u2022 former des milliers d&rsquo;officiers militaires africains,<br \/>\n\u2022 e\u0301tablir des dizaines d&rsquo;avant-postes,<br \/>\n\u2022 envoyer leurs propres commandos dans toutes sortes de missions,<br \/>\n\u2022 cre\u0301er des forces par procuration,<br \/>\n\u2022 lancer des frappes de drones,<br \/>\n\u2022 et me\u0302me engager des combats terrestres directs avec des groupes arme\u0301s sur le continent africain.<\/p>\n<p>Ne\u0301anmoins, la plupart des Ame\u0301ricains, y compris les membres du Congre\u0300s, ignoraient l\u2019ampleur de ces ope\u0301rations. En conse\u0301quence, peu de gens re\u0301alisent a\u0300 quel point la \u00ab guerre fanto\u0302me \u00bb mene\u0301e par Washington a e\u0301choue\u0301.<\/p>\n<p>En d\u2019autres termes, depuis que les E\u0301tats-Unis ont intensifie\u0301 leurs ope\u0301rations antiterroristes en Afrique, le terrorisme s\u2019est de\u0301veloppe\u0301 vertigineusement.<\/p>\n<p>D\u2019apre\u0300s le site \u00ab Counter Punch \u00bb, les chiffres bruts te\u0301moignent a\u0300 eux seuls de l\u2019ampleur du de\u0301sastre. Alors que les E\u0301tats-Unis commenc\u0327aient leurs guerres e\u0301ternelles en 2002 et 2003, le De\u0301partement d\u2019E\u0301tat ne de\u0301nombrait au total que neuf attaques terroristes en Afrique. Cette anne\u0301e, par contre, les groupes arme\u0301s extre\u0301mistes sur ce continent ont de\u0301ja\u0300 mene\u0301, selon le Pentagone, 6756 attaques.<\/p>\n<p>Il va sans dire qu\u2019en Afrique, les E\u0301tats-Unis avaient lance\u0301 une campagne, au de\u0301but des anne\u0301es 2000, soutenant et entrai\u0302nant de facto les troupes africaines depuis le Mali a\u0300 l\u2019Ouest jusqu\u2019en Somalie a\u0300 l\u2019Est tout en cre\u0301ant des forces par procuration qui combattraient aux co\u0302te\u0301s des commandos ame\u0301ricains.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"1072\" height=\"800\" class=\"alignnone wp-image-23761 size-full\" src=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228835.404747.jpg\" srcset=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228835.404747.jpg 1072w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228835.404747-300x224.jpg 300w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228835.404747-1024x764.jpg 1024w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228835.404747-768x573.jpg 768w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228835.404747-80x60.jpg 80w\" sizes=\"auto, (max-width: 1072px) 100vw, 1072px\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" class=\"alignnone wp-image-23762 size-full\" src=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228850.349055.jpg\" srcset=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228850.349055.jpg 1280w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228850.349055-300x169.jpg 300w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228850.349055-1024x576.jpg 1024w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228850.349055-768x432.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Pour mener a\u0300 bien ses missions, l&rsquo;arme\u0301e ame\u0301ricaine avait mis en place un re\u0301seau d&rsquo;avant-postes a\u0300 travers la partie nord du continent, y compris d&rsquo;importantes bases de drones, depuis le \u00ab Camp Lemonnier \u00bb et son avant-poste satellite \u00ab Chabelley Airfield \u00bb dans la nation baigne\u0301e de soleil de Djibouti jusqu&rsquo;a\u0300 la base ae\u0301rienne d&rsquo;Agadez au Niger, en plus de la multiplication des installations et des petites unite\u0301s, des forces d&rsquo;ope\u0301rations spe\u0301ciales en Libye, au Soudan du Sud et me\u0302me au milieu du continent.<\/p>\n<p>Les arme\u0301es entrai\u0302ne\u0301es par les E\u0301tats-Unis dans la re\u0301gion n\u2019ont pas pu arre\u0302ter les attaques des groupes terroristes contre les habitants, et depuis, les pays de la re\u0301gion du Sahel en Afrique de l\u2019Ouest sont en proie a\u0300 des groupes terroristes qui ont e\u0301volue\u0301, se sont divise\u0301s et se sont reconstitue\u0301s a\u0300 plusieurs reprises. Quoi qu\u2019il en soit, ces groupes ont re\u0301gulie\u0300rement pratique\u0301 la violence, tue\u0301 des civils et vole\u0301 leur argent et leurs biens, ce qui a conduit a\u0300 la de\u0301stabilisation de la plupart des pays de l\u2019Afrique de l\u2019Ouest et du sud de l\u2019Afrique co\u0302tie\u0300re, le long du golfe de Guine\u0301e.<\/p>\n<p>Sous les bannie\u0300res noires du militantisme djihadiste, des hommes a\u0300 moto, deux par motocyclette, portant des lunettes de soleil et des turbans et arme\u0301s de kalachnikovs, se pre\u0301cipitent re\u0301gulie\u0300rement dans les villages pour imposer la zakat (impo\u0302t islamique), voler du be\u0301tail, et terroriser, agresser et tuer des civils.<\/p>\n<p>D\u2019autres groupes terroristes se sont re\u0301pandus dans toute l\u2019Afrique et ailleurs, et malgre\u0301 les assurances donne\u0301es par tous les pre\u0301sidents ame\u0301ricains au cours des deux dernie\u0300res de\u0301cennies quant a\u0300 leur confiance dans la victoire sur le terrorisme, l\u2019incapacite\u0301 a\u0300 s\u2019allier aux plans ame\u0301ricains s\u2019est poursuivie dans un pays apre\u0300s l\u2019autre, et sur le continent africain un peu plus qu\u2019ailleurs. L\u2019E\u0301tat vacille se\u0301rieusement et profonde\u0301ment, et le prix de son e\u0301chec est paye\u0301 par les Africains, des gens ordinaires qui ont e\u0301te\u0301 tue\u0301s, blesse\u0301s et de\u0301place\u0301s par les groupes terroristes que les Etats-Unis s\u2019e\u0301taient engage\u0301s a\u0300 vaincre.<\/p>\n<p>Il importe de noter, entre-autres que le ge\u0301ne\u0301ral du Corps des Marines ame\u0301ricain Michael Langley, commandant du Commandement des E\u0301tats-Unis pour l&rsquo;Afrique (AFRICOM), a rendu ce qui pourrait e\u0302tre le verdict final sur les guerres e\u0301ternelles de l&rsquo;Ame\u0301rique sur ce continent, de\u0301clarant dans ce contexte que \u00ab l&rsquo;Afrique est de\u0301sormais le centre du terrorisme international \u00bb.<\/p>\n<p>L\u2019un de ses pre\u0301de\u0301cesseurs a\u0300 ce poste, le ge\u0301ne\u0301ral William Ward, nomme\u0301 en juillet 2007 a\u0300 la te\u0302te du Commandement Afrique (AFRICOM) et qui est l\u2019Africain-Ame\u0301ricain le plus haut grade\u0301 de l\u2019US Army, avait de\u0301clare\u0301 : \u00ab Soutenir le de\u0301veloppement d&rsquo;arme\u0301es professionnelles et compe\u0301tentes contribue a\u0300 accroi\u0302tre la se\u0301curite\u0301 et la stabilite\u0301 en Afrique \u00bb. Mais, ses pre\u0301dictions d\u2019une \u00ab se\u0301curite\u0301 et d\u2019une stabilite\u0301 accrues \u00bb ne se sont e\u0301videmment jamais re\u0301alise\u0301es.<\/p>\n<p>Par ailleurs, au cours des campagnes antiterroristes, le personnel militaire encadre\u0301 par les E\u0301tats-Unis dans cette re\u0301gion n\u2019a connu qu\u2019un seul type de \u00ab succe\u0300s \u00bb de\u0301montrable : renverser des gouvernements.<\/p>\n<p>Au moins 15 officiers ayant be\u0301ne\u0301ficie\u0301 d\u2019une telle assistance aupre\u0300s des ame\u0301ricains ont e\u0301te\u0301 implique\u0301s dans 12 coups d\u2019E\u0301tat en Afrique de l\u2019Ouest et dans le Grand Sahel pendant la guerre contre le terrorisme. La liste comprend des officiers du :<br \/>\n\u2022 Burkina Faso (2014, 2015 et deux fois en 2022),<br \/>\n\u2022 Tchad (2021),<br \/>\n\u2022 Gambie (2014),<br \/>\n\u2022 Guine\u0301e (2021),<br \/>\n\u2022 Mali (2012, 2020 et 2021),<br \/>\n\u2022 Mauritanie (2008),<br \/>\n\u2022 et Niger (2023).<\/p>\n<p>Au moins cinq dirigeants du coup d\u2019E\u0301tat de juillet au Niger, par exemple, ont rec\u0327u l\u2019aide ame\u0301ricaine, selon un responsable ame\u0301ricain. A\u0300 leur tour, ils ont nomme\u0301 cinq membres des forces de se\u0301curite\u0301 nige\u0301riennes forme\u0301s par les E\u0301tats-Unis pour servir de gouverneurs du pays.<\/p>\n<p><b>Coup d\u2019\u0153il sur le \u00ab Cou\u0302t e\u0301leve\u0301 \u00bb de cette guerre pour le tre\u0301sor ame\u0301ricain<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"1386\" height=\"924\" class=\"alignnone wp-image-23763 size-full\" src=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228862.454882.jpg\" srcset=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228862.454882.jpg 1386w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228862.454882-300x200.jpg 300w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228862.454882-1024x683.jpg 1024w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228862.454882-768x512.jpg 768w\" sizes=\"auto, (max-width: 1386px) 100vw, 1386px\" \/><\/p>\n<p>Un rapport de l&rsquo;Universite\u0301 Brown pre\u0301dit que le cou\u0302t de la \u00ab guerre contre le terrorisme \u00bb commence\u0301e il y a vingt ans atteindrait 6700 milliards de dollars d&rsquo;ici 2023, si l&rsquo;administration ame\u0301ricaine arre\u0302tait toutes ses ope\u0301rations militaires avant cette date, sachant que le nombre de soldats ame\u0301ricains tue\u0301s est estime\u0301 a\u0300 plus de 7000 individus.<\/p>\n<p>A ce propos, le chercheur et expert des groupes extre\u0301mistes, Hassan Abu Haniyeh, a de\u0301clare\u0301 ceci : \u00ab Environ 5500 milliards de dollars ame\u0301ricains ont e\u0301te\u0301 de\u0301pense\u0301s pour la guerre contre le terrorisme, ou si nous adoptons le chiffre exage\u0301re\u0301 de l\u2019ancien pre\u0301sident ame\u0301ricain Donald Trump, qui disait que cela s\u2019e\u0301levait a\u0300 7000 milliards, outre les pertes humaines, comme l&rsquo;indiquent les estimations concernant la mort de 7700 soldats ame\u0301ricains a\u0300 travers le monde sur les principaux fronts de cette guerre, cela signifie certainement que les E\u0301tats-Unis ont paye\u0301 un lourd tribut \u00bb.<\/p>\n<p>Le chercheur conclut que malgre\u0301 ce cou\u0302t e\u0301leve\u0301, la guerre contre le terrorisme n\u2019a pas apporte\u0301 grand-chose, ni aux ame\u0301ricains, ni au monde.<\/p>\n<p>Pour sa part, le Dr Al-Sharqawi, Professeur de conflits internationaux a\u0300 l&rsquo;Universite\u0301 George Mason de Washington et ancien membre du Comite\u0301 d&rsquo;experts des Nations Unies, attribue l&rsquo;he\u0301sitation de la lutte contre le terrorisme en partie a\u0300 la \u00ab nature mute\u0301e des guerres \u00bb au cours du nouveau sie\u0300cle, des guerres qui, selon lui, \u00ab ne sont plus traditionnelles entre pays et arme\u0301es re\u0301gulie\u0300res, comme l&rsquo;e\u0301taient les guerres de la Seconde Guerre mondiale, mais sont pluto\u0302t devenues des guerres indirectes et ine\u0301gales, entre arme\u0301es, appartenant a\u0300 des gouvernements dote\u0301s de technologies avance\u0301es et a\u0300 des mouvements radicaux dote\u0301s d&rsquo;un e\u0301quipement manuel limite\u0301 qui, dans la plupart des cas, n&rsquo;est rien de plus que des fusils, des ceintures explosives, ou encore des drones.<\/p>\n<p>Il estime qu&rsquo;il existe un paradoxe qu&rsquo;il appelle \u00ab causalite\u0301 graduelle \u00bb et il explique : \u00ab Comme le disait Isaac Newton : pour chaque action il y a une re\u0301action dans l&rsquo;autre sens, c&rsquo;est-a\u0300-dire que chacun des pays comme les E\u0301tats-Unis, et des mouvements extre\u0301mistes tels que Daech, le Front Al-Nosra et Al-Qai\u0308da, disposent d&rsquo;un ensemble de justifications pre\u0302tes a\u0300 favoriser la poursuite de la violence et de l&rsquo;agression. \u00bb La contre-attaque, la menace d&rsquo;un co\u0302te\u0301 et la vengeance de l&rsquo;autre co\u0302te\u0301, en bref : ce sont des re\u0301cits de menaces a\u0300 la se\u0301curite\u0301 nationale ame\u0301ricaine, en e\u0301change du retrait des forces e\u0301trange\u0300res.<\/p>\n<p><b>Succe\u0300s tactiques et e\u0301checs strate\u0301giques<\/b><\/p>\n<p>Les experts estiment que les E\u0301tats-Unis ont obtenu un certain succe\u0300s tactique dans leur guerre contre le terrorisme : ils ont tue\u0301 certains dirigeants, arre\u0302te\u0301 d&rsquo;autres et expulse\u0301 Daech de leurs zones de contro\u0302le, mais ils n&rsquo;ont pas re\u0301ussi a\u0300 e\u0301liminer aucune des organisations extre\u0301mistes.<\/p>\n<p>Abu Haniyeh de\u0301clare : \u00ab Les E\u0301tats-Unis n\u2019ont pas obtenu de succe\u0300s strate\u0301gique, car il n\u2019y a pas de durabilite\u0301. La strate\u0301gie s\u2019est pluto\u0302t concentre\u0301e sur les aspects militaires et se\u0301curitaires. Ils ont ne\u0301glige\u0301 les aspects lie\u0301s a\u0300 la gouvernance, a\u0300 la politique et a\u0300 la tyrannie, ou pluto\u0302t, ils ont ne\u0301glige\u0301 \u00ab les causes profondes du terrorisme \u00bb.<\/p>\n<p>De son co\u0302te\u0301, le Dr Al-Sharqawi, partage cet avis, soulignant que la lutte contre le terrorisme ne\u0301cessite des points de de\u0301part transdisciplinaires et multi-angles pour comprendre la conviction qui pousse une personne suicidaire a\u0300 porter une ceinture explosive et a\u0300 se faire exploser parmi la foule.<\/p>\n<p>En d\u2019autres termes, les gouvernements et les organisations internationales s\u2019attaquent au proble\u0300me du terrorisme lorsqu\u2019il devient une conse\u0301quence, c\u2019est-a\u0300-dire au stade final, et ne se concentrent pas sur la causalite\u0301 ni sur la fac\u0327on dont la cole\u0300re et la frustration se transforment en re\u0301sistance, et le reste des manifestations de l\u2019extre\u0301misme, dans les premier et deuxie\u0300me stades \u00bb.<\/p>\n<p>Il conclut que \u00ab Les E\u0301tats-Unis restent une superpuissance qui flirte parfois avec les re\u0302ves impe\u0301riaux et poursuit un re\u0301alisme offensif, mais elle ne sait pas comment sortir des foyers de conflit \u00bb.<\/p>\n<p><b>Une approche antiterroriste<\/b><\/p>\n<p>Autant d\u2019indices qui confirment ce programme antiterroriste ame\u0301ricain car, sur le terrain africain, la re\u0301alite\u0301 semble justifier cette approche. Selon certains analystes, Washington a raison de se soucier d\u2019un rede\u0301ploiement du terrorisme international qui prendrait l\u2019Afrique comme nouveau champ de bataille.<\/p>\n<p>Dans un autre article de Foreign Policy, le chercheur Charles Lister estime ainsi que \u00ab c\u2019est du continent africain que les professionnels de la lutte contre le terrorisme devraient se pre\u0301occuper le plus \u00bb.<\/p>\n<p>Apre\u0300s les coups d\u2019E\u0301tat au Mali, au Burkina Faso et au Niger, les groupes arme\u0301s me\u0300neraient \u00ab une offensive alarmante au Sahel \u00bb. Les donne\u0301es du terrain sont alarmantes car, de\u0301ja\u0300, le Groupe de soutien a\u0300 l\u2019islam et aux musulmans (GSIM), affilie\u0301 a\u0300 Al-Qaida, contro\u0302le environ 40 % du territoire du Burkina Faso. Il a intensifie\u0301 ses attaques de plus de 400 % cet e\u0301te\u0301 et assie\u0300ge Tombouctou.<\/p>\n<p>Son rival, Daech au Grand Sahara, a double\u0301 la superficie qu\u2019il contro\u0302le dans la re\u0301gion sahe\u0301lienne au cours de la seule anne\u0301e e\u0301coule\u0301e. Au Mali, ce groupe a e\u0301tabli des enclaves qu\u2019il ge\u0300re en de\u0301ployant sa propre loi et sa police. Daech disposerait de \u00ab plusieurs routes actives d\u2019acheminement de combattants e\u0301trangers et d\u2019approvisionnement logistique entre le Mali et le sud de l\u2019Europe, ainsi que d\u2019une inter connectivite\u0301 constante avec sa filiale en Afrique de l\u2019Ouest \u00bb.<\/p>\n<p>\u00ab A\u0300 ce rythme, nous pourrions e\u0302tre a\u0300 quelques mois de la proclamation par Al-Qaida ou Daech, ou les deux a\u0300 la fois, d\u2019une forme de pre\u0301tendus E\u0301tats territoriaux dans la re\u0301gion du Sahel \u00bb, avertit encore le chercheur.<\/p>\n<p><b>Le terrorisme : Une menace tre\u0300s se\u0301rieuse pour les responsables ame\u0301ricains<\/b><br \/>\n<img loading=\"lazy\" decoding=\"async\" width=\"922\" height=\"615\" class=\"alignnone wp-image-23764 size-full\" src=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228874.974798.jpg\" srcset=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228874.974798.jpg 922w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228874.974798-300x200.jpg 300w, https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228874.974798-768x512.jpg 768w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/p>\n<p>Gregory LoGerfo, coordinateur adjoint du De\u0301partement d&rsquo;E\u0301tat ame\u0301ricain pour la lutte contre le terrorisme, a confirme\u0301, lors d\u2019un symposium organise\u0301 par l\u2019American Enterprise Institute for Public Policy Research a\u0300 Washington, qui a discute\u0301 des \u00ab efforts diplomatiques des E\u0301tats-Unis pour lutter contre le terrorisme \u00bb, que Daech constitue toujours une menace se\u0301rieuse \u00ab malgre\u0301 sa de\u0301faite re\u0301gionale et sa perte de leadership \u00bb.<\/p>\n<p>Il a souligne\u0301 la pre\u0301sence de branches croissantes de Daech en Afrique de l&rsquo;Ouest, au Tchad, en Somalie, au Congo et au Mozambique.<\/p>\n<p>Il a appele\u0301 les pays, dont les de\u0301tenus de l&rsquo;organisation posse\u0300dent la nationalite\u0301, a\u0300 redoubler d&rsquo;efforts pour renvoyer ces derniers dans leur pays d&rsquo;origine, soulignant que ce qu&rsquo;il a de\u0301crit comme des \u00ab groupes terroristes \u00bb s&rsquo;efforcent toujours de changer de tactique et d&rsquo;utiliser les technologies e\u0301mergentes, notamment les drones, pour mener a\u0300 bien leurs ope\u0301rations et leurs attentats.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/benin\">Benin<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Benin. Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largement secre\u0300te. Puis, subitement, est arrive\u0301e une de\u0301cision qui a plonge\u0301 la Libye et la vaste re\u0301gion du Sahel dans une spirale dont ils ne se sont jamais remis. \u00ab Nous sommes venus, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":23765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10],"tags":[36,50,37,673,331,501,45,675,500,368,563,417,328,505,318,470,344,259],"class_list":["post-23766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-benin","tag-afrique","tag-afrique-de-lest","tag-afrique-de-louest","tag-al-qaida","tag-benin","tag-counter-punch","tag-daech","tag-etats-unis","tag-golfe-de-guinee","tag-gouvernements","tag-groupes-armes","tag-guerre","tag-militaires","tag-otan","tag-sahel","tag-terrorisme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique - B\u00e9nin<\/title>\n<meta name=\"description\" content=\"Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largem ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique\" \/>\n<meta property=\"og:description\" content=\"Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largem ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\" \/>\n<meta property=\"og:site_name\" content=\"B\u00e9nin\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-19T15:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-22T10:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1386\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique\",\"datePublished\":\"2023-11-19T15:22:00+00:00\",\"dateModified\":\"2023-12-22T10:40:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\"},\"wordCount\":2791,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Benin\",\"Afrique\",\"Afrique de l\u2019Est\",\"Afrique de l\u2019Ouest\",\"Al-Qa\u00efda\",\"B\u00e9nin\",\"Counter Punch\",\"Daech\",\"Etats-Unis\",\"Golfe de Guine\u0301e\",\"Gouvernements\",\"Groupes arm\u00e9s\",\"Guerre\",\"Militaires\",\"OTAN\",\"Sahel\",\"Terrorisme\"],\"articleSection\":[\"Dossiers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\",\"url\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\",\"name\":\"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique - B\u00e9nin\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg\",\"datePublished\":\"2023-11-19T15:22:00+00:00\",\"dateModified\":\"2023-12-22T10:40:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largem ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg\",\"width\":1386,\"height\":694,\"caption\":\"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/benin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/#website\",\"url\":\"https:\/\/www.africa-press.net\/benin\/\",\"name\":\"B\u00e9nin\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/benin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/benin\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique - B\u00e9nin","description":"Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largem ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique","og_locale":"fr_FR","og_type":"article","og_title":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique","og_description":"Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largem ...","og_url":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique","og_site_name":"B\u00e9nin","article_published_time":"2023-11-19T15:22:00+00:00","article_modified_time":"2023-12-22T10:40:25+00:00","og_image":[{"width":1386,"height":694,"url":"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/benin\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique","datePublished":"2023-11-19T15:22:00+00:00","dateModified":"2023-12-22T10:40:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique"},"wordCount":2791,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg","keywords":["Africa Press","Africa Press-Benin","Afrique","Afrique de l\u2019Est","Afrique de l\u2019Ouest","Al-Qa\u00efda","B\u00e9nin","Counter Punch","Daech","Etats-Unis","Golfe de Guine\u0301e","Gouvernements","Groupes arm\u00e9s","Guerre","Militaires","OTAN","Sahel","Terrorisme"],"articleSection":["Dossiers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique","url":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique","name":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique - B\u00e9nin","isPartOf":{"@id":"https:\/\/www.africa-press.net\/benin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg","datePublished":"2023-11-19T15:22:00+00:00","dateModified":"2023-12-22T10:40:25+00:00","author":{"@id":"https:\/\/www.africa-press.net\/benin\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Pendant des de\u0301cennies, la guerre de\u0301clare\u0301e par les Etats-Unis contre les groupes arme\u0301s en Afrique, est reste\u0301e largem ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#primaryimage","url":"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg","contentUrl":"https:\/\/static.africa-press.net\/benin\/sites\/46\/2023\/12\/sm_1703228886.494451.jpg","width":1386,"height":694,"caption":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/benin\/dossiers\/quand-le-pentagone-reconnait-avoir-echoue-dans-sa-lutte-contre-le-terrorisme-en-afrique#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/benin\/"},{"@type":"ListItem","position":2,"name":"Quand le Pentagone reconnait avoir \u00e9chou\u00e9 dans sa lutte contre le terrorisme en Afrique"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/benin\/#website","url":"https:\/\/www.africa-press.net\/benin\/","name":"B\u00e9nin","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/benin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/benin\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/posts\/23766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/comments?post=23766"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/posts\/23766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/media\/23765"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/media?parent=23766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/categories?post=23766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/benin\/wp-json\/wp\/v2\/tags?post=23766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}