{"id":13730,"date":"2021-06-09T14:23:08","date_gmt":"2021-06-09T14:23:08","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/?p=13730"},"modified":"2021-06-09T20:18:20","modified_gmt":"2021-06-09T20:18:20","slug":"burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan","title":{"rendered":"des milliers de d\u00e9plac\u00e9s apr\u00e8s l&rsquo;attaque sanglante contre Solhan"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>. <\/strong><\/span><b>Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des violences jihadistes en 2015, il y a cinq jours. Le pays sah\u00e9lien est frapp\u00e9 par des offensives terroristes qui sont de plus en plus fr\u00e9quentes et meurtri\u00e8res. Plus de 7000 personnes auraient depuis fui la r\u00e9gion touch\u00e9e.<\/b><\/p>\n<p>Dans la nuit de vendredi 4 \u00e0 samedi 5 juin, des hommes arm\u00e9s soup\u00e7onn\u00e9s d&rsquo;\u00eatre des djihadistes ont attaqu\u00e9 le village de Solhan, dans la province du Yagha (Nord-Est du pays), tuant 132 personnes selon le gouvernement. Les sources locales \u00e9voquent un bilan de 160 morts tandis que le Haut Commissariat de l\u2019ONU aux r\u00e9fugi\u00e9s (HCR) fait \u00e9tat de son c\u00f4t\u00e9 de 138 personnes. Voir aussi : Burkina Faso : l&rsquo;attaque la plus meurtri\u00e8re depuis 2015 Chargement du lecteur&#8230;<\/p>\n<p><b>Quelles r\u00e9percussions sur la r\u00e9gion?<\/b><\/p>\n<p>\u00ab\u00a0Apr\u00e8s l&rsquo;attaque, le village de Solhan s&rsquo;est compl\u00e8tement vid\u00e9 de sa population. Des personnes, femmes, hommes et enfants se sont d\u00e9plac\u00e9es pour se rendre \u00e0 Sebba\u00a0\u00bb, a indiqu\u00e9 le ministre burkinab\u00e9 de la Communication, Ouss\u00e9ni Tamboura. Chef-lieu de la province du Yagha, Sebba est situ\u00e9e \u00e0 une quinzaine de kilom\u00e8tres du village de Solhan o\u00f9 l\u2019attaque a eu lieu.<\/p>\n<p>Selon un \u00e9lu local, Solhan est devenu un village \u00ab\u00a0fant\u00f4me o\u00f9 les forces arm\u00e9es ont pris position\u00a0\u00bb et o\u00f9 les assaillants \u00ab\u00a0ont quasiment tout incendi\u00e9, les habitations, le march\u00e9, l&rsquo;\u00e9cole et le dispensaire o\u00f9 tout a \u00e9t\u00e9 emport\u00e9\u00a0\u00bb. Alors que le gouvernement avait initialement annonc\u00e9 7.000 d\u00e9plac\u00e9s, il seraient au final 7.600 a avoir fui leurs foyers, de peur de repr\u00e9sailles.<\/p>\n<p><b>Qu\u2019est ce qui a \u00e9t\u00e9 mis en place ?<\/b><\/p>\n<p>\u00c0 Gen\u00e8ve, un porte-parole du HCR (Haut Commissariat des Nations unies pour les r\u00e9fugi\u00e9s), Babar Baloch, a d\u00e9clar\u00e9 que \u00ab\u00a0craignant pour leur vie, 3.300 personnes ont fui vers des villages proches, et parmi elles plus de 2.000 enfants et plus de 500 femmes\u00a0\u00bb. Ces personnes \u00ab\u00a0sont arriv\u00e9es avec tr\u00e8s peu ou aucune possession\u00a0\u00bb et la majorit\u00e9 a \u00e9t\u00e9 \u00ab\u00a0g\u00e9n\u00e9reusement accueillie par les familles locales qui partagent le peu de choses qu&rsquo;elle ont\u00a0\u00bb, a soulign\u00e9 Babar Baloch.<\/p>\n<p>Le HCR, en collaboration avec les autorit\u00e9s locales, chercherait \u00e0 mettre en place 200 abris dans la r\u00e9gion. Une assistance est aussi propos\u00e9e aux personnes d\u00e9plac\u00e9es, bien que \u00ab\u00a0plus de ressources sont n\u00e9cessaires pour augmenter l\u2019aide\u00a0\u00bb, indique M.Baloch.<\/p>\n<p>\u00ab\u00a0Les dispositions ont d\u00e9j\u00e0 \u00e9t\u00e9 prises pour leur assurer un minimum de confort, de logement, de restauration\u00a0\u00bb, a assur\u00e9 toutefois le Premier ministre burkinab\u00e9 Christophe Dabir\u00e9. Voir aussi : Burkina Faso : le bilan continue de grimper \u00e0 Solhan Chargement du lecteur&#8230;<\/p>\n<p><b>Quelles sont les renforts militaires d\u00e9ploy\u00e9es ?<\/b><\/p>\n<p>\u00ab\u00a0Nous allons nous r\u00e9organiser pour pouvoir apporter la r\u00e9ponse appropri\u00e9e \u00e0 la situation\u00a0\u00bb, a assur\u00e9 le Premier ministre Dabir\u00e9, avant de visiter le lieu du drame \u00e0 Solhan. \u00ab\u00a0Nous avons pris des dispositions s\u00e9curitaires et aujourd&rsquo;hui cette partie du territoire est occup\u00e9e par un certain nombre de forces qui sont en train de faire un ratissage\u00a0\u00bb, a-t-il ajout\u00e9, sans en d\u00e9voiler plus sur la strat\u00e9gie militaire de l\u2019arm\u00e9e pour r\u00e9tablir la s\u00e9curit\u00e9 dans la r\u00e9gion.<\/p>\n<p>La France, alli\u00e9e du Burkina dans sa lutte contre les djihadistes, a d\u00e9nonc\u00e9, elle, un \u00ab\u00a0carnage innommable, d&rsquo;une sauvagerie inou\u00efe\u00a0\u00bb. \u00ab\u00a0Il s&rsquo;agit de victimes innocentes d&rsquo;une l\u00e2chet\u00e9 terroriste\u00a0\u00bb, a d\u00e9clar\u00e9 le ministre fran\u00e7ais des Affaires \u00e9trang\u00e8res Jean-Yves Le Drian.<\/p>\n<p>\u00ab\u00a0Nous poursuivons les op\u00e9rations militaires en ce moment m\u00eame dans la zone des \u00ab trois fronti\u00e8res \u00bb en \u00e9troite coordination avec les arm\u00e9es partenaires, avec la force du G5 Sahel et \u00e9videmment avec [la force fran\u00e7aise] Barkhane\u00a0\u00bb, a expliqu\u00e9 le ministre qui se rendra ce vendredi 11 juin \u00e0 Ouagadougou. Les auteurs du massacre ne sont cependant pas encore identifi\u00e9s, selon le ministre fran\u00e7ais.<\/p>\n<p><b>Quelles sont les forces terroristes pr\u00e9sentes dans le r\u00e9gion?<\/b><\/p>\n<p>Le GSIM, ou Jnim en arabe, est la principale alliance jihadiste au Sahel et est dirig\u00e9 par le chef touareg malien Iyad Ag Ghaly. Il est responsable de tr\u00e8s nombreuses attaques, y compris contre des civils, au Burkina, au Mali et au Niger.<\/p>\n<p>Le Groupe de soutien \u00e0 l&rsquo;islam et aux musulmans (GSIM), li\u00e9 \u00e0 Al-Qa\u00efda, a toutefois ni\u00e9 \u00ab\u00a0totalement toute implication\u00a0\u00bb, a rapport\u00e9 Site, l\u2019organisme sp\u00e9cialis\u00e9 dans la surveillance des sites internet jihadistes.<\/p>\n<p>La province de Yagha, o\u00f9 est situ\u00e9 le village de Solhan, est toutefois une zone d&rsquo;action du GSIM, et du groupe Etat Islamique (EI). Rivaux, ils combattent pour le contr\u00f4le des territoires et des ressources dans la r\u00e9gion. Voir aussi : Burkina Faso : o\u00f9 en est la lutte anti-djihadiste ? Chargement du lecteur&#8230;<\/p>\n<p>Depuis l&rsquo;occupation en 2012 du Nord du Mali par des djihadistes, le Sahel est progressivement devenu le th\u00e9\u00e2tre d&rsquo;attaques et d&rsquo;attentats meurtriers d&rsquo;une myriade de groupes jihadistes, li\u00e9s soit \u00e0 Al-Qa\u00efda soit \u00e0 l&rsquo;EI, et implant\u00e9s dans des zones d\u00e9laiss\u00e9es par les pouvoirs centraux. Au Burkina Faso, les forces de s\u00e9curit\u00e9 peinent \u00e0 enrayer la spirale de violences terroristes qui ont fait depuis 2015 plus de 1.400 morts et d\u00e9plac\u00e9 plus d&rsquo;un million de personnes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des violences jihadistes en 2015, il y a cinq jours. Le pays sah\u00e9lien est frapp\u00e9 par des offensives terroristes qui sont de plus en plus fr\u00e9quentes et meurtri\u00e8res. Plus de [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":13729,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,20,10],"tags":[111,725,29],"class_list":["post-13730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>des milliers de d\u00e9plac\u00e9s apr\u00e8s l&#039;attaque sanglante contre Solhan - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des vio ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"des milliers de d\u00e9plac\u00e9s apr\u00e8s l&#039;attaque sanglante contre Solhan\" \/>\n<meta property=\"og:description\" content=\"Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des vio ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-09T14:23:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T20:18:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"des milliers de d\u00e9plac\u00e9s apr\u00e8s l&rsquo;attaque sanglante contre Solhan\",\"datePublished\":\"2021-06-09T14:23:08+00:00\",\"dateModified\":\"2021-06-09T20:18:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\"},\"wordCount\":909,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\",\"name\":\"des milliers de d\u00e9plac\u00e9s apr\u00e8s l'attaque sanglante contre Solhan - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg\",\"datePublished\":\"2021-06-09T14:23:08+00:00\",\"dateModified\":\"2021-06-09T20:18:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des vio ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg\",\"width\":770,\"height\":539,\"caption\":\"Burkina Faso : des milliers de d\u00e9plac\u00e9s apr\u00e8s l'attaque sanglante contre Solhan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"des milliers de d\u00e9plac\u00e9s apr\u00e8s l&#8217;attaque sanglante contre Solhan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"des milliers de d\u00e9plac\u00e9s apr\u00e8s l'attaque sanglante contre Solhan - Burkina Faso","description":"Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des vio ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan","og_locale":"fr_FR","og_type":"article","og_title":"des milliers de d\u00e9plac\u00e9s apr\u00e8s l'attaque sanglante contre Solhan","og_description":"Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des vio ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan","og_site_name":"Burkina Faso","article_published_time":"2021-06-09T14:23:08+00:00","article_modified_time":"2021-06-09T20:18:20+00:00","og_image":[{"width":770,"height":539,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"des milliers de d\u00e9plac\u00e9s apr\u00e8s l&rsquo;attaque sanglante contre Solhan","datePublished":"2021-06-09T14:23:08+00:00","dateModified":"2021-06-09T20:18:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan"},"wordCount":909,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Dossiers","homepage-french","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan","url":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan","name":"des milliers de d\u00e9plac\u00e9s apr\u00e8s l'attaque sanglante contre Solhan - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg","datePublished":"2021-06-09T14:23:08+00:00","dateModified":"2021-06-09T20:18:20+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le Burkina Faso, pays situ\u00e9 entre le Niger et le Mali, a connu son attaque la plus meurtri\u00e8re depuis le d\u00e9but des vio ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/06\/img-60c0c3043ca0b.jpg","width":770,"height":539,"caption":"Burkina Faso : des milliers de d\u00e9plac\u00e9s apr\u00e8s l'attaque sanglante contre Solhan"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/burkina-faso-des-milliers-de-deplaces-apres-lattaque-sanglante-contre-solhan#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"des milliers de d\u00e9plac\u00e9s apr\u00e8s l&#8217;attaque sanglante contre Solhan"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/13730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=13730"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/13730\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/13729"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=13730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=13730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=13730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}