{"id":21014,"date":"2021-09-17T17:43:22","date_gmt":"2021-09-17T17:43:22","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/?p=21014"},"modified":"2021-09-17T18:32:44","modified_gmt":"2021-09-17T18:32:44","slug":"le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients","title":{"rendered":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>. <\/strong><\/span><b>\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients. \u00abSoins maternels et n\u00e9onatals sans risque \u00bb est le th\u00e8me retenu pour cette ann\u00e9e.<\/b><\/p>\n<p>Institu\u00e9e en 2019, la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients est c\u00e9l\u00e9br\u00e9e d\u00e9sormais chaque 17 septembre. Quant au th\u00e8me choisi pour cette ann\u00e9e, le ministre de la sant\u00e9, Pr Charlemagne Ou\u00e9draogo a soulign\u00e9 l\u2019importance de la sant\u00e9 de la m\u00e8re et de l\u2019enfant. Selon les explications du ministre, la sant\u00e9 de la m\u00e8re et de l\u2019enfant constitue un indicateur de d\u00e9veloppement pour les pays du monde.<\/p>\n<p>\u00ab C\u2019est pour cela que nous avons voulu c\u00e9l\u00e9brer cette journ\u00e9e et rappeler \u00e0 l\u2019ensemble de la communaut\u00e9 nationale et internationale qu\u2019il est important d\u2019investir dans la sant\u00e9 de la m\u00e8re et de l\u2019enfant \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Il a poursuivi que cet investissement doit \u00eatre de nature \u00e0 prot\u00e9ger la m\u00e8re et l\u2019enfant en leur offrant des soins appropri\u00e9s et efficaces. \u00ab Des soins d\u00e9nou\u00e9s de toute situation qui pourraient compromettre la sant\u00e9 de la m\u00e8re et de l\u2019enfant \u00bb, a-t-il relev\u00e9.<\/p>\n<p>Pr Charlemagne a insist\u00e9 sur la qualit\u00e9 des soins de sant\u00e9. Pour lui, on ne peut pas parler de la s\u00e9curit\u00e9 des soins des patients si le volet qualit\u00e9 n\u2019est pas pris en compte dans la prise en charge des patients.<\/p>\n<p>\u00c9galement, le ministre de la sant\u00e9 a \u00e9voqu\u00e9 quelques insuffisances auxquelles les structures sanitaires font face et qui peuvent jouer n\u00e9gativement sur la prestation des soins de qualit\u00e9 aux patients. \u00ab Si vous avez un plateau technique qui est insuffisant, c\u2019est difficile de donner les soins en toute s\u00e9curit\u00e9.<\/p>\n<p><b>Si vous avez une insuffisance en \u00e9nergie avec des pannes d\u2019\u00e9lectricit\u00e9, c\u2019est difficile de donner des soins de qualit\u00e9 en toute s\u00e9curit\u00e9 dans l\u2019obscurit\u00e9. Si vous avez des agents de sant\u00e9 qui sont absents \u00e0 leurs postes de travail au moment o\u00f9 ils doivent \u00eatre, c\u2019est difficile de parler de s\u00e9curit\u00e9 des soins et donc de qualit\u00e9 des soins<\/b><\/p>\n<p>\u00bb, a-t-il \u00e9gren\u00e9.<\/p>\n<p>La repr\u00e9sentante de l\u2019OMS, Dr Alimata Diarra Nama, a, \u00e0 cette occasion, donn\u00e9 des chiffres sur les risques li\u00e9s aux soins de sant\u00e9 maternelle et n\u00e9onatale en Afrique. Chaque jour, a-t-elle affirm\u00e9, 536 femmes meurent de causes li\u00e9es \u00e0 la grossesse et \u00e0 l\u2019accouchement. \u00ab La plupart de ces d\u00e9c\u00e8s peuvent \u00eatre \u00e9vit\u00e9s moyennant l\u2019acc\u00e8s \u00e0 un professionnel de sant\u00e9 qualifi\u00e9\u00bb, a-t-elle renseign\u00e9.<\/p>\n<p>Elle a ajout\u00e9 que plus de 6700 nouveau-n\u00e9s meurent de ces causes soit 47 % des d\u00e9c\u00e8s d\u2019enfants de moins de 5 ans. Aussi, Dr Alimata Diarra Nama a signal\u00e9 que l\u2019OMS \u0153uvre de concert avec les pays pour la mise en place des plans d\u2019actions mondiales pour la s\u00e9curit\u00e9 des patients. Ces plans, selon ses dires s\u2019\u00e9tendent sur la p\u00e9riode 2021-2030.<\/p>\n<p>\u00ab Dans cette optique, les pays doivent \u00e9laborer des strat\u00e9gies nationales sur la qualit\u00e9 afin d\u2019am\u00e9liorer les pratiques et d\u2019accro\u00eetre la responsabilisation, et renforcer les capacit\u00e9s dans le cadre d\u2019initiatives ax\u00e9es sur l\u2019am\u00e9lioration de qualit\u00e9 que rencontrent les besoins des patients \u00bb, a-t-elle rajout\u00e9.<\/p>\n<p>\u00c0 l\u2019entendre, le th\u00e8me choisi pour cette ann\u00e9e est un appel \u00e0 l\u2019endroit de tous les acteurs gouvernementaux, de la soci\u00e9t\u00e9 civile et du secteur priv\u00e9 afin de jouer leur r\u00f4le afin de garantir \u00e0 toutes les femmes, un accouchement \u00e0 moindre risque.<\/p>\n<p>Pour sa part, Dr cl\u00e9mentine Dabir\u00e9 a indiqu\u00e9 que le th\u00e8me choisi cette ann\u00e9e interpelle tout le monde \u00e0 agir \u00ab maintenant \u00bb pour un accouchement s\u00fbr et respectueux. Et ce, pour am\u00e9liorer la situation des femmes et des nouveau-n\u00e9s autour de l\u2019accouchement, a-t-elle insist\u00e9.<\/p>\n<p>\u00ab En effet, \u00e0 travers le monde, 810 femmes meurent chaque jour des causes en lien avec la grossesse et l\u2019accouchement qui pourraient \u00eatre \u00e9vit\u00e9es \u00bb, a-t-elle d\u00e9plor\u00e9 en mentionnant qu\u2019au Burkina Faso, la situation s\u2019est aggrav\u00e9e par les perturbations des services essentiels de sant\u00e9 engendr\u00e9es par la pand\u00e9mie de Covid-19 et la situation s\u00e9curitaire dans certaines localit\u00e9s du pays.<\/p>\n<p><b>\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. \u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients. \u00abSoins maternels et n\u00e9onatals sans risque \u00bb est le th\u00e8me retenu pour cette ann\u00e9e. Institu\u00e9e en 2019, la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients est c\u00e9l\u00e9br\u00e9e [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":21013,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11,10],"tags":[111,725,29],"class_list":["post-21014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-et-art","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients - Burkina Faso<\/title>\n<meta name=\"description\" content=\"\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T17:43:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-17T18:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients\",\"datePublished\":\"2021-09-17T17:43:22+00:00\",\"dateModified\":\"2021-09-17T18:32:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\"},\"wordCount\":744,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Culture et Art\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\",\"name\":\"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg\",\"datePublished\":\"2021-09-17T17:43:22+00:00\",\"dateModified\":\"2021-09-17T18:32:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg\",\"width\":1024,\"height\":450,\"caption\":\"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients - Burkina Faso","description":"\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients","og_locale":"fr_FR","og_type":"article","og_title":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients","og_description":"\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients","og_site_name":"Burkina Faso","article_published_time":"2021-09-17T17:43:22+00:00","article_modified_time":"2021-09-17T18:32:44+00:00","og_image":[{"width":1024,"height":450,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients","datePublished":"2021-09-17T17:43:22+00:00","dateModified":"2021-09-17T18:32:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients"},"wordCount":744,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Culture et Art","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients","url":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients","name":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg","datePublished":"2021-09-17T17:43:22+00:00","dateModified":"2021-09-17T18:32:44+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"\u00c0 l\u2019instar des autres pays du monde, le Burkina Faso c\u00e9l\u00e8bre ce vendredi 17 septembre 2021, la journ\u00e9e mondiale de la ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cbf1a534a.jpg","width":1024,"height":450,"caption":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/culture-et-art\/le-burkina-faso-celebre-la-journee-mondiale-de-la-securite-des-patients#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Le Burkina Faso c\u00e9l\u00e8bre la journ\u00e9e mondiale de la s\u00e9curit\u00e9 des patients"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/21014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=21014"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/21014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/21013"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=21014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=21014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=21014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}