{"id":21047,"date":"2021-09-17T19:06:40","date_gmt":"2021-09-17T19:06:40","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/?p=21047"},"modified":"2021-09-17T18:31:16","modified_gmt":"2021-09-17T18:31:16","slug":"soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante","title":{"rendered":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>. <\/strong><\/span><b>Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a \u00e9t\u00e9 donn\u00e9 le mercredi 15 septembre 2021. C\u2019est Sibiri Gr\u00e9goire Ou\u00e9draogo qui a ouvert le bal. L\u2019imp\u00e9trant a analys\u00e9 \u00ab L\u2019impact de l\u2019aide publique au d\u00e9veloppement sur la r\u00e9duction de la pauvret\u00e9 : Cas du Burkina Faso \u00bb. Pour plus d\u2019impact, il propose que l\u2019aide soit orient\u00e9e vers les d\u00e9penses li\u00e9es \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9. Le th\u00e8me, le fond et la forme ont eu l\u2019approbation du jury qui lui a d\u00e9cern\u00e9 la note de 17\/20.<\/b><\/p>\n<p>Sibiri Gr\u00e9goire Ou\u00e9draogo, conseiller en \u00e9conomie de d\u00e9veloppement, est le premier \u00e0 se jeter \u00e0 l\u2019eau. Il a ouvert le bal de la s\u00e9rie de soutenances des m\u00e9moires de la session de septembre 2021, des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF). L\u2019imp\u00e9trant s\u2019est appesanti sur \u00ab L\u2019impact de l\u2019aide social publique au d\u00e9veloppement sur la r\u00e9duction de la pauvret\u00e9 : Cas du Burkina Faso \u00bb. Pour ce qui ressort de son expos\u00e9, l\u2019aide publique au d\u00e9veloppement n\u2019est pas mauvaise en soi, mais c\u2019est l\u2019utilisation qu\u2019on en fait qui cause probl\u00e8me.<\/p>\n<p>D\u2019apr\u00e8s ses explications, le choix du th\u00e8me est d\u00fb au volume d\u2019aide sans cesse croissant que re\u00e7oit le Burkina Faso. Paradoxalement, on observe une hausse de la tendance du niveau de la pauvret\u00e9 de la population. D\u2019o\u00f9 il tire la conclusion que les politiques pour favoriser la croissance n\u2019engendrent pas forcement une r\u00e9duction de la pauvret\u00e9. \u00ab Dans une telle perspective, nous nous sommes int\u00e9ress\u00e9s \u00e0 d\u2019autres mani\u00e8res d\u2019appr\u00e9hender la possibilit\u00e9 que l\u2019aide publique puisse r\u00e9duire la pauvret\u00e9 \u00bb, a-t-il expliqu\u00e9.<\/p>\n<p>M. Ou\u00e9draogo a tout de m\u00eame pr\u00e9cis\u00e9 que la question de la r\u00e9duction de la pauvret\u00e9 n\u2019est pas d\u2019ordre global. Pour ce qui concerne le Burkina Faso, il a suppos\u00e9 qu\u2019en travaillant \u00e0 lutter contre la corruption, l\u2019aide publique pourrait jouer son r\u00f4le, \u00e0 savoir r\u00e9duire la pauvret\u00e9.<\/p>\n<p>Les travaux du candidat concluent que l\u2019aide publique au d\u00e9veloppement qui finance les d\u00e9penses de sant\u00e9 et d\u2019\u00e9ducation n\u2019a pas d\u2019impact significatif sur la pauvret\u00e9 \u00e0 court terme mais montre son efficacit\u00e9 pour r\u00e9duire la pauvret\u00e9 \u00e0 long terme. Pour lui, la bonne gouvernance pourrait am\u00e9liorer l\u2019impact de l\u2019aide sur la r\u00e9duction de la pauvret\u00e9 au Burkina Faso. Et comme perspectives, il propose d\u2019appr\u00e9cier l\u2019effet de l\u2019aide en s\u2019int\u00e9ressant aux types d\u2019aide, d\u2019aligner plus de partenaires sur les financements et enfin de combiner les politiques de bonne gouvernance avec les politiques de redistribution de revenus.<\/p>\n<p><b>Un m\u00e9moire de qualit\u00e9 et un travail de fond int\u00e9ressant<\/b><\/p>\n<p>D\u2019apr\u00e8s le directeur de m\u00e9moire, par ailleurs directeur de la coordination et de l\u2019efficacit\u00e9 de l\u2019aide, Dr Jean-Marie K\u00e9br\u00e9, le document traduit de fa\u00e7on globale tout le travail qu\u2019ils ont abattu ensemble. Il est cependant revenu sur des \u00e9l\u00e9ments que l\u2019imp\u00e9trant aurait pu parfaire. Le directeur de m\u00e9moire a indiqu\u00e9 qu\u2019il y a un l\u00e9ger \u00ab rat\u00e9 \u00bb sur la d\u00e9finition de l\u2019aide publique au d\u00e9veloppement qui est selon lui, assez restrictive et ne permet pas d\u2019appr\u00e9hender la notion enti\u00e8rement. Il sied, a-t-il conseill\u00e9, d\u2019utiliser le terme, \u00ab aide int\u00e9gr\u00e9e \u00bb. La pr\u00e9sentation des tableaux dans le document par le candidat, a \u00e9galement \u00e9t\u00e9 critiqu\u00e9e par le Dr K\u00e9br\u00e9. A l\u2019en croire, la pr\u00e9sentation scientifique voudrait qu\u2019ils les pr\u00e9sentent en premier, avant les autres \u00e9l\u00e9ments. Il a souhait\u00e9, pour terminer, qu\u2019il am\u00e9liore la bibliographie du document.<\/p>\n<p>Le pr\u00e9sident du jury de la soutenance, Dr Abel Seglaro Som\u00e9, secr\u00e9taire g\u00e9n\u00e9ral du minist\u00e8re de l\u2019\u00c9conomie et des finances, a jug\u00e9 le m\u00e9moire de l\u2019imp\u00e9trant de \u00ab qualit\u00e9 \u00bb et \u00ab int\u00e9ressant \u00bb comme travail. Le sujet a \u00e9t\u00e9 jug\u00e9 \u00e9galement digne d\u2019int\u00e9r\u00eat pour la politique nationale de d\u00e9veloppement. Cependant, Dr Som\u00e9 a sugg\u00e9r\u00e9 au candidat de \u00ab muscler \u00bb davantage sa partie analytique.<\/p>\n<p>De son avis, les Burkinab\u00e8, t\u00e9moins de l\u2019accompagnement des partenaires techniques et financiers, pourraient effectivement se demander si cela apporte quelque chose au bien-\u00eatre des populations. Le travail, a-t-il poursuivi, a essay\u00e9 de faire ressortir cela avec une certaine technicit\u00e9 et des conclusions int\u00e9ressantes. L\u2019imp\u00e9trant a estim\u00e9 que si on orientait l\u2019aide sur les d\u00e9penses d\u2019\u00e9ducation et de sant\u00e9, il y allait avoir plus d\u2019effet sur la r\u00e9duction de la pauvret\u00e9.<\/p>\n<p><b>17\/20, mention tr\u00e8s bien et f\u00e9licitation du jury<\/b><\/p>\n<p>\u00ab Vous avez pr\u00e9sent\u00e9 votre m\u00e9moire sur : \u00ab L\u2019impact de l\u2019aide publique au d\u00e9veloppement pour la r\u00e9duction de la pauvret\u00e9 : Cas du Burkina Faso \u00bb. Apr\u00e8s en avoir d\u00e9lib\u00e9r\u00e9, le jury estime que du point de vue de la forme, le document est bien pr\u00e9sent\u00e9 et contient peu de fautes. C\u2019est un document qui est conforme aux r\u00e8gles de l\u2019\u00e9cole. Pour cela on lui donne la note de 4\/5. Pour ce qui concerne le fond, il estime que le sujet est digne d\u2019int\u00e9r\u00eat pour la politique nationale de d\u00e9veloppement et vous avez de bonnes recommandations, pour cela on vous donne la note de 9\/10. Enfin pour l\u2019expos\u00e9, on estime que votre pr\u00e9sentation est r\u00e9v\u00e9latrice d\u2019une bonne ma\u00eetrise du sujet. Pour cela on vous donne la note de 4\/5. Vous avez donc 17\/20, une mention tr\u00e8s bien avec f\u00e9licitation du jury \u00bb, telle est la \u00ab sanction \u00bb du jury.<\/p>\n<p>Pour rappel, la session de soutenance de septembre 2021 \u00e0 l\u2019ENAREF concerne 77 \u00e9l\u00e8ves dont 26 inspecteurs des imp\u00f4ts, 17 \u00e9l\u00e8ves administrateurs des services financiers, 14 \u00e9l\u00e8ves inspecteurs du tr\u00e9sor, 5 conseillers en \u00e9conomie de d\u00e9veloppement, 5 conseillers en am\u00e9nagement du territoire et 10 conseillers en statistiques et analyse du d\u00e9veloppement. Obissa Juste MIEN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a \u00e9t\u00e9 donn\u00e9 le mercredi 15 septembre 2021. C\u2019est Sibiri Gr\u00e9goire Ou\u00e9draogo qui a ouvert le bal. L\u2019imp\u00e9trant a analys\u00e9 \u00ab L\u2019impact de l\u2019aide publique au d\u00e9veloppement sur la r\u00e9duction de la pauvret\u00e9 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":21046,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11,10],"tags":[111,725,29],"class_list":["post-21047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9 - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9\" \/>\n<meta property=\"og:description\" content=\"Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T19:06:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9\",\"datePublished\":\"2021-09-17T19:06:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\"},\"wordCount\":1074,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\",\"name\":\"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9 - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg\",\"datePublished\":\"2021-09-17T19:06:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg\",\"width\":720,\"height\":444,\"caption\":\"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9 - Burkina Faso","description":"Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante","og_locale":"fr_FR","og_type":"article","og_title":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9","og_description":"Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante","og_site_name":"Burkina Faso","article_published_time":"2021-09-17T19:06:40+00:00","og_image":[{"width":720,"height":444,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9","datePublished":"2021-09-17T19:06:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante"},"wordCount":1074,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Communaut\u00e9","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante","name":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9 - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg","datePublished":"2021-09-17T19:06:40+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le top d\u00e9part des soutenances de m\u00e9moires des \u00e9l\u00e8ves (cycle A) de l\u2019Ecole nationale des r\u00e9gies financi\u00e8res (ENAREF) a ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-6144cd6cbb66a.jpg","width":720,"height":444,"caption":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/soutenance-de-memoires-a-lenaref-sibiri-g-ouedraogo-propose-dorienter-laide-sur-les-depenses-a-leducation-et-a-la-sante#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Soutenance de m\u00e9moires \u00e0 l\u2019ENAREF : Sibiri G. Ou\u00e9draogo propose d\u2019orienter l\u2019aide sur les d\u00e9penses \u00e0 l\u2019\u00e9ducation et \u00e0 la sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/21047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=21047"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/21047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/21046"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=21047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=21047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=21047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}