{"id":21220,"date":"2021-09-19T13:39:18","date_gmt":"2021-09-19T13:39:18","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/?p=21220"},"modified":"2021-09-20T14:05:25","modified_gmt":"2021-09-20T14:05:25","slug":"ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens","title":{"rendered":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>. <\/strong><\/span>Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sentation des avions en bois ou en pl\u00e2tre. Depuis 2012, il s\u2019est investi dans le dessin a\u00e9ronautique et artistique. Dans un atelier de fortune, ce jeune \u201cavionneur\u201d fait des merveilles. est all\u00e9 \u00e0 la rencontre de ce concepteur de r\u00eave et promoteur de la marque \u00ab Nit-Design \u00bb. D\u00e9couvrez son histoire \u00e0 travers les lignes qui suivent.<\/p>\n<p>Depuis l\u2019\u00e2ge de deux ans, Mo\u00efse Niti\u00e9ma est tomb\u00e9 \u201camoureux\u201d des avions. Le d\u00e9clic, il l\u2019explique que le jour o\u00f9 son p\u00e8re devait prendre l\u2019avion, subitement, il a voulu comprendre le fonctionnement de cet appareil. Au retour de son p\u00e8re, il le harc\u00e8le de question. S\u2019inspirant des dessins de son p\u00e8re, dessinateur en b\u00e2timent, il s\u2019est mis \u00e0 son tour \u00e0 dessiner des avions.<\/p>\n<p>En 2012, il a eu l\u2019id\u00e9e de mat\u00e9rialiser ce qu\u2019il dessinait. Il pr\u00e9cise qu\u2019au d\u00e9but, il confectionnait les avions avec du fer. En 2014, il obtient son premier t\u00e9l\u00e9phone qui pouvait prendre des photos. Ainsi, il publie ses \u0153uvres r\u00e9guli\u00e8rement sur les r\u00e9seaux sociaux. Un jour, un membre du personnel de la compagnie \u201cAir Burkina\u201d tombe sur une de ses publications.<\/p>\n<p>Alors, ce dernier rentre en contact avec lui et l\u2019invite \u00e0 l\u2019a\u00e9roport de Ouagadougou pour voir de plus pr\u00e8s les avions. Il d\u00e9couvre l\u2019avion dans tous ses compartiments pour la premi\u00e8re fois. Celui-ci commande une maquette avec lui, puis le conseille de commercialiser ses confections.<\/p>\n<p>A partir de ce jour, il \u00e9tait envahi de commande de maquettes d\u2019avions. \u00ab J\u2019ai con\u00e7u des Embraer 195 pour des employ\u00e9s de Air Burkina, des h\u00e9licopt\u00e8res MI24 pour l\u2019arm\u00e9e, Airbus A380 Air France pour un personnel de Air France, des Boeing 737 pour des particuliers \u00bb, relate-t-il.<\/p>\n<p>Puis en 2017, un ing\u00e9nieur d\u2019Airbus, le constructeur a\u00e9ronautique europ\u00e9en, est tomb\u00e9 sur ses publications sur les r\u00e9seaux sociaux. Ce dernier d\u00e9cide de l\u2019aider \u00e0 perfectionner ses conceptions. La formation \u00e0 distance a dur\u00e9 pratiquement trois ans. Actuellement, il trouve qu\u2019il a les aptitudes n\u00e9cessaires pour mat\u00e9rialiser tout type de repr\u00e9sentation.<\/p>\n<p>Son astuce pour construire quelque chose qu\u2019il n\u2019a jamais vu, il t\u00e9l\u00e9charge son image sur internet et le reproduit en 3D sur son ordinateur pour bien l\u2019observer.<\/p>\n<p>Mo\u00efse Niti\u00e9ma affirme que les maquettes des avions sont plus pris\u00e9es par les agents de l\u2019aviation civile comme militaire. Pr\u00e9sentement, il affirme ne pas s\u2019ennuyer avec plus de 27 commandes de maquettes d\u2019avion \u00e0 faire sous la main.<\/p>\n<p>En plus, des architectes lui ont demand\u00e9 la reproduction des maquettes de leur projet. En termes d\u2019\u00e9quipement, il souligne que le manque de machine handicapait la fabrication des maquettes, mais avec sa nouvelle acquisition, il peut produire 30 maquettes en une semaine.<\/p>\n<p>Air Sarada International, Air Burkina, Faso Aircraft Services, ont sponsoris\u00e9 sa marque \u00ab NIT Design \u00bb. Ce qui lui a permis de mieux s\u2019\u00e9quiper. Il n\u2019est pas avare, il partage ses connaissances avec d\u2019autres personnes. Actuellement, il forme plus d\u2019une dizaine de jeunes passionn\u00e9s de l\u2019a\u00e9ronautique.<\/p>\n<p>Concernant la rentabilit\u00e9 de sa passion, il fait savoir que \u00e7a rapporte \u201cbeaucoup\u201d. Le prix de ses maquettes d\u00e9pend de la taille, de l\u2019objet et les prix vont de 10 000 \u00e0 400 000 FCFA.<\/p>\n<p>L\u2019avionneur b\u00e9n\u00e9ficie du soutien de son p\u00e8re. Lassan\u00e9 Niti\u00e9ma, technicien sup\u00e9rieur des travaux publics, qui qualifie le savoir-faire de son fils de \u201cdon\u201d. Il rappelle que c\u2019est lors de son voyage en \u00c9gypte que son fils avait \u00e0 peine trois ans, que sa passion est n\u00e9e pour les avions.<\/p>\n<p>\u00ab C\u2019est \u00e0 l\u2019issue d\u2019un voyage en \u00c9gypte, et pour lui, tout avion qui passe c\u2019est s\u00fbr que son papa est dedans. La vocation est n\u00e9e comme cela \u00bb, explique-t-il.<\/p>\n<p>A son retour, tr\u00e8s curieux il n\u2019arr\u00eate pas d\u2019interroger son p\u00e8re sur la description d\u2019un avion. Et comme son p\u00e8re est un dessinateur, il demande \u00e0 son p\u00e8re de reproduire des mod\u00e8les d\u2019avions.<\/p>\n<p>Lassan\u00e9 Niti\u00e9ma explique qu\u2019il \u00e9tait oblig\u00e9 de se cacher les matins pour aller travailler afin d\u2019\u00e9viter les demandes r\u00e9currentes de dessiner des avions.<\/p>\n<p>\u00ab Dans le temps, pour laver ses habits il fallait faire tr\u00e8s attention. Dans ses poches, ce sont toujours des brindilles, des morceaux de fer et des lames. Nous, on l\u2019appelait le bricoleur. Aujourd\u2019hui, il fait du tout. Il est menuisier, peintre et maquettiste. Il peut vous dessiner un avion en trois minutes \u00bb, indique-t-il.<\/p>\n<p>Concernant l\u2019avenir de son fils, il fait savoir que \u00ab tout a de l\u2019avenir. Il suffit d\u2019aimer. On a constat\u00e9 que ce qu\u2019il fait, beaucoup l\u2019appr\u00e9cient et il se fait des petits sous. Il est en formation en \u00e9lectronique. Avec \u00e7a, il a d\u00e9j\u00e0 une base. Et dans le domaine de l\u2019aviation, on a besoin de l\u2019\u00e9lectronique. Quand il touche \u00e0 tout \u00e7a devient un miracle \u00bb\u2026 Jules C\u00e9sar KABORE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sentation des avions en bois ou en pl\u00e2tre. Depuis 2012, il s\u2019est investi dans le dessin a\u00e9ronautique et artistique. Dans un atelier de fortune, ce jeune \u201cavionneur\u201d fait des merveilles. est all\u00e9 \u00e0 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":21219,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[111,725,29],"class_list":["post-21220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sent ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens\" \/>\n<meta property=\"og:description\" content=\"Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sent ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-19T13:39:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-20T14:05:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens\",\"datePublished\":\"2021-09-19T13:39:18+00:00\",\"dateModified\":\"2021-09-20T14:05:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\"},\"wordCount\":896,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\",\"name\":\"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg\",\"datePublished\":\"2021-09-19T13:39:18+00:00\",\"dateModified\":\"2021-09-20T14:05:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sent ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg\",\"width\":750,\"height\":417,\"caption\":\"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens - Burkina Faso","description":"Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sent ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens","og_locale":"fr_FR","og_type":"article","og_title":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens","og_description":"Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sent ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens","og_site_name":"Burkina Faso","article_published_time":"2021-09-19T13:39:18+00:00","article_modified_time":"2021-09-20T14:05:25+00:00","og_image":[{"width":750,"height":417,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens","datePublished":"2021-09-19T13:39:18+00:00","dateModified":"2021-09-20T14:05:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens"},"wordCount":896,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens","name":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg","datePublished":"2021-09-19T13:39:18+00:00","dateModified":"2021-09-20T14:05:25+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Wend-Kuni Mo\u00efse Niti\u00e9ma, 23 ans, vit pleinement sa passion. Designer et maquettiste, il fait de sa passion, la repr\u00e9sent ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/09\/img-61472e0000737.jpg","width":750,"height":417,"caption":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/ici-au-faso-moise-nitiema-le-jeune-avionneur-qui-appate-des-europeens#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Ici Au Faso : Mo\u00efse Niti\u00e9ma, le jeune \u201cavionneur\u201d qui app\u00e2te des Europ\u00e9ens"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/21220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=21220"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/21220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/21219"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=21220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=21220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=21220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}