{"id":22977,"date":"2021-10-17T17:41:57","date_gmt":"2021-10-17T17:41:57","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/larchitecture-emblematique-de-lafrique-en-12-batiments"},"modified":"2021-10-18T20:50:00","modified_gmt":"2021-10-18T20:50:00","slug":"larchitecture-emblematique-de-lafrique-en-12-batiments","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments","title":{"rendered":"L&rsquo;architecture embl\u00e9matique de l&rsquo;Afrique en 12 b\u00e2timents"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>. <\/strong><\/span>Si les pyramides d&rsquo;\u00c9gypte sont connues dans le monde entier, une grande partie de l&rsquo;architecture africaine reste inconnue, ce que les architectes Adil Dalbai et Livingstone Mukasa esp\u00e8rent changer.<\/p>\n<p>Ils font partie de l&rsquo;\u00e9quipe qui a r\u00e9cemment publi\u00e9 le Guide architectural de l&rsquo;Afrique subsaharienne en sept volumes. Leur \u00e9tude approfondie englobe des b\u00e2timents des \u00e9poques ant\u00e9rieures, de la p\u00e9riode coloniale &#8211; comme la gare r\u00e9cemment r\u00e9nov\u00e9e (ci-dessus) construite \u00e0 Dakar, la capitale du S\u00e9n\u00e9gal, en 1910, aux chefs-d&rsquo;\u0153uvre plus modernes.<\/p>\n<p>Voici 12 des entr\u00e9es les plus innovantes, historiques et embl\u00e9matiques :<\/p>\n<p>1) Tombes de Kasubi, Ouganda &#8211; 1882Couvrant des hectares de terres agricoles dans la capitale ougandaise, Kampala, le complexe royal de Kasubi est le lieu de s\u00e9pulture des monarques du royaume du Buganda. Il a \u00e9t\u00e9 construit principalement en bois et autres mat\u00e9riaux organiques. L&rsquo;int\u00e9rieur est con\u00e7u pour reproduire une for\u00eat sacr\u00e9e et est surmont\u00e9 de 52 anneaux circulaires pour repr\u00e9senter chacun des 52 clans du Buganda.<\/p>\n<p>Mukasa, qui est n\u00e9 en Ouganda, a visit\u00e9 les tombes pour la premi\u00e8re fois lorsqu&rsquo;il avait 10 ans. \u00ab\u00a0C&rsquo;\u00e9tait stup\u00e9fiant\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 \u00e0 la BBC. \u00ab\u00a0Pas seulement l&rsquo;\u00e9chelle, mais toute la grandeur de l&rsquo;\u00e9difice.<\/p>\n<p>\u00ab\u00a0Il a \u00e9t\u00e9 construit \u00e0 la fin du XIXe si\u00e8cle, avant l&rsquo;introduction des mat\u00e9riaux modernes, en utilisant des m\u00e9thodes traditionnelles vieilles de plusieurs si\u00e8cles. Je sentais que le b\u00e2timent avait une pr\u00e9sence. Lorsque vous \u00e9tiez \u00e0 l&rsquo;int\u00e9rieur, il vous dominait.\u00a0\u00bb<\/p>\n<p>2) March\u00e9 de Lideta, \u00c9thiopie &#8211; 2017D&rsquo;inspiration contemporaine, ce centre commercial a \u00e9t\u00e9 construit par Vilalta Studio dans la capitale \u00e9thiopienne, Addis-Abeba, avec du b\u00e9ton l\u00e9ger.<\/p>\n<p>La conception r\u00e9fl\u00e9chie comprend une fa\u00e7ade perfor\u00e9e qui contr\u00f4le le flux de lumi\u00e8re naturelle et la ventilation \u00e0 l&rsquo;int\u00e9rieur.<\/p>\n<p>En outre, le motif d\u00e9coup\u00e9 qui d\u00e9core la coque blanche \u00e9tincelante du b\u00e2timent imite un tissu \u00e9thiopien traditionnel.<\/p>\n<p>3) Complexe Hikma, Niger &#8211; 2018La fondatrice nig\u00e9rienne du studio d&rsquo;architecture Atelier Mas\u014dm\u012b, Mariam Kamara, a collabor\u00e9 avec Yasaman Esmaili du Studio Chahar pour restaurer une ancienne mosqu\u00e9e Hausa qui \u00e9tait tomb\u00e9e en ruine, en y ajoutant un espace communautaire et une biblioth\u00e8que.<\/p>\n<p>Les briques de terre comprim\u00e9e constituent la majeure partie du b\u00e2timent et les mat\u00e9riaux proviennent principalement d&rsquo;un rayon de 5 km autour du site, dans le village de Dandaji.<\/p>\n<p>Pour M. Dalbai, le projet est particuli\u00e8rement impressionnant en raison du m\u00e9lange harmonieux de l&rsquo;ancien et du nouveau.<\/p>\n<p>\u00ab\u00a0C&rsquo;est clairement un b\u00e2timent contemporain qui est profond\u00e9ment ancr\u00e9 dans la tradition nig\u00e9rienne\u00a0\u00bb, a d\u00e9clar\u00e9 l&rsquo;architecte allemand \u00e0 la BBC. \u00ab\u00a0Non seulement sur le plan culturel, mais aussi sur le plan technique, car il s&rsquo;appuie sur des techniques de construction et des mat\u00e9riaux traditionnels anciens.\u00a0\u00bb<\/p>\n<p>4) Centre des visiteurs de Maropeng, Afrique du Sud &#8211; 2006Connu comme le site du patrimoine mondial du berceau de l&rsquo;humanit\u00e9, Maropeng est un centre de visiteurs ultramoderne con\u00e7u pour aider les gens \u00e0 s&rsquo;informer sur le d\u00e9veloppement pr\u00e9coce de l&rsquo;homme moderne.<\/p>\n<p>Cette structure embl\u00e9matique a \u00e9t\u00e9 con\u00e7ue par les cabinets sud-africains GAPP Architects et MMA Studio.<\/p>\n<p>Le b\u00e2timent lui-m\u00eame ressemble \u00e0 un monticule fun\u00e9raire \u00e9mergeant de la terre dans un design qui semble v\u00e9ritablement int\u00e9gr\u00e9 \u00e0 la nature.<\/p>\n<p>5) Pyramides de Mero\u00eb, Soudan &#8211; 300 avant J.-C.Les plus anciennes entr\u00e9es du guide sont ces pyramides \u00e0 degr\u00e9s, qui datent de 3 000 ans avant J\u00e9sus-Christ, situ\u00e9es \u00e0 environ 200 km de Khartoum, la capitale du Soudan, \u00e0 Mero\u00eb, dans la vall\u00e9e du Nil.<\/p>\n<p>Ce site inscrit au patrimoine mondial de l&rsquo;Unesco \u00e9tait autrefois la capitale de l&rsquo;ancien empire koushite et les fouilles ont r\u00e9v\u00e9l\u00e9 les vestiges de palais, de temples et de thermes royaux.<\/p>\n<p>Les pyramides de ce site fun\u00e9raire ont \u00e9t\u00e9 construites avec des blocs de gr\u00e8s, tandis que des reliefs \u00e9labor\u00e9s sont grav\u00e9s \u00e0 l&rsquo;int\u00e9rieur.<\/p>\n<p>6) Maisons basotho, Lesotho &#8211; date inconnueAu Lesotho, le \u00ab\u00a0litema\u00a0\u00bb est une d\u00e9coration murale comprenant des \u00e9l\u00e9ments de gravure, de mosa\u00efque et de relief sur les fa\u00e7ades des maisons. Construite en briques de terre et en pl\u00e2tre, cette maison est peinte dans les couleurs traditionnelles de l&rsquo;ocre rouge pour symboliser le sang de la fertilit\u00e9 et du sacrifice, du blanc pour repr\u00e9senter la puret\u00e9 et la paix, et du noir pour faire r\u00e9f\u00e9rence aux anc\u00eatres et \u00e0 la promesse de pluie symbolis\u00e9e par les \u00ab\u00a0nuages de pluie sombres\u00a0\u00bb.<\/p>\n<p>\u00ab\u00a0Les maisons basotho m&rsquo;ont toujours int\u00e9ress\u00e9 par la fa\u00e7on dont elles se d\u00e9tachent dans le paysage &#8211; l&rsquo;utilisation des couleurs et des formes g\u00e9om\u00e9triques\u00a0\u00bb, explique Mukasa.<\/p>\n<p>\u00ab\u00a0J&rsquo;ai toujours trouv\u00e9 int\u00e9ressant que les gens utilisent ce qui les entoure pour transformer une structure rudimentaire en une \u0153uvre d&rsquo;art.\u00a0\u00bb<\/p>\n<p>7) Biblioth\u00e8que Kenneth Dike, Nigeria &#8211; 1954Cette biblioth\u00e8que est souvent cit\u00e9e comme l&rsquo;une des \u0153uvres cl\u00e9s de ce que l&rsquo;on appelle le \u00ab\u00a0modernisme tropical\u00a0\u00bb.<\/p>\n<p>Elle a \u00e9t\u00e9 construite \u00e0 une \u00e9poque o\u00f9 les brise-soleil \u00e0 motifs \u00e9taient de plus en plus populaires, s&rsquo;inspirant de l&rsquo;utilisation par l&rsquo;architecte franco-suisse Le Corbusier du \u00ab\u00a0brise-soleil\u00a0\u00bb &#8211; une caract\u00e9ristique architecturale d&rsquo;un b\u00e2timent qui r\u00e9duit la chaleur \u00e0 l&rsquo;int\u00e9rieur d&rsquo;un b\u00e2timent en d\u00e9viant la lumi\u00e8re du soleil.<\/p>\n<p>Le b\u00e2timent a \u00e9t\u00e9 con\u00e7u par Maxwell Fry et Jane Drew, qui \u00e9taient des pionniers du mouvement moderne en Angleterre. La biblioth\u00e8que fait partie du campus de l&rsquo;universit\u00e9 d&rsquo;Ibadan &#8211; fond\u00e9e par les autorit\u00e9s coloniales britanniques en 1948 &#8211; et est devenue un mod\u00e8le influent pour l&rsquo;architecture sensible au climat dans la sous-r\u00e9gion.<\/p>\n<p>8) Grande Mosqu\u00e9e de Djenn\u00e9, Mali &#8211; 13\u00e8me si\u00e8cleMonument de l&rsquo;Islam, la Grande Mosqu\u00e9e est la plus grande structure construite en terre au monde. La mosqu\u00e9e est un symbole de la ville de Djenn\u00e9, qui a prosp\u00e9r\u00e9 comme centre de commerce entre 800 et 1250.<\/p>\n<p>Les murs lisses et sculpt\u00e9s de l&rsquo;\u00e9difice sont construits avec des briques de terre cuites au soleil, du mortier \u00e0 base de sable et de terre et une couche de pl\u00e2tre.<\/p>\n<p>Chaque ann\u00e9e, les habitants de la ville refont ensemble le cr\u00e9pissage de la mosqu\u00e9e au cours d&rsquo;un \u00e9v\u00e9nement d&rsquo;une journ\u00e9e connu sous le nom de Cr\u00e9pissage de la Grande Mosqu\u00e9e.<\/p>\n<p>9) Palais de l&#8217;empereur Fasilides, \u00c9thiopie &#8211; d\u00e9but du 17e si\u00e8cleCe palais est situ\u00e9 dans la ville de Gondar, au nord de l&rsquo;\u00c9thiopie, dans une enceinte fortifi\u00e9e connue sous le nom de \u00ab\u00a0Fasil Ghebbi\u00a0\u00bb (enceinte royale).<\/p>\n<p>Le site comprend une vingtaine de palais, de b\u00e2timents royaux, d&rsquo;\u00e9glises, de monast\u00e8res et de b\u00e2timents uniques d\u00e9cor\u00e9s de fa\u00e7on \u00e9labor\u00e9e.<\/p>\n<p>La conception de ces b\u00e2timents a \u00e9t\u00e9 influenc\u00e9e par le style baroque apport\u00e9 \u00e0 Gondar par les missionnaires j\u00e9suites.<\/p>\n<p>10) Chapelle dominicaine, Nigeria -1973L&rsquo;artiste Demas Nwoko m\u00e9lange des \u00e9l\u00e9ments sculpturaux et la modernit\u00e9 avec un style d&rsquo;architecture vernaculaire nig\u00e9rian dans cette chapelle dominicaine r\u00e9imagin\u00e9e \u00e0 Ibadan.<\/p>\n<p>La structure int\u00e8gre des caract\u00e9ristiques telles que des colonnes en bois sculpt\u00e9 et un travail m\u00e9tallique \u00e9labor\u00e9 sur les balustrades et les portes.<\/p>\n<p>Selon Mukasa, elle a marqu\u00e9 une rupture radicale avec le mouvement moderniste qui s&rsquo;\u00e9tait impos\u00e9 sur le continent africain, en faveur d&rsquo;un moyen d&rsquo;expression \u00ab\u00a0local et d\u00e9riv\u00e9 de la culture locale\u00a0\u00bb.<\/p>\n<p>11) Grande Mosqu\u00e9e, B\u00e9nin &#8211; 1912-1935Cette mosqu\u00e9e situ\u00e9e \u00e0 Port-Novo, la capitale du B\u00e9nin, est un exemple frappant d&rsquo;architecture afro-br\u00e9silienne construite dans le style des \u00e9glises des XVIIe et XVIIIe si\u00e8cles dans l&rsquo;\u00c9tat de Bahia, au nord-est du Br\u00e9sil. La palette de couleurs jaune vif, marron, vert et bleu rappelle l&rsquo;architecture historique de Bahia.<\/p>\n<p>Situ\u00e9e le long de la c\u00f4te ouest-africaine, cette mosqu\u00e9e est l&rsquo;une des nombreuses mosqu\u00e9es afro-br\u00e9siliennes construites au d\u00e9but du XXe si\u00e8cle par des descendants d&rsquo;esclaves lib\u00e9r\u00e9s qui sont revenus au pays.<\/p>\n<p>\u00ab\u00a0Elle montre les nombreuses couches propres au patrimoine architectural de l&rsquo;Afrique de l&rsquo;Ouest &#8211; les connexions intercontinentales entre l&rsquo;Europe, l&rsquo;Am\u00e9rique du Sud et la c\u00f4te ouest-africaine dans la baie du B\u00e9nin \u00e0 une \u00e9poque o\u00f9 les \u00e9changes \u00e9taient nombreux\u00a0\u00bb, d\u00e9clare Dalbai.<\/p>\n<p>12) Centre d&rsquo;interpr\u00e9tation de Mapungubwe, Afrique du Sud &#8211; 2009Situ\u00e9 dans un paysage rocheux au sein du parc national de Mapungubwe, ce centre a valu \u00e0 l&rsquo;architecte sud-africain Peter Rich le prix du b\u00e2timent de l&rsquo;ann\u00e9e 2009 au Festival mondial d&rsquo;architecture.<\/p>\n<p>Ce projet c\u00e9l\u00e8bre est construit selon \u00ab\u00a0une technique de vo\u00fbte oubli\u00e9e depuis longtemps, que les ma\u00e7ons d&rsquo;Afrique du Nord ont apport\u00e9e en Catalogne et qui a \u00e9t\u00e9 utilis\u00e9e par des architectes tels qu&rsquo;Antoni Gaudi\u00a0\u00bb, selon Peter Rich.<\/p>\n<p>Les briques de boue ont \u00e9t\u00e9 form\u00e9es en utilisant la terre du site de construction et seulement 5 % de ciment suppl\u00e9mentaire pour cr\u00e9er un m\u00e9lange d&rsquo;argile.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Si les pyramides d&rsquo;\u00c9gypte sont connues dans le monde entier, une grande partie de l&rsquo;architecture africaine reste inconnue, ce que les architectes Adil Dalbai et Livingstone Mukasa esp\u00e8rent changer. Ils font partie de l&rsquo;\u00e9quipe qui a r\u00e9cemment publi\u00e9 le Guide architectural de l&rsquo;Afrique subsaharienne en sept volumes. Leur \u00e9tude approfondie englobe [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":22976,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[111,725,3120,3121,29],"class_list":["post-22977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-architecture","tag-batiments","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;architecture embl\u00e9matique de l&#039;Afrique en 12 b\u00e2timents - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Si les pyramides d&#039;\u00c9gypte sont connues dans le monde entier, une grande partie de l&#039;architecture africaine reste inconnu ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;architecture embl\u00e9matique de l&#039;Afrique en 12 b\u00e2timents\" \/>\n<meta property=\"og:description\" content=\"Si les pyramides d&#039;\u00c9gypte sont connues dans le monde entier, une grande partie de l&#039;architecture africaine reste inconnu ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-17T17:41:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-18T20:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"L&rsquo;architecture embl\u00e9matique de l&rsquo;Afrique en 12 b\u00e2timents\",\"datePublished\":\"2021-10-17T17:41:57+00:00\",\"dateModified\":\"2021-10-18T20:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\"},\"wordCount\":1582,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"architecture\",\"b\u00e2timents\",\"Burkina Faso\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\",\"name\":\"L'architecture embl\u00e9matique de l'Afrique en 12 b\u00e2timents - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg\",\"datePublished\":\"2021-10-17T17:41:57+00:00\",\"dateModified\":\"2021-10-18T20:50:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Si les pyramides d'\u00c9gypte sont connues dans le monde entier, une grande partie de l'architecture africaine reste inconnu ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg\",\"width\":976,\"height\":549,\"caption\":\"L'architecture embl\u00e9matique de l'Afrique en 12 b\u00e2timents\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;architecture embl\u00e9matique de l&#8217;Afrique en 12 b\u00e2timents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'architecture embl\u00e9matique de l'Afrique en 12 b\u00e2timents - Burkina Faso","description":"Si les pyramides d'\u00c9gypte sont connues dans le monde entier, une grande partie de l'architecture africaine reste inconnu ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments","og_locale":"fr_FR","og_type":"article","og_title":"L'architecture embl\u00e9matique de l'Afrique en 12 b\u00e2timents","og_description":"Si les pyramides d'\u00c9gypte sont connues dans le monde entier, une grande partie de l'architecture africaine reste inconnu ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments","og_site_name":"Burkina Faso","article_published_time":"2021-10-17T17:41:57+00:00","article_modified_time":"2021-10-18T20:50:00+00:00","og_image":[{"width":976,"height":549,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"L&rsquo;architecture embl\u00e9matique de l&rsquo;Afrique en 12 b\u00e2timents","datePublished":"2021-10-17T17:41:57+00:00","dateModified":"2021-10-18T20:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments"},"wordCount":1582,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","architecture","b\u00e2timents","Burkina Faso"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments","name":"L'architecture embl\u00e9matique de l'Afrique en 12 b\u00e2timents - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg","datePublished":"2021-10-17T17:41:57+00:00","dateModified":"2021-10-18T20:50:00+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Si les pyramides d'\u00c9gypte sont connues dans le monde entier, une grande partie de l'architecture africaine reste inconnu ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/10\/img-616c631de7913.jpg","width":976,"height":549,"caption":"L'architecture embl\u00e9matique de l'Afrique en 12 b\u00e2timents"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/larchitecture-emblematique-de-lafrique-en-12-batiments#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"L&#8217;architecture embl\u00e9matique de l&#8217;Afrique en 12 b\u00e2timents"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/22977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=22977"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/22977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/22976"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=22977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=22977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=22977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}