{"id":27675,"date":"2021-12-15T17:57:55","date_gmt":"2021-12-15T17:57:55","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas"},"modified":"2021-12-15T18:39:27","modified_gmt":"2021-12-15T18:39:27","slug":"omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas","title":{"rendered":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid.<\/p>\n<p>Deux doses de certains vaccins n&rsquo;offrent pratiquement aucune protection contre une infection par le variant Omicron, m\u00eame si elles devraient r\u00e9duire consid\u00e9rablement le risque de tomber malade au point de devoir \u00eatre hospitalis\u00e9.<\/p>\n<p>Les vaccins ont tous \u00e9t\u00e9 mis au point pour combattre la premi\u00e8re forme du virus apparue il y a deux ans.<\/p>\n<p>Une troisi\u00e8me dose, ou dose de rappel, de ces vaccins originaux peut-elle faire la diff\u00e9rence ou Omicron a-t-il d\u00e9j\u00e0 d\u00e9pass\u00e9 la protection qu&rsquo;ils peuvent offrir ?<\/p>\n<p>Heureusement pour nous, m\u00eame si le contenu de la seringue est identique, un rappel n&rsquo;est pas une simple r\u00e9p\u00e9tition de la m\u00eame chose pour le syst\u00e8me immunitaire.<\/p>\n<p>La protection que vous obtenez apr\u00e8s la troisi\u00e8me dose est plus importante, plus large et plus m\u00e9morable que celle que vous aviez auparavant.<\/p>\n<p>\u00c9cole du coronavirusCombattre le coronavirus est une chose que votre syst\u00e8me immunitaire doit apprendre.<\/p>\n<p>Une solution consiste \u00e0 le d\u00e9couvrir sur le terrain, lorsque vous rencontrez le virus pour de vrai. Cependant, il existe un risque de se tromper et de tomber gravement malade.<\/p>\n<p>Les vaccins s&rsquo;apparentent davantage \u00e0 une \u00e9cole &#8211; un environnement plus s\u00fbr pour poursuivre l&rsquo;\u00e9ducation de votre syst\u00e8me immunitaire en mati\u00e8re de Covid.<\/p>\n<p>La premi\u00e8re dose est l&rsquo;enseignement primaire qui permet d&rsquo;acqu\u00e9rir les connaissances de base.<\/p>\n<p>La deuxi\u00e8me et la troisi\u00e8me dose sont comparables \u00e0 l&rsquo;envoi de votre syst\u00e8me immunitaire au lyc\u00e9e puis \u00e0 l&rsquo;universit\u00e9 pour approfondir consid\u00e9rablement ses connaissances. Il ne s&rsquo;agit pas simplement de r\u00e9p\u00e9ter l&rsquo;\u00e9cole primaire encore et encore.<\/p>\n<p>\u00ab\u00a0Le syst\u00e8me immunitaire acquiert une meilleure connaissance et une meilleure compr\u00e9hension du virus\u00a0\u00bb, a d\u00e9clar\u00e9 le professeur Jonathan Ball, virologue \u00e0 l&rsquo;universit\u00e9 de Nottingham.<\/p>\n<p>Il a ajout\u00e9 que, m\u00eame si l&rsquo;on parle beaucoup des tours mal\u00e9fiques d&rsquo;Omicron, un syst\u00e8me immunitaire bien entra\u00een\u00e9 constitue \u00ab\u00a0un environnement incroyablement difficile et hostile\u00a0\u00bb pour le virus et ses variants.<\/p>\n<p>Les anticorps sont les grands b\u00e9n\u00e9ficiaires de cette \u00e9ducation.<\/p>\n<p>Ce sont les prot\u00e9ines collantes qui se fixent \u00e0 l&rsquo;ext\u00e9rieur du coronavirus. Les anticorps neutralisants peuvent gommer le virus pour l&#8217;emp\u00eacher d&rsquo;envahir vos cellules. D&rsquo;autres restent l\u00e0, comme l&rsquo;\u00e9quivalent biologique d&rsquo;un n\u00e9on clignotant qui vous dit \u00ab\u00a0tuez ce virus\u00a0\u00bb.<\/p>\n<p>Une s\u00e9rie d&rsquo;\u00e9tudes en laboratoire et de donn\u00e9es r\u00e9elles ont montr\u00e9 que les anticorps neutralisants produits apr\u00e8s deux doses d&rsquo;un vaccin Covid \u00e9taient beaucoup moins efficaces contre Omicron.<\/p>\n<p>Le professeur Danny Altmann, immunologiste \u00e0 l&rsquo;Imperial College de Londres, a d\u00e9clar\u00e9 qu&rsquo;il n&rsquo;en restait \u00ab\u00a0absolument rien\u00a0\u00bb et que vous \u00e9tiez une \u00ab\u00a0cible facile pour l&rsquo;infection\u00a0\u00bb.<\/p>\n<p>Alors, retour \u00e0 l&rsquo;\u00e9cole.<\/p>\n<p>Chaque dose du vaccin d\u00e9clenche un nouveau cycle d&rsquo;\u00e9volution des anticorps au sein du syst\u00e8me immunitaire. Il recherche de meilleurs anticorps qui se fixent plus fermement au virus. C&rsquo;est un processus appel\u00e9 maturation par affinit\u00e9.<\/p>\n<p>\u00ab\u00a0Vos anticorps s&rsquo;adaptent mieux au fil du temps, ils deviennent de plus en plus sophistiqu\u00e9s\u00a0\u00bb, explique le professeur Altmann.<\/p>\n<p>Si les anticorps sont capables de se lier plus \u00e9troitement au coronavirus, il sera plus difficile pour les mutations d&rsquo;Omicron de l&rsquo;aider \u00e0 se lib\u00e9rer. Et bien que le nouveau variant soit fortement mut\u00e9, il s&rsquo;agit toujours du m\u00eame virus fondamental, dont certaines parties n&rsquo;ont pas chang\u00e9 du tout.<\/p>\n<p>D&rsquo;autres cycles de vaccination conduisent \u00e9galement le syst\u00e8me immunitaire \u00e0 \u00e9largir son r\u00e9pertoire d&rsquo;anticorps, car il trouve de nouveaux moyens d&rsquo;attaquer le virus.<\/p>\n<p>Le jeu des nombresIl ne s&rsquo;agit pas seulement de la qualit\u00e9 des anticorps, la quantit\u00e9 augmente \u00e9galement avec le renforcement.<\/p>\n<p>Le professeur Charles Bangham, de l&rsquo;Imperial College, a d\u00e9clar\u00e9 : \u00ab\u00a0Ils sont plus nombreux, leur concentration dans le sang augmente et nous ne savons pas combien de temps cela va durer, mais plus vous \u00eates vaccin\u00e9, plus la m\u00e9moire immunitaire est durable.\u00a0\u00bb<\/p>\n<p>L&rsquo;impact de tout cela est clair dans les m\u00eames \u00e9tudes qui ont montr\u00e9 que deux doses \u00e9taient plus faibles contre Omicron. La protection contre les sympt\u00f4mes de Covid est pass\u00e9e \u00e0 environ 75 % apr\u00e8s le rappel.<\/p>\n<p>Ailleurs dans le syst\u00e8me immunitaire, le renforcement donne \u00e9galement \u00e0 notre corps une longueur d&rsquo;avance sur les futures variants.<\/p>\n<p>Les cellules B sont la partie du corps qui produit en masse les anticorps. Certaines arrivent \u00e0 maturit\u00e9 pour produire ces anticorps super collants et tr\u00e8s raffin\u00e9s apr\u00e8s un rappel. D&rsquo;autres peuvent rep\u00e9rer le coronavirus, mais restent \u00e0 moiti\u00e9 cuites et flexibles.<\/p>\n<p>\u00ab\u00a0Elles peuvent partir dans diff\u00e9rentes directions et, lorsqu&rsquo;elles prolif\u00e8rent, elles commencent \u00e0 s&rsquo;attaquer au nouveau variant\u00a0\u00bb, explique le professeur Ball.<\/p>\n<p>Et puis il y a les lymphocytes T, qui deviennent \u00e0 nouveau plus nombreux et plus efficaces pour attaquer les virus Covid en r\u00e9ponse \u00e0 la stimulation.<\/p>\n<p>Les lymphocytes T utilisent une astuce diff\u00e9rente pour rep\u00e9rer le virus et patrouillent dans notre corps \u00e0 la recherche de tout signe de cellules infect\u00e9es par Covid. Les lymphocytes T reconnaissent les parties du coronavirus que le virus a plus de mal \u00e0 faire muter.<\/p>\n<p>Ainsi, alors qu&rsquo;Omicron se d\u00e9robe \u00e0 notre syst\u00e8me immunitaire, chaque dose de vaccin, voire chaque infection, donne aux d\u00e9fenses de notre organisme davantage d&rsquo;outils pour le traquer.<\/p>\n<p>Tout cela est de bon augure pour les vaccins qui nous prot\u00e8gent contre les maladies graves.<\/p>\n<p>\u00ab\u00a0L&rsquo;immunit\u00e9 contre un virus n&rsquo;est presque jamais absolue &#8211; on peut presque toujours \u00eatre r\u00e9infect\u00e9 et ce que l&rsquo;on veut, c&rsquo;est que la r\u00e9infection soit si insignifiante que l&rsquo;on ne s&rsquo;en rende pas compte ou qu&rsquo;elle soit tr\u00e8s l\u00e9g\u00e8re\u00a0\u00bb, a d\u00e9clar\u00e9 le professeur Bangham.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. Deux doses de certains vaccins n&rsquo;offrent pratiquement aucune protection contre une infection par le variant Omicron, m\u00eame si elles devraient r\u00e9duire consid\u00e9rablement le risque de tomber malade au point de devoir \u00eatre [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":27674,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[111,725,29,2088],"class_list":["post-27675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso","tag-virus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ? - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?\" \/>\n<meta property=\"og:description\" content=\"Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T17:57:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-15T18:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?\",\"datePublished\":\"2021-12-15T17:57:55+00:00\",\"dateModified\":\"2021-12-15T18:39:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\"},\"wordCount\":1031,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\",\"Virus\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\",\"name\":\"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ? - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg\",\"datePublished\":\"2021-12-15T17:57:55+00:00\",\"dateModified\":\"2021-12-15T18:39:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg\",\"width\":800,\"height\":450,\"caption\":\"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ? - Burkina Faso","description":"Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas","og_locale":"fr_FR","og_type":"article","og_title":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?","og_description":"Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas","og_site_name":"Burkina Faso","article_published_time":"2021-12-15T17:57:55+00:00","article_modified_time":"2021-12-15T18:39:27+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?","datePublished":"2021-12-15T17:57:55+00:00","dateModified":"2021-12-15T18:39:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas"},"wordCount":1031,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso","Virus"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas","name":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ? - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg","datePublished":"2021-12-15T17:57:55+00:00","dateModified":"2021-12-15T18:39:27+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le variant Omicron, fortement mut\u00e9, a s\u00e9rieusement entam\u00e9 la capacit\u00e9 des vaccins \u00e0 nous prot\u00e9ger contre le virus Covid. ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2021\/12\/img-61ba36035d841.jpg","width":800,"height":450,"caption":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/omicron-pourquoi-un-rappel-fonctionne-si-deux-doses-ne-suffisent-pas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Omicron : pourquoi un rappel fonctionne si deux doses ne suffisent pas ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/27675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=27675"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/27675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/27674"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=27675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=27675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=27675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}