{"id":31309,"date":"2022-01-25T20:31:04","date_gmt":"2022-01-25T20:31:04","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/?p=31309"},"modified":"2022-01-25T17:26:30","modified_gmt":"2022-01-25T17:26:30","slug":"coups-detat-en-afrique-de-louest-a-qui-le-tour","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour","title":{"rendered":"Coups d&rsquo;\u00c9tat en Afrique de l&rsquo;Ouest : \u00ab\u00a0\u00c0 qui le tour\u00a0?\u00a0\u00bb"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span><b>\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9v\u00e9nement est per\u00e7u comme un nouveau coup dur pour l\u2019op\u00e9ration Barkhane au Sahel. La d\u00e9cision de l\u2019ex-Premier ministre libanais Saad Hariri de quitter la vie politique. Et un nouvel \u00e9pisode du \u00ab\u00a0Partygate\u00a0\u00bb au Royaume-Uni.<\/b><\/p>\n<p><b>Le +<\/b><\/p>\n<p>: Recevez tous les matins la Revue de presse de France 24 sur votre iPhone ou sur tout autre mobile. Et \u00e9galement toujours sur votre PC en devenant fan sur Facebook\u2026<\/p>\n<p>\u00c0 la une de la presse, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, o\u00f9 les militaires ont destitu\u00e9, lundi 24 janvier, le pr\u00e9sident Roch Marc Kabor\u00e9.<\/p>\n<p>Outre le \u00ab\u00a0cocktail explosif\u00a0\u00bb des \u00ab\u00a0querelles incessantes entre politiciens\u00a0\u00bb et de \u00ab\u00a0l\u2019incapacit\u00e9 des dirigeants \u00e0 assurer la s\u00e9curit\u00e9\u00a0\u00bb, Wakat Sera explique aussi ce coup d\u2019\u00c9tat par un \u00ab\u00a0effet de contagion\u00a0\u00bb venu du Mali voisin. Alors que la Coupe d\u2019Afrique des nations, la CAN, bat son plein, le site burkinab\u00e9 file la m\u00e9taphore footballistique: \u00ab\u00a0Apr\u00e8s un dribble diabolique qui a d\u00e9sar\u00e7onn\u00e9 la d\u00e9fense malienne, le colonel Assimi Go\u00efta a adress\u00e9 une courte passe au colonel guin\u00e9en Mamady Doumbouya, qui a fait un long centre vers le colonel burkinab\u00e8 Paul Henri Sandaogo Damiba, le nouvel homme fort du pays, qui d\u2019une t\u00eate imparable, a clou\u00e9 au pilori le gardien de but Roch Marc Christian Kabor\u00e9\u00a0\u00bb.<\/p>\n<p>Avec ce coup de force, une nouvelle p\u00e9riode d\u2019interrogations s\u2019ouvre pour le pays des Hommes int\u00e8gres. \u00ab\u00a0Quels lendemains pour le Burkina Faso ?\u00a0\u00bb : Le Pays esp\u00e8re que \u00ab\u00a0la situation n\u2019expose pas (sa population) \u00e0 de lourdes sanctions internationales\u00a0\u00bb, \u00e0 l\u2019image du Mali. Le journal burkinab\u00e8 estime qu\u2019il est temps, pour les Africains, \u00ab\u00a0de revoir de fond en comble leur syst\u00e8me \u00e9lectoral\u00a0\u00bb, \u00ab\u00a0pour qu\u2019au-del\u00e0 de la l\u00e9galit\u00e9 des urnes\u00a0\u00bb, les pr\u00e9sidents \u00e9lus \u00ab\u00a0aient la l\u00e9gitimit\u00e9 n\u00e9cessaire pour \u00eatre \u00e0 l\u2019abri des coups d\u2019\u00c9tat\u00a0\u00bb.<\/p>\n<p>Apr\u00e8s le Mali, la Guin\u00e9e et le Burkina Faso, \u00ab\u00a0\u00e0 qui le tour?\u00a0\u00bb, s\u2019interroge Le Dj\u00e9ly. D\u2019apr\u00e8s le site d\u2019information guin\u00e9en, l\u2019Afrique de l\u2019ouest ferait actuellement \u00ab\u00a0les frais de la d\u00e9cadence \u00e9thique de ses dirigeants\u00a0\u00bb. Selon lui, deux d\u2019entre eux illustreraient particuli\u00e8rement \u00ab\u00a0ce recul pr\u00e9judiciable\u00a0\u00bb: l\u2019ancien pr\u00e9sident guin\u00e9en Alpha Cond\u00e9 et l\u2019actuel pr\u00e9sident ivoirien Alassane Ouattara, deux anciens opposants martyris\u00e9s (qui ont) fait le choix, avec une arrogance assum\u00e9e, de s\u2019offrir des troisi\u00e8mes mandats\u00a0\u00bb, envoyant ainsi un tr\u00e8s mauvais signal \u00e0 l\u2019ensemble de la r\u00e9gion. Selon Le Dj\u00e9ly, tel serait \u00ab\u00a0le dirigeant-type\u00a0\u00bb de l\u2019Afrique de l\u2019ouest d\u2019aujourd\u2019hui : \u00ab\u00a0aucune empathie, mais un m\u00e9pris \u00e9rig\u00e9 en comportement. D\u2019o\u00f9 la d\u00e9sinvolture avec laquelle certains d\u2019entre eux ont abord\u00e9 la d\u00e9gradation de la situation s\u00e9curitaire au Sahel. Rien d\u2019\u00e9tonnant donc, si partout on c\u00e9l\u00e8bre leur chute. Rien d\u2019\u00e9tonnant que partout, l\u2019arm\u00e9e veuille exploiter ce foss\u00e9 entre les dirigeants et les populations\u00a0\u00bb. \u00ab\u00a0Ce qui s\u2019est pass\u00e9 au Mali, en Guin\u00e9e et hier au Burkina Faso, risque de se produire prochainement \u00e0 Niamey, \u00e0 Abidjan, \u00e0 Cotonou ou m\u00eame \u00e0 Dakar\u00a0\u00bb, proph\u00e9tise site, qui \u00e9voque lui aussi un \u00ab\u00a0effet de contagion\u00a0\u00bb, renforc\u00e9 par un contexte \u00ab\u00a0o\u00f9 la France est per\u00e7ue comme la complice du diable\u00a0\u00bb.<\/p>\n<p>\u00ab\u00a0L\u2019Afrique de l\u2019Ouest serait-elle en train d\u2019inventer un nouveau concept? Celui de &lsquo;coup d\u2019\u00c9tat militaire populaire'\u00a0\u00bb, \u00e9crit Lib\u00e9ration. D\u2019apr\u00e8s le journal, \u00ab\u00a0les scandales de corruption et l\u2019incapacit\u00e9 \u00e0 freiner les djihadistes, ont fini par d\u00e9cr\u00e9dibiliser le pouvoir civil\u00a0\u00bb dans la r\u00e9gion. \u00ab\u00a0La tentative de coup d\u2019\u00c9tat au Burkina menace l\u2019avenir de l&rsquo;op\u00e9ration Barkhane et risque de porter un coup fatal \u00e0 l\u2019engagement militaire des europ\u00e9ens dans la sous-r\u00e9gion\u00a0\u00bb: La Croix parle d\u2019\u00a0\u00bbun sc\u00e9nario catastrophe pour la France\u00a0\u00bb, qui consid\u00e8re le Sahel \u00ab\u00a0comme capital pour sa s\u00e9curit\u00e9 et celle de l\u2019Europe\u00a0\u00bb. Le journal, lui, se demande \u00ab\u00a0si c\u2019est encore le cas\u00a0\u00bb, tant les candidats \u00e0 la pr\u00e9sidentielle \u00ab\u00a0sont avares de propositions sur le sujet\u00a0\u00bb.<\/p>\n<p>La France, pr\u00e9occup\u00e9e, \u00e9galement, par la situation au Liban, o\u00f9 l\u2019ex-Premier ministre Saad Hariri a annonc\u00e9, hier, son retrait de la vie politique. L&rsquo;Orient Le Jour \u00e9voque \u00ab\u00a0un tremblement de terre pour la sc\u00e8ne sunnite et dans une moindre mesure pour le Liban\u00a0\u00bb. Selon le journal libanais, \u00ab\u00a0le retrait de Saad Hariri change compl\u00e8tement l\u2019\u00e9quation politique\u00a0\u00bb, \u00e0 l\u2019approche des l\u00e9gislatives pr\u00e9vues en mai prochain, \u00ab\u00a0puisqu\u2019il cr\u00e9e un vide que personne aujourd\u2019hui (ne serait) en mesure de combler\u00a0\u00bb. \u00ab\u00a0Mais parce qu\u2019il s\u2019inscrit dans un contexte de d\u00e9clin, depuis des ann\u00e9es, de l\u2019influence haririenne, et parce que l\u2019hypoth\u00e8se est sur la table depuis des semaines, les r\u00e9actions sont rest\u00e9es mesur\u00e9es.\u00a0\u00bb<\/p>\n<p>Sa d\u00e9mission \u00e0 lui est-elle in\u00e9luctable ? Au Royaume-Uni, Boris Johnson ne se d\u00e9p\u00eatre pas du \u00ab\u00a0Partygate\u00a0\u00bb. \u00ab\u00a0Un autre jour, une autre f\u00eate\u00a0\u00bb, annonce, un brin d\u00e9sabus\u00e9, The Daily Mirror. Dernier \u00e9pisode en date du feuilleton \u00ab\u00a0Partygate\u00a0\u00bb : la participation du Premier ministre britannique \u00e0 une f\u00eate d\u2019anniversaire organis\u00e9e en son honneur au 10 Downing Street -une sauterie \u00e0 laquelle 30 convives ont particip\u00e9 le 19 juin 2020, en plein confinement. Une belle \u00ab\u00a0tranche d\u2019hypocrisie\u00a0\u00bb, s\u2019\u00e9trangle le tablo\u00efd. \u00ab\u00a0Non, Boris, tu ne peux pas avoir le beurre et l\u2019argent du beurre\u00a0\u00bb (\u00a0\u00bb You can\u2019t have your birthday cake and eat it\u00a0\u00bb) : The Sun rapporte que l\u2019entourage du Premier ministre a tent\u00e9 de le d\u00e9fendre, une nouvelle fois, en pr\u00e9cisant, cette fois, qu\u2019il n\u2019\u00e9tait rest\u00e9 que 10 minutes. Voil\u00e0 qui change tout&#8230;<\/p>\n<p><b>Retrouvez tous les matins sur France 24 la Revue de presse (du lundi au vendredi, \u00e0 7h20 et 9h20 heure de Paris). Suivez \u00e9galement tous les week-ends en multidiffusion la Revue des Hebdos.<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. \u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9v\u00e9nement est per\u00e7u comme un nouveau coup dur pour l\u2019op\u00e9ration Barkhane au Sahel. La d\u00e9cision de l\u2019ex-Premier ministre libanais Saad Hariri de quitter la vie politique. Et un nouvel [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":31308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[111,725,3831,4008,3841,4006,29,4005,4003,112,4007,234,3078,4004,4009],"class_list":["post-31309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-alassane-ouattara","tag-alpha-conde","tag-assimi-goita","tag-boris-johnson","tag-burkina-faso","tag-confinement","tag-liban","tag-mali","tag-paul-henri-sandaogo-damiba","tag-roch-marc-kabore","tag-royaume-uni","tag-saad-hariri","tag-sunnites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coups d&#039;\u00c9tat en Afrique de l&#039;Ouest : &quot;\u00c0 qui le tour\u00a0?&quot; - Burkina Faso<\/title>\n<meta name=\"description\" content=\"\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9 ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coups d&#039;\u00c9tat en Afrique de l&#039;Ouest : &quot;\u00c0 qui le tour\u00a0?&quot;\" \/>\n<meta property=\"og:description\" content=\"\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T20:31:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Coups d&rsquo;\u00c9tat en Afrique de l&rsquo;Ouest : \u00ab\u00a0\u00c0 qui le tour\u00a0?\u00a0\u00bb\",\"datePublished\":\"2022-01-25T20:31:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\"},\"wordCount\":1044,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Alassane Ouattara\",\"Alpha Cond\u00e9\",\"Assimi Go\u00efta\",\"Boris Johnson\",\"Burkina Faso\",\"Confinement\",\"Liban\",\"Mali\",\"Paul-Henri Sandaogo Damiba\",\"Roch Marc Kabor\u00e9\",\"Royaume-Uni\",\"Saad Hariri\",\"Sunnites\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\",\"name\":\"Coups d'\u00c9tat en Afrique de l'Ouest : \\\"\u00c0 qui le tour\u00a0?\\\" - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg\",\"datePublished\":\"2022-01-25T20:31:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9 ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Coups d'\u00c9tat en Afrique de l'Ouest : \\\"\u00c0 qui le tour\u00a0?\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coups d&#8217;\u00c9tat en Afrique de l&#8217;Ouest : &#8220;\u00c0 qui le tour\u00a0?&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coups d'\u00c9tat en Afrique de l'Ouest : \"\u00c0 qui le tour\u00a0?\" - Burkina Faso","description":"\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9 ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour","og_locale":"fr_FR","og_type":"article","og_title":"Coups d'\u00c9tat en Afrique de l'Ouest : \"\u00c0 qui le tour\u00a0?\"","og_description":"\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9 ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour","og_site_name":"Burkina Faso","article_published_time":"2022-01-25T20:31:04+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Coups d&rsquo;\u00c9tat en Afrique de l&rsquo;Ouest : \u00ab\u00a0\u00c0 qui le tour\u00a0?\u00a0\u00bb","datePublished":"2022-01-25T20:31:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour"},"wordCount":1044,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Alassane Ouattara","Alpha Cond\u00e9","Assimi Go\u00efta","Boris Johnson","Burkina Faso","Confinement","Liban","Mali","Paul-Henri Sandaogo Damiba","Roch Marc Kabor\u00e9","Royaume-Uni","Saad Hariri","Sunnites"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour","url":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour","name":"Coups d'\u00c9tat en Afrique de l'Ouest : \"\u00c0 qui le tour\u00a0?\" - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg","datePublished":"2022-01-25T20:31:04+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"\u00c0 la une de la presse, ce mardi 25 janvier, les r\u00e9actions au coup d\u2019\u00c9tat au Burkina Faso, notamment en France, o\u00f9 l\u2019\u00e9 ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/01\/img-61f03290eb915.jpg","width":1280,"height":720,"caption":"Coups d'\u00c9tat en Afrique de l'Ouest : \"\u00c0 qui le tour\u00a0?\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/coups-detat-en-afrique-de-louest-a-qui-le-tour#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Coups d&#8217;\u00c9tat en Afrique de l&#8217;Ouest : &#8220;\u00c0 qui le tour\u00a0?&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/31309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=31309"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/31309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/31308"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=31309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=31309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=31309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}