{"id":33342,"date":"2022-02-13T02:43:05","date_gmt":"2022-02-13T02:43:05","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region"},"modified":"2022-03-14T22:37:42","modified_gmt":"2022-03-14T22:37:42","slug":"come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region","title":{"rendered":"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en plus rejet\u00e9e, des protestations et des affrontements arm\u00e9s ont \u00e9clat\u00e9 au cours de la p\u00e9riode r\u00e9cente dans plusieurs r\u00e9gions et pays africains, dont certains ont exig\u00e9 le retrait des forces militaires fran\u00e7aises et la fin du \u00ab colonialisme \u00bb, qui a commenc\u00e9 \u00e0 y prendre des formes diverses, drainer ses richesses pendant des d\u00e9cennies, et s&rsquo;y approfondir, sans toutefois mettre fin au danger des groupes djihadistes arm\u00e9s et de leurs attentats sanglants, principal argument invoqu\u00e9 par Paris pour justifier sa pr\u00e9sence dans ces zones.<\/p>\n<p>Mais il semble qu&rsquo;aujourd&rsquo;hui, l&rsquo;\u00e9tau se resserre s\u00e9rieusement sur la France, dans sa zone d&rsquo;influence traditionnelle, et qu&rsquo;elle soit devenue confront\u00e9e \u00e0 de nombreux d\u00e9fis et troubles qui emp\u00eachent la r\u00e9ussite de ses plans strat\u00e9giques dans les pays du Sahel et du Sahara.<\/p>\n<p><b>Le Putsch burkinab\u00e9<\/b><\/p>\n<p>Alors que la Guin\u00e9e Conakry et le Mali ont, \u00e0 des degr\u00e9s divers, surmont\u00e9 les \u00e9cueils de l&rsquo;exp\u00e9rience du \u00ab putsch \u00bb et les d\u00e9fis d&rsquo;une reconfiguration radicale de leurs relations ext\u00e9rieures (internationales et r\u00e9gionales) et d&rsquo;imposer le fait accompli sur la voie des r\u00e9formes politiques et du retour au \u00ab processus constitutionnel \u00bb, des militaires du Burkina Faso, voisin frontalier du Mali, conduits par le nouvel homme fort le colonel Paul-Henri Sandaogo Damiba, n\u2019ont pas h\u00e9sit\u00e9 \u00e0 arr\u00eater le pr\u00e9sident Roch Marc Christian Kabor\u00e9, dans la soir\u00e9e du dimanche 23 janvier 2022, \u00e0 son domicile, apr\u00e8s une s\u00e9rie de r\u00e9bellions dans plusieurs casernes pour exiger le limogeage des chefs militaires et l&rsquo;allocation de plus de moyens aux efforts de la lutte contre les groupes terroristes.<\/p>\n<p>Des t\u00e9moins oculaires \u00e0 Ouagadougou, la capitale burkinab\u00e9, ont confirm\u00e9 avoir vu un h\u00e9licopt\u00e8re au-dessus de la maison du pr\u00e9sident renvers\u00e9, apr\u00e8s des tirs sporadiques dans plusieurs bases militaires, ce qui a imm\u00e9diatement fait craindre un coup d&rsquo;\u00c9tat militaire dans le pays, qui souffre d\u00e9j\u00e0 de conditions \u00e9conomiques et s\u00e9curitaires extr\u00eamement difficiles.<\/p>\n<p>Ces craintes sur le terrain ont \u00e9galement \u00e9t\u00e9 renforc\u00e9es par le d\u00e9ploiement de soldats burkinab\u00e9s tout autour du b\u00e2timent de la t\u00e9l\u00e9vision publique, avec la suspension de tous les services de t\u00e9l\u00e9phonie mobile et Internet, depuis dimanche soir.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-35081\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/3-300x169.jpg\" alt=\"\" width=\"772\" height=\"435\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/3-300x169.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/3-768x432.jpg 768w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/3.jpg 780w\" sizes=\"auto, (max-width: 772px) 100vw, 772px\" \/><\/p>\n<p><b>Si l\u2019on revenait sur le contexte de la crise au Burkina Faso !<\/b><\/p>\n<p>Depuis qu&rsquo;il avait pris le pouvoir \u00e0 la t\u00eate du pays en 2015, le pr\u00e9sident \u00ab destitu\u00e9 \u00bb, Roch Marc Kabor\u00e9, n&rsquo;a pas concr\u00e9tis\u00e9 de r\u00e9alisations tangibles pour le citoyen burkinab\u00e9 dans les domaines politique, social, \u00e9conomique et s\u00e9curitaire, alors que l&rsquo;\u00e9tat d&rsquo;ins\u00e9curit\u00e9 s&rsquo;est accru.<\/p>\n<p>Burkina Faso, est un pays \u00e0 faible revenu et des ressources naturelles limit\u00e9es, dont l&rsquo;\u00e9conomie est bas\u00e9e principalement sur le secteur agricole, lequel emploie 80% de la main-d&rsquo;\u0153uvre locale, depuis le d\u00e9but de l&rsquo;ann\u00e9e 2019, et le d\u00e9placement interne de la population a augment\u00e9 vertigineusement depuis lors, passant de 50 mille personnes \u00e0 1,4 million personnes, en ao\u00fbt 2021, repr\u00e9sentant ainsi plus de 6% de la population totale du pays.<\/p>\n<p>A noter que cette crise s\u00e9curitaire a \u00e9galement entra\u00een\u00e9 la perturbation de la dynamique de travail de l&rsquo;\u00c9tat, comme la fermeture d&rsquo;environ 2.250 \u00e9coles (environ 11% de la taille des \u00e9tablissements d&rsquo;enseignement au Burkina Faso).<\/p>\n<p>Bien que Kabor\u00e9 ait remport\u00e9 un nouveau mandat pr\u00e9sidentiel \u00e0 la fin de l&rsquo;ann\u00e9e 2020, il n&rsquo;a pas engag\u00e9 de v\u00e9ritables r\u00e9formes, d&rsquo;autant plus que le parti au pouvoir, le Mouvement du Peuple pour le Progr\u00e8s*, et ses alli\u00e9s, dominait une majorit\u00e9 confortable \u00e0 l&rsquo;Assembl\u00e9e nationale.<\/p>\n<p>\u2022 Le Mouvement du peuple pour le progr\u00e8s (MPP) est un parti politique du Burkina Faso, fond\u00e9 en janvier 2014 et se r\u00e9clamant de la social-d\u00e9mocratie, il est issu du Congr\u00e8s pour la d\u00e9mocratie et le progr\u00e8s (CDP), le parti de l&rsquo;ancien pr\u00e9sident Blaise Compaor\u00e9, chass\u00e9 du pouvoir en 2014 lors de la deuxi\u00e8me r\u00e9volution burkinab\u00e9. Ce parti f\u00fbt fond\u00e9 par Roch Marc Christian Kabor\u00e9, Salif Diallo et Simon Compaor\u00e9, d&rsquo;anciens piliers du CDP.<\/p>\n<p>Sur le plan \u00e9conomique, la croissance au Burkina Faso n&rsquo;a pas d\u00e9pass\u00e9 1,9% en 2020 en raison des r\u00e9percussions de la pand\u00e9mie de Covid-19, et les niveaux de production du secteur agricole sont rest\u00e9s relativement \u00e9lev\u00e9s gr\u00e2ce \u00e0 l&rsquo;accent mis sur les cultures vivri\u00e8res et le coton, tandis que le secteur secondaire, repr\u00e9sent\u00e9 dans les mines, a connu une augmentation gr\u00e2ce \u00e0 l&rsquo;expansion majeure des mines d&rsquo;or.<\/p>\n<p>N\u00e9anmoins, au cours des derniers mois de 2021 et au d\u00e9but de cette ann\u00e9e, le Burkina Faso a connu une vague de protestations populaires, renforc\u00e9e par de graves r\u00e9percussions sociales et \u00e9conomiques \u00e0 la suite de la crise des d\u00e9placements internes, qui reste l&rsquo;une des plus grandes crises similaires aujourd\u2019hui en Afrique, et une alliance des groupes d&rsquo;opposition au r\u00e9gime, ce qui a impos\u00e9 une pression croissante et \u00e9touffante \u00e0 l\u2019encontre de ce dernier pour introduire des r\u00e9formes, y compris la formation d&rsquo;un nouveau gouvernement et le changement de la direction des arm\u00e9es.<\/p>\n<p>Cependant, le r\u00e9gime de Kabor\u00e9 n&rsquo;a pas tenu compte de ces demandes croissantes, se sentant en s\u00e9curit\u00e9 du fait du soutien important et permanent dont il b\u00e9n\u00e9ficiait de la France, ce qui a approfondi la col\u00e8re populaire contre le pr\u00e9sident lui-m\u00eame et la pr\u00e9sence militaire fran\u00e7aise dans le pays, et dans le contexte d&rsquo;un sentiment g\u00e9n\u00e9ral d&rsquo;hostilit\u00e9 dans la r\u00e9gion du Sahel contre cette pr\u00e9sence, ces derni\u00e8res ann\u00e9es, malgr\u00e9 la contribution des forces fran\u00e7aises dans la guerre contre les groupes terroristes.<\/p>\n<p>Ainsi, les conditions s\u00e9curitaires, et l&rsquo;incapacit\u00e9 du r\u00e9gime de Roch Marc Kabor\u00e9 \u00e0 avancer dans le dossier de \u00ab la lutte contre le terrorisme \u00bb, parall\u00e8lement \u00e0 la r\u00e9forme institutionnelle et au renforcement des capacit\u00e9s des forces arm\u00e9es burkinab\u00e9, ont incit\u00e9 la situation \u00e0 se d\u00e9t\u00e9riorer actuellement d&rsquo;une mani\u00e8re quasiment identique au \u00ab sc\u00e9nario du Mali \u00bb, tant en interne qu&rsquo;en externe.<\/p>\n<p><b>Les militaires et la politique !<\/b><\/p>\n<p>L&rsquo;arm\u00e9e burkinab\u00e9 a tr\u00e8s vite resserr\u00e9 son emprise sur l&rsquo;administration du pays, le 23 janvier dernier, et a r\u00e9ussi \u00e0 semer la confusion chez les autorit\u00e9s gouvernementales de l&rsquo;\u00e9poque du r\u00e9gime.<\/p>\n<p>Il est \u00e0 noter que le gouvernement n&rsquo;a pas r\u00e9pondu s\u00e9rieusement \u00e0 une liste de demandes visant \u00e0 exhorter le r\u00e9gime \u00e0 travailler s\u00e9rieusement pour am\u00e9liorer sa strat\u00e9gie anti-terroriste, fournir plus de soutien aux forces arm\u00e9es et soigner les bless\u00e9s et leurs familles.<\/p>\n<p>A noter que les \u00e9v\u00e9nements r\u00e9cents sont survenus une semaine apr\u00e8s l&rsquo;arrestation de 12 personnes, dont un \u00e9minent responsable militaire, accus\u00e9es d&rsquo;avoir complot\u00e9 pour d\u00e9stabiliser les institutions de l&rsquo;\u00c9tat, et environ deux mois apr\u00e8s que Kabor\u00e9 ait limog\u00e9 un grand nombre de hauts responsables militaires, en novembre 2021.<\/p>\n<p>Il s\u2019av\u00e8re entre-autres que le pr\u00e9sident Kabor\u00e9 a \u00e9galement fait face, depuis sa r\u00e9\u00e9lection \u00e0 la pr\u00e9sidence pour un second mandat en novembre 2020, \u00e0 des protestations et \u00e0 une escalade des appels \u00e0 sa d\u00e9mission, l\u2019obligeant \u00e0 changer le Premier ministre et les commandants de l&rsquo;arm\u00e9e, mais les opposants \u00e0 sa politique ont soulign\u00e9 l&rsquo;insuffisance de ces mesures.<\/p>\n<p>Et finalement, dans la soir\u00e9e du lundi 24 janvier 2022, l&rsquo;arm\u00e9e burkinab\u00e9 a r\u00e9solu la pol\u00e9mique qui avait \u00e9clat\u00e9 t\u00f4t en confirmant la destitution du pr\u00e9sident Kabor\u00e9, la suspension de la constitution, la dissolution du gouvernement et de l&rsquo;Assembl\u00e9e nationale ainsi que la fermeture des fronti\u00e8res du pays.<\/p>\n<p>La confirmation \u00e9tait venue dans le contexte de ce que l&rsquo;arm\u00e9e consid\u00e9rait comme une d\u00e9t\u00e9rioration de la situation s\u00e9curitaire dans le pays et de l&rsquo;incapacit\u00e9 du pr\u00e9sident \u00e0 l&rsquo;unifier et \u00e0 r\u00e9pondre efficacement aux d\u00e9fis, notamment terroristes.<\/p>\n<p>Verra-t-on bient\u00f4t le pouvoir remis aux civils au Burkina Faso, ou bien la junte militaire va-t-elle s\u2019y agripper de toutes ses forces ?<\/p>\n<p><b>Anouar CHENNOUFI<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en plus rejet\u00e9e, des protestations et des affrontements arm\u00e9s ont \u00e9clat\u00e9 au cours de la p\u00e9riode r\u00e9cente dans plusieurs r\u00e9gions et pays africains, dont certains ont exig\u00e9 le retrait des forces militaires [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":33341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,11,10],"tags":[111,725,4119,29,2284,236,112,4118,1918],"class_list":["post-33342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-analyse","tag-burkina-faso","tag-coup-detat","tag-france","tag-mali","tag-putsch-militaire","tag-terroristes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en p ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion\" \/>\n<meta property=\"og:description\" content=\"Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en p ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-13T02:43:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-14T22:37:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion\",\"datePublished\":\"2022-02-13T02:43:05+00:00\",\"dateModified\":\"2022-03-14T22:37:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\"},\"wordCount\":1441,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Analyse\",\"Burkina Faso\",\"coup d\u2019Etat\",\"France\",\"Mali\",\"Putsch militaire\",\"terroristes\"],\"articleSection\":[\"Dossiers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\",\"name\":\"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg\",\"datePublished\":\"2022-02-13T02:43:05+00:00\",\"dateModified\":\"2022-03-14T22:37:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en p ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg\",\"width\":800,\"height\":570,\"caption\":\"Le pr\u00e9sident d\u00e9chu \/ L\u2019auteur du putsch militaire\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion - Burkina Faso","description":"Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en p ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region","og_locale":"fr_FR","og_type":"article","og_title":"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion","og_description":"Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en p ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region","og_site_name":"Burkina Faso","article_published_time":"2022-02-13T02:43:05+00:00","article_modified_time":"2022-03-14T22:37:42+00:00","og_image":[{"width":800,"height":570,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion","datePublished":"2022-02-13T02:43:05+00:00","dateModified":"2022-03-14T22:37:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region"},"wordCount":1441,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Analyse","Burkina Faso","coup d\u2019Etat","France","Mali","Putsch militaire","terroristes"],"articleSection":["Dossiers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region","url":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region","name":"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg","datePublished":"2022-02-13T02:43:05+00:00","dateModified":"2022-03-14T22:37:42+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Suite aux sentiments croissants de col\u00e8re et de congestion contre la pr\u00e9sence fran\u00e7aise en Afrique, qui est de plus en p ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/02\/img-62105f078b34b.jpg","width":800,"height":570,"caption":"Le pr\u00e9sident d\u00e9chu \/ L\u2019auteur du putsch militaire"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/come-back-sur-le-putsch-militaire-au-burkina-faso-et-ses-repercussions-sur-la-region#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Come-back sur le putsch militaire au Burkina Faso et ses r\u00e9percussions sur la r\u00e9gion"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/33342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=33342"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/33342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/33341"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=33342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=33342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=33342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}