{"id":49619,"date":"2022-09-28T11:44:52","date_gmt":"2022-09-28T11:44:52","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet"},"modified":"2022-09-28T12:20:13","modified_gmt":"2022-09-28T12:20:13","slug":"interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet","title":{"rendered":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span><b>A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armes<\/b><br \/>\n<b>nucl\u00e9aires, une r\u00e9union minist\u00e9rielle de haut niveau a eu lieu le lundi<\/b><br \/>\n<b>26 septembre 2022 \u00e0 New York (Etats-Unis). Le Burkina Faso \u00e9tait<\/b><br \/>\n<b>repr\u00e9sent\u00e9 par la ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration<\/b><br \/>\n<b>r\u00e9gionale et des Burkinab\u00e8 de l\u2019ext\u00e9rieur, Olivia Rouamba.<\/b><\/p>\n<p>Le monde entier comm\u00e9more, chaque 26 septembre, la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armes nucl\u00e9aires. A cet effet, une rencontre minist\u00e9rielle de haut niveau s\u2019est tenue le lundi 26 septembre 2022 \u00e0 New<\/p>\n<p>York (Etats-Unis). La rencontre a \u00e9t\u00e9 ponctu\u00e9e par plusieurs discours dont ceux des repr\u00e9sentants des \u00c9tats Membres et de la soci\u00e9t\u00e9 civile, des ONG, du Pr\u00e9sident de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale, du Secr\u00e9taire g\u00e9n\u00e9ral des<\/p>\n<p>Nations Unies, et de la ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration r\u00e9gionale et des Burkinab\u00e8 de l\u2019ext\u00e9rieur, Olivia Rouamba. Les intervenants \u00e0 la tribune ont unanimement d\u00e9plor\u00e9 \u00ab un d\u00e9sarmement<\/p>\n<p>nucl\u00e9aire tardif, incertain et incomplet \u00bb. Cette critique fait \u00e9cho aux pr\u00e9occupations croissantes li\u00e9es aux cons\u00e9quences humanitaires potentielles en cas d\u2019utilisation d\u2019une seule arme nucl\u00e9aire, et pire des<\/p>\n<p>cons\u00e9quences catastrophiques que pourraient engendrer une v\u00e9ritable guerre nucl\u00e9aire r\u00e9gionale ou mondiale. \u00ab Sans l\u2019\u00e9limination des armes nucl\u00e9aires, il ne peut y avoir de paix, il ne peut y avoir de confiance ni<\/p>\n<p>d\u2019avenir durable \u00bb, a d\u00e9clar\u00e9 le secr\u00e9taire g\u00e9n\u00e9ral de l\u2019ONU, Antonio Guterres. Il a invit\u00e9, de ce fait, les Etats \u00e0 conclure le d\u00e9bat g\u00e9n\u00e9ral annuel de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies par un nouvel engagement<\/p>\n<p>envers un avenir pacifique. Le Pr\u00e9sident de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, Csaba K\u0151r\u00f6si a soutenu, pour sa part, que la guerre en Ukraine accentue les risques cr\u00e9dibles d\u2019une catastrophe nucl\u00e9aire<\/p>\n<p>mondiale. Il a soulign\u00e9, en effet, l\u2019augmentation des investissements dans les armes nucl\u00e9aires, un arsenal mondial de 13.000 ogives, alors que \u00ab tant de gens peinent \u00e0 trouver \u00e0 manger, \u00e0 \u00e9duquer leurs enfants et \u00e0 se<\/p>\n<p>r\u00e9chauffer \u00bb. Quant \u00e0 la ministre en charge des affaires \u00e9trang\u00e8res, Olivia Rouamba, elle a dit partager les points de vue du Groupe africain et du Mouvement des Non-Align\u00e9s. Elle a ensuite affirm\u00e9 que l\u2019un des axes majeurs de la politique \u00e9trang\u00e8re du Burkina Faso est la recherche de la paix et de la s\u00e9curit\u00e9 r\u00e9gionale et internationale.<\/p>\n<p><b>Une \u00e9tape essentielle<\/b><\/p>\n<p>Pour ce faire, le Burkina Faso, a-t-elle indiqu\u00e9, s\u2019est toujours associ\u00e9 aux efforts internationaux visant \u00e0 promouvoir la paix dans le monde. \u00ab Fort de<\/p>\n<p>cet engagement, notre pays s\u2019att\u00e8le \u00e0 adh\u00e9rer et \u00e0 mettre en \u0153uvre les instruments internationaux y relatifs. C\u2019est dans cette dynamique que le Burkina a sign\u00e9 le 22 septembre dernier le Trait\u00e9 sur l\u2019interdiction des<\/p>\n<p>armes nucl\u00e9aires (TIAN) \u00bb, a rappel\u00e9 Mme Rouamba. La cessation des essais nucl\u00e9aires sous toutes ses formes constitue, a-t-elle poursuivi, une \u00e9tape essentielle de la non-prolif\u00e9ration nucl\u00e9aire. Aussi, faut-il d\u00e9plorer, a-<\/p>\n<p>t-elle relev\u00e9, la non entr\u00e9e en vigueur du Trait\u00e9 sur l\u2019Interdiction Compl\u00e8te des Essais Nucl\u00e9aires (TICEN) plus de deux d\u00e9cennies apr\u00e8s son adoption en 1996. Pour elle, la responsabilit\u00e9 de tous les Etats en particulier ceux de<\/p>\n<p>l\u2019annexe 2, dont la ratification est indispensable \u00e0 l\u2019entr\u00e9e en vigueur du Trait\u00e9, est engag\u00e9e. Le Burkina Faso les exhorte \u00e0 s\u2019associer aux efforts en cours, a fait savoir la ministre en charge des affaires \u00e9trang\u00e8res. \u00ab Mon<\/p>\n<p>pays reconnait les bienfaits de l\u2019utilisation pacifique du nucl\u00e9aire, toutefois en raison des cons\u00e9quences humanitaires, environnementales, \u00e9conomiques et sociales qui pourrait d\u00e9couler d\u2019une d\u00e9flagration<\/p>\n<p>accidentelle ou volontaire d\u2019armes nucl\u00e9aires, le Burkina voudrait insister sur la n\u00e9cessit\u00e9 de l\u2019\u00e9limination totale desdites armes, gage de s\u00e9curit\u00e9 pour l\u2019humanit\u00e9 toute enti\u00e8re \u00bb, a conclu Olivia Rouamba\u2026La Journ\u00e9e<\/p>\n<p>mondiale de l\u2019\u00e9limination totale des armes nucl\u00e9aires est l&rsquo;occasion pour la communaut\u00e9 internationale de r\u00e9affirmer son engagement en faveur du d\u00e9sarmement nucl\u00e9aire mondial et de reconna\u00eetre l\u2019urgence d\u2019y parvenir.<\/p>\n<p>Elle permet \u00e9galement de sensibiliser le grand public, ainsi que les dirigeants, aux avantages socio-\u00e9conomiques d\u2019un monde exempt d\u2019armes nucl\u00e9aires. Cette Journ\u00e9e est particuli\u00e8rement importante pour<\/p>\n<p>l\u2019Organisation des Nations Unies, \u00e9tant donn\u00e9 la nature universelle de ses membres. Il s\u2019agit du lieu id\u00e9al pour trouver des solutions aux plus grands<\/p>\n<p>d\u00e9fis de l&rsquo;humanit\u00e9 et pour parvenir \u00e0 la paix et la s\u00e9curit\u00e9 internationales. Conform\u00e9ment \u00e0 la r\u00e9solution 68\/32 de l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale, l\u2019objectif de<\/p>\n<p>la journ\u00e9e est donc de promouvoir et atteindre l&rsquo;\u00e9limination totale des armes nucl\u00e9aires en renfor\u00e7ant la sensibilisation et l&rsquo;\u00e9ducation du public sur la menace que repr\u00e9sentent ces armes pour l&rsquo;humanit\u00e9 et sur la<\/p>\n<p>n\u00e9cessit\u00e9 de leur \u00e9limination totale. Elle encourage enfin la communaut\u00e9 internationale \u00e0 redoubler d\u2019efforts pour parvenir finalement \u00e0 l\u2019\u00e9dification d\u2019un monde exempt d\u2019armes nucl\u00e9aires. W. Aubin NANA A New York (Etats-Unis)<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a57bb8d7f07d  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a57bb8d7f07d  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_2-63343bda06067-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a57bb8d7f07d\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 2<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d.jpg\" title=\"postMediaimg_29_1-63343bce27e0d\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d.jpg 1080w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d-300x191.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d-1024x652.jpg 1024w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_1-63343bce27e0d-768x489.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_2-63343bda06067.jpg\" title=\"postMediaimg_29_2-63343bda06067\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_2-63343bda06067.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_2-63343bda06067.jpg 706w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_2-63343bda06067-300x210.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postMediaimg_29_2-63343bda06067-100x70.jpg 100w\" sizes=\"(max-width: 706px) 100vw, 706px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armes nucl\u00e9aires, une r\u00e9union minist\u00e9rielle de haut niveau a eu lieu le lundi 26 septembre 2022 \u00e0 New York (Etats-Unis). Le Burkina Faso \u00e9tait repr\u00e9sent\u00e9 par la ministre des Affaires \u00e9trang\u00e8res, de la Coop\u00e9ration r\u00e9gionale et des Burkinab\u00e8 de l\u2019ext\u00e9rieur, Olivia [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":49618,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8,2,10],"tags":[111,725,130,29,5113,5114,1530],"class_list":["post-49619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-photo","category-politique","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina","tag-burkina-faso","tag-desarmement_complet-28septembre2022","tag-interdiction_des_armes_nucleaires","tag-plaide"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet - Burkina Faso<\/title>\n<meta name=\"description\" content=\"A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armesnucl\u00e9aires, une r\u00e9union minist\u00e9rielle de ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet\" \/>\n<meta property=\"og:description\" content=\"A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armesnucl\u00e9aires, une r\u00e9union minist\u00e9rielle de ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T11:44:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T12:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"503\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet\",\"datePublished\":\"2022-09-28T11:44:52+00:00\",\"dateModified\":\"2022-09-28T12:20:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\"},\"wordCount\":924,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"burkina\",\"Burkina Faso\",\"d\u00e9sarmement_complet 28septembre2022\",\"Interdiction_des_armes_nucl\u00e9aires\",\"plaide\"],\"articleSection\":[\"homepage-french\",\"Photo\",\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\",\"name\":\"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg\",\"datePublished\":\"2022-09-28T11:44:52+00:00\",\"dateModified\":\"2022-09-28T12:20:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armesnucl\u00e9aires, une r\u00e9union minist\u00e9rielle de ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg\",\"width\":720,\"height\":503,\"caption\":\"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet - Burkina Faso","description":"A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armesnucl\u00e9aires, une r\u00e9union minist\u00e9rielle de ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet","og_locale":"fr_FR","og_type":"article","og_title":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet","og_description":"A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armesnucl\u00e9aires, une r\u00e9union minist\u00e9rielle de ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet","og_site_name":"Burkina Faso","article_published_time":"2022-09-28T11:44:52+00:00","article_modified_time":"2022-09-28T12:20:13+00:00","og_image":[{"width":720,"height":503,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet","datePublished":"2022-09-28T11:44:52+00:00","dateModified":"2022-09-28T12:20:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet"},"wordCount":924,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","burkina","Burkina Faso","d\u00e9sarmement_complet 28septembre2022","Interdiction_des_armes_nucl\u00e9aires","plaide"],"articleSection":["homepage-french","Photo","Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet","url":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet","name":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg","datePublished":"2022-09-28T11:44:52+00:00","dateModified":"2022-09-28T12:20:13+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"A l\u2019occasion de la Journ\u00e9e mondiale de l\u2019\u00e9limination totale des armesnucl\u00e9aires, une r\u00e9union minist\u00e9rielle de ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/09\/postQueueImg_29-63343be34392a.jpg","width":720,"height":503,"caption":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/interdiction-des-armes-nucleaires-le-burkina-plaide-pour-un-desarmement-complet#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Interdiction des armes nucl\u00e9aires: Le Burkina plaide pour un d\u00e9sarmement complet"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/49619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=49619"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/49619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/49618"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=49619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=49619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=49619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}