{"id":55707,"date":"2022-12-29T17:19:16","date_gmt":"2022-12-29T17:19:16","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes"},"modified":"2022-12-29T17:42:59","modified_gmt":"2022-12-29T17:42:59","slug":"passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes","title":{"rendered":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span><b>Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zones a\u0300 forte affluence, sont ignore\u0301es par la majorite\u0301 des Ouagavillois qui pre\u0301fe\u0300rent les laisser aux enfants et continuer a\u0300 lutter dangereusement avec les automobilistes et les motocyclistes pour se frayer un passage. Constat.<\/b><\/p>\n<p>Ce jeudi 1er de\u0301cembre 2022 aux environs de 9h, Alima Taonsa est bloque\u0301e au beau milieu de la route devant le CHU Yalgado- Oue\u0301draogo, le visage grave. Elle fulmine et crie contre ces automobilistes qui refusent de lui ce\u0301der le passage. Mais peine perdue. Non seulement, les conducteurs refusent la priorite\u0301 a\u0300 dame Taonsa mais l\u2019assourdissent aussi avec leurs klaxons comme pour lui dire qu\u2019elle a inte\u0301re\u0302t a\u0300 rester sur place, si elle tient a\u0300 sa vie. Au bout de quelques minutes, la pie\u0301tonne re\u0301ussit tant bien que mal a\u0300 s\u2019en sortir.<\/p>\n<p>Pourtant, la vendeuse d\u2019eau et de jus devant l\u2019ho\u0302pital avait une solution sous les yeux : le pont pour pie\u0301tons ou passerelle pie\u0301tonne, construit (e) il y a moins d\u2019un an. Tout comme Alima Taonsa, ils sont nombreux ces Ouagavillois qui ne se servent pas encore de cette dizaine d\u2019infrastructures re\u0301alise\u0301es devant des lieux de fortes affluences tels que les ho\u0302pitaux, les marche\u0301s et les e\u0301coles pour faciliter la traverse\u0301e. C\u2019est le cas de Roukiatou Bermone\u0300.<\/p>\n<p>Un peu plus to\u0302t au niveau du marche\u0301 de Nioko 2, la jeune me\u0300re, un nourrisson a\u0300 la hauteur de la poitrine, a engage\u0301 une course pour traverser un tronc\u0327on tristement ce\u0301le\u0300bre pour la fre\u0301quence des accidents, parfois mortels. La passerelle situe\u0301e a\u0300 deux pas d\u2019elle, est surtout emprunte\u0301e par les enfants, surtout les e\u0301coliers. Malgre\u0301 un marche\u0301 et ses abords bonde\u0301s en cette heure matinale d\u2019achats de condiments et une chausse\u0301e drainant de tre\u0300s nombreux travailleurs et e\u0301le\u0300ves vers le centre-ville, le pont cherche de\u0301sespe\u0301re\u0301ment des adultes.<\/p>\n<p>Ces derniers pre\u0301fe\u0300rent se faufiler entre les voitures et les motos pour se frayer un passage pluto\u0302t que de prendre les escaliers. Le constat est le me\u0302me a\u0300 la passerelle situe\u0301e pre\u0300s de l\u2019e\u0301changeur de l\u2019Est et de la gare de l\u2019Est, non loin du marche\u0301 de Dassasgo. Seuls des rares passagers ou des petits marchands ambulants grimpent le pont. Moumouni Compaore\u0301 est a\u0300 la recherche d\u2019un objet utilitaire au niveau des boutiques qui longent le sud de la passerelle.<\/p>\n<p>Apre\u0300s satisfaction, pas question pour lui de refaire 300 m en arrie\u0300re pour emprunter le pont. Si l\u2019e\u0301crasante majorite\u0301 des usagers de la route s\u2019abstiennent de passer par les passerelles pie\u0301tonnes, quelques-uns s\u2019en accommodent. Anne Marie Ilboudo prend le pont de Nioko2 avec sa petite fille en route pour l\u2019e\u0301cole. La cinquantenaire assure qu\u2019elle le fait a\u0300 chaque fois, seule ou accompagne\u0301e, pour sa se\u0301curite\u0301 et pour celle des siens.<\/p>\n<p>A Tampouy, Zacharia Bamogo a abandonne\u0301 un court instant, sa moto devant une boutique, avant de prendre la passerelle pour rejoindre une cour situe\u0301e a\u0300 l\u2019oppose\u0301. Il exprime sa gratitude aux autorite\u0301s pour avoir pense\u0301 a\u0300 la se\u0301curite\u0301 des citoyens. Par peur des nombreuses motos et voitures, Boalidioa Lompo pre\u0301fe\u0300re aller payer \u00ab tranquillement sa cigarette \u00bb en passant par la passerelle de Yalgado. Il est suivi par Oumarou Tamboura. Le jeune homme, arrive\u0301 le 29 novembre 2022, de Djibo avec un proche malade, utilise le pont chaque fois qu\u2019il va a\u0300 la pharmacie de l\u2019ho\u0302pital.<\/p>\n<p>En fin de journe\u0301e du 1er de\u0301cembre 2022, Madeleine Nyampa, en classe de 4e, prend la passerelle de Nonsin pour rentrer a\u0300 la maison. A cause d\u2019un mal respiratoire chronique, l\u2019adolescente ne prend jamais le risque de traverser la voie par peur de perdre le souffle en milieu de chausse\u0301e. Ibrahim Kabore\u0301 est conscient qu\u2019en cas d\u2019accident sous la passerelle, il ne pourra s\u2019en prendre qu\u2019a\u0300 lui-me\u0302me.<\/p>\n<p>C\u2019est pourquoi le jeune marchand de ve\u0302tements trouve tre\u0300s judicieux de prendre l\u2019infrastructure de Baskuy (route de Ouahigouya). Toutefois, malgre\u0301 la tre\u0300s grande affluence en cette heure de descente (18h), certains te\u0301me\u0301raires n\u2019he\u0301sitent pas a\u0300 enjamber les blocs de be\u0301ton surmonte\u0301s de fer pour traverser la route. Asse\u0300ta Sawadogo (16 ans environ) ne s\u2019explique pas pourquoi \u00ables garc\u0327ons\u00bb jouent avec leur vie.<\/p>\n<p>A ce sujet, elle n\u2019est pas la seule a\u0300 chercher a\u0300 comprendre les motivations profondes des citoyens qui n\u2019empruntent pas les passerelles. Les explications vont du simple au complexe en fonction des intervenants. Pour Issaka Oue\u0301draogo, vendeur de cache-nez devant l\u2019entre\u0301e de l\u2019ho\u0302pital Yalgado-Oue\u0301draogo, c\u2019est parce que l\u2019infrastructure n\u2019a pas encore e\u0301te\u0301 inaugure\u0301e que les gens ne l\u2019empruntent pas.<\/p>\n<p>\u00ab Le principal mal qui ronge les gens aujourd\u2019hui, est le mal des articulations. Chaque fois que j\u2019emprunte la passerelle durant la journe\u0301e, la nuit au moment de me coucher, j\u2019ai mal partout. C\u2019est pourquoi je pre\u0301fe\u0300re ne\u0301gocier pour traverser. Le pont est une bonne ide\u0301e. Seulement il n\u2019est pas fait pour les souffrants\u00bb, se justifie Alima Taonsa.<\/p>\n<p>Seydou Tiemtore\u0301, vendeur de pie\u0300ces de\u0301tache\u0301es au pied de la passerelle de l\u2019Est, te\u0301moigne que ceux qui viennent des provinces utilisent davantage ces infrastructures plus que les citadins. Il pense que les autorite\u0301s devraient d\u2019abord donner l\u2019exemple en prenant re\u0301gulie\u0300rement les ponts. De l\u2019avis de Salif Bikienga, vendeur d\u2019objets plastiques sous la passerelle de Nioko 2, la nouveaute\u0301 de l\u2019infrastructure fait que certains passent pluto\u0302t leur temps a\u0300 l\u2019admirer et pensent me\u0302me qu\u2019il faut payer avant de l\u2019utiliser.<\/p>\n<p>La sexage\u0301naire, Sophie Kagambega, dit avoir des vertiges quand elle emprunte ledit pont. C\u2019est pourquoi elle traverse chaque fois la chausse\u0301e pour aller au marche\u0301 de Nioko 2. \u00ab Le pont aide nos enfants. Mais les adultes peuvent se de\u0301merder en regardant bien a\u0300 droite et a\u0300 gauche avant de traverser \u00bb, se convainc Roukiatou Bermone\u0300. Le marai\u0302cher Salfo Sawadogo comprend les vieilles personnes mais interpelle les plus jeunes sur le fait qu\u2019il ne doit pas e\u0302tre question de facilite\u0301 ou de paresse quand leurs vies sont en jeu.<\/p>\n<p>\u00ab Vraiment, les agents de se\u0301curite\u0301 font des efforts pour nous encadrer. C\u2019est nous seulement qui sommes te\u0302tus. De nos jours, nous sommes devenus tous des re\u0301calcitrants. Nous faisons comme bon nous semble. Pourtant, ce n\u2019est ni a\u0300 notre avantage ni a\u0300 celui de nos enfants \u00bb, ajoute-t-il. La vendeuse de fruits, Kadi Balma, pointe l\u2019inaccessibilite\u0301 de la passerelle de l\u2019ho\u0302pital de Bogodogo.<\/p>\n<p>En effet, des balises qui vont jusqu\u2019a\u0300 l\u2019Agence nationale de se\u0301curite\u0301 alimentaire, de l\u2019environnement, de l\u2019alimentation et du travail (ex-Laboratoire national de sante\u0301 publique) barrent l\u2019acce\u0300s aux marches du pont pour les usagers qui sortent du centre de sante\u0301. Mme Balma rele\u0300ve aussi le co\u0302te\u0301 insalubre de l\u2019infrastructure, devenue une ve\u0301ritable toilette publique pour les enfants en situation de rue et un gi\u0302te pour des pre\u0301sume\u0301s de\u0301linquants.<\/p>\n<p>C\u2019est fort de ce constat que la vendeuse dit avoir interdit a\u0300 ses enfants de ne plus emprunter la passerelle. Le pont a\u0300 pie\u0301tons de la gare de l\u2019Est et celui de l\u2019ho\u0302pital pe\u0301diatrique Charles-de-Gaulle, sentent aussi des odeurs nause\u0301abondes a\u0300 cause des urines et des excre\u0301ments humains qui sont visibles a\u0300 plusieurs endroits. Pour les cas d\u2019inaccessibilite\u0301, il faut noter aussi le cas du pont pour pie\u0301tons de l\u2019ho\u0302pital Yalgado-Oue\u0301draogo.<\/p>\n<p>A des moments de la journe\u0301e, le parking interne re\u0301serve\u0301 aux engins a\u0300 deux roues est tellement bonde\u0301, que les motos sont simplement parque\u0301es contre les marches, rendant l\u2019utilisation de l\u2019infrastructure presque impossible. La passerelle de Nioko 2 est difficilement empruntable les matins, co\u0302te\u0301 marche\u0301, a\u0300 cause des nombreuses vendeuses qui se sont installe\u0301es pre\u0300s des escaliers et de leurs clients qui y laissent ve\u0301los et motos avant de faire leurs achats.<\/p>\n<p>\u00ab Chaque semaine, des voleurs de\u0301robent au moins une moto de valeur sans compter les descentes de la Police municipale mais elles refusent de changer d\u2019endroit ou de mettre simplement leurs engins au parking. C\u2019est comme si elles ne tiraient pas lec\u0327on du vol des engins et des contraventions \u00bb, peste un vendeur de me\u0301dicaments de la rue de l\u2019autre co\u0302te\u0301 de la voie. Wendemi Kabore\u0301 est l\u2019une de ces vendeuses.<\/p>\n<p>\u00ab Les policiers nous fatiguent mais nous les fatiguons e\u0301galement. Pourtant, ils se soucient de nous mais nous sommes pluto\u0302t pre\u0301occupe\u0301s par la recherche de notre pitance quotidienne \u00bb, indique la vendeuse de salade et d\u2019oignons a\u0300 une coude\u0301e des escaliers. Elle dit e\u0302tre sur les lieux par contrainte car ayant perdu sa place au sein du marche\u0301. Le charge\u0301 des relations publiques de la Police municipale de Ouagadougou, Adama Pamtaba, confirme ces propos.<\/p>\n<p>Il estime qu\u2019il est difficile d\u2019avoir a\u0300 chaque me\u0300tre carre\u0301 de la ville, un agent pour re\u0301soudre le proble\u0300me d\u2019occupation anarchique de la voie publique. Le policier soutient que c\u2019est parce que les ponts pour pie\u0301tons ne sont pas utilise\u0301s qu\u2019ils sont de\u0301tourne\u0301s a\u0300 d\u2019autres fins. Si des petits de\u0301linquants en font leurs gi\u0302tes, d\u2019autres citoyens en font leurs lieux de sport. C\u2019est le cas de la passerelle de Tanghin ou\u0300 chaque soir, des sportifs cavalent sur les marches ou font des pompes.<\/p>\n<p>Selon Adama Pamtaba, des patrouilles ciblent re\u0301gulie\u0300rement les zones criminoge\u0300nes, y compris les passerelles. Pour l\u2019insalubrite\u0301, il indique que la Police municipale a le devoir d\u2019adresser une contravention a\u0300 toute personne prise sur- le-champ en train de salir la passerelle mais que le nettoyage ne rele\u0300ve pas de ses pre\u0301rogatives. Par ailleurs, M. Pamtaba estime que les gens e\u0301prouvent des difficulte\u0301s ou sont re\u0301ticents a\u0300 prendre ces infrastructures qui minimisent les risques d\u2019accidents, parce qu\u2019elles ne sont pas encore suffisamment entre\u0301es dans les m\u0153urs.<\/p>\n<p>Ce dernier aspect est partage\u0301 par le psychologue Valentin Couraogo. \u00ab Nous sommes dans une zone urbaine dense\u0301ment peuple\u0301e mais qui n\u2019a pas encore acquis des habitudes des grandes agglome\u0301rations comme nous le voyons un peu ailleurs. Ces infrastructures sont assez re\u0301centes et leur mise a\u0300 disposition n\u2019est pas souvent suivie de vastes campagnes de sensibilisation \u00bb, dit M. Couraogo.<\/p>\n<p>Le spe\u0301cialiste du comportement humain parle aussi du gou\u0302t du risque chez les jeunes pour tanto\u0302t prouver leur bravoure tanto\u0302t pour de\u0301fier l\u2019autorite\u0301. D\u2019apre\u0300s le psychologue, si certains individus changent de comportement apre\u0300s \u00ab avoir fro\u0302le\u0301 la mort \u00bb, pour d\u2019autres, il faut la sensibilisation, voire l\u2019e\u0301ducation sur les tenants et les aboutissants des passerelles. Selon Valentin Couraogo, un individu auparavant re\u0301ticent peut changer par \u00ab intuition \u00bb, ou lorsqu\u2019il voit que son entourage ou des leaders charismatiques empruntent les ponts pour pie\u0301tons.<\/p>\n<p>Le directeur ge\u0301ne\u0301ral de la Mobilite\u0301 urbaine, Abel Wend-Gomde\u0301 Sawadogo, insiste quant a\u0300 lui sur le respect de normes techniques. Selon lui, la voirie urbaine doit placer des e\u0301le\u0301ments de contrainte qui obligent les usagers a\u0300 passer force\u0301ment sur les passerelles. \u00ab Dans certains pays, on met des blocs suffisamment hauts au niveau des bordures late\u0301rales ou au niveau du terre-plein central pour obliger les gens a\u0300 utiliser les ponts. Parce que les gens sont dans la logique de facilite\u0301, en voulant courir pour traverser pluto\u0302t que de faire l\u2019effort de monter sur l\u2019escalier et de descendre de l\u2019autre co\u0302te\u0301 \u00bb, explique M. Sawadogo, par ailleurs responsable du programme \u2018\u2019Mobilite\u0301 et Se\u0301curite\u0301 routie\u0300re\u2019\u2019.<\/p>\n<p>A titre d\u2019exemple, il note que les pie\u0301tons vont naturellement utiliser les feux tricolores situe\u0301s a\u0300 proximite\u0301 des ponts pour traverser la route que de mettre plus de temps et d\u2019efforts avec les passerelles. Abel Wend-Gomde\u0301 Sawadogo pre\u0301cise que des cadres de concertation ont vu le jour entre des acteurs a\u0300 diffe\u0301rents niveaux pour que de\u0301sormais, tous les e\u0301le\u0301ments soient pris en compte pour minimiser les de\u0301fauts d\u2019utilisation.<\/p>\n<p><b>Tilado Apollinaire ABGA<\/b><\/p>\n<p>Le jeudi 1er de\u0301cembre 2022 aux environs de 17h20mn, un groupe d\u2019e\u0301le\u0300ves a\u0300 ve\u0301lo, traversent la chausse\u0301e sous la passerelle pie\u0301tonne de Nonsin. Majoritairement des adolescentes, elles e\u0301vitent soigneusement les intersections pour se faufiler entre une grille \u2018\u2019de\u0301chire\u0301e\u2019\u2019, place\u0301e au niveau du Terre-plein central (TPC), afin de se\u0301parer les deux voies. Tout a\u0300 coup, une voiture projeta la dernie\u0300re du groupe sur le bitume dans un bruit sec qui fit sursauter les riverains.<\/p>\n<p>Fort heureusement, la voiture immatricule\u0301e \u00ab France au revoir \u00bb a pu freiner a\u0300 quelque deux ou trois me\u0300tres de la gamine, a\u0302ge\u0301e d\u2019environ 11 a\u0300 13 ans. Des secouristes improvise\u0301s ordonnent a\u0300 l\u2019enfant te\u0301tanise\u0301e de rester immobile, pendant que ses camarades l\u2019observent avec angoisse de l\u2019autre bout de la voie. Au bout d\u2019une vingtaine de minutes, elle se releva et s\u2019assis sur le bord du TPC. Des professeurs ont quitte\u0301 son e\u0301tablissement situe\u0301 a\u0300 un jet de pierre pour venir prendre ses nouvelles.<\/p>\n<p>En attendant des e\u0301ventuels examens me\u0301dicaux, visiblement il y a eu plus de peur que de mal. Nous qui avons parcouru les diffe\u0301rentes passerelles pie\u0301tonnes de la ville de Ouagadougou, le me\u0302me jour entre 6h et 19h pour comprendre les raisons qui poussent les gens a\u0300 les e\u0301viter malgre\u0301 les dangers, venions d\u2019e\u0302tre malheureusement servi en direct. En effet, ce qui est arrive\u0301 a\u0300 la petite a de\u0301ja\u0300 touche\u0301 de nombreux pie\u0301tons, alors que la passerelle est a\u0300 leur porte\u0301e.<\/p>\n<p><b>T.A.A. <\/b><\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a03ff90e81fc  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_1-63add1421c8e6-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a03ff90e81fc  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_2-63add14d92bd0-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a03ff90e81fc  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_3-63add15746bca-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a03ff90e81fc  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a03ff90e81fc  .td-doubleSlider-2 .td-item5 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a03ff90e81fc\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 5<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_1-63add1421c8e6.jpg\" title=\"postMediaimg_18_1-63add1421c8e6\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_1-63add1421c8e6.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_1-63add1421c8e6.jpg 752w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_1-63add1421c8e6-300x163.jpg 300w\" sizes=\"(max-width: 752px) 100vw, 752px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_2-63add14d92bd0.jpg\" title=\"postMediaimg_18_2-63add14d92bd0\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_2-63add14d92bd0.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_2-63add14d92bd0.jpg 670w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_2-63add14d92bd0-300x220.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_2-63add14d92bd0-80x60.jpg 80w\" sizes=\"(max-width: 670px) 100vw, 670px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_3-63add15746bca.jpg\" title=\"postMediaimg_18_3-63add15746bca\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_3-63add15746bca.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_3-63add15746bca.jpg 749w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_3-63add15746bca-300x181.jpg 300w\" sizes=\"(max-width: 749px) 100vw, 749px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d.jpg\" title=\"postMediaimg_18_4-63add15f5620d\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d.jpg 787w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d-300x186.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d-768x475.jpg 768w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_4-63add15f5620d-356x220.jpg 356w\" sizes=\"(max-width: 787px) 100vw, 787px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item5\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5.jpg\" title=\"postMediaimg_18_5\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5.jpg 787w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5-300x225.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5-768x576.jpg 768w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_18_5-80x60.jpg 80w\" sizes=\"(max-width: 787px) 100vw, 787px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item5\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zones a\u0300 forte affluence, sont ignore\u0301es par la majorite\u0301 des Ouagavillois qui pre\u0301fe\u0300rent les laisser aux enfants et continuer a\u0300 lutter dangereusement avec les automobilistes et les motocyclistes pour se frayer un passage. Constat. Ce [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":55706,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,8,10],"tags":[5263,111,725,29,2417,36,5264,5265],"class_list":["post-55707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-photo","category-toutes-les-actualites","tag-adoptees","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso","tag-enfants","tag-ouagadougou","tag-passerelles","tag-pietonnes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zo ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes\" \/>\n<meta property=\"og:description\" content=\"Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zo ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-29T17:19:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-29T17:42:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes\",\"datePublished\":\"2022-12-29T17:19:16+00:00\",\"dateModified\":\"2022-12-29T17:42:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\"},\"wordCount\":2454,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg\",\"keywords\":[\"adopt\u00e9es\",\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\",\"Enfants\",\"ouagadougou\",\"Passerelles\",\"pi\u00e9tonnes\"],\"articleSection\":[\"Communaut\u00e9\",\"Photo\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\",\"name\":\"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg\",\"datePublished\":\"2022-12-29T17:19:16+00:00\",\"dateModified\":\"2022-12-29T17:42:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zo ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg\",\"width\":787,\"height\":487,\"caption\":\"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes - Burkina Faso","description":"Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zo ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes","og_locale":"fr_FR","og_type":"article","og_title":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes","og_description":"Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zo ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes","og_site_name":"Burkina Faso","article_published_time":"2022-12-29T17:19:16+00:00","article_modified_time":"2022-12-29T17:42:59+00:00","og_image":[{"width":787,"height":487,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes","datePublished":"2022-12-29T17:19:16+00:00","dateModified":"2022-12-29T17:42:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes"},"wordCount":2454,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg","keywords":["adopt\u00e9es","Africa Press","Africa Press-Burkina Faso","Burkina Faso","Enfants","ouagadougou","Passerelles","pi\u00e9tonnes"],"articleSection":["Communaut\u00e9","Photo","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes","url":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes","name":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg","datePublished":"2022-12-29T17:19:16+00:00","dateModified":"2022-12-29T17:42:59+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les passerelles pour pie\u0301tons construites pour faciliter la traverse\u0301e en toute se\u0301curite\u0301, au niveau de certaines zo ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321778.47.jpg","width":787,"height":487,"caption":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/passerelles-pietonnes-a-ouagadougou-adoptees-par-les-enfants-rejetees-par-les-adultes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Passerelles pi\u00e9tonnes \u00e0 Ouagadougou : adopt\u00e9es par les enfants, rejet\u00e9es par les adultes"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/55707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=55707"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/55707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/55706"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=55707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=55707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=55707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}