{"id":55714,"date":"2022-12-29T17:20:00","date_gmt":"2022-12-29T17:20:00","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique"},"modified":"2022-12-29T17:45:13","modified_gmt":"2022-12-29T17:45:13","slug":"securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique","title":{"rendered":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span><b>Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des grands centres urbains. De 2019 au 18 novembre 2022, ce sont 10 349 cas d\u2019accidents de circulation qui ont e\u0301te\u0301 enregistre\u0301s, pour 9 963 blesse\u0301s et 219 de\u0301ce\u0300s dans la capitale e\u0301conomique du Burkina Faso. L\u2019incivisme, l\u2019intole\u0301rance, le manque de courtoisie, la ve\u0301tuste\u0301 des infrastructures routie\u0300res ou des engins sont indexe\u0301s comme les causes de cette he\u0301catombe routie\u0300re. <\/b><\/p>\n<p>Dimanche 9 octobre 2022. Il est 16 heures environ, en face de la re\u0301sidence du gouverneur de la re\u0301gion des Hauts-Bassins, sur l\u2019avenue Charles-de-Gaulle. Des e\u0301le\u0301ments de la Compagnie re\u0301publicaine de se\u0301curite\u0301 (CRS) re\u0300glementent la circulation en de\u0301viant les usagers qui sont prie\u0301s de bifurquer vers l\u2019Institut franc\u0327ais. La raison, un accident mortel. Un camion \u00ab 10 tonnes \u00bb a mortellement percute\u0301 une personne du troisie\u0300me a\u0302ge.<\/p>\n<p>\u00ab C\u2019est en voulant e\u0301viter une dame qu\u2019il suivait que le vieux s\u2019est retrouve\u0301 sur la route du ve\u0301hicule. Malgre\u0301 les efforts, le conducteur n\u2019a pas pu e\u0301viter le pire \u00bb, narre un voisin du quartier du vieil homme, soutenant que c\u2019est tout joyeux que la victime les a salue\u0301s avant de prendre ce chemin mortel pour la ville.<\/p>\n<p>Le lundi 17 octobre 2022, soit une semaine apre\u0300s cet accident, c\u2019est une dame qui faisait les frais d\u2019un autre ve\u0301hicule \u00ab 10 tonnes \u00bb aux alentours de la Maison de la culture Mgr Anselme- Titianma Sanon, to\u0302t le matin a\u0300 7 heures. Aux dires des te\u0301moins de cet autre accident mortel, la victime e\u0301tait avec son enfant. \u00ab Heureusement que l\u2019enfant est sorti sain et sauf \u00bb, s\u2019exclame l\u2019un des te\u0301moins visiblement soulage\u0301 de voir le mo\u0302me en vie apre\u0300s cet accident qui a o\u0302te\u0301 la vie a\u0300 sa ge\u0301nitrice.<\/p>\n<p>Le samedi 29 octobre 2022, a\u0300 10 heures, une femme avec ses trois enfants sur sa motocyclette, tente un mauvais de\u0301passement au feu tricolore de la place Tie\u0301fo-Amoro. Malheureusement, elle percute un obstacle et se retrouve a\u0300 terre avec ses bambins dont l\u2019un (le plus a\u0302ge\u0301 de 7 ans aux dires des te\u0301moins) sous le camion-remorque qu\u2019elle voulait de\u0301passer. Le constat est implacable. L\u2019enfant est e\u0301crase\u0301 par le gros porteur.<\/p>\n<p>Dans la nuit du samedi 12 au dimanche 13 novembre 2022, aux environs de 3 heures du matin, c\u2019est le corps sans vie d\u2019un automobiliste et une e\u0301pave que les agents de la section accident de la Police nationale ont retrouve\u0301 sur la chausse\u0301e du boulevard de l\u2019Inde\u0301pendance. \u00ab Roulant a\u0300 tombeau ouvert, le conducteur, seul a\u0300 bord de son ve\u0301hicule, a percute\u0301 un arbre et y est reste\u0301 sur le champ \u00bb, confie un te\u0301moin.<\/p>\n<p>Ces exemples macabres sont la preuve que la \u00ab route tue \u00bb a\u0300 Bobo-Dioulasso, comme dans la plupart des grands centres urbains du Burkina Faso, en plus de handicaper et de marquer a\u0300 jamais de nombreuses personnes. Les routes nationale n\u00b01 (Bobo-Dioulasso-Ouagadougou), Bobo-Dioulasso-De\u0301dougou, Bobo-Dioulasso-Banfora et celles menant a\u0300 Nasso et Bama, sont entre autres axes identifie\u0301s par le commandant de la 2e compagnie de la Brigade nationale de sapeurs-pompiers (BNSP), Mamadou Go, comme accidentoge\u0300nes de la cite\u0301 de Sya.<\/p>\n<p>Selon les chiffres de la section accident de la Police nationale du commissariat central de Bobo-Dioulasso, de 2019 a\u0300 2021, ce sont 8 104 cas d\u2019accidents de la route qui ont e\u0301te\u0301 re\u0301pertorie\u0301s dont 7 737 blesse\u0301s et 175 de\u0301ce\u0300s. Pour la seule anne\u0301e 2022 (a\u0300 la date du vendredi 18 novembre 2022), ce sont 2 245 cas d\u2019accidents de circulation qui ont e\u0301te\u0301 enregistre\u0301s pour 2 226 blesse\u0301s et 44 de\u0301ce\u0300s. De janvier a\u0300 novembre 2022, les services de la 2e compagnie de la BNSP sont intervenus sur 3 008 cas d\u2019accidents de circulation qui ont cou\u0302te\u0301 la vie a\u0300 158 personnes.<\/p>\n<p>Les cas les plus fre\u0301quents, aux dires du commandant de la 2e compagnie de la BNSP, Mamadou Go, mettent en cause les engins a\u0300 deux roues et les tricycles. \u00ab Ces statistiques de\u0301montrent a\u0300 souhait que les accidents de circulation sont un proble\u0300me de sante\u0301 publique qui cause beaucoup de pertes en vies humaines autant que les grandes pande\u0301mies comme le SIDA ou le paludisme \u00bb, soutient avec tristesse le chef de la section des accidents de la ville de Bobo-Dioulasso, le lieutenant de police Salomon Kafando.<\/p>\n<p>En vue de pre\u0301venir les accidents, la Police municipale de la ville de Bobo-Dioulasso, a\u0300 moins d\u2019un mois de la fin de l\u2019anne\u0301e 2022, a saisi plus de 10 000 engins a\u0300 deux roues pour non-respect des re\u0300gles de la circulation. Preuve que les re\u0300gles de la circulation sont foule\u0301es aux pieds, aux dires du directeur de la Police municipale de Bobo-Dioulasso, l\u2019inspecteur de police Seydou Coulibaly. Plusieurs ope\u0301rations, poursuit-il, ont e\u0301te\u0301 mene\u0301es au cours de l\u2019anne\u0301e en cours dans le cadre du de\u0301sencombrement des voies d\u2019acce\u0300s.<\/p>\n<p>Trois facteurs, selon le lieutenant de police Kafando, sont les ve\u0301ritables sources de ces drames de la circulation de la route. Ce sont les facteurs lie\u0301s a\u0300 l\u2019homme, aux engins et a\u0300 l\u2019environnement. L\u2019incivisme routier, de\u0301plore-t-il, est la principale cause des accidents de la circulation routie\u0300re dans la capitale e\u0301conomique du Burkina Faso.<\/p>\n<p>Il se manifeste, de\u0301taille-t-il, par l\u2019usage du te\u0301le\u0301phone au volant, le non-respect ou la me\u0301connaissance du code de la route, l\u2019intole\u0301rance, l\u2019imprudence, la circulation frontale, le transport illicite des passagers, le de\u0301passement ou le stationnement de\u0301fectueux ainsi que l\u2019encombrement de la voie, la fatigue au volant et les acrobaties sur la voie publique.<\/p>\n<p>\u00ab En plus de communiquer au volant, certains usagers se permettent d\u2019e\u0301changer des SMS en pleine circulation \u00bb, regrette le lieutenant Salomon Kafando. L\u2019e\u0301tat du re\u0301seau routier, l\u2019e\u0301troitesse et le mauvais e\u0301tat des voies publiques, l\u2019absence ou le manque de panneaux de signalisation ou de marquage, les dangers non signale\u0301s (ponts, virages&#8230;) tout comme l\u2019insuffisance ou la quasi inexistence d\u2019e\u0301clairage public, l\u2019occupation anarchique des bordures des routes et la divagation des animaux sont les autres facteurs lie\u0301s a\u0300 l\u2019environnement et sources des accidents de circulation a\u0300 Bobo-Dioulasso, explique-t-il.<\/p>\n<p>Quant aux facteurs lie\u0301s aux engins, le chef de la section accident de la Police nationale fait cas du dysfonctionnement des syste\u0300mes de se\u0301curite\u0301 des ve\u0301hicules, de la ve\u0301tuste\u0301 des moyens de transport, du non-respect des de\u0301lais de la visite technique, du mauvais e\u0301tat du pneumatique et de l\u2019absence de feux de gabarit, triangles de signalisation.<\/p>\n<p>Dans les centres de sante\u0301, les accidente\u0301s sont conduits par dizaines chaque jour. \u00ab Il y a des jours ou\u0300 on rec\u0327oit une trentaine de patients. Tout est en fonction de la pe\u0301riode. Vers la fin de l\u2019anne\u0301e qui correspond a\u0300 la pe\u0301riode de festivite\u0301 ou pendant l\u2019anne\u0301e scolaire, surtout aux heures de pointe les matins de 7 heures a\u0300 8 heures et aux heures de descente, il y a un manque de prudence sur les voies et cela cre\u0301e des accidents \u00bb, pre\u0301cise le chirurgien-orthope\u0301diste-traumatologue au Centre hospitalier universitaire Souro- Sanon (CHUSS) de Bobo-Dioulasso, Dr Herve\u0301 Ouattara.<\/p>\n<p>Du 1er janvier au 28 novembre 2022, les services de chirurgie du CHUSS ont enregistre\u0301 5 540 patients. Les cas les plus fre\u0301quemment rec\u0327us, selon le chirurgien-orthope\u0301diste- traumatologue, sont les traumatismes cra\u0302niens et du membre pelvien, notamment les fractures des jambes. \u00ab Lorsque le patient arrive a\u0300 temps, dans un moment minime au traumatisme, nous parvenons a\u0300 le sauver.<\/p>\n<p>Mais dans le cas ou\u0300 le patient arrive de fac\u0327on grabataire, dans une situation de polytraumatisme, c\u2019est-a\u0300-dire un patient qui pre\u0301sente au moins deux le\u0301sions dont une des le\u0301sions peut l\u2019emporter, comme le cas d\u2019un traumatisme du bassin, dans ce cas, c\u2019est difficile de le sauver \u00bb, regrette Dr Ouattara. Toujours est-il que, poursuit Dr Ouattara, le patient, s\u2019il est sauve\u0301, s\u2019en tire avec des se\u0301quelles souvent graves en fonction du choc subi.<\/p>\n<p>\u00ab Dans les cas ou\u0300 ce ne sont pas des le\u0301sions grabataires, nous travaillons a\u0300 faire en sorte qu\u2019il puisse re\u0301cupe\u0301rer ses membres \u00bb, soutient-il. Pour freiner l\u2019he\u0301morragie des accidents de la route, le lieutenant de police Salomom Kafando invite les usagers de la route au respect du code de la route, a\u0300 inte\u0301grer le port du casque dans leurs habitudes, a\u0300 nouer la ceinture de se\u0301curite\u0301 pour les automobilistes et a\u0300 se de\u0301marquer des actes inciviques.<\/p>\n<p>Le directeur de la Police municipale de Bobo-Dioulasso, Seydou Coulibaly, quant a\u0300 lui, lance un appel aux acteurs de l\u2019e\u0301ducation a\u0300 inte\u0301grer l\u2019enseignement du code de la route dans les curricula scolaires afin de sensibiliser les e\u0301le\u0300ves de\u0300s le bas a\u0302ge aux re\u0300gles de la circulation. Pour sa part, le chirurgien- orthope\u0301diste-traumatologue au CHUSS de Bobo-Dioulasso, Dr Herve\u0301 Ouattara, invite les autorite\u0301s a\u0300 user de la sensibilisation pour re\u0301duire les accidents.<\/p>\n<p><b>Kame\u0301le\u0301 FAYAMA<\/b><\/p>\n<p>Seydou Coulibaly, directeur de la Police municipale de Bobo-Dioulasso<\/p>\n<p><b>\u00ab L\u2019occupation ille\u0301gale de nos rues est due aux faiblesses de l\u2019ame\u0301nagement urbain \u00bb<\/b><\/p>\n<p>\u00ab Ce n\u2019est pas parce qu\u2019on ne se\u0301vit pas. Le proble\u0300me de l\u2019occupation de la voie publique ille\u0301gale a\u0300 Bobo-Dioulasso est un proble\u0300me qu\u2019il faut prendre presque comme un proble\u0300me a\u0300 part entie\u0300re. Il faut un ensemble de mesures. D\u2019ou\u0300 est venu cet encombrement ou cette occupation ille\u0301gale de nos rues ? Cela du\u0302 aux faiblesses de l\u2019ame\u0301nagement urbain. Si l\u2019ame\u0301nagement des trottoirs ou des marche\u0301s secondaires e\u0301tait effectif, on n\u2019allait pas trouver des commerces sur les abords ou sur la chausse\u0301e. Les citoyens ont tendance a\u0300 dire que c\u2019est parce qu\u2019on n\u2019a pas besoin de cette partie, c\u2019est pourquoi on a laisse\u0301. C\u2019est vrai que ce ne sont pas des actions a\u0300 encourager. Il faut dire que la lutte contre l\u2019encombrement demande le regroupement de plusieurs acteurs et nous pensons que l\u2019ame\u0301nagement urbain est l\u2019un des premiers facteurs \u00bb.<\/p>\n<p><b>F.K.<\/b><\/p>\n<p>Mamadou Go, commandant de la 2e compagnie de la BNSP<\/p>\n<p><b>\u00ab Certaines personnes, pour tester leur te\u0301le\u0301phone, n\u2019he\u0301sitent pas a\u0300 composer notre nume\u0301ro \u00bb<\/b><\/p>\n<p>\u00ab Les fausses alertes sont l\u2019un de nos ve\u0301ritables proble\u0300mes. Nous recevons beaucoup de fausses alertes. Comme la ligne est gratuite, certaines personnes, pour tester leur te\u0301le\u0301phone, n\u2019he\u0301sitent pas a\u0300 composer notre nume\u0301ro. Cela nous rend la ta\u0302che difficile parce qu\u2019en moyenne nous recevons pre\u0300s de 1 000 appels par jour. Souvent, on nous appelle mais quand nous arrivons sur les lieux, nous constatons qu\u2019il n\u2019y a rien. J\u2019invite la population a\u0300 plus de se\u0301rieux en nous aidant a\u0300 apporter notre secours a\u0300 ceux qui en ont vraiment besoin \u00bb. K.F.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a577b6478358  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a577b6478358  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_2-63add1d9ed1ac-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a577b6478358  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_3-63add1f7d831b-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a577b6478358  .td-doubleSlider-2 .td-item4 {\r\n                        background: url(https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_4-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a577b6478358\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 4<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6.jpg\" title=\"postMediaimg_19_1-63add1b57dee6\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6.jpg 787w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6-300x221.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6-768x567.jpg 768w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_1-63add1b57dee6-80x60.jpg 80w\" sizes=\"(max-width: 787px) 100vw, 787px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_2-63add1d9ed1ac.jpg\" title=\"postMediaimg_19_2-63add1d9ed1ac\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_2-63add1d9ed1ac.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_2-63add1d9ed1ac.jpg 787w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_2-63add1d9ed1ac-300x167.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_2-63add1d9ed1ac-768x427.jpg 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_3-63add1f7d831b.jpg\" title=\"postMediaimg_19_3-63add1f7d831b\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_3-63add1f7d831b.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_3-63add1f7d831b.jpg 787w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_3-63add1f7d831b-300x188.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_3-63add1f7d831b-768x482.jpg 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item4\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_4.jpg\" title=\"postMediaimg_19_4\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_4.jpg\" srcset=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_4.jpg 750w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_4-300x221.jpg 300w, https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postMediaimg_19_4-80x60.jpg 80w\" sizes=\"(max-width: 750px) 100vw, 750px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item4\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des grands centres urbains. De 2019 au 18 novembre 2022, ce sont 10 349 cas d\u2019accidents de circulation qui ont e\u0301te\u0301 enregistre\u0301s, pour 9 963 blesse\u0301s et 219 de\u0301ce\u0300s dans la capitale e\u0301conomique du [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":55713,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,8,1017,10],"tags":[111,725,130,29,271,1768,3860,331,86],"class_list":["post-55714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-photo","category-to-homepage","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina","tag-burkina-faso","tag-faso","tag-publique","tag-routiere","tag-sante","tag-securite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des gran ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb\" \/>\n<meta property=\"og:description\" content=\"Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des gran ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-29T17:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-29T17:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb\",\"datePublished\":\"2022-12-29T17:20:00+00:00\",\"dateModified\":\"2022-12-29T17:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\"},\"wordCount\":1919,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"burkina\",\"Burkina Faso\",\"faso\",\"publique\",\"routi\u00e8re\",\"sant\u00e9\",\"s\u00e9curit\u00e9\"],\"articleSection\":[\"Communaut\u00e9\",\"Photo\",\"to-homepage\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\",\"name\":\"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg\",\"datePublished\":\"2022-12-29T17:20:00+00:00\",\"dateModified\":\"2022-12-29T17:45:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des gran ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg\",\"width\":787,\"height\":438,\"caption\":\"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb - Burkina Faso","description":"Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des gran ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb","og_description":"Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des gran ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique","og_site_name":"Burkina Faso","article_published_time":"2022-12-29T17:20:00+00:00","article_modified_time":"2022-12-29T17:45:13+00:00","og_image":[{"width":787,"height":438,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb","datePublished":"2022-12-29T17:20:00+00:00","dateModified":"2022-12-29T17:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique"},"wordCount":1919,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","burkina","Burkina Faso","faso","publique","routi\u00e8re","sant\u00e9","s\u00e9curit\u00e9"],"articleSection":["Communaut\u00e9","Photo","to-homepage","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique","url":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique","name":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg","datePublished":"2022-12-29T17:20:00+00:00","dateModified":"2022-12-29T17:45:13+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les accidents de la circulation routie\u0300re sont le\u0301sion dans la ville de Bobo-Dioulasso comme dans la plupart des gran ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2022\/12\/postQueueImg_1672321820.46.jpg","width":787,"height":438,"caption":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/photo\/securite-routiere-a-bobo-dioulasso-les-accidents-de-circulation-un-probleme-de-sante-publique#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"S\u00e9curit\u00e9 routi\u00e8re \u00e0 Bobo-Dioulasso : Les accidents de circulation, \u00ab un probl\u00e8me de sant\u00e9 publique \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/55714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=55714"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/55714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/55713"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=55714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=55714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=55714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}