{"id":62357,"date":"2023-04-29T14:03:14","date_gmt":"2023-04-29T14:03:14","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan"},"modified":"2023-04-29T14:03:14","modified_gmt":"2023-04-29T14:03:14","slug":"en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/dossiers\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan","title":{"rendered":"En l&rsquo;absence de consensus, quelles perspectives d&rsquo;affrontement entre l&rsquo;arm\u00e9e et les Forces de soutien rapide au Soudan ?"},"content":{"rendered":"<p><b>Anouar CHENNOUFI <\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>Ce n&rsquo;est plus un secret pour personne que le conflit actuel entre l&rsquo;arme\u0301e et les Forces de soutien rapide a\u0300 Khartoum soit d&rsquo;une grande importance pour les puissances re\u0301gionales et internationales en raison de l&#8217;emplacement strate\u0301gique du Soudan sur la mer Rouge et de son lien avec la re\u0301gion de se\u0301curite\u0301 anxieuse de la Corne de l&rsquo;Afrique.<\/p>\n<p>Malgre\u0301 les craintes que les combats ne se transforment en guerre par procuration, des acteurs re\u0301gionaux cle\u0301s, dont l&rsquo;E\u0301gypte, l&rsquo;Arabie saoudite et les E\u0301mirats arabes unis, ont appele\u0301 a\u0300 la paix. Ils ne souhaitent pas un conflit re\u0301gional qui constitue un fardeau supple\u0301mentaire pour la re\u0301gion. Des partenaires internationaux tels que l&rsquo;Union europe\u0301enne, le Royaume-Uni et les E\u0301tats-Unis ont e\u0301galement condamne\u0301 la violence et appele\u0301 a\u0300 la reprise des pourparlers, mais ils manquent de force pour imposer une action coercitive.<\/p>\n<p>Cependant, les deux parties en conflit semblent e\u0302tre a\u0300 e\u0301galite\u0301, ce qui augmente le risque d&rsquo;un conflit civil en cours qui pourrait faire de\u0301railler la transition du pays vers un re\u0301gime civil et exacerber la crise humanitaire. Les affrontements en cours a\u0300 Khartoum et dans d&rsquo;autres parties du pays indiquent qu&rsquo;une solution pacifique reste insaisissable pour le moment, malgre\u0301 les efforts des partenaires internationaux pour ne\u0301gocier la paix.<\/p>\n<p>Apre\u0300s notre pre\u0301ce\u0301dent article sur la situation au Soudan, nous allons tenter d&rsquo;analyser l&rsquo;issue et les perspectives d&rsquo;avenir du conflit militaire qui fait rage dans ce pays, et explore le chemin qui me\u0300ne a\u0300 l&rsquo;abi\u0302me, et les pre\u0301mices d\u2019un glissement vers la piste libyenne, ainsi que le proble\u0300me de la recherche d&rsquo;un me\u0301diateur pour mettre fin au conflit et parvenir a\u0300 la paix dans le pays.<\/p>\n<p><b>La me\u0301diation du Soudan du Sud re\u0301ussira-t-elle ?<\/b><\/p>\n<p>Dans la me\u0302le\u0301e des e\u0301ve\u0300nements qui ont lieu au Soudan, le Soudan du sud a tente\u0301 d\u2019intervenir en tant que \u00ab me\u0301diateur \u00bb entre les deux parties en conflit et, dans ce contexte, il nous est parvenu que le commandant de l&rsquo;arme\u0301e soudanaise, Abdel Fattah al-Burhan, aurait accepte\u0301 en principe de rencontrer le commandant des Forces de soutien rapide, Muhammad Hamdan Dagalo (Hemedti), selon une information rendue publique par le ministre adjoint des Affaires e\u0301trange\u0300res du Soudan du Sud, Deng Dau Deng.<\/p>\n<p>Dau a fait savoir, lors d&rsquo;une conversation te\u0301le\u0301phonique, dans la soire\u0301e du mercredi 26 avril, que le pre\u0301sident de son pays, Salva Kiir, s\u2019entretenait avec Al-Burhan et Hemedti depuis mardi, pour organiser une re\u0301union entre les deux parties et re\u0301soudre la crise actuelle, et que Kiir a appele\u0301 les deux parties au conflit au Soudan de cesser le feu, exprimant sa volonte\u0301 de se rendre a\u0300 Khartoum a\u0300 tout moment.<\/p>\n<p>De son co\u0302te\u0301, l&rsquo;arme\u0301e soudanaise a confirme\u0301 que les propositions de l&rsquo;Autorite\u0301 intergouvernementale pour le de\u0301veloppement (IGAD) pre\u0301voient l&rsquo;envoi d&rsquo;un repre\u0301sentant de l&rsquo;arme\u0301e et des Forces de soutien rapide a\u0300 Juba pour des ne\u0301gociations.<\/p>\n<p><b>Al-Burhan donne son accord pour cette me\u0301diation<\/b><\/p>\n<p>Dau a souligne\u0301 qu&rsquo;Al-Burhan avait accepte\u0301 en principe la possibilite\u0301 de s&rsquo;entretenir avec le commandant des Forces de soutien rapide, notant que le pre\u0301sident du Soudan du Sud tentait de convaincre Hemedti de saisir la possibilite\u0301 de rencontrer Al-Burhan.<\/p>\n<p>\u00ab Abdel Fattah Al-Burhan a accepte\u0301 en principe de tenir des pourparlers a\u0300 l&rsquo;inte\u0301rieur du Soudan, pendant que nous essayons d&rsquo;atteindre Hemedti et de lui parler de cette proposition \u00bb, a indique\u0301 Dau qui a fait re\u0301fe\u0301rence a\u0300 l&rsquo;appel de son pays a\u0300 prolonger le cessez-le-feu au Soudan pour 72 heures supple\u0301mentaires, en soulignant que \u00ab Le pre\u0301sident a fait cette proposition au nom de l&rsquo;IGAD, et nous attendons une re\u0301ponse pour arre\u0302ter l&rsquo;effusion de sang qui pourrait affecter toute la re\u0301gion, en particulier le sud Soudan \u00bb.<\/p>\n<p>Ne\u0301anmoins, jusqu\u2019a\u0300 la date du 27 avril, les deux parties ne se sont pas mise d&rsquo;accord quant au lieu ou\u0300 les pourparlers se de\u0301rouleront.<\/p>\n<p>Il est tout a\u0300 fait clair que les violents combats militaires auxquels Khartoum et certaines autres re\u0301gions du Soudan assistent sont plus proches du sce\u0301nario effrayant du \u00ab bord du gouffre \u00bb, dans lequel chaque camp tente d&rsquo;e\u0301liminer l&rsquo;autre par KO. Le Soudan est en conflit depuis de nombreuses anne\u0301es, la dernie\u0300re vague de violence ayant commence\u0301 apre\u0300s le renversement de l&rsquo;ancien Premier ministre Abdalla Hamdok en octobre 2021. Le conflit est actuellement une guerre entre deux parties facilement identifiables qui tentent de contro\u0302ler le pouvoir de l&rsquo;E\u0301tat : Les Forces arme\u0301es soudanaises, dirige\u0301es par le ge\u0301ne\u0301ral Abdel Fattah al-Burhan et les Forces de soutien rapide, dirige\u0301es par le lieutenant-ge\u0301ne\u0301ral Muhammad Hamdan Dagalo (Hemedti), qui se disputent le contro\u0302le du pays.<\/p>\n<p><b>Le proble\u0300me de se mettre d\u2019accord sur un me\u0301diateur<\/b><\/p>\n<p>Alors que le conflit a continue\u0301 de s&rsquo;intensifier, le ro\u0302le des acteurs externes devient de plus en plus important, les diffe\u0301rents E\u0301tats poursuivant leurs propres inte\u0301re\u0302ts et se disputant l&rsquo;influence dans la re\u0301gion. On peut rappeler que la participation des grandes puissances re\u0301gionales reve\u0302t une importance particulie\u0300re dans le dossier soudanais. L&rsquo;E\u0301gypte, par exemple, a des inte\u0301re\u0302ts strate\u0301giques en vertu des relations de parente\u0301 et des contacts civilisationnels et culturels entre les peuples e\u0301gyptien et soudanais, ce qui fait du Soudan une affaire e\u0301gyptienne et de l&rsquo;E\u0301gypte une affaire soudanaise en retour. Cela e\u0301tait e\u0301vident dans le lancement rapide par les dirigeants e\u0301gyptiens d&rsquo;une initiative visant a\u0300 re\u0301gler le conflit entre les deux parties, en coordination avec le Soudan du Sud.<\/p>\n<p><b>L&rsquo;E\u0301gypte confronte\u0301e a\u0300 un dilemme dans la gestion du conflit dans le pays voisin<\/b><\/p>\n<p>On peut dire que l&rsquo;Egypte, puissant voisin du Soudan au nord, observe avec une grande inquie\u0301tude ce qui se passe dans le pays, mais semble incapable de prendre une position claire sur la lutte pour le pouvoir.<\/p>\n<p>On peut dire e\u0301galement que, de facto, le pays des Pharaons s\u2019est trouve\u0301 au milieu d&rsquo;un dilemme, bien qu&rsquo;il puisse supporter plus que d&rsquo;autres la facture d&rsquo;un conflit qui risque de se prolonger.<\/p>\n<p>L&rsquo;E\u0301gypte est proche de l&rsquo;une des parties au conflit, l&rsquo;arme\u0301e soudanaise, alors qu&rsquo;il est probable que le commandant des Forces de soutien rapide, Muhammad Hamdan Dagalo (Hemedti), be\u0301ne\u0301ficie du soutien des E\u0301mirats arabes unis, qui est l&rsquo;un des plus grands bailleurs de fonds partisans de l&rsquo;E\u0301gypte.<\/p>\n<p>Ceci, en sachant que l&rsquo;Egypte accueille environ cinq millions de Soudanais qui ont fui le fle\u0301au de la pauvrete\u0301 et des combats. Il existe un accord de libre circulation entre les deux pays, qui permet aux citoyens des deux co\u0302te\u0301s de se de\u0301placer entre eux dans les deux sens pour la re\u0301sidence et le travail.<\/p>\n<p><b>La crainte que l&rsquo;e\u0301tincelle du conflit soudanais franchisse les frontie\u0300res<\/b><\/p>\n<p>Le conflit soudanais a ajoute\u0301 une nouvelle dimension a\u0300 la crise e\u0301conomique, politique et se\u0301curitaire interne, et il est devenu comple\u0301mentaire du cercle de conflits dans la re\u0301gion de la Corne de l&rsquo;Afrique, non loin du conflit en Afrique de l&rsquo;Ouest et dans la re\u0301gion du Sahel, qui a\u0300 son tour s&rsquo;est e\u0301tendu du Mali vers les pays voisins, notamment le Niger et le Burkina Faso, ce qui a fait que la re\u0301gion a e\u0301te\u0301 le the\u0301a\u0302tre d&rsquo;e\u0301changes entre les forces militaires internationales, tanto\u0302t franc\u0327aises, tanto\u0302t issues des combattants du groupe prive\u0301 russe \u00ab Wagner \u00bb.<\/p>\n<p>De me\u0302me, le Tchad a subi le me\u0302me conflit qui a touche\u0301 la re\u0301gion du Sahel, en plus d&rsquo;un autre conflit centre\u0301 dans le bassin du lac Tchad.<\/p>\n<p><b>Re\u0301percussions du conflit soudanais sur la re\u0301gion et le voisinage<\/b><\/p>\n<p>Ce conflit entrai\u0302nera la formulation d&rsquo;un nouveau contrat social dans lequel les conflits ethniques augmenteront, et certaines ethnies des pays voisins ayant des chevauchements ethniques avec les zones de jonction aux frontie\u0300res du Soudan be\u0301ne\u0301ficieront de cette situation, qui constitue une grande menace pour le la stabilite\u0301 des pays voisins, et cela est souvent lie\u0301 au fait que les pays voisins ont des liens ethniques.<\/p>\n<p>On peut conside\u0301rer e\u0301galement que tout conflit interne dans le pays voisin augmente la possibilite\u0301 qu&rsquo;il soit expose\u0301 aussi a\u0300 un conflit civil. Les tribus d&rsquo;origine africaine de l&rsquo;ouest du Soudan, en particulier dans les re\u0301gions instables comme le Darfour, trouvent leur opportunite\u0301 de s&rsquo;unir aux tribus de la re\u0301gion, profitant de la fragilite\u0301 croissante de la se\u0301curite\u0301, tout comme les tribus de l&rsquo;est du Soudan, qui se chevauchent avec les tribus e\u0301thiopiennes, et qui en fait des zones de conflit renouvele\u0301es dans la re\u0301gion d&rsquo;Al-Fashqa et d&rsquo;autres un environnement fertile pour ge\u0301ne\u0301rer une socie\u0301te\u0301 qui peut imposer une nouvelle re\u0301alite\u0301 au Soudan.<\/p>\n<p>Cet effet de\u0301pend de plusieurs facteurs en premier :<br \/>\n\u2022 D\u2019une part l&rsquo;ampleur de la continuite\u0301 du conflit soudanais et l&rsquo;impact de la taille des longues frontie\u0300res s&rsquo;e\u0301tendant a\u0300 l&rsquo;ouest et a\u0300 l&rsquo;est du pays.<br \/>\n\u2022 D&rsquo;autre part, il indique que les pays sont ge\u0301ne\u0301ralement prudents dans leurs relations avec le pays en proie a\u0300 un conflit arme\u0301.<\/p>\n<p>Deuxie\u0300mement, il est le re\u0301sultat du conflit arme\u0301 actuel, avec sa fin ou la poursuite de ses re\u0301percussions, et l&rsquo;expansion de son territoire, qui peut s&rsquo;e\u0301tendre a\u0300 la re\u0301gion du Darfour a\u0300 l&rsquo;ouest, a\u0300 l&rsquo;E\u0301thiopie a\u0300 l&rsquo;est et a\u0300 l&rsquo;E\u0301tat du Sud Soudan.<\/p>\n<p>Dans ce cas, les re\u0301percussions du conflit, dans son aspect se\u0301curitaire, se divisent en trois dimensions principales.<\/p>\n<p>\u2022 La premie\u0300re est l&rsquo;e\u0301tendue de la capacite\u0301 de l&rsquo;arme\u0301e soudanaise a\u0300 re\u0301soudre le chaos qui pourrait surgir dans les frontie\u0300res en flammes.<br \/>\n\u2022 La deuxie\u0300me dimension est repre\u0301sente\u0301e dans les cas d&rsquo;asile et de circulation entre les frontie\u0300res et l&rsquo;apparition d&rsquo;autres complications telles que les empie\u0300tements sur les terres, la propagation de la criminalite\u0301, le terrorisme et le trafic d&rsquo;e\u0302tres humains, ainsi que le trafic de drogue et d&rsquo;armes.<br \/>\n\u2022 Quant a\u0300 la troisie\u0300me dimension, elle est lie\u0301e a\u0300 la mesure dans laquelle le syste\u0300me politique soudanais s&rsquo;appuie sur des axes re\u0301gionaux pour re\u0301soudre ses proble\u0300mes, car toutes les solutions aux crises pre\u0301ce\u0301dentes pendant la guerre civile au Sud-Soudan e\u0301taient base\u0301es sur la solution de facilite\u0301, qui est tenir un re\u0301fe\u0301rendum sur la se\u0301cession puis le mettre en \u0153uvre dans un de\u0301lai serre\u0301, sans exploiter aucun facteur de temps pour l&rsquo;examen ou la re\u0301tractation.<\/p>\n<p>Sur la base de ces facteurs de risque pertinents, la nature de\u0301sastreuse de ce conflit re\u0301side dans sa composition, ses causes et les lacunes par lesquelles il s&rsquo;e\u0301tend.<\/p>\n<p>Le point essentiel ici est que le conflit arme\u0301 actuel peut largement s&rsquo;e\u0301tendre aux pays de la re\u0301gion, et ces effets peuvent se re\u0301percuter a\u0300 nouveau sur le Soudan, et peuvent me\u0302me e\u0301voluer avec le temps et conduire a\u0300 des re\u0301ponses politiques qui peuvent avoir des effets a\u0300 long terme, et les re\u0301percussions ne repre\u0301sentent pas ne\u0301cessairement le de\u0301clenchement d&rsquo;un conflit arme\u0301 dans les pays voisins, mais elles peuvent se manifester dans le fardeau e\u0301conomique supporte\u0301 par l&rsquo;ensemble de la re\u0301gion en raison du de\u0301clenchement du conflit, a\u0300 commencer par l&rsquo;impact sur les flux commerciaux bilate\u0301raux ou multilate\u0301raux avec les organisations e\u0301conomiques re\u0301gionales , et aussi non loin de la\u0300 que si la guerre entrave le secteur industriel et commercial, le Il y a une autre activite\u0301 e\u0301conomique qui en re\u0301sulte, comme la fabrication et le commerce d&rsquo;armes et les activite\u0301s de contrebande.<\/p>\n<p><b>Quelle est la position adopte\u0301e par le Tchad ?<\/b><\/p>\n<p>Le gouvernement tchadien a nie\u0301 quant a\u0300 lui s&rsquo;e\u0302tre range\u0301 du co\u0302te\u0301 de l&rsquo;une des parties bellige\u0301rantes au Soudan. Et ceci est venu en re\u0301ponse a\u0300 des me\u0301dias qui ont indique\u0301 que le Tchad soutient l&rsquo;une des deux parties au conflit au Soudan.<\/p>\n<p>Ces informations, publie\u0301es dimanche 23 avril 2023, citent une \u00ab source diplomatique tchadienne \u00bb disant que le Conseil de transition tchadien, dirige\u0301 par Mahamat Idriss Deby, se tient aux co\u0302te\u0301s des forces arme\u0301es soudanaises dans leur \u00ab guerre \u00bb contre ce qu&rsquo;elles ont appele\u0301 la \u00ab milice de soutien rapide \u00bb.<\/p>\n<p>Dans ces circonstances, le ministe\u0300re tchadien des Affaires e\u0301trange\u0300res reste la source diplomatique la plus fiable, du fait que le ministre lui-me\u0302me a de\u0301clare\u0301 lundi dans un communique\u0301 qu&rsquo;il \u00ab de\u0301ment officiellement les fausses informations fournies par une source diplomatique tchadienne \u00bb, qualifiant la publication d&rsquo;informations visant a\u0300 \u00ab ternir \u00bb l&rsquo;image du Tchad.<\/p>\n<p><b>Pre\u0301occupation des pays voisins, les E\u0301tats-Unis et d&rsquo;autres pays<\/b><\/p>\n<p>Le conflit en cours au Soudan inquie\u0300te les pays voisins, les E\u0301tats-Unis et d&rsquo;autres, pour des raisons allant des inquie\u0301tudes concernant les eaux partage\u0301es du Nil et les ole\u0301oducs a\u0300 la forme du nouveau gouvernement et a\u0300 une nouvelle crise humanitaire imminente.<\/p>\n<p>Les conflits ne sont pas nouveaux au Soudan, qui de\u0301pend fortement de l&rsquo;aide e\u0301trange\u0300re, mais les combats de\u0301chirent cette fois la capitale du pays, situe\u0301e dans une re\u0301gion instable aux confins de la mer Rouge, du Sahel et de la Corne de l&rsquo;Afrique.<\/p>\n<p>Cinq des sept pays voisins du Soudan &#8211; l&rsquo;E\u0301thiopie, le Tchad, la Re\u0301publique centrafricaine, la Libye et le Soudan du Sud &#8211; ont connu des troubles politiques ou des conflits au cours des dernie\u0300res anne\u0301es.<\/p>\n<p>\u2022 Quels sont les risques pour les pays de la re\u0301gion ?<\/p>\n<p><b>L&rsquo;Egypte &#8211;<\/b> le pays arabe le plus peuple\u0301 avec une arme\u0301e puissante, a une histoire commune avec le Soudan dans la politique, le commerce, la culture et les eaux partage\u0301es du Nil. Le Caire s&rsquo;inquie\u0300te des troubles politiques dans le pays a\u0300 sa frontie\u0300re sud depuis le soule\u0300vement de 2019 qui a renverse\u0301 Al-Bashir. En plus le pre\u0301sident e\u0301gyptien Abdel Fattah El-Sissi, qui a e\u0301galement pris le pouvoir apre\u0300s la prise de contro\u0302le du pays par l&rsquo;arme\u0301e, est proche d&rsquo;Al-Burhan.<\/p>\n<p>Par ailleurs, l&rsquo;E\u0301gypte et le Soudan, qui de\u0301pendent du Nil comme source d&rsquo;eau douce, s&rsquo;inquie\u0300tent des menaces qui pe\u0300sent sur leur approvisionnement en raison du projet du grand barrage de la renaissance en Ethiopie, en amont sur le Nil Bleu. Les deux pays poussent a\u0300 re\u0301glementer les travaux du barrage e\u0301thiopien, sachant que toute tension dans les relations entre Khartoum et Le Caire pourrait entraver leurs efforts pour parvenir a\u0300 un accord sur ce barrage.<\/p>\n<p>Reste que le pire cauchemar pour le Caire aujourd\u2019hui serait de voir le sce\u0301nario libyen se re\u0301pe\u0301ter au Soudan. Elle est e\u0301galement devant un dilemme : l\u2019accession au pouvoir des forces du ge\u0301ne\u0301ral Hemedti pourrait s\u2019opposer a\u0300 ses inte\u0301re\u0302ts au Soudan, surtout (si) en pre\u0301sence des soutiens e\u0301trangers, re\u0301gionaux ou internationaux a\u0300 Hemedti.<\/p>\n<p><b>La Libye &#8211;<\/b> Des mercenaires et des miliciens soudanais ont joue\u0301 un ro\u0302le actif des deux co\u0302te\u0301s du conflit interne qui a divise\u0301 la Libye apre\u0300s 2011. De nombreux combattants soudanais sont retourne\u0301s au Soudan ces dernie\u0300res anne\u0301es, ce qui a contribue\u0301 a\u0300 attiser les tensions dans la re\u0301gion du Darfour, a\u0300 l&rsquo;ouest du Soudan, ou\u0300 un autre conflit a fait rage il y a des anne\u0301es et les combats se sont poursuivis jusqu&rsquo;a\u0300 la conclusion d&rsquo;un accord avec certains groupes rebelles en 2020.<\/p>\n<p>Le Soudan est devenu une e\u0301tape et une voie de transit pour les migrants cherchant a\u0300 se rendre en Europe via la Libye, ou\u0300 les passeurs ont exploite\u0301 les conflits et les troubles politiques a\u0300 leur avantage.<\/p>\n<p><b>Le Tchad &#8211; <\/b>Depuis le de\u0301but des derniers combats, quelque 20.000 re\u0301fugie\u0301s soudanais supple\u0301mentaires sont arrive\u0301s au Tchad, le voisin occidental appauvri du Soudan, ou\u0300 de\u0301ja\u0300 quelque 400.000 de\u0301place\u0301s soudanais sont arrive\u0301s lors de conflits pre\u0301ce\u0301dents, selon les Nations Unies.<\/p>\n<p>Le Tchad est pre\u0301occupe\u0301 par le de\u0301bordement de la crise a\u0300 travers la frontie\u0300re dans les zones ou\u0300 il accueille des re\u0301fugie\u0301s, la plupart d&rsquo;entre eux du Darfour. Pendant le conflit au Darfour, le Tchad a e\u0301te\u0301 attaque\u0301 de l&rsquo;autre co\u0302te\u0301 de la frontie\u0300re par des milices arabes au Soudan connues sous le nom de \u00ab Janjaweed \u00bb qui sont devenues apre\u0300s les Forces de soutien rapide. Des membres de ces milices ont attaque\u0301 des re\u0301fugie\u0301s du Darfour et des villageois tchadiens, saisissant du be\u0301tail et tuant ceux qui leur re\u0301sistaient.<\/p>\n<p>Le gouvernement tchadien a de\u0301clare\u0301 avoir de\u0301sarme\u0301 un bataillon paramilitaire de 320 hommes qui e\u0301tait entre\u0301 sur son territoire lundi, et le Tchad craint que les rebelles tchadiens qui menacent le gouvernement de N&rsquo;Djamena ne trouvent le soutien du groupe militaire prive\u0301 russe Wagner, base\u0301 en Re\u0301publique centrafricaine voisine, qui entretiendrait des liens e\u0301troits avec les Forces de soutien rapide, sauf que Wagner nie toute implication au Soudan.<\/p>\n<p><b>Le Soudan du Sud &#8211;<\/b> Un pays qui s&rsquo;est se\u0301pare\u0301 du Soudan en 2011 apre\u0300s des de\u0301cennies de guerre civile et exporte ses 170.000 barils\/jour de production de pe\u0301trole via un ole\u0301oduc passant par son voisin du nord.<\/p>\n<p>Dans ce contexte, les analystes disent qu&rsquo;il n&rsquo;est dans l&rsquo;inte\u0301re\u0302t d&rsquo;aucune des parties au conflit au Soudan de perturber ces flux, mais le gouvernement sud-soudanais a de\u0301clare\u0301 cette semaine que les combats avaient de\u0301ja\u0300 entrave\u0301 les liaisons logistiques et de transport entre les champs pe\u0301trolife\u0300res et Port-Soudan.<\/p>\n<p>Le Soudan accueille 800.000 re\u0301fugie\u0301s du Soudan du Sud. Tout retour massif pourrait encore mettre a\u0300 rude e\u0301preuve les efforts visant a\u0300 fournir une aide de base a\u0300 plus de deux millions de personnes de\u0301place\u0301es au Soudan du Sud qui ont fui leur foyer dans le pays en raison de la guerre civile.<\/p>\n<p><b>L\u2019E\u0301thiopie &#8211; <\/b>Des escarmouches e\u0301clatent pe\u0301riodiquement le long des zones frontalie\u0300res conteste\u0301es entre le Soudan et l&rsquo;E\u0301thiopie, et les analystes disent que l&rsquo;une ou l&rsquo;autre des parties pourrait profiter de l&rsquo;agitation au Soudan pour faire pression pour atteindre son objectif.<\/p>\n<p>Apre\u0300s le de\u0301clenchement de la guerre dans la re\u0301gion du Tigre\u0301 au nord de l&rsquo;E\u0301thiopie en 2020, des tensions sont apparues au sujet de la fertile re\u0301gion conteste\u0301e d&rsquo;Al-Fashqa a\u0300 la frontie\u0300re et ont pousse\u0301 plus de 50.000 re\u0301fugie\u0301s e\u0301thiopiens vers des zones de\u0301ja\u0300 pauvres de l&rsquo;est du Soudan.<\/p>\n<p>L&rsquo;E\u0301thiopie surveillera e\u0301galement l&rsquo;e\u0301volution de la situation a\u0300 la lumie\u0300re des tensions autour du Grand barrage e\u0301thiopien de la Renaissance de 4 milliards de dollars, qui, selon le Soudan, pourrait constituer une menace pour ses barrages sur le Nil et ses citoyens.<\/p>\n<p><b>L\u2019E\u0301rythre\u0301e \u2013 <\/b>A noter que le Soudan accueille plus de 134.000 re\u0301fugie\u0301s et demandeurs d&rsquo;asile d&rsquo;E\u0301rythre\u0301e et constitue la principale voie d&rsquo;acce\u0300s pour les E\u0301rythre\u0301ens fuyant la conscription impose\u0301e par le re\u0301gime re\u0301pressif d&rsquo;Asmara.<\/p>\n<p>De nombreux re\u0301fugie\u0301s e\u0301rythre\u0301ens dans le nord de l&rsquo;E\u0301thiopie ont fui leurs camps lors des combats au Tigre\u0301 entre 2020 et 2022, et ainsi, les re\u0301fugie\u0301s e\u0301rythre\u0301ens au Soudan pourraient subir une e\u0301preuve similaire si un conflit en dehors de Khartoum s&rsquo;intensifiait.<\/p>\n<p>\u2022 Bilan officiel provisoire des e\u0301ve\u0300nements au Soudan<\/p>\n<p>Le Soudan continue de compter ses morts, notamment les vies perdues a\u0300 la suite de violents combats qui opposent l\u2019arme\u0301e, commande\u0301e par Al-Burhan, aux paramilitaires des Forces de soutien rapide, dirige\u0301s par \u00ab Hemedti \u00bb.<\/p>\n<p>En effet, un communique\u0301 officiel du gouvernement a indique\u0301 que :<\/p>\n<p>\u00ab Le bilan des victimes fait e\u0301tat de 512 morts, tandis que le nombre total de blesse\u0301s s\u2019e\u0301le\u0300ve a\u0300 4 193, a\u0300 Khartoum et dans les diffe\u0301rentes re\u0301gions du pays, depuis le 15 avril \u00bb.<\/p>\n<p>Les vies humaines sont tombe\u0301es malheureusement dans quatre re\u0301gions : il s\u2019agit de Khartoum, le Darfour-Sud, le Darfour-Ouest et le Darfour-Central.<\/p>\n<p><b>Dernie\u0300re nouvelle<\/b><\/p>\n<p>Alors que nous clo\u0302turons le pre\u0301sent article, nous avons appris, au milieu des combats incessants qui ont fait des centaines de morts et des dizaines de milliers de personnes fuyant pour sauver leur vie, que les parties bellige\u0301rantes au Soudan ont annonce\u0301 qu&rsquo;elles prolongeraient le \u00ab cessez-le-feu de soixante-douze heures supple\u0301mentaires \u00bb.<\/p>\n<p>Les Nations Unies, l&rsquo;Union africaine, l&rsquo;Autorite\u0301 intergouvernementale pour le de\u0301veloppement (IGAD) et les pays dits du Quartet, a\u0300 savoir les E\u0301tats-Unis, la Grande-Bretagne, les E\u0301mirats arabes unis et l&rsquo;Arabie saoudite, ont salue\u0301 la prolongation du cessez-le-feu.<\/p>\n<p><b>Appui me\u0301diatique vide\u0301o<\/b><\/p>\n<p><iframe loading=\"lazy\" title=\"Soudan : violents combats \u00e0 Khartoum et au Darfour, n\u00e9gociations en cours pour prolonger la tr\u00eave\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/sQW3DVs88ZU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"&quot;Une fois de plus le cessez-le-feu n&#039;a pas tenu au Soudan&quot; \u2022 FRANCE 24\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/hmIql8BcGMo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Les combats s\u2019intensifient au Soudan : un cessez-le-feu est accept\u00e9\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/arlDKGSouO8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anouar CHENNOUFI Africa-Press &#8211; Burkina Faso. Ce n&rsquo;est plus un secret pour personne que le conflit actuel entre l&rsquo;arme\u0301e et les Forces de soutien rapide a\u0300 Khartoum soit d&rsquo;une grande importance pour les puissances re\u0301gionales et internationales en raison de l&#8217;emplacement strate\u0301gique du Soudan sur la mer Rouge et de son lien avec la re\u0301gion [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":62356,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,10],"tags":[5430,111,725,29,182,5429,5428,5427,1728],"class_list":["post-62357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-toutes-les-actualites","tag-abdel-fattah-al-burhan","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso","tag-forces-armees-nationales","tag-forces-de-soutien-rapide","tag-muhammad-hamdan-dagalo-hemedti","tag-salva-kirr","tag-soudan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>En l&#039;absence de consensus, quelles perspectives d&#039;affrontement entre l&#039;arm\u00e9e et les Forces de soutien rapide au Soudan ? - Burkina Faso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En l&#039;absence de consensus, quelles perspectives d&#039;affrontement entre l&#039;arm\u00e9e et les Forces de soutien rapide au Soudan ?\" \/>\n<meta property=\"og:description\" content=\"Anouar CHENNOUFI Africa-Press &#8211; Burkina Faso. Ce n&rsquo;est plus un secret pour personne que le conflit actuel entre l&rsquo;arme\u0301e et les Forces de soutien rapide a\u0300 Khartoum soit d&rsquo;une grande importance pour les puissances re\u0301gionales et internationales en raison de l&#8217;emplacement strate\u0301gique du Soudan sur la mer Rouge et de son lien avec la re\u0301gion [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T14:03:14+00:00\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"En l&rsquo;absence de consensus, quelles perspectives d&rsquo;affrontement entre l&rsquo;arm\u00e9e et les Forces de soutien rapide au Soudan ?\",\"datePublished\":\"2023-04-29T14:03:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\"},\"wordCount\":3732,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg\",\"keywords\":[\"Abdel Fattah Al-Burhan\",\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\",\"Forces arm\u00e9es nationales\",\"Forces de soutien rapide\",\"Muhammad Hamdan Dagalo (Hemedti)\",\"Salva Kirr\",\"Soudan\"],\"articleSection\":[\"Dossiers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\",\"name\":\"En l'absence de consensus, quelles perspectives d'affrontement entre l'arm\u00e9e et les Forces de soutien rapide au Soudan ? - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg\",\"datePublished\":\"2023-04-29T14:03:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg\",\"width\":1200,\"height\":630,\"caption\":\"En l'absence de consensus, quelles perspectives d'affrontement entre l'arm\u00e9e et les Forces de soutien rapide au Soudan ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En l&#8217;absence de consensus, quelles perspectives d&#8217;affrontement entre l&#8217;arm\u00e9e et les Forces de soutien rapide au Soudan ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"En l'absence de consensus, quelles perspectives d'affrontement entre l'arm\u00e9e et les Forces de soutien rapide au Soudan ? - Burkina Faso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan","og_locale":"fr_FR","og_type":"article","og_title":"En l'absence de consensus, quelles perspectives d'affrontement entre l'arm\u00e9e et les Forces de soutien rapide au Soudan ?","og_description":"Anouar CHENNOUFI Africa-Press &#8211; Burkina Faso. Ce n&rsquo;est plus un secret pour personne que le conflit actuel entre l&rsquo;arme\u0301e et les Forces de soutien rapide a\u0300 Khartoum soit d&rsquo;une grande importance pour les puissances re\u0301gionales et internationales en raison de l&#8217;emplacement strate\u0301gique du Soudan sur la mer Rouge et de son lien avec la re\u0301gion [&hellip;]","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan","og_site_name":"Burkina Faso","article_published_time":"2023-04-29T14:03:14+00:00","author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"En l&rsquo;absence de consensus, quelles perspectives d&rsquo;affrontement entre l&rsquo;arm\u00e9e et les Forces de soutien rapide au Soudan ?","datePublished":"2023-04-29T14:03:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan"},"wordCount":3732,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg","keywords":["Abdel Fattah Al-Burhan","Africa Press","Africa Press-Burkina Faso","Burkina Faso","Forces arm\u00e9es nationales","Forces de soutien rapide","Muhammad Hamdan Dagalo (Hemedti)","Salva Kirr","Soudan"],"articleSection":["Dossiers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan","url":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan","name":"En l'absence de consensus, quelles perspectives d'affrontement entre l'arm\u00e9e et les Forces de soutien rapide au Soudan ? - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg","datePublished":"2023-04-29T14:03:14+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/04\/postQueueImg_1682769664.92.jpg","width":1200,"height":630,"caption":"En l'absence de consensus, quelles perspectives d'affrontement entre l'arm\u00e9e et les Forces de soutien rapide au Soudan ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/en-labsence-de-consensus-quelles-perspectives-daffrontement-entre-larmee-et-les-forces-de-soutien-rapide-au-soudan#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"En l&#8217;absence de consensus, quelles perspectives d&#8217;affrontement entre l&#8217;arm\u00e9e et les Forces de soutien rapide au Soudan ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/62357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=62357"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/62357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/62356"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=62357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=62357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=62357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}