{"id":72275,"date":"2023-10-09T15:46:10","date_gmt":"2023-10-09T15:46:10","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans"},"modified":"2023-10-09T15:58:29","modified_gmt":"2023-10-09T15:58:29","slug":"une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans","title":{"rendered":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>Ce sont des souches d&rsquo;arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont e\u0301te\u0301 a\u0300 l&rsquo;origine de la mise en e\u0301vidence de cette tempe\u0302te solaire qui s&rsquo;est produite il y a 14.300 ans. Ce serait l&rsquo;un des e\u0301ve\u0300nements les plus violents jamais enregistre\u0301s et s&rsquo;il se produisait aujourd&rsquo;hui, ces conse\u0301quences seraient catastrophiques sur les activite\u0301s humaines.<\/p>\n<p><b>Pic de radiocarbone<\/b><\/p>\n<p>C&rsquo;est dans les cernes de ces arbres pe\u0301trifie\u0301s que des scientifiques de plusieurs organismes franc\u0327ais associe\u0301s a\u0300 des chercheurs de l&rsquo;Universite\u0301 de Leeds, en Angleterre, ont repe\u0301re\u0301 un pic de carbone 14, un isotope radioactif du carbone qui se forme dans la haute atmosphe\u0300re sous l&rsquo;effet des rayons cosmiques solaires.<\/p>\n<p>Le lien entre ces pics de carbone et l&rsquo;activite\u0301 solaire est de\u0301sormais bien documente\u0301 et il apparai\u0302t que l&rsquo;occurrence de\u0301crite dans cette e\u0301tude, qui est publie\u0301e dans la revue Philosophical Transactions of the Royal Society A, est environ deux fois plus importante que les plus grosses tempe\u0302tes solaires enregistre\u0301es depuis 15.000 ans.<\/p>\n<p><b>Les e\u0301ve\u0300nements de Miyake, ou les tempe\u0302tes solaires d&rsquo;exception<\/b><\/p>\n<p>Ces tempe\u0302tes exceptionnelles sont appele\u0301es e\u0301ve\u0300nements de Miyake, d&rsquo;apre\u0300s Fusa Miyake, un physicien japonais qui a identifie\u0301 certains d&rsquo;entre eux dans les cernes de ce\u0300dres du Japon, dans un article publie\u0301 dans la revue Nature, en 2012.<\/p>\n<p>Depuis, 9 ont e\u0301te\u0301 identifie\u0301s dont les plus re\u0301cents remontent au premier mille\u0301naire, en 774 et 993 ap. J.-C. Aucun n&rsquo;ayant pu e\u0302tre e\u0301tudie\u0301 avec des instruments, il existe encore beaucoup d&rsquo;interrogations a\u0300 leur sujet, notamment quant a\u0300 leur cause et a\u0300 leur fre\u0301quence de survenue.<\/p>\n<p>Pour la pe\u0301riode moderne, la tempe\u0302te solaire la plus importante observe\u0301e est celle de 1859, nomme\u0301e e\u0301ve\u0300nement de Carrington. Elle a ge\u0301ne\u0301re\u0301 des aurores polaires visibles jusque dans les tropiques et des perturbations des re\u0301seaux e\u0301lectriques et de communication par te\u0301le\u0301graphie filaire.<\/p>\n<p><b>Le Soleil en cole\u0300re<\/b><\/p>\n<p>Les e\u0301ruptions se produisent au niveau des taches sombres du Soleil, des zones de l&rsquo;atmosphe\u0300re ou\u0300 le champ magne\u0301tique est tre\u0300s fort et la tempe\u0301rature moins e\u0301leve\u0301e. Les champs magne\u0301tiques y acce\u0301le\u0300rent des particules a\u0300 des niveaux d&rsquo;e\u0301nergie conside\u0301rables, des millions de fois supe\u0301rieures a\u0300 ceux d&rsquo;une explosion nucle\u0301aire et parfois les arcades magne\u0301tiques se rompent et ge\u0301ne\u0300rent une e\u0301ruption qui projettent dans l&rsquo;espace des particules hautement ve\u0301loces et e\u0301nerge\u0301tiques.<\/p>\n<p>Lorsqu&rsquo;elles arrivent autour de la Terre, ces particules provoquent des tempe\u0302tes ge\u0301omagne\u0301tiques qui forment des aurores polaires. Ces perturbations ge\u0301omagne\u0301tiques ont e\u0301galement des conse\u0301quences de plus en plus redoute\u0301es : l&rsquo;omnipre\u0301sence de l&rsquo;e\u0301lectronique, des syste\u0300mes assiste\u0301s par satellites ou ordinateurs rend les activite\u0301s humaines bien plus sensibles aux caprices du Soleil qu&rsquo;il y a un sie\u0300cle.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Ce sont des souches d&rsquo;arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont e\u0301te\u0301 a\u0300 l&rsquo;origine de la mise en e\u0301vidence de cette tempe\u0302te solaire qui s&rsquo;est produite il y a 14.300 ans. Ce serait l&rsquo;un des e\u0301ve\u0300nements les plus violents jamais enregistre\u0301s [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":72274,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[111,725,29],"class_list":["post-72275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Ce sont des souches d&#039;arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans\" \/>\n<meta property=\"og:description\" content=\"Ce sont des souches d&#039;arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-09T15:46:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T15:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans\",\"datePublished\":\"2023-10-09T15:46:10+00:00\",\"dateModified\":\"2023-10-09T15:58:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\"},\"wordCount\":568,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\",\"name\":\"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg\",\"datePublished\":\"2023-10-09T15:46:10+00:00\",\"dateModified\":\"2023-10-09T15:58:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Ce sont des souches d'arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg\",\"width\":1200,\"height\":899,\"caption\":\"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans - Burkina Faso","description":"Ce sont des souches d'arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans","og_locale":"fr_FR","og_type":"article","og_title":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans","og_description":"Ce sont des souches d'arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans","og_site_name":"Burkina Faso","article_published_time":"2023-10-09T15:46:10+00:00","article_modified_time":"2023-10-09T15:58:29+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans","datePublished":"2023-10-09T15:46:10+00:00","dateModified":"2023-10-09T15:58:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans"},"wordCount":568,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans","name":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg","datePublished":"2023-10-09T15:46:10+00:00","dateModified":"2023-10-09T15:58:29+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Ce sont des souches d'arbres fossilise\u0301s et pre\u0301serve\u0301s le long des berges de la rivie\u0300re Drouzet, pre\u0300s de Gap, qui ont ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696854420.716217.jpg","width":1200,"height":899,"caption":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/une-violente-tempete-solaire-a-eu-lieu-il-y-a-14-300-ans#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Une violente temp\u00eate solaire a eu lieu il y a 14.300 ans"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=72275"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/72274"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=72275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=72275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=72275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}