{"id":72318,"date":"2023-10-10T14:08:57","date_gmt":"2023-10-10T14:08:57","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain"},"modified":"2023-10-10T14:13:53","modified_gmt":"2023-10-10T14:13:53","slug":"addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain","title":{"rendered":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principale agence de sante\u0301 de ce pays, les Centres pour le contro\u0302le et la pre\u0301vention des maladies (CDC), plus de 80.000 personnes y ont pe\u0301ri en 2021 a\u0300 cause de ces de\u0301rive\u0301s d\u2019opiace\u0301s (ce qui repre\u0301sente 75 % de tous les de\u0301ce\u0300s cause\u0301s par une overdose).<\/p>\n<p>Cette crise risque de devenir globale, car il a e\u0301te\u0301 montre\u0301 que les entreprises pharmaceutiques produisant ces opioi\u0308des tentent de les exporter pour e\u0301chapper aux re\u0301gulations ame\u0301ricaines. Pour faire face au tsunami des cas d\u2019overdose, le gouvernement des Etats-Unis autorise de\u0301sormais la vente sans ordonnance d\u2019un me\u0301dicament pouvant ranimer les victimes d\u2019overdose par opioi\u0308des.<\/p>\n<p><b>Tromper le syste\u0300me immunitaire pour lutter contre les opioi\u0308des<\/b><\/p>\n<p>Cependant, il serait bien plus efficace de pre\u0301venir ces cas au lieu de les traiter apre\u0300s l\u2019overdose. Pour ce faire, plusieurs e\u0301quipes scientifiques ont conc\u0327u des vaccins qui reconnaissent ces mole\u0301cules. Ces vaccins trompent le syste\u0300me immunitaire en lui faisant croire que l\u2019opioi\u0308de est la prote\u0301ine d\u2019un pathoge\u0300ne. Le corps de l\u2019individu vaccine\u0301 produit donc des anticorps qui ciblent cette mole\u0301cule et la recouvrent, lui empe\u0302chant de traverser la barrie\u0300re he\u0301matoence\u0301phalique, qui prote\u0300ge le cerveau.<\/p>\n<p>Lire aussi\u00a0\u00bb16 ans pour toujours\u00a0\u00bb : les ravages du fentanyl au sein de la jeunesse ame\u0301ricaine<\/p>\n<p>Ainsi, l\u2019opioi\u0308de ne peut pas pe\u0301ne\u0301trer dans le cerveau et ne peut plus produire son effet euphorique et de de\u0301tente. Ce qui devrait aider a\u0300 la personne atteinte d&rsquo;addiction a\u0300 arre\u0302ter de l\u2019utiliser.<\/p>\n<p>C\u2019est par exemple le cas d\u2019un vaccin de\u0301veloppe\u0301 a\u0300 l\u2019Universite\u0301 de Houston, qui diminue de 90 % la quantite\u0301 de fentanyl qui pe\u0301ne\u0300tre le cerveau de rats vaccine\u0301s, e\u0301vitant ainsi les effets ne\u0301fastes de cette drogue. Apre\u0300s ces re\u0301sultats tre\u0300s encourageants chez des mode\u0300les animaux, les premiers de ses vaccins commencent a\u0300 e\u0302tre teste\u0301s chez l\u2019humain.<\/p>\n<p><b>Le premier essai clinique vise l\u2019oxycodone<\/b><\/p>\n<p>Plusieurs mole\u0301cules de\u0301rive\u0301es d\u2019opiace\u0301s existent actuellement, telles que la code\u0301ine, le tramadol, le fentanyl ou l\u2019oxycodone. Ce dernier, cre\u0301e\u0301 il y a plus d\u2019un sie\u0300cle en Allemagne, est un des opioi\u0308des les plus prescrits et un des plus addictifs, e\u0301tant a\u0300 l\u2019origine de la vague de cas d\u2019overdose aux E\u0301tats-Unis.<\/p>\n<p>En 2011, l\u2019oxycodone e\u0301tait la drogue causant le plus de de\u0301ce\u0300s par overdose, elle a e\u0301te\u0301 de\u0301passe\u0301e par le fentanyl depuis 2014, selon les donne\u0301es des CDC. Des candidats vaccins contre cette mole\u0301cule sont en de\u0301veloppement depuis des anne\u0301es, et un d\u2019eux sera le premier vaccin contre un opioi\u0308de teste\u0301 chez l\u2019humain.<\/p>\n<p>Lire aussiVaccin contre le Covid : pourquoi la protection est-elle de si courte dure\u0301e ?<\/p>\n<p>Cet essai clinique de phase I est mene\u0301 par la neurobiologiste de l\u2019Universite\u0301 de Columbia et de l\u2019Institut psychiatrique de l\u2019e\u0301tat de New York Sandra D. Comer et le pharmacologue Marco Pravetoni de l\u2019Universite\u0301 de Washington, directeur du Centre pour le de\u0301veloppement de me\u0301dicaments contre les addictions a\u0300 Seattle. Leur but est de tester la su\u0302rete\u0301 du vaccin et son efficacite\u0301 pour ge\u0301ne\u0301rer des antibiotiques contre l\u2019oxycodone et pour re\u0301duire la de\u0301pendance pour cette drogue.<\/p>\n<p>Le recrutement pour cet essai a commence\u0301 le 8 octobre 2023 et l\u2019e\u0301tude devrait finir le 30 de\u0301cembre de la me\u0302me anne\u0301e. Le vaccin sera teste\u0301 chez 45 personnes a\u0302ge\u0301es entre 18 et 59 ans avec une de\u0301pendance physique a\u0300 l\u2019oxycodone. Selon les chercheurs, leur objectif a\u0300 long terme est de de\u0301velopper un vaccin combine\u0301 qui ciblera l\u2019oxycodone et l\u2019he\u0301roi\u0308ne, mais pour le moment ils testeront uniquement le vaccin contre l\u2019oxycodone.<\/p>\n<p><b>Un essai clinique pour un vaccin contre le fentanyl devrait commencer en 2024<\/b><\/p>\n<p>L\u2019Universite\u0301 du Montana annonce\u0301 le 29 aou\u0302t 2023 que des chercheurs de leur universite\u0301 vont collaborer avec l\u2019Universite\u0301 de Columbia et celle de Washington pour deux autres essais cliniques, cette fois sur des vaccins contre l\u2019he\u0301roi\u0308ne et le fentanyl.<\/p>\n<p>Ces essais devraient commencer leur recrutement en 2024 et si les re\u0301sultats sont positifs, les chercheurs espe\u0300rent que les vaccins seront pre\u0302ts pour e\u0302tre commercialise\u0301s en 2028. Ces vaccins devraient e\u0302tre efficaces uniquement pendant une pe\u0301riode de maximum deux ans, suffisamment pour permettre a\u0300 une personne avec une addiction d\u2019arre\u0302ter son utilisation, mais lui permettant de pouvoir, plus tard, utiliser ces drogues afin de traiter des douleurs dans des cas d\u2019urgence me\u0301dicale.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principale agence de sante\u0301 de ce pays, les Centres pour le contro\u0302le et la pre\u0301vention des maladies (CDC), plus de 80.000 personnes y ont pe\u0301ri en 2021 a\u0300 cause de ces de\u0301rive\u0301s [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":72317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[111,725,29],"class_list":["post-72318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain - Burkina Faso<\/title>\n<meta name=\"description\" content=\"La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principa ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain\" \/>\n<meta property=\"og:description\" content=\"La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principa ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T14:08:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T14:13:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain\",\"datePublished\":\"2023-10-10T14:08:57+00:00\",\"dateModified\":\"2023-10-10T14:13:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\"},\"wordCount\":855,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\",\"name\":\"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg\",\"datePublished\":\"2023-10-10T14:08:57+00:00\",\"dateModified\":\"2023-10-10T14:13:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principa ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg\",\"width\":1200,\"height\":899,\"caption\":\"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain - Burkina Faso","description":"La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principa ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain","og_locale":"fr_FR","og_type":"article","og_title":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain","og_description":"La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principa ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain","og_site_name":"Burkina Faso","article_published_time":"2023-10-10T14:08:57+00:00","article_modified_time":"2023-10-10T14:13:53+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain","datePublished":"2023-10-10T14:08:57+00:00","dateModified":"2023-10-10T14:13:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain"},"wordCount":855,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain","name":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg","datePublished":"2023-10-10T14:08:57+00:00","dateModified":"2023-10-10T14:13:53+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"La crise des opioi\u0308des bat son plein aux E\u0301tats-Unis, booste\u0301e en partie par la pande\u0301mie de Covid-19. Selon la principa ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934591.433141.jpg","width":1200,"height":899,"caption":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/addiction-aux-opioides-plusieurs-vaccins-a-letude-chez-lhumain#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Addiction aux opio\u00efdes\u00a0: plusieurs vaccins \u00e0 l\u2019\u00e9tude chez l\u2019humain"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=72318"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/72317"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=72318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=72318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=72318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}