{"id":72321,"date":"2023-10-10T14:09:21","date_gmt":"2023-10-10T14:09:21","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/depression-le-jogging-aussi-efficace-que-les-medicaments"},"modified":"2023-10-10T14:17:02","modified_gmt":"2023-10-10T14:17:02","slug":"depression-le-jogging-aussi-efficace-que-les-medicaments","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments","title":{"rendered":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisant pour traiter la de\u0301pression ? C\u2019est la question que s\u2019est pose\u0301e la professeure Brenda Penninx de l\u2019Universite\u0301 Vrije a\u0300 Amsterdam (Pays-Bas). Avec son e\u0301quipe, elle a compare\u0301 les effets des antide\u0301presseurs a\u0300 ceux du jogging sur un groupe de patients souffrant de de\u0301pression et d\u2019anxie\u0301te\u0301. Les re\u0301sultats ont e\u0301te\u0301 publie\u0301s dans la revue Journal of Affective Disorders.<\/p>\n<p><b>Le me\u0302me taux de re\u0301ussite sur la sante\u0301 mentale des patients<\/b><\/p>\n<p>Apre\u0300s quatre mois de traitements, les deux approches ont montre\u0301 le me\u0302me taux de re\u0301ussite sur la sante\u0301 mentale des patients. Environ 44% d\u2019entre eux &#8211; dans chacun des groupes &#8211; ont surmonte\u0301 leur diagnostic de de\u0301pression et\/ou d\u2019anxie\u0301te\u0301. Toutefois, la sante\u0301 physique s\u2019est aussi ame\u0301liore\u0301e chez le groupe de coureurs tandis qu\u2019elle s\u2019est le\u0301ge\u0300rement de\u0301te\u0301riore\u0301e pour les patients traite\u0301s aux antide\u0301presseurs.<\/p>\n<p>En plus de la souffrance psychologique, la de\u0301pression entrai\u0302ne des conse\u0301quences ne\u0301gatives sur la sante\u0301 physique des patients. Et bien que les antide\u0301presseurs soient efficaces, ils peuvent avoir des effets secondaires inde\u0301sirables qui contribuent au de\u0301clin de l\u2019e\u0301tat de sante\u0301 du patient, tels que la prise de poids, l\u2019augmentation de la pression sanguine et des troubles de la libido.<\/p>\n<p>\u00ab\u00a0Les conse\u0301quences des traitements psychiatriques sont encore peu e\u0301tudie\u0301es, explique la professeure Brenda Penninx de l\u2019Universite\u0301 Vrije a\u0300 Amsterdam (Pays-Bas) lors du Congre\u0300s du Colle\u0300ge Europe\u0301en de neuropharmacologie. C\u2019est pourquoi nous voulions comparer les effets de l\u2019activite\u0301 physique et des antide\u0301presseurs sur la sante\u0301 ge\u0301ne\u0301rale des individus, pas uniquement sur la sante\u0301 mentale\u00a0\u00bb, ajoute la professeure.<\/p>\n<p><b>Se de\u0301passer et sortir de l&rsquo;isolement<\/b><\/p>\n<p>L\u2019e\u0301quipe de recherche a e\u0301tudie\u0301 141 participants souffrant de de\u0301pression et\/ou d\u2019anxie\u0301te\u0301 pendant 16 semaines. \u00ab\u00a0Nous leur avons donne\u0301 le choix entre l\u2019exercice physique et les antide\u0301presseurs\u00a0\u00bb, explique la professeure Brenda Penninx. \u00ab\u00a0E\u0301tonnamment, ils ont e\u0301te\u0301 plus nombreux a\u0300 choisir le sport.\u00a0\u00bb En effet, seuls 45 d\u2019entre eux ont choisi les antide\u0301presseurs, alors que les 96 autres ont opte\u0301 pour le traitement base\u0301 sur le jogging.<\/p>\n<p>Pour le traitement sportif, les patients devaient participer a\u0300 des entrai\u0302nements supervise\u0301s deux a\u0300 trois fois par semaine. Les se\u0301ances de jogging avaient lieu en groupe, a\u0300 l\u2019exte\u0301rieur et avec des objectifs personnalise\u0301s pour chacun. \u00ab\u00a0Ce n\u2019est pas suffisant de dire aux patients d\u2019aller courir, indique Mme Penninx. Pour modifier leurs habitudes d\u2019activite\u0301 physique, il faut leur donner des encouragements et une supervision ade\u0301quate.\u00a0\u00bb<\/p>\n<p>L\u2019e\u0301tude souligne une fois de plus que la sante\u0301 physique peut influencer la sante\u0301 mentale. \u00ab\u00a0Cette approche re\u0301pond directement au mode de vie se\u0301dentaire souvent associe\u0301 a\u0300 la de\u0301pression et l\u2019anxie\u0301te\u0301 en encourageant les patients a\u0300 sortir dehors, a\u0300 se donner des objectifs personnels, a\u0300 participer a\u0300 des activite\u0301s de groupe et a\u0300 ame\u0301liorer leur forme physique\u00a0\u00bb.<\/p>\n<p><b>Plus d\u2019abandon du traitement avec la course <\/b><\/p>\n<p>Cependant, s\u2019entrai\u0302ner deux ou trois fois par semaine reste une habitude beaucoup plus difficile a\u0300 garder que simplement prendre un me\u0301dicament. Et surtout pour quelqu\u2019un qui souffre de de\u0301pression. Malgre\u0301 le soutien du groupe et l\u2019encadrement des se\u0301ances de jogging, uniquement 52% des patients ayant choisi le sport ont maintenu le programme dans son entie\u0300rete\u0301. En d\u2019autres mots, pre\u0300s de la moitie\u0301 d\u2019entre eux ont abandonne\u0301. Puis d\u2019entre\u0301e de jeu, 15% du groupe n\u2019a participe\u0301 a\u0300 aucune se\u0301ance de sport. Ces re\u0301sultats montrent a\u0300 quel point il peut e\u0302tre difficile de maintenir un tel traitement, et me\u0302me de l\u2019entamer, aussi efficace soit-il.<\/p>\n<p>A\u0300 l\u2019inverse, 82% des patients me\u0301dicamente\u0301s ont comple\u0301te\u0301 leurs 16 semaines de traitement : une proportion nettement supe\u0301rieure. \u00ab\u00a0Notre e\u0301tude montre que beaucoup de gens aiment l\u2019ide\u0301e de faire sport pour gue\u0301rir, raconte Brenda Penninx. Mais, on note que c\u2019est plus difficile a\u0300 appliquer, me\u0302me si les be\u0301ne\u0301fices sont significatifs.\u00a0\u00bb Tout de me\u0302me, l\u2019activite\u0301 physique s\u2019est re\u0301ve\u0301le\u0301e remarquablement efficace pour ceux qui ont re\u0301ussi a\u0300 comple\u0301ter leur programme.<\/p>\n<p><b>\u00ab\u00a0On devrait conside\u0301rer la the\u0301rapie sportive plus se\u0301rieusement\u00a0\u00bb<\/b><\/p>\n<p>Les auteurs de l\u2019e\u0301tude pre\u0301cisent que leurs re\u0301sultats n\u2019invalident en aucun cas la pertinence des antide\u0301presseurs. \u00ab\u00a0Ces me\u0301dicaments fonctionnent pour la plupart des gens et nous savons qu\u2019une de\u0301pression non traite\u0301e risque d&#8217;empirer et d\u2019entrai\u0302ner de graves conse\u0301quences\u00a0\u00bb, explique la chercheuse hollandaise. Ce trouble de sante\u0301 mentale n\u2019est pas a\u0300 prendre a\u0300 la le\u0301ge\u0300re : on estime que pre\u0300s d\u2019un Franc\u0327ais sur cinq va en souffrir au cours de sa vie, et il repre\u0301sente la principale cause de suicide.<\/p>\n<p>L\u2019e\u0301tude permet d\u2019e\u0301largir l\u2019arsenal de traitements que les patients et les cliniciens peuvent choisir pour vaincre la de\u0301pression. Un atout fort utile pour ceux qui ne peuvent ou ne veulent pas prendre d\u2019antide\u0301presseurs a\u0300 cause des effets secondaires. \u00ab\u00a0Nos re\u0301sultats sugge\u0300rent qu\u2019on devrait prendre la the\u0301rapie sportive beaucoup plus se\u0301rieusement. On voit qu\u2019elle peut e\u0302tre une option efficace \u2013 voir meilleure \u2013 pour certains patients\u00a0\u00bb, raconte la chercheuse. Certes, il ne s\u2019agit pas d\u2019un traitement miracle qui fonctionnera toujours, mais il pourrait certainement e\u0302tre be\u0301ne\u0301fique pour des sous-groupes de patients.<\/p>\n<p>Pour la suite, les chercheurs souhaitent justement examiner quels sous-groupes de patients, selon certaines caracte\u0301ristiques biologiques, pourraient mieux re\u0301pondre a\u0300 un traitement ou a\u0300 un autre. D\u2019ici la\u0300, la professeure Brenda Penninx pense fermement qu\u2019 \u00ab\u00a0il faut rendre la the\u0301rapie par la course plus accessible. Pour les personnes souffrant de de\u0301pression et d&rsquo;anxie\u0301te\u0301, nous devons implanter davantage de soins de sante\u0301 mentale qui interviennent sur le mode de vie.\u00a0\u00bb<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisant pour traiter la de\u0301pression ? C\u2019est la question que s\u2019est pose\u0301e la professeure Brenda Penninx de l\u2019Universite\u0301 Vrije a\u0300 Amsterdam (Pays-Bas). Avec son e\u0301quipe, elle a compare\u0301 les effets des antide\u0301presseurs [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":72320,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[111,725,29],"class_list":["post-72321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ? - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisan ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?\" \/>\n<meta property=\"og:description\" content=\"Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisan ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T14:09:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T14:17:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?\",\"datePublished\":\"2023-10-10T14:09:21+00:00\",\"dateModified\":\"2023-10-10T14:17:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\"},\"wordCount\":1080,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\",\"name\":\"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ? - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg\",\"datePublished\":\"2023-10-10T14:09:21+00:00\",\"dateModified\":\"2023-10-10T14:17:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisan ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg\",\"width\":1200,\"height\":628,\"caption\":\"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ? - Burkina Faso","description":"Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisan ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?","og_description":"Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisan ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments","og_site_name":"Burkina Faso","article_published_time":"2023-10-10T14:09:21+00:00","article_modified_time":"2023-10-10T14:17:02+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?","datePublished":"2023-10-10T14:09:21+00:00","dateModified":"2023-10-10T14:17:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments"},"wordCount":1080,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments","name":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ? - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg","datePublished":"2023-10-10T14:09:21+00:00","dateModified":"2023-10-10T14:17:02+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Ce n\u2019est plus un secret pour personne, le sport est be\u0301ne\u0301fique pour la sante\u0301 physique et mentale. Mais est-ce suffisan ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1696934779.4527.jpg","width":1200,"height":628,"caption":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/depression-le-jogging-aussi-efficace-que-les-medicaments#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"D\u00e9pression\u00a0: le jogging aussi efficace que les m\u00e9dicaments ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=72321"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/72320"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=72321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=72321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=72321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}