{"id":72445,"date":"2023-10-13T12:12:27","date_gmt":"2023-10-13T12:12:27","guid":{"rendered":"https:\/\/www.africa-press.net\/burkina-faso\/politique\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes"},"modified":"2023-10-13T13:32:08","modified_gmt":"2023-10-13T13:32:08","slug":"snus-les-dangers-dune-drogue-qui-seduit-les-jeunes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes","title":{"rendered":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burkina Faso. <\/strong><\/span>Qu&rsquo;est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ? Pour le savoir, Sciences et Avenir s&rsquo;est entretenu avec Ste\u0301phanie Caille\u0301-Garnier, directrice de recherche CNRS et responsable de l\u2019e\u0301quipe \u00ab\u00a0Emotion, Motivation &amp; Cognition\u00a0\u00bb, au sein de l\u2019Incia (Institut des sciences cognitives et inte\u0301gratives d\u2019Aquitaine) a\u0300 l\u2019Universite\u0301 de Bordeaux. Ses travaux cherchent a\u0300 identifier les me\u0301canismes comportementaux et neurobiologiques implique\u0301s dans la mise en place des comportements addictifs et plus particulie\u0300rement aux facteurs de de\u0301pendance a\u0300 la nicotine, mole\u0301cule addictive du tabac. Dans cet entretien, elle nous informe sur l\u2019addiction au snus, des dosettes de tabac a\u0300 ma\u0302cher ou a\u0300 sucer.<\/p>\n<p>L\u2019Union europe\u0301enne a interdit sa commercialisation depuis 1992, sauf en Sue\u0300de pour des raisons culturelles. Mais il existe une alternative sans tabac, appele\u0301e \u00ab\u00a0snus blanc\u00a0\u00bb. Il s\u2019agit d\u2019un sachet contenant un me\u0301lange ve\u0301ge\u0301tal auquel la nicotine est ajoute\u0301e soit sous forme liquide soit sous forme de poudre. Le snus blanc est bien plus accessible et pourtant tout aussi addictif. En l\u2019absence de tabac, sa commercialisation n\u2019est pas re\u0301glemente\u0301e en France, contrairement a\u0300 la Belgique ou aux Pays-Bas. Cependant, sa concentration en nicotine est tre\u0300s e\u0301leve\u0301e, ce qui le rend tout aussi ne\u0301faste que le snus sue\u0301dois.<\/p>\n<p><b>\u00ab\u00a0Le me\u0301canisme d&rsquo;action, c&rsquo;est ce qui fait la diffe\u0301rence entre le snus et la cigarette\u00a0\u00bb<\/b><br \/>\n<b> Ste\u0301phanie Caille\u0301-Garnier :<\/b> Il s\u2019agit d\u2019un petit sachet initialement rempli de poudre de tabac, et particulie\u0300rement concentre\u0301 en nicotine : elle varie de 3 a\u0300 20 mg par poche contre 1 ou 2 mg pour une cigarette. Il est place\u0301 sous la le\u0300vre au niveau des gencives, ou chique\u0301. Au contact de la salive, il s\u2019humidifie et de\u0301livre alors un jus, parfois aromatise\u0301 pour rendre cette drogue plus attractive. Les compose\u0301s du snus, dont la nicotine, sont ainsi absorbe\u0301s par les muqueuses.<\/p>\n<p><b> Ste\u0301phanie Caille\u0301-Garnier : <\/b>C\u2019est ce qui fait la diffe\u0301rence entre le snus et la cigarette. L\u2019un est absorbe\u0301 dans l\u2019estomac, l\u2019autre dans les poumons : la cine\u0301tique des effets ne sont donc pas les me\u0302mes. La fume\u0301e de la cigarette entre tre\u0300s rapidement en contact avec les capillaires sanguins, qui repre\u0301sentent une surface conside\u0301rable dans les poumons. Les mole\u0301cules sont donc tre\u0300s vite achemine\u0301es vers le cerveau. En revanche, l\u2019absorption du snus se fait au niveau des muqueuses de la bouche puis une seconde absorption a lieu au niveau des muqueuses du syste\u0300me digestif. C\u2019est pourquoi la diffusion des mole\u0301cules du snus est plus lente et durable que celle des mole\u0301cules de cigarettes.<\/p>\n<p><b>\u00ab\u00a0Des effets irre\u0301versibles sur l\u2019hygie\u0300ne buccale\u00a0\u00bb<\/b><\/p>\n<p>La nicotine se fixe sur les re\u0301cepteurs des neurones a\u0300 dopamines dits \u00ab\u00a0me\u0301socorticolimbiques\u00a0\u00bb, e\u0301le\u0301ments essentiels du circuit neuronal de la re\u0301compense. Ce circuit relie plusieurs structures entre elles et permet notre survie : il favorise un comportement d\u2019approche pour la nourriture, et d\u2019e\u0301vitement pour les aliments toxiques par exemple. Ce syste\u0300me est la premie\u0300re cible des drogues. Elles le de\u0301tournent pour provoquer un comportement de recherche de la drogue, et ce, malgre\u0301 les conse\u0301quences ne\u0301gatives. La nicotine agit aussi sur les fonctions ce\u0301re\u0301brales qui re\u0301gulent l\u2019e\u0301veil, la concentration, la me\u0301moire ou encore, la re\u0301gulation de l\u2019humeur&#8230; elle cre\u0301e un effet de bien-e\u0302tre. C\u2019est l\u2019ensemble de ces proprie\u0301te\u0301s qui rend la nicotine addictive.<\/p>\n<p>Comme toutes les drogues, une majorite\u0301 des personnes qui expe\u0301rimentent le snus n\u2019y sera pas sensible, mais une petite proportion plus vulne\u0301rable peut de\u0301velopper une de\u0301pendance. Se sevrer devient alors difficile, et les rechutes sont fre\u0301quentes. Contrairement a\u0300 la cigarette, il n&rsquo;y a pas de risque pulmonaire, mais un risque e\u0301leve\u0301 de cancer au niveau oral et digestif. Et c\u2019est sans compter les effets irre\u0301versibles sur l\u2019hygie\u0300ne buccale, le\u0301sion des muqueuses de la bouche, re\u0301traction des gencives&#8230; D\u2019ou\u0300 la ne\u0301cessite\u0301 d\u2019informer sur ses dangers. En cas de de\u0301pendance, il est recommande\u0301 d\u2019en parler a\u0300 son me\u0301decin pour mettre en place un accompagnement et un traitement adapte\u0301.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/burkina-faso\">Burkina Faso<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burkina Faso. Qu&rsquo;est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ? Pour le savoir, Sciences et Avenir s&rsquo;est entretenu avec Ste\u0301phanie Caille\u0301-Garnier, directrice de recherche CNRS et responsable de l\u2019e\u0301quipe \u00ab\u00a0Emotion, Motivation &amp; Cognition\u00a0\u00bb, au sein de l\u2019Incia (Institut [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":72444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[111,725,29],"class_list":["post-72445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-burkina-faso","tag-burkina-faso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes - Burkina Faso<\/title>\n<meta name=\"description\" content=\"Qu&#039;est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes\" \/>\n<meta property=\"og:description\" content=\"Qu&#039;est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\" \/>\n<meta property=\"og:site_name\" content=\"Burkina Faso\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T12:12:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-13T13:32:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes\",\"datePublished\":\"2023-10-13T12:12:27+00:00\",\"dateModified\":\"2023-10-13T13:32:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\"},\"wordCount\":780,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Burkina Faso\",\"Burkina Faso\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\",\"name\":\"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes - Burkina Faso\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg\",\"datePublished\":\"2023-10-13T12:12:27+00:00\",\"dateModified\":\"2023-10-13T13:32:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Qu'est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg\",\"width\":1200,\"height\":899,\"caption\":\"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burkina-faso\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burkina-faso\/\",\"name\":\"Burkina Faso\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes - Burkina Faso","description":"Qu'est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes","og_locale":"fr_FR","og_type":"article","og_title":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes","og_description":"Qu'est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ...","og_url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes","og_site_name":"Burkina Faso","article_published_time":"2023-10-13T12:12:27+00:00","article_modified_time":"2023-10-13T13:32:08+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes","datePublished":"2023-10-13T12:12:27+00:00","dateModified":"2023-10-13T13:32:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes"},"wordCount":780,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg","keywords":["Africa Press","Africa Press-Burkina Faso","Burkina Faso"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes","url":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes","name":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes - Burkina Faso","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg","datePublished":"2023-10-13T12:12:27+00:00","dateModified":"2023-10-13T13:32:08+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Qu'est-ce que le snus ? Comment agit-il sur le cerveau ? Quels sont les risques lie\u0301s a\u0300 la consommation de cette drogue ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#primaryimage","url":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg","contentUrl":"https:\/\/static.africa-press.net\/burkina\/sites\/42\/2023\/10\/sm_1697191244.877721.jpg","width":1200,"height":899,"caption":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burkina-faso\/toutes-les-actualites\/snus-les-dangers-dune-drogue-qui-seduit-les-jeunes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burkina-faso\/"},{"@type":"ListItem","position":2,"name":"Snus\u00a0: les dangers d\u2019une drogue qui s\u00e9duit les jeunes"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#website","url":"https:\/\/www.africa-press.net\/burkina-faso\/","name":"Burkina Faso","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burkina-faso\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burkina-faso\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/comments?post=72445"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/posts\/72445\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media\/72444"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/media?parent=72445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/categories?post=72445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burkina-faso\/wp-json\/wp\/v2\/tags?post=72445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}