{"id":16283,"date":"2024-09-12T11:00:00","date_gmt":"2024-09-12T11:00:00","guid":{"rendered":"https:\/\/www.africa-press.net\/burundi\/?p=16283"},"modified":"2024-09-12T10:26:21","modified_gmt":"2024-09-12T10:26:21","slug":"mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies","title":{"rendered":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burundi. <\/strong><\/span>L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e pour intensifier d\u2019urgence les efforts de re\u0301ponse et de pre\u0301vention en faveur des re\u0301fugie\u0301s dans les pays touche\u0301s par l\u2019e\u0301pide\u0301mie de Mpox.<\/p>\n<p>L\u2019appel, lance\u0301 ce mercredi, vise a\u0300 soutenir pre\u0300s de 10 millions de personnes de\u0301place\u0301es de force et de communaute\u0301s ho\u0302tes dans 35 pays d\u2019Afrique, pre\u0301cise l\u2019ONU dans un communique\u0301.<\/p>\n<p>Bien que le mpox soit ende\u0301mique dans certaines re\u0301gions d\u2019Afrique depuis des de\u0301cennies, le nombre croissant de cas de la nouvelle souche de la maladie, le clade 1b, en particulier en Re\u0301publique de\u0301mocratique du Congo (RDC), a conduit l\u2019Organisation mondiale de la Sante\u0301 (OMS) a\u0300 de\u0301clarer, le 14 aou\u0302t dernier, une urgence de sante\u0301 publique de porte\u0301e internationale, rappelle l&rsquo;ONU soulignant qu&rsquo;a\u0300 ce jour, plus de 20.000 cas suspects ont e\u0301te\u0301 signale\u0301s en 2024 en Afrique.<\/p>\n<p>Au moins 88 cas de mpox ont e\u0301te\u0301 signale\u0301s parmi les re\u0301fugie\u0301s en Afrique, dont 68 en RDC, le pays qui a enregistre\u0301 le plus grand nombre de cas dans le monde, indique la me\u0302me source ajoutant que des cas ont e\u0301galement e\u0301te\u0301 signale\u0301s parmi les re\u0301fugie\u0301s de la Re\u0301publique du Congo et du Rwanda.<\/p>\n<p>\u00ab Cette nouvelle e\u0301pide\u0301mie de variole met en danger les populations les plus vulne\u0301rables, notamment de nombreux re\u0301fugie\u0301s et communaute\u0301s de\u0301place\u0301es de force qui vivent dans des conditions difficiles \u00bb, a de\u0301clare\u0301 dans un communique\u0301, Allen Maina, Responsable de la sante\u0301 publique au HCR.<\/p>\n<p>L\u2019Afrique abrite plus d\u2019un tiers des personnes de\u0301place\u0301es de force dans le monde. Nombre d\u2019entre elles re\u0301sident dans des pays confronte\u0301s a\u0300 la transmission du mpox et se trouvent dans des situations extre\u0302mement vulne\u0301rables, aggrave\u0301es par des conflits prolonge\u0301s, un manque chronique de financement humanitaire et des catastrophes multiples, souligne l&rsquo;ONU.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la Burundi, suivez Africa-Press<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burundi. L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e pour intensifier d\u2019urgence les efforts de re\u0301ponse et de pre\u0301vention en faveur des re\u0301fugie\u0301s dans les pays touche\u0301s par l\u2019e\u0301pide\u0301mie de Mpox. L\u2019appel, lance\u0301 ce mercredi, vise a\u0300 soutenir pre\u0300s de 10 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":16282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2,10],"tags":[715,45,692],"class_list":["post-16283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-politique","category-toutes-les-actualites","tag-agence-des-nations-unies-pour-les-refugies-hcr","tag-burundi","tag-mpox"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s - Burundi<\/title>\n<meta name=\"description\" content=\"L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e po ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s\" \/>\n<meta property=\"og:description\" content=\"L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e po ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\" \/>\n<meta property=\"og:site_name\" content=\"Burundi\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-12T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s\",\"datePublished\":\"2024-09-12T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\"},\"wordCount\":394,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg\",\"keywords\":[\"Agence des Nations unies pour les r\u00e9fugi\u00e9s (HCR)\",\"Burundi\",\"Mpox\"],\"articleSection\":[\"\u00c9conomie\",\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\",\"url\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\",\"name\":\"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s - Burundi\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg\",\"datePublished\":\"2024-09-12T11:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e po ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg\",\"width\":864,\"height\":486,\"caption\":\"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burundi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burundi\/\",\"name\":\"Burundi\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burundi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s - Burundi","description":"L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e po ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies","og_locale":"fr_FR","og_type":"article","og_title":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s","og_description":"L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e po ...","og_url":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies","og_site_name":"Burundi","article_published_time":"2024-09-12T11:00:00+00:00","og_image":[{"width":864,"height":486,"url":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s","datePublished":"2024-09-12T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies"},"wordCount":394,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg","keywords":["Agence des Nations unies pour les r\u00e9fugi\u00e9s (HCR)","Burundi","Mpox"],"articleSection":["\u00c9conomie","Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies","url":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies","name":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s - Burundi","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burundi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg","datePublished":"2024-09-12T11:00:00+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"L\u2019Agence des Nations Unies pour les re\u0301fugie\u0301s (HCR) a besoin de 21,4 millions de dollars jusqu\u2019a\u0300 la fin de l\u2019anne\u0301e po ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#primaryimage","url":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg","contentUrl":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2024\/09\/sm_1726120395.816653.jpg","width":864,"height":486,"caption":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/mpox-en-afrique-le-hcr-en-quete-de-21-millions-de-dollars-pour-la-prevention-aupres-des-refugies#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burundi\/"},{"@type":"ListItem","position":2,"name":"Mpox en Afrique : le HCR en qu\u00eate de 21 millions de dollars pour la pr\u00e9vention aupr\u00e8s des r\u00e9fugi\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burundi\/#website","url":"https:\/\/www.africa-press.net\/burundi\/","name":"Burundi","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burundi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/posts\/16283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/comments?post=16283"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/posts\/16283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/media\/16282"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/media?parent=16283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/categories?post=16283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/tags?post=16283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}