{"id":20583,"date":"2025-02-17T13:00:00","date_gmt":"2025-02-17T13:00:00","guid":{"rendered":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier"},"modified":"2025-02-17T13:00:00","modified_gmt":"2025-02-17T13:00:00","slug":"est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier","title":{"rendered":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Burundi. <\/strong><\/span>Le Burundi a accueilli pre\u0300s de dix mille personnes qui fuient en provenance de la Re\u0301publique de\u0301mocratique du Congo (RDC) voisine du 14 au 16 fe\u0301vrier 2025, a de\u0301clare\u0301 lundi dans un communique\u0301, le ministre burundais de l&rsquo;Inte\u0301rieur, Martin Niteretse.<\/p>\n<p>Selon le ministre, de\u0300s leur arrive\u0301e au Burundi, ces re\u0301fugie\u0301s sont rassemble\u0301s \u00ab\u00a0dans des centres d&rsquo;accueil de Gihanga en province de Bubanza et a\u0300 Cibitoke pour passer a\u0300 l&rsquo;identification en vue de se\u0301parer les militaires e\u0301ventuels des civils, les malades et les biens portants&#8230; afin de continuer a\u0300 les assister\u00a0\u00bb.<\/p>\n<p>Le ministre a aussi pre\u0301cise\u0301 que le HCR collabore avec les autorite\u0301s burundaises \u00ab\u00a0afin que les proble\u0300mes qui se manifestent dans l&rsquo;accueil de ces voisins puissent e\u0302tre re\u0301solus \u00ab\u00a0.<\/p>\n<p>Cette vague de re\u0301fugie\u0301s intervient au lendemain de la prise de Bukavu, capitale du Sud-Kivu, par le M23.<\/p>\n<p>Pour rappel, les rebelles du M23 avaient conquis la ville de Goma, chef-lieu de la province du Nord-Kivu, fin janvier dernier lors d\u2019une offensive rapide contre l\u2019arme\u0301e congolaise. Suite a\u0300 cette victoire, les rebelles ont poursuivi leur avance\u0301e dans la province voisine du Sud-Kivu ou\u0300 ils ont conquis plusieurs autres localite\u0301s.<\/p>\n<p>Le Mouvement du 23 Mars (M23) a e\u0301te\u0301 cre\u0301e\u0301 en 2012 par des militaires dissidents de l\u2019arme\u0301e congolaise. Apre\u0300s une bre\u0300ve monte\u0301e en puissance, il a e\u0301te\u0301 de\u0301fait en 2013 par les Forces arme\u0301es de la Re\u0301publique de\u0301mocratique du Congo (FARDC), appuye\u0301es par les Casques bleus de la MONUSCO. Cependant, le M23 a repris les armes en 2022, s\u2019emparant de plusieurs localite\u0301s dans la province du Nord-Kivu, situe\u0301e a\u0300 la frontie\u0300re du Rwanda et de l\u2019Ouganda.<\/p>\n<p>Kinshasa accuse le Rwanda de soutenir activement le M23 pour acce\u0301der aux richesses minie\u0300res de la re\u0301gion. Ces accusations sont e\u0301taye\u0301es par des rapports d\u2019agences onusiennes, qui pointent un appui militaire rwandais au mouvement rebelle. Pour la RDC, le M23 est un groupe \u00ab\u00a0terroriste\u00a0\u00bb et toute forme de ne\u0301gociation est cate\u0301goriquement rejete\u0301e.<\/p>\n<p>Le Rwanda re\u0301fute ces alle\u0301gations, affirmant que le M23 est un mouvement congolais dirige\u0301 par des Congolais, bien que ses membres parlent le kinyarwanda, la langue rwandaise. Kigali rejette e\u0301galement les conclusions des rapports onusiens et rappelle avoir de\u0301sarme\u0301 les rebelles du M23 qui s\u2019e\u0301taient re\u0301fugie\u0301s sur son sol en 2012-2013, avant de remettre leur arsenal aux autorite\u0301s congolaises.<\/p>\n<p>Pour Kigali, \u00ab\u00a0la question du M23 est une menace se\u0301curitaire pour le Rwanda\u00a0\u00bb. \u00ab\u00a0La RDC, a\u0300 cause de l\u2019assimilation permanente du M23 au Rwanda, a ba\u0302ti une large coalition militaire avec des soldats burundais, avec des mercenaires europe\u0301ens, des miliciens Wazalendo et des ge\u0301nocidaires FDLR (Forces de\u0301mocratiques de libe\u0301ration du Rwanda, NDLR)\u00a0\u00bb, avait soutenu le ministre rwandais des Affaires e\u0301trange\u0300res, Olivier Jean Patrick Nduhungirehe, dans une interview accorde\u0301e a\u0300 Africa 24.<\/p>\n<p>Ces alliances, selon Nduhungirehe, s\u2019inscriraient dans une strate\u0301gie visant a\u0300 renverser le gouvernement rwandais.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <span style=\"color: #ff6600\">Burundi<\/span>, suivez <span style=\"color: #ff6600\">Africa-Press<span style=\"color: #ff6600\"><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Burundi. Le Burundi a accueilli pre\u0300s de dix mille personnes qui fuient en provenance de la Re\u0301publique de\u0301mocratique du Congo (RDC) voisine du 14 au 16 fe\u0301vrier 2025, a de\u0301clare\u0301 lundi dans un communique\u0301, le ministre burundais de l&rsquo;Inte\u0301rieur, Martin Niteretse. Selon le ministre, de\u0300s leur arrive\u0301e au Burundi, ces re\u0301fugie\u0301s sont rassemble\u0301s [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":20582,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[45,870,869,871,40],"class_list":["post-20583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-burundi","tag-centres-daccueil","tag-est-de-la-rdc","tag-martin-niteretse","tag-refugies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier - Burundi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier\" \/>\n<meta property=\"og:description\" content=\"Africa-Press &#8211; Burundi. Le Burundi a accueilli pre\u0300s de dix mille personnes qui fuient en provenance de la Re\u0301publique de\u0301mocratique du Congo (RDC) voisine du 14 au 16 fe\u0301vrier 2025, a de\u0301clare\u0301 lundi dans un communique\u0301, le ministre burundais de l&rsquo;Inte\u0301rieur, Martin Niteretse. Selon le ministre, de\u0300s leur arrive\u0301e au Burundi, ces re\u0301fugie\u0301s sont rassemble\u0301s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\" \/>\n<meta property=\"og:site_name\" content=\"Burundi\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T13:00:00+00:00\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier\",\"datePublished\":\"2025-02-17T13:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\"},\"wordCount\":562,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg\",\"keywords\":[\"Burundi\",\"Centres d'accueil\",\"Est de la RDC\",\"Martin Niteretse\",\"R\u00e9fugi\u00e9s\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\",\"url\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\",\"name\":\"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier - Burundi\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg\",\"datePublished\":\"2025-02-17T13:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg\",\"width\":864,\"height\":486,\"caption\":\"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/burundi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#website\",\"url\":\"https:\/\/www.africa-press.net\/burundi\/\",\"name\":\"Burundi\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/burundi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier - Burundi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier","og_locale":"fr_FR","og_type":"article","og_title":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier","og_description":"Africa-Press &#8211; Burundi. Le Burundi a accueilli pre\u0300s de dix mille personnes qui fuient en provenance de la Re\u0301publique de\u0301mocratique du Congo (RDC) voisine du 14 au 16 fe\u0301vrier 2025, a de\u0301clare\u0301 lundi dans un communique\u0301, le ministre burundais de l&rsquo;Inte\u0301rieur, Martin Niteretse. Selon le ministre, de\u0300s leur arrive\u0301e au Burundi, ces re\u0301fugie\u0301s sont rassemble\u0301s [&hellip;]","og_url":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier","og_site_name":"Burundi","article_published_time":"2025-02-17T13:00:00+00:00","author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier","datePublished":"2025-02-17T13:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier"},"wordCount":562,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg","keywords":["Burundi","Centres d'accueil","Est de la RDC","Martin Niteretse","R\u00e9fugi\u00e9s"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier","url":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier","name":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier - Burundi","isPartOf":{"@id":"https:\/\/www.africa-press.net\/burundi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg","datePublished":"2025-02-17T13:00:00+00:00","author":{"@id":"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"breadcrumb":{"@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#primaryimage","url":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg","contentUrl":"https:\/\/static.africa-press.net\/burundi\/sites\/47\/2025\/02\/sm_1739868965.16456.jpg","width":864,"height":486,"caption":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/burundi\/politique\/est-de-la-rdc-pres-de-dix-mille-personnes-ont-fui-vers-le-burundi-depuis-le-14-fevrier#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/burundi\/"},{"@type":"ListItem","position":2,"name":"Est de la RDC : pr\u00e8s de Dix Mille Personnes Ont Fui vers le Burundi depuis le 14 F\u00e9vrier"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/burundi\/#website","url":"https:\/\/www.africa-press.net\/burundi\/","name":"Burundi","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/burundi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/burundi\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/posts\/20583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/comments?post=20583"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/posts\/20583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/media\/20582"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/media?parent=20583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/categories?post=20583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/burundi\/wp-json\/wp\/v2\/tags?post=20583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}