{"id":41548,"date":"2023-04-11T18:23:58","date_gmt":"2023-04-11T18:23:58","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde"},"modified":"2023-04-11T18:45:52","modified_gmt":"2023-04-11T18:45:52","slug":"cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde","title":{"rendered":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9."},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span>Le patron de la sante\u0301 s&rsquo;est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la ville de Yaounde\u0301, pour comprendre les circonstances du de\u0301ce\u0300s controverse\u0301 le 02 avril 2023, d&rsquo;Andrea Abe, un be\u0301be\u0301 de sexe fe\u0301minin ne\u0301e le 12 fe\u0301vrier dernier.<\/p>\n<p>La maman de l&rsquo;enfant de\u0301ce\u0301de\u0301 avait, dans une publication faite sur les re\u0301seaux sociaux, accuse\u0301 le personnel soignant de \u00ab La Clinique le Jourdain \u00bb d&rsquo;avoir tue\u0301 le fruit de ses entrailles.<\/p>\n<p>Ce lundi, a\u0300 l&rsquo;issue de sa visite et en attendant les conclusions de l&rsquo;enque\u0302te qu&rsquo;il a ordonne\u0301e, le ministre de la sante\u0301 publique, constate que plusieurs indices corroborent les de\u0301clarations de la plainte.<\/p>\n<p>\u00ab Le re\u0301cit des faits attestant des de\u0301faillances graves dans la prise en charge du be\u0301be\u0301 rec\u0327u le 31 mars et de\u0301ce\u0301de\u0301 le 02 avril va davantage de\u0301clencher l&rsquo;ire du ministre de la Sante\u0301 publique. Entre autres e\u0301le\u0301ments, l&rsquo;indisponibilite\u0301 d&rsquo;un pe\u0301diatre, la manipulation de l&rsquo;enfant par un personnel non qualifie\u0301, l&rsquo;accord verbal (non expresse\u0301ment e\u0301crit) par la famille pour une ponction lombaire sur ledit enfant apre\u0300s un refus pre\u0301alable. Plus grave, la description des sympto\u0302mes et de l&rsquo;e\u0301tat de l&rsquo;enfant a\u0300 un spe\u0301cialiste au te\u0301le\u0301phone ainsi que le releve\u0301 de ses instructions par le me\u0302me canal \u00bb a rapporte\u0301 la cellule de communication du ministe\u0300re de la sante\u0301 publique.<\/p>\n<p>\u00ab Par la suite, le Dr MANAOUDA Malachie va encore aller plus longe. Il va exiger de consulter les documents administratifs qui vont re\u0301ve\u0301ler qu&rsquo;une autorisation d&rsquo;exercice a e\u0301te\u0301 accorde\u0301e a\u0300 cette formation sanitaire pour la cate\u0301gorie \u00ab\u00a0C\u00a0\u00bb, l&rsquo;e\u0301quivalent d&rsquo;un Centre de sante\u0301. Ce qui laisse parai\u0302tre que \u00ab\u00a0Le Jourdain\u00a0\u00bb, de par les services offerts (IRM, Scanner, bloc ope\u0301ratoire, fibroscopie, etc.) est en irre\u0301gularite\u0301, parce qu&rsquo;ayant de\u0301passe\u0301 ses capacite\u0301s re\u0301glementaires. Plus encore, le me\u0301decin rendant compte de cette situation malheureuse est un agent public absent a\u0300 son poste d&rsquo;affectation. Le cas de ce personnel est sans doute l&rsquo;irre\u0301gularite\u0301 de trop qui va pousser le patron de la sante\u0301 a\u0300 instruire l&rsquo;ouverture d&rsquo;une enque\u0302te administrative au sortir de laquelle le concerne\u0301 et la Fosa pourraient e\u0302tre sanctionne\u0301s \u00bb a ajoute\u0301 la cellule de communication du Ministe\u0300re de la sante publique.<\/p>\n<p><b>Ci-dessous la maman raconte les circonstances du de\u0301ce\u0300s tragique de sa fille<\/b><\/p>\n<p>Ma fille s&rsquo;appelait Abe Andrea, elle est ne\u0301e le 12 fe\u0301vrier 2023. Tout commence le 01 avril 2023 il e\u0301tait 4h44( elle se re\u0301veillait tous les matins a\u0300 4h40 pour sa te\u0301te\u0301e ) je constate qu&rsquo;elle a de la fie\u0300vre lorsque je prends sa tempe\u0301rature elle e\u0301tait a\u0300 38,5. Elle avait beaucoup de douleurs au ventre et e\u0301tait constipe\u0301e depuis 48h donc je me suis dit que c&rsquo;est peut e\u0302tre c\u0327a qui l&rsquo;a de\u0301ranger et que je vais observer. Elle s&rsquo;e\u0301tait aussi faite vacciner le mardi d&rsquo;avant donc je pensais aussi a\u0300 c\u0327a. Je lui donne Algofene, la fie\u0300vre descend. J&rsquo;appelle a\u0300 la clinique le Jourdain pour savoir s&rsquo;il y a un pe\u0301diatre de garde, ils me re\u0301pondent oui. Vers 16h on se rend compte que la fie\u0300vre remonte on de\u0301cide donc d&rsquo;aller aux urgences de l&rsquo;ho\u0302pital le Jourdain quand on arrive Ils nous disent qu&rsquo;en fait il nya pas de pe\u0301diatre de garde. Elle e\u0301tait de\u0301ja\u0300 38,<\/p>\n<p>Pendant qu&rsquo;elle e\u0301tait en consultation dans le bureau du me\u0301decin ge\u0301ne\u0301raliste, elle a re\u0301ussi a\u0300 faire les selles. Quand on vient lui passer la perfusion sa fie\u0300vre e\u0301tait de\u0301ja\u0300 tombe\u0301e toute seule il e\u0301tait 18h. On l&rsquo;hospitalise donc a\u0300 18h, on fait des examens et on met l&rsquo;enfant sous envisage. La petite n&rsquo;a plus fait de fie\u0300vre. Le matin a\u0300 7h on vient nous de\u0301poser une facture de 100.000fr a\u0300 payer avant 9h nous payons. il e\u0301tait 9h, apre\u0300s avoir constate\u0301 qu&rsquo;on a paye\u0301, le me\u0301decin vient nous dire qu&rsquo;au vu des re\u0301sultats elle a une infection et qu&rsquo;ils ont pris l&rsquo;avis du pe\u0301diatre qui pre\u0301conise une ponction lombaire en urgence pour e\u0301liminer la me\u0301ningite .<\/p>\n<p>Je refuse, je dis que ma fille a un proble\u0300me au ventre, elle n&rsquo;a pas de me\u0301ningite. Depuis le matin elle allait beaucoup mieux elle avait re\u0301ussi a\u0300 faire les selles 2 fois. Elle e\u0301tait e\u0301nergique comme d&rsquo;habitude, elle riait, elle avait me\u0302me e\u0301clate\u0301 de rire un moment. Elle mangeait bien. Ils m&rsquo;expliquent que c&rsquo;est irresponsable de ne pas faire la ponction lombaire et etc&#8230; ensuite un infirmier dit anesthe\u0301siste se pre\u0301sente a\u0300 12h disant qu&rsquo;il vient faire la ponction lombaire : il s&rsquo;appelle Mvondo. Je le vois entrer et je dis directement que cet homme ne touche pas mon enfant parce que je ne veux pas de ponction lombaire encore moins exe\u0301cute\u0301 par un infirmier.<\/p>\n<p>Il sort et le me\u0301decin remonte en nous expliquant que l&rsquo;infirmier Mvondo fait c\u0327a tous les jours. Il mai\u0302trise. Qu&rsquo;elle ne sait pas faire aussi bien que lui. Et qu&rsquo;il faut absolument faire une ponction lombaire que c&rsquo;est impe\u0301ratif pour l&rsquo;enfant. Je lui demande si c&rsquo;est sans risque, elle me garantit qu&rsquo;il y en a aucun de grave, au pire une douleur lombaire et se montre tre\u0300s insistante. Elle insiste et insiste. Finalement nous ce\u0301dons.<\/p>\n<p>A 12h55 on nous demande de sortir car les parents n&rsquo;assistent pas a\u0300 c\u0327a. Je dis a\u0300 cet homme que voila\u0300 la prunelle de mes yeux ils re\u0301pondent \u00ab anti \u00bb en riant. Je ne sais pas pourquoi je suis sortie. On entend l&rsquo;enfant crieur. Puis plus rien a\u0300 13h05 on de\u0301cide d&rsquo;aller voir. 13h10 Ils nous disent que c\u0327a s&rsquo;est bien passe\u0301 \u00ab elle s&rsquo;est endormie \u00bb.<\/p>\n<p>Quand on regarde l&rsquo;enfant, on voit qu&rsquo;elle ne respire pas. On les appelle et on se met a\u0300 crier. Ils disent que non, elle dort juste profonde\u0301ment et ils rigolent. On voyait pourtant bien que l&rsquo;enfant ne respirait pas. On leur dit qu&rsquo;ils se mettent a\u0300 rigoler. Finalement je me mets a\u0300 crier ils font semblant de re\u0301agir. Mon fiance\u0301 descend en courant chercher le me\u0301decin qui monte avec nonchalance et de\u0301sinvolture Quand ils de\u0301cident de re\u0301animer l&rsquo;enfant 40 minutes s&rsquo;e\u0301taient e\u0301coule\u0301es.<\/p>\n<p>Ils sont entre\u0301s en salle de re\u0301animation en disant qu&rsquo;ils vont la re\u0301animer et pourtant l&rsquo;enfant e\u0301tait mort depuis. Finalement 1h plus tard, ils nous annoncent son de\u0301ce\u0300s et mentent que c&rsquo;est suite a\u0300 une \u00ab fausse route \u00bb . Quand on met la pression a\u0300 la dame me\u0301decin, ils finissent par avouer qu&rsquo;on a mis une anesthe\u0301sie a\u0300 l&rsquo;enfant. Elle e\u0301tait tre\u0300s agite\u0301e pendant la ponction ils ont donc de\u0301cide\u0301 de lui mettre une dose d&rsquo;anesthe\u0301sie pour la calmer : C&rsquo;est a\u0300 ce moment qu&rsquo;ils ont tue\u0301 l&rsquo;enfant. Une bagarre commence entre le me\u0301decin et moi. Entre mon fre\u0300re et un infirmier. Mvondo avait disparu. Depuis le moment ou\u0300 il nous dit que l&rsquo;enfant dormait, on ne l&rsquo;a jamais revu. Ils ont commence\u0301 a\u0300 nous dire que leur promoteur le Dr Mbarga est commissaire divisionnaire qu&rsquo;on ne peut rien leur faire. \u00ab Agitez-vous comme vous voulez le promoteur est commissaire divisionnaire on va voir ce qu&rsquo;on va leur faire \u00bb Ils l&rsquo;ont appele\u0301, il a envoye\u0301 la police. 2 micros, 2 policiers lourdement arme\u0301s.<\/p>\n<p>Nous sommes reste\u0301s la\u0300 on a demande\u0301 a\u0300 voir le responsable qui a dit qu&rsquo;on a qu&rsquo;a\u0300 porter le corps venir le lendemain on a insiste\u0301 et finalement il est venu il nous faire un discours politique. Mon hypothe\u0300se est qu&rsquo;ils ont tue\u0301 l&rsquo;enfant dans la chambre et ont voulu nous faire croire qu&rsquo;il dormait pour partir rapidement et dire apre\u0300s que ce n&rsquo;e\u0301tait pas eux.<\/p>\n<p>Vous jouez avec la vie des gens pour fabricant pour faire entrer de l&rsquo;argent ! Vous vous en foutez des conse\u0301quences parce que votre promoteur est commissaire divisionnaire.\u00a0\u00bb<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Le patron de la sante\u0301 s&rsquo;est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la ville de Yaounde\u0301, pour comprendre les circonstances du de\u0301ce\u0300s controverse\u0301 le 02 avril 2023, d&rsquo;Andrea Abe, un be\u0301be\u0301 de sexe fe\u0301minin ne\u0301e le 12 fe\u0301vrier dernier. La maman de l&rsquo;enfant [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":41547,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-41548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9. - Cameroun<\/title>\n<meta name=\"description\" content=\"Le patron de la sante\u0301 s&#039;est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la v ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9.\" \/>\n<meta property=\"og:description\" content=\"Le patron de la sante\u0301 s&#039;est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la v ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T18:23:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T18:45:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9.\",\"datePublished\":\"2023-04-11T18:23:58+00:00\",\"dateModified\":\"2023-04-11T18:45:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\"},\"wordCount\":1505,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\",\"name\":\"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9. - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg\",\"datePublished\":\"2023-04-11T18:23:58+00:00\",\"dateModified\":\"2023-04-11T18:45:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le patron de la sante\u0301 s'est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la v ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg\",\"width\":800,\"height\":600,\"caption\":\"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9. - Cameroun","description":"Le patron de la sante\u0301 s'est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la v ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde","og_locale":"fr_FR","og_type":"article","og_title":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9.","og_description":"Le patron de la sante\u0301 s'est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la v ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde","og_site_name":"Cameroun","article_published_time":"2023-04-11T18:23:58+00:00","article_modified_time":"2023-04-11T18:45:52+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9.","datePublished":"2023-04-11T18:23:58+00:00","dateModified":"2023-04-11T18:45:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde"},"wordCount":1505,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde","name":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9. - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg","datePublished":"2023-04-11T18:23:58+00:00","dateModified":"2023-04-11T18:45:52+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le patron de la sante\u0301 s'est rendu au sein de cette formation sanitaire situe\u0301e a\u0300 Nlongkak, un quartier au c\u0153ur de la v ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681224846.97.jpg","width":800,"height":600,"caption":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9."},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-le-ministre-de-la-sante-manaouda-malachie-en-colere-contre-une-operation-qui-a-entraine-la-mort-dun-nouveau-ne-au-centre-medical-le-jourdain-a-yaounde#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Cameroun\u00a0: Le Ministre de la sant\u00e9, Manaouda Malachie, en col\u00e8re contre une op\u00e9ration qui a entra\u00een\u00e9 la mort d\u2019un nouveau-n\u00e9 au Centre m\u00e9dical le Jourdain \u00e0 Yaound\u00e9."}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/41548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=41548"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/41548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/41547"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=41548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=41548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=41548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}