{"id":41613,"date":"2023-04-11T18:27:53","date_gmt":"2023-04-11T18:27:53","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde"},"modified":"2023-04-11T19:03:44","modified_gmt":"2023-04-11T19:03:44","slug":"cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde","title":{"rendered":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span><b>Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir avec les inondations a\u0300 Yaounde\u0301. <\/b><\/p>\n<p>Face a\u0300 la vague d\u2019inondation qui ne cesse de paralyser le centre-ville de Yaounde\u0301, le Minhdu tente de rassurer l\u2019opinion. En effet, apre\u0300s les Projets d\u2019assainissement de la ville de Yaounde\u0301 (Pady 1 et 2) qui ont englouti 100 milliards de FCFA, Ce\u0301lestine Ketcha Courte\u0300s promet, dans un communique\u0301 publie\u0301 le 6 avril dernier, de \u00ab re\u0301sorber de manie\u0300re plus significative et durable les inondations dans la capitale \u00bb avec le Projet comple\u0301mentaire d\u2019assainissement pluvial durable de la ville de Yaounde\u0301 (Pcady).<\/p>\n<p>Le Pcady est un projet finance\u0301 par la Banque africaine de de\u0301veloppement (Bad) a\u0300 hauteur de 15,8 milliards FCFA. Ces fonds \u00ab seront consacre\u0301s a\u0300 la construction de nouveaux ouvrages, au renforcement de la gestion des eaux pluviales et a\u0300 l\u2019hygie\u0300ne \u00bb, fait savoir le Minhdu.<\/p>\n<p>Pour la Bad, le Pcady \u00ab s\u2019inscrit dans la continuite\u0301 des objectifs vise\u0301s par les phases 1 et 2 du Projet PADY, tout en apportant les ajustements ne\u0301cessaires pour accroi\u0302tre les re\u0301sultats escompte\u0301s \u00bb. Dans un article de de\u0301cembre 2021, l\u2019institution financie\u0300re africaine explique que \u00ab la construction de 17 km de canaux sur les cours d\u2019eau qui drainent la ville de Yaounde\u0301 lors de la premie\u0300re et de la deuxie\u0300me phase du projet a contribue\u0301 a\u0300 re\u0301duire de manie\u0300re significative la fre\u0301quence et les effets des inondations dans une partie de la ville \u00bb.<\/p>\n<p>Pour la Bad les inondations actuelles sont donc a\u0300 mettre sur le dos d\u2019une pluviome\u0301trie de plus en plus abondante au fil des anne\u0301es. \u00ab C\u2019est ainsi qu\u2019une e\u0301tude re\u0301alise\u0301e dans la deuxie\u0300me phase du projet a montre\u0301 la ne\u0301cessite\u0301 de re\u0301aliser de nouveaux ouvrages afin de re\u0301duire significativement la fre\u0301quence des inondations dans la ville dans un contexte de changement climatique \u00bb, e\u0301crit la Bad.<\/p>\n<p>De son co\u0302te\u0301, Ketcha Courte\u0300s accuse une fois de plus l\u2019incivisme des populations qui seraient la cause de la \u00ab re\u0301currence du phe\u0301nome\u0300ne des inondations \u00bb. \u00ab Il s\u2019agit notamment du de\u0301sordre urbain qui se traduit par l\u2019occupation anarchique des drains par des constructions ou le remplissage de ceux-ci par des ordures qui les obstruent totalement \u00bb.<\/p>\n<p>Lance\u0301 en 2007, le Projet d\u2019assainissement de Yaounde\u0301 (PADY), finance\u0301 par la Banque africaine de de\u0301veloppement, a depuis montre\u0301 ses limites. Le nombre d\u2019inondation dans la capitale camerounaise ne cesse de croitre. La deuxie\u0300me phase du Projet, entame\u0301e en 2013, visait de\u0301ja\u0300 a\u0300 atteindre l\u2019objectif \u00ab ze\u0301ro inondation \u00bb en 2020. Au vu des nombreuses inondations a\u0300 Yaounde\u0301 en cette saison des pluies, on en est encore tre\u0300s loin des objectifs fixe\u0301s.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir avec les inondations a\u0300 Yaounde\u0301. Face a\u0300 la vague d\u2019inondation qui ne cesse de paralyser le centre-ville de Yaounde\u0301, le Minhdu tente de rassurer l\u2019opinion. En effet, apre\u0300s les Projets d\u2019assainissement de la ville [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":41612,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-41613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9 - Cameroun<\/title>\n<meta name=\"description\" content=\"Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9\" \/>\n<meta property=\"og:description\" content=\"Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T18:27:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-11T19:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9\",\"datePublished\":\"2023-04-11T18:27:53+00:00\",\"dateModified\":\"2023-04-11T19:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\"},\"wordCount\":504,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\",\"name\":\"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9 - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg\",\"datePublished\":\"2023-04-11T18:27:53+00:00\",\"dateModified\":\"2023-04-11T19:03:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg\",\"width\":720,\"height\":360,\"caption\":\"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9 - Cameroun","description":"Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde","og_locale":"fr_FR","og_type":"article","og_title":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9","og_description":"Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde","og_site_name":"Cameroun","article_published_time":"2023-04-11T18:27:53+00:00","article_modified_time":"2023-04-11T19:03:44+00:00","og_image":[{"width":720,"height":360,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9","datePublished":"2023-04-11T18:27:53+00:00","dateModified":"2023-04-11T19:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde"},"wordCount":504,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde","name":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9 - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg","datePublished":"2023-04-11T18:27:53+00:00","dateModified":"2023-04-11T19:03:44+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Ketcha Courte\u0300s, la ministre de l\u2019Habitat et du De\u0301veloppement urbain (Minhdu) promet un nouveau projet pour en finir ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/04\/postQueueImg_1681225077.19.jpg","width":720,"height":360,"caption":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-16-milliards-de-f-pour-en-finir-avec-les-inondations-a-yaounde#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Cameroun : 16 milliards de F pour en finir avec les inondations \u00e0 Yaound\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/41613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=41613"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/41613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/41612"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=41613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=41613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=41613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}