{"id":49112,"date":"2023-08-18T12:11:57","date_gmt":"2023-08-18T12:11:57","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise"},"modified":"2023-08-18T12:23:34","modified_gmt":"2023-08-18T12:23:34","slug":"cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise","title":{"rendered":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span>Investir au Cameroun) &#8211; L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. SHT Overseas Petroleum (SOP), Tchad Petroleum Company (TPC), la Re\u0301publique du Tchad et la Socie\u0301te\u0301 nationale des hydrocarbures (SNH) sont les nouveaux actionnaires, a indique\u0301 l\u2019entreprise lors de la visite de son directeur ge\u0301ne\u0301ral, Harouna Bako, le 7 aou\u0302t 2023, a\u0300 la station de pompage 3 du pipeline Tchad-Cameroun, situe\u0301e a\u0300 Belabo, dans la re\u0301gion de l\u2019Est du Cameroun. Les parts de chaque actionnaire n\u2019ont pas e\u0301te\u0301 pre\u0301cise\u0301es.<\/p>\n<p>Ne\u0301anmoins, dans un communique\u0301 de presse, signe\u0301 le 1er aou\u0302t 2023, Harouna Bako informe que le \u00ab projet de gestion partage\u0301e \u00bb de l\u2019ole\u0301oduc Tchad-Cameroun s\u2019est \u00ab re\u0301cemment mate\u0301rialise\u0301 par le transfert par le Tchad de 20% de parts de la socie\u0301te\u0301 a\u0300 la Re\u0301publique du Cameroun, portant ainsi son actionnariat a\u0300 25% (pre\u0301cise\u0301ment 25,17%, puisque la SNH, qui porte les actions du Cameroun, de\u0301tenait de\u0301ja\u0300 5,17% des parts, NDLR) \u00bb. Ce qui signifie que l\u2019actionnariat de N\u2019Djamena est de\u0301sormais de 74,83%, SOP et TPC e\u0301tant a\u0300 100% des entreprises publiques tchadiennes.<\/p>\n<p>Pour comprendre cette nouvelle configuration de l\u2019actionnariat, il faut se rappeler que N\u2019Djamena conside\u0300re que Savannah Energy n\u2019est plus actionnaire de Cotco. En effet, dans un communique\u0301 rendu public le 2 juin 2023, le ministe\u0300re tchadien des Hydrocarbures affirme que tous les administrateurs de cette entreprise ont e\u0301te\u0301 re\u0301voque\u0301s lors de l\u2019assemble\u0301e ge\u0301ne\u0301rale de Cotco tenue a\u0300 Paris, en France, le 24 mai 2023. Motif : Savannah Energy n\u2019est plus membre du consortium d\u2019entreprise qui exploite le champ pe\u0301trolier de Doba au Tchad, en conse\u0301quence de la nationalisation des actifs de ExxonMobil dans le pays (re\u0301pute\u0301s acquis par la junior pe\u0301tro-gazie\u0300re britannique), intervenue le 31 mars 2023, et de ce fait n\u2019a plus le droit de de\u0301tenir des actions dans Cotco, selon ses statuts.<\/p>\n<p>Une position a\u0300 laquelle N\u2019Djamena a re\u0301ussi a\u0300 rallier Yaounde\u0301, apre\u0300s une crise diplomatique qui a dure\u0301 plusieurs mois. Certainement en contrepartie du transfert de 20% des parts de Cotco au Cameroun et de l\u2019octroi du poste de directeur ge\u0301ne\u0301ral de l\u2019entreprise, qui ge\u0300re les 903 km du pipeline Tchad-Cameroun situe\u0301s en terre camerounaise. Ce qui est mieux que les 10% que le pays aurait obtenus dans le deal (finalement gele\u0301) entre la SNH et Savannah Energy.<\/p>\n<p><b>Ordonnance de la CCI<\/b><\/p>\n<p>Toujours est-il que lors du conseil d\u2019administration tenu le 4 juillet dernier a\u0300 Douala, a\u0300 l\u2019initiative du Tchad, le magistrat camerounais Harouna Bako est nomme\u0301 directeur ge\u0301ne\u0301ral, sur proposition du Cameroun. La pre\u0301sidence du conseil d\u2019administration et la direction ge\u0301ne\u0301rale adjointe e\u0301choient respectivement aux Tchadiens Djerassem Le Bemadjiel et Haoua Daoussa. Il est aussi de\u0301cide\u0301 du transfert des actions pre\u0301ce\u0301demment de\u0301tenues par Savannah Energy dans Cotco a\u0300 Tchad Petroleum Company, de\u0301sormais proprie\u0301taire des actifs d\u2019ExxonMobil au Tchad a\u0300 la suite de la nationalisation. \u00ab A\u0300 l\u2019issue de cette ope\u0301ration, le Tchad proce\u0300dera au transfert a\u0300 l\u2019E\u0301tat du Cameroun, d\u2019un pourcentage supple\u0301mentaire de 20% des actions de la socie\u0301te\u0301 \u00bb, pre\u0301cise une autre re\u0301solution de cette re\u0301union. Ce qui a e\u0301te\u0301 fait si l\u2019on en croit l\u2019extrait du compte titres de Cotco. D\u2019ou\u0300 la ge\u0301ographie actuelle du capital.<\/p>\n<p>Pour Savannah Energy, cette situation est une voie de fait. L\u2019entreprise britannique conteste la nationalisation des actifs de ExxonMobil qui la priverait de ses droits d\u2019actionnaire dans Cotco. Les proce\u0301dures sont en cours sur le sujet, notamment devant la Cour internationale d\u2019arbitrage de la Chambre de commerce internationale de Paris (CCI). Le 12 juillet 2023, la junior pe\u0301tro-gazie\u0300re sollicite donc un arbitrage d\u2019urgence de la CCI pour que ses administrateurs soient re\u0301tablis, dont Nicolas de Blanpre\u0301 au poste de pre\u0301sident-directeur ge\u0301ne\u0301ral. Elle demande aussi que toutes les de\u0301cisions prises depuis leur re\u0301vocation soient suspendues, en attendant de statuer sur le fond de son diffe\u0301rend avec le Tchad au sujet de la nationalisation des actifs d\u2019ExxonMobil. Savannah Energy sollicite expresse\u0301ment la suspension de l\u2019assemble\u0301e ge\u0301ne\u0301rale du 24 mai et du conseil d\u2019administration du 4 juillet, qui a vu la nomination des dirigeants actuels de Cotco et le transfert de ses actions a\u0300 TPC.<\/p>\n<p>Dans son ordonnance du 28 juillet, l\u2019arbitre d\u2019urgence, Marc Henry, ordonne \u00ab la suspension des effets des re\u0301solutions adopte\u0301es \u00bb lors de ces deux re\u0301unions, de me\u0302me que \u00ab l\u2019interdiction pour la Re\u0301publique du Tchad (&#8230;) de se pre\u0301valoir a\u0300 l\u2019e\u0301gard des tiers ou des parties aux statuts de Cotco \u00bb de ces re\u0301solutions jusqu\u2019a\u0300 la re\u0301solution du diffe\u0301rend au fond. \u00ab Par conse\u0301quent, le conseil d\u2019administration de Cotco est celui du 24 mai 2023, qui n\u2019a fait l\u2019objet d\u2019aucune mesure de suspension \u00bb, estime Nicolas de Blanpre\u0301 dans un message envoye\u0301 au personnel de l\u2019entreprise le 3 aou\u0302t 2023. Dans ce message, ce dernier se pre\u0301sente me\u0302me comme directeur ge\u0301ne\u0301ral de Cotco.<\/p>\n<p><b>Bako toujours en poste <\/b><\/p>\n<p>Cette conclusion de Savannah Energy est discutable. Car, dans la me\u0302me de\u0301cision, Marc Henry refuse de de\u0301clarer que \u00ab la composition du conseil d\u2019administration de Cotco est celle enregistre\u0301e aupre\u0300s du greffe du tribunal de premie\u0300re instance de Douala-Bonanjo le 6 juin 2023, jusqu\u2019a\u0300 ce que le tribunal arbitral constitue\u0301 sur le fond se prononce sur cette question \u00bb. C\u2019est-a\u0300-dire qu\u2019il refuse de reconnaitre formellement Nicolas de Blanpre\u0301 comme administrateur de Cotco. Et pour cause, cela \u00ab reviendrait a\u0300 acter une situation actionnariale qui peut apparai\u0302tre contestable, et qui ne justifie donc pas, a priori, d\u2019e\u0302tre \u201csanctuarise\u0301e\u201d dans l\u2019attente de la de\u0301cision au fond \u00bb, justifie-t-il dans l\u2019ordonnance.<\/p>\n<p>En effet, selon l\u2019arbitre d\u2019urgence, Savannah Energy a finalise\u0301 l\u2019acquisition des actifs de ExxonMobil au Tchad en l\u2019absence d\u2019approbation pre\u0301alable des autorite\u0301s tchadiennes et des lettres de renonciation au be\u0301ne\u0301fice du droit de pre\u0301emption, comme exige\u0301 par les conventions liant les parties. Dans ces conditions, ce dernier conside\u0300re qu\u2019il est permis de \u00ab s\u2019interroger sur la validite\u0301 \u00bb de cette acquisition.<\/p>\n<p>Fort de ce qui pre\u0301ce\u0300de, le Camerounais Harouna Bako est reste\u0301 a\u0300 la te\u0302te de Cotco. Pour montrer qu\u2019il est bien aux commandes, le magistrat a organise\u0301 une visite de travail dans certains sites de l\u2019ole\u0301oduc. \u00ab Cette visite intervient dans un contexte particulier&#8230; Il fallait donc encourager le personnel sur place et leur transmettre un message fort en leur demandant de rester au travail et d\u2019e\u0301viter de se laisser distraire par les manipulateurs \u00bb, avoue-t-il, devant la presse, lors de son passage, le 7 aou\u0302t, a\u0300 la station de pompage de Belabo, dans la re\u0301gion de l\u2019Est du Cameroun. Le 31 juillet, il s\u2019e\u0301tait de\u0301ja\u0300 rendu a\u0300 la station de re\u0301duction de pression, situe\u0301e a\u0300 Kribi dans la cite\u0301 balne\u0301aire du Sud du pays.<\/p>\n<p>Les ope\u0301rations se poursuivent donc \u00ab sereinement \u00bb sur le pipeline Tchad-Cameroun, malgre\u0301 \u00ab les communications manipulatrices et malveillantes de Savannah Energy \u00bb, assure Harouna Bako. Ce dernier a d\u2019autant plus de marge de man\u0153uvre que l\u2019arbitre a e\u0301galement refuse\u0301 d\u2019acce\u0301der a\u0300 la demande de Savannah Energy d\u2019interdire \u00ab a\u0300 Cotco de proce\u0301der a\u0300 tous paiements de ses comptes ou d\u2019effectuer des mouvements de comptes entre ses comptes (&#8230;) \u00bb. Le magistrat doit ne\u0301anmoins soigner ses relations avec la SNH. L\u2019entreprise publique qui repre\u0301sente l\u2019E\u0301tat du Cameroun au sein du conseil d\u2019administration de Cotco continue d\u2019avoir une posture ambigu\u0308e. Dans le cadre de la proce\u0301dure d\u2019urgence a\u0300 la CCI, la SNH a demande\u0301 a\u0300 l\u2019arbitre de constater qu\u2019elle \u00ab s\u2019en rapporte a\u0300 justice \u00bb. C\u2019est-a\u0300-dire qu\u2019elle n\u2019a pas d\u2019arguments a\u0300 opposer a\u0300 Savannah Energy.<\/p>\n<p><b>Aboudi Ottou<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Investir au Cameroun) &#8211; L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. SHT Overseas Petroleum (SOP), Tchad Petroleum Company (TPC), la Re\u0301publique du Tchad et la Socie\u0301te\u0301 nationale des hydrocarbures (SNH) sont les nouveaux actionnaires, a indique\u0301 l\u2019entreprise lors de la visite de son directeur ge\u0301ne\u0301ral, Harouna Bako, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":49111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[36,50,49],"class_list":["post-49112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise - Cameroun<\/title>\n<meta name=\"description\" content=\"Investir au Cameroun) - L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. S ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise\" \/>\n<meta property=\"og:description\" content=\"Investir au Cameroun) - L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. S ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T12:11:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T12:23:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise\",\"datePublished\":\"2023-08-18T12:11:57+00:00\",\"dateModified\":\"2023-08-18T12:23:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\"},\"wordCount\":1405,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"\u00c9conomie\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\",\"name\":\"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg\",\"datePublished\":\"2023-08-18T12:11:57+00:00\",\"dateModified\":\"2023-08-18T12:23:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Investir au Cameroun) - L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. S ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg\",\"width\":720,\"height\":479,\"caption\":\"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise - Cameroun","description":"Investir au Cameroun) - L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. S ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise","og_locale":"fr_FR","og_type":"article","og_title":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise","og_description":"Investir au Cameroun) - L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. S ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise","og_site_name":"Cameroun","article_published_time":"2023-08-18T12:11:57+00:00","article_modified_time":"2023-08-18T12:23:34+00:00","og_image":[{"width":720,"height":479,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise","datePublished":"2023-08-18T12:11:57+00:00","dateModified":"2023-08-18T12:23:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise"},"wordCount":1405,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["\u00c9conomie","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise","url":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise","name":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg","datePublished":"2023-08-18T12:11:57+00:00","dateModified":"2023-08-18T12:23:34+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Investir au Cameroun) - L\u2019actionnariat de la Cameroon Oil Transportation Company (Cotco) a une nouvelle configuration. S ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692348729.702605.jpg","width":720,"height":479,"caption":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/economie\/cotco-le-tchad-cede-20-du-capital-au-cameroun-qui-monte-a-2517-et-se-conforte-a-la-tete-de-lentreprise#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Cotco\u00a0: le Tchad c\u00e8de 20% du capital au Cameroun qui monte \u00e0 25,17% et se conforte \u00e0 la t\u00eate de l\u2019entreprise"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/49112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=49112"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/49112\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/49111"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=49112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=49112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=49112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}