{"id":49233,"date":"2023-08-19T22:36:57","date_gmt":"2023-08-19T22:36:57","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam"},"modified":"2023-08-19T22:46:45","modified_gmt":"2023-08-19T22:46:45","slug":"most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam","title":{"rendered":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span>Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l&rsquo;Ouest. Une femme a fait un coup terrible aux siens et est tre\u0300s recherche\u0301 par ceux-ci.<\/p>\n<p>\u00ab Alerte enle\u0300vement d&rsquo;enfant. Cet enfant au nom de Fouaguieng Edouardo Maxual a e\u0301te\u0301 enleve\u0301 le 16 aou\u0302t 2023 au domicile de ses parents a\u0300 Bafoussam par sa tante la nomme\u0301e Ndjougang Fouaguimg Ire\u0300ne \u00bb, apprend-on.<\/p>\n<p>Le lanceur d\u2019alerte a publie\u0301 la photo de l\u2019enfant. Il e\u0301crit que \u00ab le mercredi 16 aou\u0302t 2023, cette dame s&rsquo;est rendue au domicile de sa grande s\u0153ur au quartier Kongoue a\u0300 Bafoussam aux environs de 14 heures sous le pre\u0301texte qu&rsquo;elle venait voir leur maman malade \u00bb.<\/p>\n<p>C\u2019est alors qu\u2019elle finira par de\u0301jouer l&rsquo;attention des habitants de la maison et des voisins avant de se fondre dans la nature avec cet enfant qui n&rsquo;est autre que son neveu (enfant de sa s\u0153ur ai\u0302ne\u0301e chez qui elle s&rsquo;est rendue) \u00bb.<\/p>\n<p>\u00ab Depuis lors l&rsquo;enfant et la dame sont introuvables. Cette dernie\u0300re est injoignable. Prie\u0300re de bien vouloir nous aider a\u0300 retrouver l\u2019enfant \u00bb, conclut la source.<\/p>\n<p>\u00ab On va se me\u0301fier de tout le monde maintenant. Que chacun reste chez soi (&#8230;). C&rsquo;est su\u0302rement le qu\u2019un mauvais personnage lui a demande\u0301 de faire c\u0327a pour avoir le gain, la vie facile ma grande \u00bb, avertit la population.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l&rsquo;Ouest. Une femme a fait un coup terrible aux siens et est tre\u0300s recherche\u0301 par ceux-ci. \u00ab Alerte enle\u0300vement d&rsquo;enfant. Cet enfant au nom de Fouaguieng Edouardo Maxual a e\u0301te\u0301 enleve\u0301 le [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":49232,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-49233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam - Cameroun<\/title>\n<meta name=\"description\" content=\"Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l&#039;O ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam\" \/>\n<meta property=\"og:description\" content=\"Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l&#039;O ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-19T22:36:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-19T22:46:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam\",\"datePublished\":\"2023-08-19T22:36:57+00:00\",\"dateModified\":\"2023-08-19T22:46:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\"},\"wordCount\":276,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\",\"name\":\"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg\",\"datePublished\":\"2023-08-19T22:36:57+00:00\",\"dateModified\":\"2023-08-19T22:46:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l'O ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam - Cameroun","description":"Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l'O ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam","og_locale":"fr_FR","og_type":"article","og_title":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam","og_description":"Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l'O ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam","og_site_name":"Cameroun","article_published_time":"2023-08-19T22:36:57+00:00","article_modified_time":"2023-08-19T22:46:45+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam","datePublished":"2023-08-19T22:36:57+00:00","dateModified":"2023-08-19T22:46:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam"},"wordCount":276,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam","name":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg","datePublished":"2023-08-19T22:36:57+00:00","dateModified":"2023-08-19T22:46:45+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Situation vraiment alarmante a\u0300 Bafoussam, ville du pays et chef-lieu du de\u0301partement de la Mifi et de la re\u0301gion de l'O ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472448.165941.jpg","width":1280,"height":720,"caption":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/most-wanted-toute-la-ville-a-ses-trousses-pour-un-coup-a-bafoussam#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Most wanted : toute la ville \u00e0 ses trousses pour un coup \u00e0 Bafoussam"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/49233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=49233"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/49233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/49232"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=49233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=49233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=49233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}