{"id":49237,"date":"2023-08-19T22:37:22","date_gmt":"2023-08-19T22:37:22","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur"},"modified":"2023-08-19T22:47:55","modified_gmt":"2023-08-19T22:47:55","slug":"suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur","title":{"rendered":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&rsquo;Ambassadeur"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span>Christian Hue s&rsquo;est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informations, les premiers responsables de la mission diplomatique franc\u0327aise au Cameroun entretiennent un curieux flou autour de cette affaire.<\/p>\n<p>L&rsquo;informations tourne pourtant en boucle sur les re\u0301seaux sociaux et sur les me\u0301dias depuis hier vendredi. Mais l&rsquo;Ambassade de France au Cameroun entretient un curieux silence sur ce suicide du vice-consul Hue. Ce silence laisse la place a\u0300 plusieurs supputations, sur les re\u0301seau sociaux.<\/p>\n<p>Les me\u0301dias et l&rsquo;opinion publique aimerait au moins savoir si vraiment le vice-consul s&rsquo;est suicide\u0301, ou s&rsquo;il a e\u0301te\u0301 e\u0301te\u0301 tue\u0301 et le crime masque\u0301?<\/p>\n<p>D&rsquo;apre\u0300s des renseignements de la re\u0301daction de CamerounWeb, le vice-consul de France a\u0300 Douala e\u0301tait soupc\u0327onne\u0301 de faire parti d&rsquo;un vaste re\u0301seau de trafic de faux visas aussi bien au Cameroun qu&rsquo;au Gabon.<\/p>\n<p>Les autorite\u0301 franc\u0327aises et gabonaises ont ferme\u0301 le 30 novembre 2021, le consulat de France a\u0300 Port-Gentil. En lieu et place, une agence consulaire a e\u0301te\u0301 ouverte pour les inte\u0301re\u0302ts des deux pays. La mutation du consulat ge\u0301ne\u0301ral de la France a\u0300 Port-Gentil, en consul honoraire avait mis fin a\u0300 la mission du consul Christian Hue. Il e\u0301tait a\u0300 ce poste depuis trois anne\u0301es.<\/p>\n<p>Au Cameroun, le consulat de France qui avait e\u0301galement pour chef Christian Hue, avait re\u0301cemment e\u0301te\u0301 secoue\u0301 par un scandale lie\u0301 au trafic de faux visas. Les autorite\u0301s camerounaises et franc\u0327aises ont conjointement ouvert une enque\u0302te au sein de cette repre\u0301sentation diplomatique base\u0301e au Cameroun pour e\u0301lucider cette affaire.<\/p>\n<p>Quelques mois apre\u0300s l&rsquo;ouverture de cette enque\u0302te, l&rsquo;on apprend que Christian Hue s&rsquo;est suicide\u0301.<\/p>\n<p>Craignait-il les re\u0301sultats de cette enque\u0302te? Les autorite\u0301s s&rsquo;appre\u0302taient-elles a\u0300 arre\u0302ter le vice-consul? Quelles sont les autres personnes implique\u0301es dans ce vaste re\u0301seaux de de\u0301livrance des visas? Autant de questions qui ne tarderont pas a\u0300 avoir re\u0301ponses dans les prochaines heures.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Christian Hue s&rsquo;est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informations, les premiers responsables de la mission diplomatique franc\u0327aise au Cameroun entretiennent un curieux flou autour de cette affaire. L&rsquo;informations tourne pourtant en boucle sur les re\u0301seaux sociaux et sur les me\u0301dias [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":49236,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-49237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&#039;Ambassadeur - Cameroun<\/title>\n<meta name=\"description\" content=\"Christian Hue s&#039;est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informa ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&#039;Ambassadeur\" \/>\n<meta property=\"og:description\" content=\"Christian Hue s&#039;est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informa ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-19T22:37:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-19T22:47:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&rsquo;Ambassadeur\",\"datePublished\":\"2023-08-19T22:37:22+00:00\",\"dateModified\":\"2023-08-19T22:47:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\"},\"wordCount\":388,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\",\"name\":\"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l'Ambassadeur - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg\",\"datePublished\":\"2023-08-19T22:37:22+00:00\",\"dateModified\":\"2023-08-19T22:47:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Christian Hue s'est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informa ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg\",\"width\":720,\"height\":480,\"caption\":\"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l'Ambassadeur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&#8217;Ambassadeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l'Ambassadeur - Cameroun","description":"Christian Hue s'est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informa ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur","og_locale":"fr_FR","og_type":"article","og_title":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l'Ambassadeur","og_description":"Christian Hue s'est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informa ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur","og_site_name":"Cameroun","article_published_time":"2023-08-19T22:37:22+00:00","article_modified_time":"2023-08-19T22:47:55+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&rsquo;Ambassadeur","datePublished":"2023-08-19T22:37:22+00:00","dateModified":"2023-08-19T22:47:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur"},"wordCount":388,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur","name":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l'Ambassadeur - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg","datePublished":"2023-08-19T22:37:22+00:00","dateModified":"2023-08-19T22:47:55+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Christian Hue s'est donne\u0301 la mort ce vendredi 18 aou\u0302t 2023 a\u0300 son domicile au Cameroun. 24 heures apre\u0300s cette informa ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2023\/08\/sm_1692472528.946337.jpg","width":720,"height":480,"caption":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l'Ambassadeur"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/suicide-du-vice-consul-de-france-a-douala-le-silence-tres-bruissant-de-lambassadeur#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Suicide du vice-consul de France \u00e0 Douala: le silence tr\u00e8s bruissant de l&#8217;Ambassadeur"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/49237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=49237"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/49237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/49236"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=49237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=49237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=49237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}