{"id":63657,"date":"2024-04-15T21:25:13","date_gmt":"2024-04-15T21:25:13","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent"},"modified":"2024-04-15T22:22:14","modified_gmt":"2024-04-15T22:22:14","slug":"congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent","title":{"rendered":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span><b>Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301cision du maire de Brazzaville.<\/b><\/p>\n<p>Le maire de Brazzaville, Dieudonne\u0301 Bantsimba a instruit en milieu de semaine dernie\u0300re a\u0300 la police d\u2019arre\u0302ter tous les motos-taxis en circulation au centre-ville de la capitale congolaise. La municipalite\u0301 e\u0301voque comme raison les multiples accidents de la circulation qui impliquent ces engins a\u0300 deux roues. Une consigne que condamnent les acteurs de ce secteur.<\/p>\n<p>Dans une de\u0301claration rendue public samedi 13 avril a\u0300 Brazzaville, le Collectif des conducteurs des taxis-motos ont de\u0301nonce\u0301 la note du maire de la ville. Pour ce groupement, Dieudonne\u0301 Bantsimba devrait demander au gouvernement d\u2019acce\u0301le\u0301rer le processus de re\u0301glementation de ce secteur de transport en commun.<\/p>\n<p>\u00ab Nous avons e\u0301te\u0301 de\u0301sagre\u0301ablement surpris de voir un courrier du maire central donnant ordre aux forces de police de nous interdire d\u2019exercer notre activite\u0301 au centre-ville. Il ordonne une interdiction formelle sans indiquer le pe\u0301rime\u0300tre du centre-ville \u00bb, a indique\u0301 Sadath Ouchak, vice-pre\u0301sident du collectif des conducteurs de taxis motos.<\/p>\n<p>Pour le pre\u0301sident du collectif des conducteurs des taxis motos, Jules Ondele\u0301, la consigne du maire de la capitale congolaise a e\u0301te\u0301 applique\u0301e de fac\u0327on anarchique par la police. \u00ab La police profite de cette instruction pour arre\u0302ter les taxis motos a\u0300 Mikalou, a\u0300 PK et a\u0300 Moukondo, comme si ces zones relevaient du centre-ville \u00bb, a-t-il de\u0301plore\u0301.<\/p>\n<p>Les conducteurs des taxi-motos attendent que le gouvernement re\u0300glemente le secteur de transport en commun.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301cision du maire de Brazzaville. Le maire de Brazzaville, Dieudonne\u0301 Bantsimba a instruit en milieu de semaine dernie\u0300re a\u0300 la police d\u2019arre\u0302ter tous les motos-taxis en circulation au centre-ville de la capitale congolaise. La municipalite\u0301 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":63656,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-63657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent - Cameroun<\/title>\n<meta name=\"description\" content=\"Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301 ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent\" \/>\n<meta property=\"og:description\" content=\"Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T21:25:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-15T22:22:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent\",\"datePublished\":\"2024-04-15T21:25:13+00:00\",\"dateModified\":\"2024-04-15T22:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\"},\"wordCount\":297,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\",\"name\":\"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg\",\"datePublished\":\"2024-04-15T21:25:13+00:00\",\"dateModified\":\"2024-04-15T22:22:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301 ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg\",\"width\":780,\"height\":440,\"caption\":\"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent - Cameroun","description":"Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301 ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent","og_locale":"fr_FR","og_type":"article","og_title":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent","og_description":"Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301 ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent","og_site_name":"Cameroun","article_published_time":"2024-04-15T21:25:13+00:00","article_modified_time":"2024-04-15T22:22:14+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent","datePublished":"2024-04-15T21:25:13+00:00","dateModified":"2024-04-15T22:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent"},"wordCount":297,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent","name":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg","datePublished":"2024-04-15T21:25:13+00:00","dateModified":"2024-04-15T22:22:14+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Dans une de\u0301claration publie\u0301e samedi 13 avril dernier, les acteurs de ce secteur d\u2019activite\u0301 ont de\u0301nonce\u0301 cette de\u0301 ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/04\/sm_1713206709.76284.jpg","width":780,"height":440,"caption":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/congo-interdiction-des-moto-taxis-de-circuler-au-centre-ville-les-conducteurs-sy-opposent#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Congo-interdiction des moto-taxis de circuler au centre-ville : les conducteurs s\u2019y opposent"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/63657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=63657"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/63657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/63656"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=63657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=63657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=63657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}