{"id":64627,"date":"2024-05-05T00:04:15","date_gmt":"2024-05-05T00:04:15","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala"},"modified":"2024-05-05T00:32:02","modified_gmt":"2024-05-05T00:32:02","slug":"cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala","title":{"rendered":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span><b>Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala 4e\u0300, une activite\u0301 de proximite\u0301.<\/b><\/p>\n<p>Le but de cette descente sur le terrain de l\u2019homme politique est de convaincre les Camerounais en a\u0302ge de voter a\u0300 s\u2019enro\u0302ler pour s\u2019acquitter de leur devoir d\u2019e\u0301lecteur. Car, \u00ab l\u2019inscription sur les listes e\u0301lectorales est un devoir citoyen \u00bb, rappelle Serge Espoir Matomba, premier secre\u0301taire du Peuple uni pour la re\u0301novation sociale (PURS).<\/p>\n<p>Sous un soleil ardent, l\u2019opposant a parcourt les rues de Grand hangar au lieu-dit \u201cAngle 90\u201d dans le quatrie\u0300me arrondissement de la me\u0301tropole e\u0301conomique pour sensibiliser les personnes qui y vivent. Dans les de\u0301bits de boissons, salons de beaute\u0301, e\u0301choppes, marche\u0301s&#8230; l\u2019ancien candidat a\u0300 la pre\u0301sidentielle camerounaise de 2018 ne manque pas des mots pour adresser un message incitatif aux citoyens lambdas rencontre\u0301s dans la rue.<\/p>\n<p>\u00ab Je suis sur le terrain aujourd\u2019hui pour encourager le travail que les e\u0301quipes font depuis plusieurs mois. Je crois que l\u2019engouement constate\u0301 aujourd\u2019hui pour les inscriptions sur les listes e\u0301lectorales est la preuve que les gens ont compris qu\u2019ils ne doivent plus rester sceptiques a\u0300 cet acte \u00bb, ajoute Serge Espoir Matomba.<\/p>\n<p>Un engouement observe\u0301 dans les deux postes fixes d\u2019inscriptions sur les listes e\u0301lectorales de\u0301ploye\u0301s au carrefour Angle 90 de Grand hangar-Bonabe\u0301ri par Elecam. Un citoyen a\u0302ge\u0301 d\u2019une quarantaine d\u2019anne\u0301es, de\u0301tenant de\u0301ja\u0300 sa carte d\u2019e\u0301lecteur de\u0301roule les mobiles ne\u0301cessitant une inscription massive dans le fichier des e\u0301lecteurs.: \u00ab C\u2019est tre\u0300s important de s\u2019inscrire sur les listes e\u0301lectorales. Il faut que tout le monde sorte le jour du vote pour changer le re\u0301gime. Trop c\u2019est trop ! Beaucoup de gens souffrent \u00bb, scande-t-il. La situation est la me\u0302me chez Annie, commerc\u0327ante: \u00ab Je suis de\u0301ja\u0300 inscrite sur les listes e\u0301lectorales. Je veux un changement. Je veux qu\u2019on essaie d\u2019aider les parents qui souffrent pour leurs enfants qui sont l\u2019e\u0301cole \u00bb, implore-t-elle.<\/p>\n<p>Pour accompagner l\u2019action du quatrie\u0300me adjoint au maire de Douala 4e\u0300me sur le terrain, des artistes ont accorde\u0301 leurs violons. Les plus connus sont ceux de genre makossa tels que Njohreur, Junior E\u0301yango et Monny E\u0301ka de Petit Pays. Tous a\u0300 tour de ro\u0302le sur le car-podium, poussent un titre de leurs re\u0301pertoires musicaux avec un message phare: celui d\u2019aller s\u2019inscrire sur les listes e\u0301lectorales avant le 31 aou\u0302t prochain.<\/p>\n<p>\u00ab Il est e\u0301vident que si tous les Camerounais se le\u0300vent, remplissent ce devoir citoyen, s\u2019inscrivent et ensuite votent, ine\u0301vitablement, nous aurons un nouveau pays. Ce pays que tous les Camerounais re\u0302vent \u00bb, est convaincu Serge Espoir, Matomba.<\/p>\n<p>Avant la convocation du corps e\u0301lectoral pour la Pre\u0301sidentielle de 2025, le PURS annonce la tenue de son congre\u0300s en fe\u0301vrier de la me\u0302me anne\u0301e. Une rencontre au cours de laquelle sera investi le candidat du parti pour cette e\u0301che\u0301ance e\u0301lectorale majeure de la vie de la nation camerounaise.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala 4e\u0300, une activite\u0301 de proximite\u0301. Le but de cette descente sur le terrain de l\u2019homme politique est de convaincre les Camerounais en a\u0302ge de voter a\u0300 s\u2019enro\u0302ler pour s\u2019acquitter de leur devoir d\u2019e\u0301lecteur. [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":64626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[36,50,49],"class_list":["post-64627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala - Cameroun<\/title>\n<meta name=\"description\" content=\"Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala\" \/>\n<meta property=\"og:description\" content=\"Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T00:04:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-05T00:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala\",\"datePublished\":\"2024-05-05T00:04:15+00:00\",\"dateModified\":\"2024-05-05T00:32:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\"},\"wordCount\":568,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\",\"name\":\"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg\",\"datePublished\":\"2024-05-05T00:04:15+00:00\",\"dateModified\":\"2024-05-05T00:32:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg\",\"width\":780,\"height\":440,\"caption\":\"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala - Cameroun","description":"Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala","og_locale":"fr_FR","og_type":"article","og_title":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala","og_description":"Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala","og_site_name":"Cameroun","article_published_time":"2024-05-05T00:04:15+00:00","article_modified_time":"2024-05-05T00:32:02+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala","datePublished":"2024-05-05T00:04:15+00:00","dateModified":"2024-05-05T00:32:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala"},"wordCount":568,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala","url":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala","name":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg","datePublished":"2024-05-05T00:04:15+00:00","dateModified":"2024-05-05T00:32:02+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Par l\u2019entremise de son premier secre\u0301taire, Serge Espoir Matomba, le parti politique a organise\u0301 ce 02 mai a\u0300 Douala ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1714856345.95671.jpg","width":780,"height":440,"caption":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-le-purs-motive-les-citoyens-a-sinscrire-sur-les-listes-electorales-a-douala#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Cameroun : le PURS motive les citoyens \u00e0 s\u2019inscrire sur les listes \u00e9lectorales \u00e0 Douala"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=64627"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/64626"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=64627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=64627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=64627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}