{"id":64678,"date":"2024-05-06T21:48:42","date_gmt":"2024-05-06T21:48:42","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort"},"modified":"2024-05-07T11:44:27","modified_gmt":"2024-05-07T11:44:27","slug":"mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort","title":{"rendered":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span>Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon sens, me\u0302me si tout n\u2019est pas encore parfait.<\/p>\n<p>Le lanceur d\u2019alerte ce\u0301le\u0300bre publie sur sa page Facebook que \u00ab malgre\u0301 les intimidations du ministre dont les gros yeux n&rsquo;effrayent plus personne, me\u0302me pas une mouche, les jeunes camerounais, principales victimes du re\u0301gime Biya-RDPC et te\u0301moins du martyr du peuple depuis 42 ans, sont de\u0301sormais debout pour le changement et l&rsquo;alternance au Cameroun \u00bb.<\/p>\n<p>\u00ab C&rsquo;en est fini pour l&rsquo;imposture du Rassemblement de\u0301mocratique du peuple camerounais (RDPC) et de ses allie\u0301s officiels et officieux. Le peuple a compris qu&rsquo;on peut en de\u0301coudre avec ce re\u0301gime en jouant a\u0300 son jeu et avec ses propres re\u0300gles \u00bb, pre\u0301cise Chouta.<\/p>\n<p>Ces images instantane\u0301es (images poste\u0301es par Paul Chouta sur sa page, ndlr) ont e\u0301te\u0301 prises a\u0300 Maroua, Mora, Douala 1er\/Ancien Cine\u0301ma Omnisports. \u00ab On informe le ministre Paul Atanga Nji ou on attend apre\u0300s octobre 2025, et pre\u0301cise\u0301ment apre\u0300s la prestation de serment du troisie\u0300me pre\u0301sident de la Re\u0301publique ? Dans tous les cas, dites-lui que les cordes ne sont pas finies chez Fokou \u00bb.<\/p>\n<p>Pour bien comprendre l\u2019allusion de Paul Chouta, Fokou c\u2019est Bernard Fokou qui est un grand industriel du pays qui a ba\u0302ti sa le\u0301gende dans la vente des mate\u0301riaux de construction et autres&#8230; De fac\u0327on ironique, on mentionne son nom et la corde lorsqu\u2019on veut parler de suicide par pendaison.<\/p>\n<p>\u00ab \u00ab\u00a0Les harcele\u0301s heureux\u00a0\u00bb peuvent donner l&rsquo;AVC aux gens-la\u0300. Inscrivons-nous massivement sur les listes e\u0301lectorales et exigeons les re\u0301ce\u0301pisse\u0301 une fois inscrits. Ce pays doit changer par tous les moyens. Trop c\u2019est trop \u00bb, chute Chouta qui croit dur comme fer que l\u2019alternance se re\u0301alisera en 2025. Ce n\u2019est plus loin.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon sens, me\u0302me si tout n\u2019est pas encore parfait. Le lanceur d\u2019alerte ce\u0301le\u0300bre publie sur sa page Facebook que \u00ab malgre\u0301 les intimidations du ministre dont les gros yeux n&rsquo;effrayent plus personne, me\u0302me pas [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":64677,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[36,50,49],"class_list":["post-64678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort - Cameroun<\/title>\n<meta name=\"description\" content=\"Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon s ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort\" \/>\n<meta property=\"og:description\" content=\"Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon s ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T21:48:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T11:44:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"321\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort\",\"datePublished\":\"2024-05-06T21:48:42+00:00\",\"dateModified\":\"2024-05-07T11:44:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\"},\"wordCount\":354,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\",\"name\":\"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg\",\"datePublished\":\"2024-05-06T21:48:42+00:00\",\"dateModified\":\"2024-05-07T11:44:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon s ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg\",\"width\":720,\"height\":321,\"caption\":\"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort - Cameroun","description":"Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon s ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort","og_locale":"fr_FR","og_type":"article","og_title":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort","og_description":"Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon s ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort","og_site_name":"Cameroun","article_published_time":"2024-05-06T21:48:42+00:00","article_modified_time":"2024-05-07T11:44:27+00:00","og_image":[{"width":720,"height":321,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort","datePublished":"2024-05-06T21:48:42+00:00","dateModified":"2024-05-07T11:44:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort"},"wordCount":354,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort","url":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort","name":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg","datePublished":"2024-05-06T21:48:42+00:00","dateModified":"2024-05-07T11:44:27+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Mauvaise nouvelle pour Paul Atanga Nji, lance le journaliste Paul Chouta. Les choses semblent bouger enfin dans le bon s ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022635.376364.jpg","width":720,"height":321,"caption":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/politique\/mort-par-pendaison-un-ministre-du-gouvernement-actuel-frappe-par-le-sort#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Mort par pendaison : un ministre du gouvernement actuel frapp\u00e9 par le sort"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=64678"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/64677"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=64678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=64678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=64678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}