{"id":64682,"date":"2024-05-06T21:48:54","date_gmt":"2024-05-06T21:48:54","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout"},"modified":"2024-05-07T11:45:10","modified_gmt":"2024-05-07T11:45:10","slug":"dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout","title":{"rendered":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span>Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302tre inquie\u0301te\u0301s. Quelques suspects rapidement de\u0301signe\u0301s ont e\u0301te\u0301 envoye\u0301s en prison comme le milliardaire Jean-Pierre Amougou Belinga, le lieutenant-colonel Justin Danwe, l\u2019ancien patron de la DGRE Le\u0301opold Maxime Eko Eko et autres.<\/p>\n<p>Martinez Zogo avait e\u0301te\u0301 enleve\u0301 le 17 janvier 2023 a\u0300 Yaounde\u0301. Le 22 janvier de la me\u0302me anne\u0301e, son corps sans vie et apparemment victime de tortures inhumaines, a e\u0301te\u0301 retrouve\u0301 dans la capitale.<\/p>\n<p>Radio France internationale fait e\u0301tat de ce que les 30 avocats de la de\u0301fense qui repre\u0301sentent donc les 17 accuse\u0301s lors du proce\u0300s sur l&rsquo;assassinat de Martinez Zogo en font \u00ab un pre\u0301alable non ne\u0301gociable dans la pre\u0301paration de leur de\u0301fense alors que le tribunal les invite a\u0300 consulter le dossier sur place \u00bb.<\/p>\n<p>Selon RFI, Me Seri Zokou qui est l&rsquo;un des avocats de Maxime Eko Eko juge\u0301 dans la proce\u0301dure pour complicite\u0301 de tortures, indique qu\u2019il est \u00ab pre\u0301vu dans le Code de proce\u0301dure pe\u0301nale que la personne qui est mise en accusation a le droit de lever copie du dossier. On veut nous faire croire que cela ne vaut que pour la phase d&rsquo;instruction. Cela est une interpre\u0301tation extensive que le tribunal fait et une interpre\u0301tation errone\u0301e. Et ici, nous sommes face a\u0300 une injustice flagrante \u00bb.<\/p>\n<p>Il enchai\u0302ne que \u00ab le commissaire du gouvernement, donc le parquet, est une partie au proce\u0300s au me\u0302me titre que les avocats, que la de\u0301fense. Par conse\u0301quent, il ne peut pas, lui, avoir acce\u0300s aux arguments qui vont lui permettre d\u2019incriminer nos clients, tandis que nous n&rsquo;y avons pas acce\u0300s \u00bb.<\/p>\n<p>\u00ab Donc, nous en faisons une question a\u0300 la fois de principe, parce qu&rsquo;il s&rsquo;agit de principes fondamentaux du droit, et nous en faisons une question fondamentale pour la suite du proce\u0300s. Nous sommes pre\u0302ts a\u0300 mener cette bataille pour que le dossier nous soit communique\u0301, pas simplement qu&rsquo;on puisse le consulter \u00bb, pre\u0301vient-il.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302tre inquie\u0301te\u0301s. Quelques suspects rapidement de\u0301signe\u0301s ont e\u0301te\u0301 envoye\u0301s en prison comme le milliardaire Jean-Pierre Amougou Belinga, le lieutenant-colonel Justin Danwe, l\u2019ancien patron de la DGRE Le\u0301opold Maxime Eko Eko et autres. Martinez [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":64681,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-64682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout - Cameroun<\/title>\n<meta name=\"description\" content=\"Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302 ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout\" \/>\n<meta property=\"og:description\" content=\"Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T21:48:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-07T11:45:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout\",\"datePublished\":\"2024-05-06T21:48:54+00:00\",\"dateModified\":\"2024-05-07T11:45:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\"},\"wordCount\":398,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\",\"name\":\"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg\",\"datePublished\":\"2024-05-06T21:48:54+00:00\",\"dateModified\":\"2024-05-07T11:45:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302 ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg\",\"width\":720,\"height\":376,\"caption\":\"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout - Cameroun","description":"Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302 ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout","og_locale":"fr_FR","og_type":"article","og_title":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout","og_description":"Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302 ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout","og_site_name":"Cameroun","article_published_time":"2024-05-06T21:48:54+00:00","article_modified_time":"2024-05-07T11:45:10+00:00","og_image":[{"width":720,"height":376,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout","datePublished":"2024-05-06T21:48:54+00:00","dateModified":"2024-05-07T11:45:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout"},"wordCount":398,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout","name":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg","datePublished":"2024-05-06T21:48:54+00:00","dateModified":"2024-05-07T11:45:10+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les meurtriers du journaliste radio Arse\u0300ne Mbani Salomon Zogo peuvent e\u0302tre su\u0302rs de ce qu\u2019ils ne resteront pas sans e\u0302 ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715022670.066547.jpg","width":720,"height":376,"caption":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/dossier-martinez-zogo-les-avocats-des-17-accuses-font-une-demande-qui-change-tout#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Dossier Martinez Zogo : les avocats des 17 accus\u00e9s font une demande qui change tout"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=64682"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/64681"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=64682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=64682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=64682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}