{"id":64737,"date":"2024-05-07T23:11:50","date_gmt":"2024-05-07T23:11:50","guid":{"rendered":"https:\/\/www.africa-press.net\/cameroun\/politique\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux"},"modified":"2024-05-08T09:16:56","modified_gmt":"2024-05-08T09:16:56","slug":"cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux","title":{"rendered":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Cameroun. <\/strong><\/span><b>Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Douala a e\u0301te\u0301 rappele\u0301e au cours de la concertation pre\u0301side\u0301e par le ministre de ce de\u0301partement, au terme du parcours concerne\u0301 par les travaux.<\/b><\/p>\n<p>L\u2019entre\u0301e Est de Douala a entre autres pour objectifs de faciliter l\u2019acce\u0300s a\u0300 la ville de Douala ; rendre aise\u0301 le de\u0301placement des personnes et des biens et d\u2019ame\u0301liorer l\u2019acce\u0300s au stade de Japoma et aux autres infrastructures socio-e\u0301conomiques environnantes.<\/p>\n<p>D\u2019apre\u0300s le ministe\u0300re des travaux publics, de manie\u0300re globale, les prestations exe\u0301cute\u0301es ou programme\u0301es par Magil et ses sous-traitants concernent: l\u2019ame\u0301nagement des voies alternatives, notamment: Ari-logements sociaux (3,1 km), Ari-e\u0301cole publique de Yatchika (4 km) et colle\u0300ge CPLAN-Cimetie\u0300re de Nyalla-Parisco (3,8 km). Aussi, le de\u0301placement des re\u0301seaux d\u2019eau, d\u2019e\u0301lectricite\u0301 et de te\u0301le\u0301phone et l\u2019e\u0301largissement de 2\u00d71 voies a\u0300 3\u00d72 voies de 3,50m (Plateforme L&gt;=34m) du PK10+400 au PK19+300.<\/p>\n<p>Par ailleurs, la construction de quatre giratoires (carrefour ARI, ho\u0302pital gyne\u0301co, Yassa et Japoma) ; la construction des ouvrages d\u2019art et d\u2019assainissement dont un e\u0301changeur type PIPO au Carrefour YASSA et un e\u0301changeur de Type SPDA a\u0300 l\u2019entre\u0301e du stade de JAPOMA ; l\u2019e\u0301laboration et le suivi d\u2019un Plan environnemental et social et la construction des e\u0301quipements urbains et publics. De plus, il y a la signalisation routie\u0300re ; l\u2019e\u0301clairage public et les ame\u0301nagements paysagers.<\/p>\n<p>En me\u0301moire, le cou\u0302t pre\u0301visionnel des travaux de la phase 2 s\u2019e\u0301le\u0300ve a\u0300 146 milliards de FCFA. Les de\u0301lais contractuels sont de 36 mois, et la fin des travaux de chausse\u0301e est envisage\u0301e en mars 2024.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cameroun\">Cameroun<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Cameroun. Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Douala a e\u0301te\u0301 rappele\u0301e au cours de la concertation pre\u0301side\u0301e par le ministre de ce de\u0301partement, au terme du parcours concerne\u0301 par les travaux. L\u2019entre\u0301e Est de Douala a entre autres pour objectifs de [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":64735,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[36,50,49],"class_list":["post-64737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-cameroun"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux - Cameroun<\/title>\n<meta name=\"description\" content=\"Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Do ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux\" \/>\n<meta property=\"og:description\" content=\"Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Do ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\" \/>\n<meta property=\"og:site_name\" content=\"Cameroun\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-07T23:11:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T09:16:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux\",\"datePublished\":\"2024-05-07T23:11:50+00:00\",\"dateModified\":\"2024-05-08T09:16:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\"},\"wordCount\":342,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Cameroun\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\",\"name\":\"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux - Cameroun\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg\",\"datePublished\":\"2024-05-07T23:11:50+00:00\",\"dateModified\":\"2024-05-08T09:16:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Do ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg\",\"width\":780,\"height\":440,\"caption\":\"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cameroun\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cameroun\/\",\"name\":\"Cameroun\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux - Cameroun","description":"Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Do ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux","og_locale":"fr_FR","og_type":"article","og_title":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux","og_description":"Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Do ...","og_url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux","og_site_name":"Cameroun","article_published_time":"2024-05-07T23:11:50+00:00","article_modified_time":"2024-05-08T09:16:56+00:00","og_image":[{"width":780,"height":440,"url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux","datePublished":"2024-05-07T23:11:50+00:00","dateModified":"2024-05-08T09:16:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux"},"wordCount":342,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg","keywords":["Africa Press","Africa Press-Cameroun","Cameroun"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux","url":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux","name":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux - Cameroun","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg","datePublished":"2024-05-07T23:11:50+00:00","dateModified":"2024-05-08T09:16:56+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Selon le ministe\u0300re des Travaux publics, la consistance des travaux d\u2019ame\u0301nagement de l\u2019Entre\u0301e Est de la ville de Do ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#primaryimage","url":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg","contentUrl":"https:\/\/static.africa-press.net\/cameroun\/sites\/57\/2024\/05\/sm_1715113604.193186.jpg","width":780,"height":440,"caption":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cameroun\/toutes-les-actualites\/cameroun-entree-est-de-douala-voici-en-quoi-consistent-les-travaux#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cameroun\/"},{"@type":"ListItem","position":2,"name":"Cameroun-entr\u00e9e Est de Douala : voici en quoi consistent les travaux"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cameroun\/#website","url":"https:\/\/www.africa-press.net\/cameroun\/","name":"Cameroun","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cameroun\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cameroun\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/comments?post=64737"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/posts\/64737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media\/64735"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/media?parent=64737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/categories?post=64737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cameroun\/wp-json\/wp\/v2\/tags?post=64737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}