{"id":30438,"date":"2022-10-22T17:44:26","date_gmt":"2022-10-22T17:44:26","guid":{"rendered":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca"},"modified":"2022-10-22T17:57:26","modified_gmt":"2022-10-22T17:57:26","slug":"la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca","title":{"rendered":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; CentrAfricaine. <\/strong><\/span>De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e sur la voie de la paix, de la tranquillite\u0301 et de la se\u0301curite\u0301, ce qui permettent a\u0300 la RCA de tourner de\u0301finitivement les pages sombres de re\u0301bellions et coup d\u2019Etat au profit de projets de de\u0301veloppement qui peuvent donner aux Centrafricains le sourire et l\u2019espoir de vivre. Cette transition a e\u0301te\u0301 rendue possible gra\u0302ce a\u0300 la qualite\u0301 et au professionnalisme des soldats de l\u2019arme\u0301e nationale centrafricaine (les FACA), qui risquent chaque jour leur vie pour effectuer les missions de combat les plus dangereuses contre les rebelles arme\u0301s et prote\u0301ger les civils, au service du peuple centrafricain.<\/p>\n<p>Les actes he\u0301roi\u0308ques des soldats des FACA ne peuvent pas passer inaperc\u0327us et c\u2019est pourquoi la ce\u0301re\u0301monie de remise des prix du 8e bataillon des FACA a eu lieu le 9 octobre 2022. Les capitaines, les lieutenants, les sous-lieutenants et les adjudants ont rec\u0327u des me\u0301dailles pour la planification et l\u2019exe\u0301cution efficaces de missions de combat visant a\u0300 trouver et a\u0300 de\u0301truire les insurge\u0301s dans leur zone de responsabilite\u0301. Les chefs d`Etat Major ont e\u0301galement appre\u0301cie\u0301 le haut niveau de discipline et le moral des soldats des FACA.<\/p>\n<p>Les officiers adjoints charge\u0301s des affaires du personnel, qui effectuent re\u0301gulie\u0300rement des entrai\u0302nements au combat et a\u0300 la discipline avec le personnel, ont e\u0301galement e\u0301te\u0301 re\u0301compense\u0301s. Ils sont tre\u0300s respecte\u0301s par le personnel. Ils ont e\u0301te\u0301 engage\u0301s a\u0300 plusieurs reprises dans des ope\u0301rations de lutte et ont rec\u0327u de nombreuses re\u0301compenses de combat. L\u2019un des commandants re\u0301compense\u0301s dirigeait un de\u0301ploiement, qui a repousse\u0301 trois attaques des militants, tuant et blessant jusqu\u2019a\u0300 7 adversaires.<\/p>\n<p>La caracte\u0301ristique commune de tous les officiers re\u0301compense\u0301s est que, pendant la dure\u0301e de leur commandement du bataillon, ils ont fait preuve a\u0300 plusieurs reprises de leur professionnalisme. Ce sont des commandants forts et autoritaires qui ont re\u0301gulie\u0300rement participe\u0301 a\u0300 des ope\u0301rations de combat.<\/p>\n<p>La population centrafricaine fait confiance aux forces de de\u0301fense, les gens sont conscients que les FACA sont en mesure de les prote\u0301ger. Selon certains analystes, le renforcement de l\u2019arme\u0301e nationale et sa capacite\u0301 a\u0300 prote\u0301ger la population sur l\u2019ensemble du territoire centrafricain sont les fruits de la politique de reconstruction de l\u2019arme\u0301e mene\u0301e par le pre\u0301sident Faustin Archange Touadera. Le pre\u0301sident de la RCA a fixe\u0301 l\u2019objectif d\u2019e\u0301craser une \u00ab arme\u0301e de garnison \u00bb et nous sommes maintenant dans le processus des retombe\u0301es.<\/p>\n<p>Outre cela, les FACA ont e\u0301te\u0301 forme\u0301es de manie\u0300re excellente par des instructeurs professionnels russes. Les soldats centrafricains ne refusent pas seulement de s\u2019occuper de leurs localite\u0301s lorsqu\u2019elles sont attaque\u0301es par la gue\u0301rilla, mais ils participent e\u0301galement a\u0300 des man\u0153uvres proactives et me\u0300nent des ope\u0301rations de repre\u0301sailles.<\/p>\n<p>En conclusion, la coope\u0301ration entre les instructeurs russes et les FACA est un aspect important de la paix durable sur l\u2019ensemble du territoire de la Re\u0301publique centrafricaine.<\/p>\n\r\n                <style type=\"text\/css\">\r\n                    \r\n                    #td_uid_1_6a5786422a37d  .td-doubleSlider-2 .td-item1 {\r\n                        background: url(https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_1-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5786422a37d  .td-doubleSlider-2 .td-item2 {\r\n                        background: url(https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_2-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                    #td_uid_1_6a5786422a37d  .td-doubleSlider-2 .td-item3 {\r\n                        background: url(https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_3-80x60.jpg) 0 0 no-repeat;\r\n                    }\r\n                <\/style>\r\n\r\n                <div id=\"td_uid_1_6a5786422a37d\" class=\"td-gallery td-slide-on-2-columns\">\r\n                    <div class=\"post_td_gallery\">\r\n                        <div class=\"td-gallery-slide-top\">\r\n                           <div class=\"td-gallery-title\"><\/div>\r\n\r\n                            <div class=\"td-gallery-controls-wrapper\">\r\n                                <div class=\"td-gallery-slide-count\"><span class=\"td-gallery-slide-item-focus\">1<\/span> de 3<\/div>\r\n                                <div class=\"td-gallery-slide-prev-next-but\">\r\n                                    <i class = \"td-icon-left doubleSliderPrevButton\"><\/i>\r\n                                    <i class = \"td-icon-right doubleSliderNextButton\"><\/i>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-1 \">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-slide-item td-item1\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_1.jpg\" title=\"postMediaimg_5_1\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_1.jpg\" srcset=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_1.jpg 640w, https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_1-300x203.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item2\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_2.jpg\" title=\"postMediaimg_5_2\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_2.jpg\" srcset=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_2.jpg 300w, https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_2-80x60.jpg 80w\" sizes=\"(max-width: 300px) 100vw, 300px\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                    <div class = \"td-slide-item td-item3\">\r\n                        <figure class=\"td-slide-galery-figure td-slide-popup-gallery\">\r\n                            <a class=\"slide-gallery-image-link\" href=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_3.jpg\" title=\"postMediaimg_5_3\"  data-caption=\"\"  data-description=\"\">\r\n                                <img decoding=\"async\" src=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postMediaimg_5_3.jpg\" alt=\"\">\r\n                            <\/a>\r\n                            \r\n                        <\/figure>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                        <div class = \"td-doubleSlider-2\">\r\n                            <div class = \"td-slider\">\r\n                                \r\n                    <div class = \"td-button td-item1\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item2\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                    <div class = \"td-button td-item3\">\r\n                        <div class = \"td-border\"><\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n\r\n                    <\/div>\r\n\r\n                <\/div>\r\n                \n<p><b>La Source: Ndjoni Sango<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/centrafricaine\">CentrAfricaine<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; CentrAfricaine. De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e sur la voie de la paix, de la tranquillite\u0301 et de la se\u0301curite\u0301, ce qui permettent a\u0300 la RCA de tourner de\u0301finitivement les pages sombres de re\u0301bellions et coup d\u2019Etat au profit de projets de de\u0301veloppement qui [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":30437,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,2,20,10],"tags":[36,58,3153,30,41,741,426,1828],"class_list":["post-30438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photo","category-politique","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-centrafricaine","tag-bit8","tag-centrafricaine","tag-centrafrique","tag-faca","tag-formation","tag-instructeurs-russes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA - centrafricaine<\/title>\n<meta name=\"description\" content=\"De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA\" \/>\n<meta property=\"og:description\" content=\"De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\" \/>\n<meta property=\"og:site_name\" content=\"centrafricaine\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-22T17:44:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-22T17:57:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"488\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA\",\"datePublished\":\"2022-10-22T17:44:26+00:00\",\"dateModified\":\"2022-10-22T17:57:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\"},\"wordCount\":603,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-CentrAfricaine\",\"BIT8\",\"CentrAfricaine\",\"Centrafrique\",\"FACA\",\"FORMATION\",\"instructeurs russes\"],\"articleSection\":[\"Photo\",\"Politique\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\",\"url\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\",\"name\":\"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA - centrafricaine\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg\",\"datePublished\":\"2022-10-22T17:44:26+00:00\",\"dateModified\":\"2022-10-22T17:57:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg\",\"width\":720,\"height\":488,\"caption\":\"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/centrafricaine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/#website\",\"url\":\"https:\/\/www.africa-press.net\/centrafricaine\/\",\"name\":\"centrafricaine\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/centrafricaine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/centrafricaine\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA - centrafricaine","description":"De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca","og_locale":"fr_FR","og_type":"article","og_title":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA","og_description":"De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e ...","og_url":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca","og_site_name":"centrafricaine","article_published_time":"2022-10-22T17:44:26+00:00","article_modified_time":"2022-10-22T17:57:26+00:00","og_image":[{"width":720,"height":488,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/centrafricaine\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA","datePublished":"2022-10-22T17:44:26+00:00","dateModified":"2022-10-22T17:57:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca"},"wordCount":603,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg","keywords":["Africa Press","Africa Press-CentrAfricaine","BIT8","CentrAfricaine","Centrafrique","FACA","FORMATION","instructeurs russes"],"articleSection":["Photo","Politique","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca","url":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca","name":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA - centrafricaine","isPartOf":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg","datePublished":"2022-10-22T17:44:26+00:00","dateModified":"2022-10-22T17:57:26+00:00","author":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"De\u0301chire\u0301e depuis des anne\u0301es par des conflits arme\u0301s permanents, la Re\u0301publique centrafricaine semble s\u2019e\u0302tre engage\u0301e ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/45\/2022\/10\/postQueueImg_5-63542ed835fdc.jpg","width":720,"height":488,"caption":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/centrafricaine\/politique\/la-remise-des-medailles-aux-membres-du-8eme-bataillon-des-faca#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/centrafricaine\/"},{"@type":"ListItem","position":2,"name":"la remise des m\u00e9dailles aux membres du 8\u00e8me bataillon des FACA"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/centrafricaine\/#website","url":"https:\/\/www.africa-press.net\/centrafricaine\/","name":"centrafricaine","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/centrafricaine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/centrafricaine\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/posts\/30438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/comments?post=30438"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/posts\/30438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/media\/30437"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/media?parent=30438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/categories?post=30438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/centrafricaine\/wp-json\/wp\/v2\/tags?post=30438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}