{"id":2557,"date":"2022-06-18T17:27:42","date_gmt":"2022-06-18T17:27:42","guid":{"rendered":"https:\/\/www.africa-press.net\/comores\/politique\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2"},"modified":"2022-06-18T17:37:39","modified_gmt":"2022-06-18T17:37:39","slug":"espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2","title":{"rendered":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Comores. <\/strong><\/span>De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En juin, toutes les plan\u00e8tes du Syst\u00e8me solaire brilleront dans le ciel en seconde partie de nuit et \u00e0 l\u2019aube.<\/p>\n<p>Les plus brillantes, celles que l\u2019on peut ais\u00e9ment rep\u00e9rer \u00e0 l\u2019\u0153il nu, seront align\u00e9es sur pr\u00e8s de 110\u00b0 de l\u2019est-nord-est au sud \u00e0 l\u2019aube apr\u00e8s le 15 et elles seront dispos\u00e9es dans leur ordre naturel d\u2019\u00e9loignement au Soleil : Mercure, V\u00e9nus, Mars, Jupiter et Saturne.<\/p>\n<p>Uranus et Neptune seront \u00e9galement pr\u00e9sentes, mais il faudra des jumelles ou une lunette astronomique pour essayer de les rep\u00e9rer : en fin de nuit pour Neptune \u2013 \u00e0 10\u00b0 sur la droite de Jupiter \u2013 et au tout d\u00e9but de l\u2019aube pour Uranus \u2013 \u00e0 7\u00b0 sur la droite de V\u00e9nus.<\/p>\n<p>Vous pouvez suivre la mise en place de cet alignement apparent au fil du mois de juin. Que vous habitiez en ville ou \u00e0 la campagne, vous devez choisir un site offrant un horizon est-nord-est bien d\u00e9gag\u00e9 pour voir l\u2019\u00e9clatant V\u00e9nus d\u00e8s son lever, pr\u00e8s d\u2019une heure et demie avant le Soleil.<\/p>\n<p>Saturne brille alors \u00e0 plus de 20\u00b0 de hauteur au-dessus de l\u2019horizon sud-est et les plan\u00e8tes Jupiter et Mars forment un joli couple \u00e0 une douzaine de degr\u00e9s de hauteur au-dessus de l\u2019horizon est-sud-est, \u00e0 peu pr\u00e8s \u00e0 mi-distance entre V\u00e9nus et Saturne ; l\u2019\u00e9cart apparent entre Mars et Jupiter augmente tout au long du mois.<\/p>\n<p>Il est ais\u00e9 de reconna\u00eetre ces diff\u00e9rentes plan\u00e8tes qui sont plus brillantes que les \u00e9toiles qui les entourent dans cette portion de la sph\u00e8re c\u00e9leste ; V\u00e9nus et Jupiter sont particuli\u00e8rement \u00e9clatantes, bien plus que Mars et Saturne.<\/p>\n<p>Peu apr\u00e8s le 15 juin, vous pourrez rep\u00e9rer Mercure une heure avant le jour au ras d\u2019un horizon est-nord-est parfaitement d\u00e9gag\u00e9. Elle sera alors plus brillante que Saturne, mais comme elle brillera dans un ciel d\u00e9j\u00e0 bien clair, elle sera plus d\u00e9licate \u00e0 trouver.<\/p>\n<p>Utilisez V\u00e9nus comme point de rep\u00e8re et cherchez Mercure \u00e0 pr\u00e8s de 10\u00b0 sur sa gauche vers l\u2019horizon en prolongeant l\u2019alignement sugg\u00e9r\u00e9 par Jupiter, Mars et V\u00e9nus. Notez que, du 18 au 27 juin, la Lune rend visite \u00e0 ces plan\u00e8tes en se m\u00e9tamorphosant en un croissant de plus en plus mince.<\/p>\n<p>L\u2019\u00e9cart apparent entre Mercure et Saturne est proche de 110\u00b0 \u00e0 la fin du mois de juin, il est donc d\u00e9licat de photographier toutes ces plan\u00e8tes d\u2019un coup \u2013 il faut faire un panorama ou une mosa\u00efque d\u2019images \u2013, mais la contemplation sereine de cette superbe perspective plan\u00e9taire \u00e0 la fin de la courte nuit solsticiale, avec les sons de la nature ou de la ville qui s\u2019\u00e9veille autour de vous, vaut largement l\u2019effort d\u2019un lever tr\u00e8s matinal !<\/p>\n<p><b>Quelques rendez-vous \u00e0 admirer dans le ciel de juin<\/b><\/p>\n<p>La Terre tournant in\u00e9luctablement autour du Soleil, celui-ci semble se d\u00e9placer jour apr\u00e8s jour vers l\u2019est de l\u2019\u00e9cliptique et les constellations qui disparaissent dans l\u2019\u00e9clat du ciel cr\u00e9pusculaire \u00e0 son approche sont de retour \u00e0 l\u2019aube quelques semaines apr\u00e8s.<\/p>\n<p>Ce cycle est immuable et, de la m\u00eame fa\u00e7on qu\u2019il est plaisant de retrouver le Scorpion et le Sagittaire \u00e0 la fin des longues et froides nuits hivernales, il est satisfaisant de saluer le lever des Pl\u00e9iades \u00e0 l\u2019aube des courtes nuits qui entourent le solstice d\u2019\u00e9t\u00e9.<\/p>\n<p>V\u00e9nus partage notre enthousiasme cette ann\u00e9e puisqu\u2019elle brille vivement \u00e0 une dizaine de degr\u00e9s sur la droite de l\u2019amas ouvert du Taureau. Le vendredi 17 juin \u00e0 l\u2019aube, une heure et demie avant l\u2019\u00e9closion de l\u2019\u0153uf solaire, elle ressemble \u00e0 un phare \u00e9tincelant juste au-dessus de l\u2019horizon est-nord-est qui guiderait la course des Pl\u00e9iades.<\/p>\n<p>Ces \u00e9toiles sont d\u00e9licates \u00e0 rep\u00e9rer \u00e0 l\u2019\u0153il nu aussi bas dans le ciel, mais laissez passer quelques matins et elles deviendront \u00e9videntes et pourront participer \u00e0 de beaux rassemblements plan\u00e9taires et lunaires.<\/p>\n<p>Le samedi 18 et le dimanche 19 juin en fin de nuit, trois heures avant le lever du Soleil, la Lune c\u00f4toie Saturne loin au-dessus de l\u2019horizon sud-est.<\/p>\n<p>La plan\u00e8te est \u00e0 une vingtaine de degr\u00e9s de hauteur et, dans une lunette ou un t\u00e9lescope, l\u2019observation de ses merveilleux anneaux est de moins en moins d\u00e9grad\u00e9e par la turbulence atmosph\u00e9rique.<\/p>\n<p>La Lune qui brille \u00e0 ses c\u00f4t\u00e9s nous montre une phase gibbeuse d\u00e9croissante, ce qui signifie que nous approchons de l\u2019opposition de cette plan\u00e8te, le moment de l\u2019ann\u00e9e o\u00f9 elle se situe \u00e0 l\u2019oppos\u00e9 du Soleil par rapport \u00e0 la Terre. Durant cette p\u00e9riode, nous pourrons l\u2019observer lorsqu\u2019elle croisera le m\u00e9ridien au c\u0153ur de la nuit.<\/p>\n<p>Gr\u00e2ce \u00e0 son glissement vers l\u2019est du Capricorne par rapport \u00e0 l\u2019ann\u00e9e derni\u00e8re, Saturne franchira cette ligne, qui coupe le ciel en deux selon l\u2019axe nord-sud, \u00e0 plus de trente degr\u00e9s de hauteur, soit plus que la hauteur de votre main grande ouverte et bras tendu.<\/p>\n<p>Elle sera donc loin des halos de pollution lumineuse et des zones les plus instables de l\u2019atmosph\u00e8re, ce qui devrait nous offrir de belles conditions d\u2019observation aux instruments.<\/p>\n<p>Le samedi 18 et le dimanche 19 juin en fin de nuit, trois heures avant le lever du Soleil, la Lune c\u00f4toie Saturne loin au-dessus de l\u2019horizon sud-est.<\/p>\n<p>La plan\u00e8te est \u00e0 une vingtaine de degr\u00e9s de hauteur et, dans une lunette ou un t\u00e9lescope, l\u2019observation de ses merveilleux anneaux est de moins en moins d\u00e9grad\u00e9e par la turbulence atmosph\u00e9rique.<\/p>\n<p>La Lune qui brille \u00e0 ses c\u00f4t\u00e9s nous montre une phase gibbeuse d\u00e9croissante, ce qui signifie que nous approchons de l\u2019opposition de cette plan\u00e8te, le moment de l\u2019ann\u00e9e o\u00f9 elle se situe \u00e0 l\u2019oppos\u00e9 du Soleil par rapport \u00e0 la Terre. Durant cette p\u00e9riode, nous pourrons l\u2019observer lorsqu\u2019elle croisera le m\u00e9ridien au c\u0153ur de la nuit.<\/p>\n<p>Gr\u00e2ce \u00e0 son glissement vers l\u2019est du Capricorne par rapport \u00e0 l\u2019ann\u00e9e derni\u00e8re, Saturne franchira cette ligne, qui coupe le ciel en deux selon l\u2019axe nord-sud, \u00e0 plus de trente degr\u00e9s de hauteur, soit plus que la hauteur de votre main grande ouverte et bras tendu.<\/p>\n<p>Elle sera donc loin des halos de pollution lumineuse et des zones les plus instables de l\u2019atmosph\u00e8re, ce qui devrait nous offrir de belles conditions d\u2019observation aux instruments.<\/p>\n<p>Le dimanche 26 et le lundi 27 juin \u00e0 l\u2019aube, une heure avant le lever du Soleil, alors que Saturne atteint le m\u00e9ridien et qu\u2019au sud-est Jupiter s\u2019avance dans la Baleine sous le regard rougi de Mars, V\u00e9nus re\u00e7oit la visite d\u2019un mince croissant lunaire \u00e0 l\u2019est-nord-est.<\/p>\n<p>L\u2019arc d\u2019argent est d\u2019une finesse appr\u00e9ciable et la lumi\u00e8re cendr\u00e9e fait luire le pourtour du globe s\u00e9l\u00e8ne qui, le lendemain, surplombe l\u2019\u00e9clat d\u00e9licat de Mercure au ras du sol.<\/p>\n<p>En commen\u00e7ant votre observation une demi-heure plus t\u00f4t, alors que V\u00e9nus se l\u00e8ve \u00e0 peine, l\u2019amas des Pl\u00e9iades est visible sept degr\u00e9s plus haut que la plan\u00e8te.<\/p>\n<p>La plan\u00e8te de la d\u00e9esse de l\u2019amour et ce groupe scintillant \u00e9taient en conjonction \u00e0 moins de six degr\u00e9s d\u2019\u00e9cart le 23 juin, mais les choses ne durent jamais lorsque V\u00e9nus est impliqu\u00e9e et elle s\u2019\u00e9loigne d\u00e9j\u00e0 en poursuivant sa course vers le Soleil.<\/p>\n<p>Phases de la Lune en juin La Lune est au premier quartier le 7 dans le Lion, pleine le 14 dans Ophiuchus, au dernier quartier le 21 dans les Poissons et nouvelle le 29 dans les G\u00e9meaux.<\/p>\n<p>Le ciel de juin Les tr\u00e8s longs cr\u00e9puscules de juin repoussent le d\u00e9but des observations jusqu\u2019\u00e0 minuit. Et l\u00e0 o\u00f9 la vo\u00fbte c\u00e9leste n\u2019est pas compl\u00e9tement noire, il est tout de m\u00eame possible de rep\u00e9rer les belles constellations du ciel estival.<\/p>\n<p>Au sud, le Scorpion dresse un corps doublement arqu\u00e9 dont la portion sup\u00e9rieure abrite la superbe \u00e9toile Antar\u00e8s, \u00e0 l\u2019\u00e9clat rougeoyant ais\u00e9ment identifiable. En remontant le m\u00e9ridien, vous traversez l\u2019immense figure d\u2019Ophiuchus, le Serpentaire, avant d\u2019atteindre Hercule.<\/p>\n<p>Les \u00e9toiles d\u2019Hercule ne sont gu\u00e8re brillantes et je vous conseille de vous allonger ou de vous asseoir dans une chaise longue, car elles sont juste sous le z\u00e9nith.<\/p>\n<p>Sur la droite d\u2019Hercule, en redescendant vers Arcturus du Bouvier, remarquez le petit diad\u00e8me de la Couronne bor\u00e9ale, dont Alphecca, l\u2019\u00e9toile la plus brillante, est parfois appel\u00e9e Gemma.<\/p>\n<p>Sur la gauche d\u2019Hercule brille la superbe V\u00e9ga de la Lyre, l\u2019une des premi\u00e8res \u00e9toiles visibles au cr\u00e9puscule de l\u2019\u00e9t\u00e9 \u00e0 l\u2019automne. Entre V\u00e9ga et Hercule se situe l\u2019apex, le point qui nous indique la direction vers laquelle le Soleil fonce avec l\u2019ensemble du Syst\u00e8me solaire \u00e0 pr\u00e8s de 20 kilom\u00e8tres par seconde.<\/p>\n<p>Dessinez le Triangle d\u2019\u00e9t\u00e9 avec Deneb du Cygne et Alta\u00efr de l\u2019Aigle en plus de V\u00e9ga et cherchez le petit losange du Dauphin en glissant vers l\u2019horizon est.<\/p>\n<p>Plus tard dans la nuit, alors que la Voie lact\u00e9e domine le ciel et que V\u00e9ga s\u2019accroche au z\u00e9nith, la constellation de P\u00e9gase revient \u2013 nous l\u2019avions perdue dans les lueurs cr\u00e9pusculaires en f\u00e9vrier.<\/p>\n<p>Carte du ciel visible en juin 2022 vers la fin du cr\u00e9puscule \u00e0 la latitude de la France m\u00e9tropolitaine. Les cartes de ce billet peuvent \u00eatre utilis\u00e9es en Europe et dans le monde \u00e0 l\u2019int\u00e9rieur d\u2019une bande s\u2019\u00e9tendant de 38\u00b0 \u00e0 52\u00b0 de latitude nord.<\/p>\n<p>Si vous \u00eates \u00e0 plus de 45\u00b0 nord, l\u2019\u00e9toile Polaire sera plus haute dans votre ciel et, le soir, V\u00e9ga de la Lyre sera d\u2019autant plus proche de l\u2019horizon sud-est.<\/p>\n<p>Si vous \u00eates \u00e0 moins de 45\u00b0 nord, l\u2019\u00e9toile Polaire sera plus proche de l\u2019horizon nord et V\u00e9ga sera plus \u00e9loign\u00e9e de l\u2019horizon sud-est. Cliquez sur la carte pour l\u2019afficher en grand et l\u2019imprimer pour votre usage personnel.<\/p>\n<p>Cette carte montre le ciel visible en juin 2022 \u00e0 l\u2019or\u00e9e de l\u2019aube \u00e0 la latitude de la France m\u00e9tropolitaine. Attention, les cartes du ciel ne sont pas \u00e0 l\u2019envers ! Elles repr\u00e9sentent simplement les astres qui sont situ\u00e9s au-dessus de nos t\u00eates.<\/p>\n<p>Si vous vous allongiez avec la t\u00eate vers le nord et les pieds vers le sud, l\u2019est serait bien \u00e0 votre gauche et l\u2019ouest \u00e0 votre droite. Utilisez ces cartes en les imprimant et en les faisant tourner de telle sorte que le nom de la direction dans laquelle vous observez soit \u00e9crit \u00e0 l\u2019endroit.<\/p>\n<p>Les constellations et les \u00e9toiles que vous retrouverez dans la portion du ciel qui vous fait face sont toutes celles dont le nom est lisible sans trop pencher la t\u00eate.<\/p>\n<p>Les noms des constellations et de leurs principales \u00e9toiles sont indiqu\u00e9s, ainsi que le trac\u00e9 des constellations les plus importantes ; ce trac\u00e9 est parfois incomplet lorsque la figure est en partie cach\u00e9e sous l\u2019horizon.<\/p>\n<p>Le ciel est tr\u00e8s vaste et les constellations qui semblent petites sur les cartes sont, en fait, tr\u00e8s grandes : votre main ouverte et bras tendu cache ainsi \u00e0 peine l\u2019ensemble du Chariot de la Grande Ourse. La 28e \u00e9dition de mon Guide du Ciel arrive en librairie le 16 juin.<\/p>\n<p>Si vous voulez tout savoir sur le ciel, je vous propose jour par jour, de juin 2022 \u00e0 juin 2023, plus de 1 000 ph\u00e9nom\u00e8nes c\u00e9lestes (conjonctions, \u00e9clipses de Lune et de Soleil, \u00e9toiles filantes, occultations, aurores polaires, com\u00e8tes, cycles solaires, lumi\u00e8re zodiacale, gegenschein, nuages noctiluques, meilleures p\u00e9riodes pour admirer la Voie lact\u00e9e et photographier ses arches et ses piliers, etc.<\/p>\n<p>), des conseils pratiques, des centaines de cartes, de photographies et de sch\u00e9mas pour pratiquer l\u2019observation du ciel aussi souvent que possible !<\/p>\n<p>Le 28 juin, lors de la soir\u00e9e d\u2019ouverture de la quinzaine Arts &amp; Sciences au Crat\u00e8re \u2013 Sc\u00e8ne national d\u2019Al\u00e8s, j\u2019aurai le plaisir de vous faire visiter le ciel, de la Lune aux profondeurs du cosmos, juste avant un tour de chant lunaire d\u2019Elsa Gelly avec Sylvain Griotto au piano. Tout cela se d\u00e9roulera sous l\u2019\u0153uvre de Luke Jerram, Museum of the Moon, une impressionnante lune de sept m\u00e8tres de.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/comores\">Comores<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Comores. De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En juin, toutes les plan\u00e8tes du Syst\u00e8me solaire brilleront dans le ciel en seconde partie de nuit et \u00e0 l\u2019aube. Les plus brillantes, celles que l\u2019on peut ais\u00e9ment rep\u00e9rer \u00e0 l\u2019\u0153il nu, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":2556,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[36,379,53,378,45],"class_list":["post-2557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cameroun","tag-africa-press-comores","tag-cameroun","tag-comores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin - Comores<\/title>\n<meta name=\"description\" content=\"De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En j ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin\" \/>\n<meta property=\"og:description\" content=\"De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En j ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\" \/>\n<meta property=\"og:site_name\" content=\"Comores\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-18T17:27:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-18T17:37:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1556\" \/>\n\t<meta property=\"og:image:height\" content=\"996\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin\",\"datePublished\":\"2022-06-18T17:27:42+00:00\",\"dateModified\":\"2022-06-18T17:37:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\"},\"wordCount\":2160,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Cameroun\",\"Africa Press-Comores\",\"Cameroun\",\"Comores\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\",\"url\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\",\"name\":\"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin - Comores\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg\",\"datePublished\":\"2022-06-18T17:27:42+00:00\",\"dateModified\":\"2022-06-18T17:37:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En j ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg\",\"width\":1556,\"height\":996,\"caption\":\"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/comores\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/#website\",\"url\":\"https:\/\/www.africa-press.net\/comores\/\",\"name\":\"Comores\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/comores\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/comores\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin - Comores","description":"De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En j ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2","og_locale":"fr_FR","og_type":"article","og_title":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin","og_description":"De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En j ...","og_url":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2","og_site_name":"Comores","article_published_time":"2022-06-18T17:27:42+00:00","article_modified_time":"2022-06-18T17:37:39+00:00","og_image":[{"width":1556,"height":996,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/comores\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin","datePublished":"2022-06-18T17:27:42+00:00","dateModified":"2022-06-18T17:37:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2"},"wordCount":2160,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg","keywords":["Africa Press","Africa Press-Cameroun","Africa Press-Comores","Cameroun","Comores"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2","url":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2","name":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin - Comores","isPartOf":{"@id":"https:\/\/www.africa-press.net\/comores\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg","datePublished":"2022-06-18T17:27:42+00:00","dateModified":"2022-06-18T17:37:39+00:00","author":{"@id":"https:\/\/www.africa-press.net\/comores\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"De Mercure \u00e0 Saturne, les plan\u00e8tes les plus brillantes du Syst\u00e8me solaire vont s\u2019aligner \u00e0 l\u2019aube au cours du mois. En j ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/48\/2022\/06\/postQueueImg_3-62ae0d3d18b5d.jpg","width":1556,"height":996,"caption":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/comores\/toutes-les-actualites\/espace-un-grand-alignement-des-planetes-du-systeme-solaire-visible-en-ce-mois-de-juin-2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/comores\/"},{"@type":"ListItem","position":2,"name":"Espace: un grand alignement des plan\u00e8tes du syst\u00e8me solaire visible en ce mois de juin"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/comores\/#website","url":"https:\/\/www.africa-press.net\/comores\/","name":"Comores","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/comores\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/comores\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/posts\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/posts\/2557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/media\/2556"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/media?parent=2557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/categories?post=2557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/comores\/wp-json\/wp\/v2\/tags?post=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}