{"id":55073,"date":"2026-04-23T11:41:37","date_gmt":"2026-04-23T11:41:37","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-brazzaville\/politique\/quatre-astronautes-vers-la-lune-apres-cinquante-ans"},"modified":"2026-05-06T12:21:22","modified_gmt":"2026-05-06T12:21:22","slug":"quatre-astronautes-vers-la-lune-apres-cinquante-ans","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans","title":{"rendered":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans"},"content":{"rendered":"<p><span class=\"ap-article-header-tag\"> <strong>Africa-Press &#8211; Congo Brazzaville. <\/strong> <\/span>Les quatre astronautes de la mission Arte\u0301mis 2 de la Nasa se sont envole\u0301s le 1er avril 2026 pour un aller-retour de dix jours autour de la Lune, une mission test pour ouvrir la voie a\u0300 un retour sur le sol lunaire en 2028. \u00ab\u00a0Apre\u0300s une bre\u0300ve interruption de 54 ans, la Nasa reprend sa mission d&rsquo;envoyer des astronautes vers la Lune\u00a0\u00bb, a de\u0301clare\u0301 Jared Isaacman, le patron de l&rsquo;agence spatiale ame\u0301ricaine nomme\u0301 par Donald Trump, lors d&rsquo;une confe\u0301rence de presse apre\u0300s le lancement.<\/p>\n<p>La fuse\u0301e Space Launch System a de\u0301colle\u0301 a\u0300 l&rsquo;heure, a\u0300 18h35 (22h35 GMT), depuis le centre spatial Kennedy en Floride. Quelques minutes plus tard, le commandant ame\u0301ricain de la mission, Reid Wiseman, s&rsquo;exclamait de\u0301ja\u0300: \u00ab\u00a0Nous voyons un beau lever de Lune\u00a0\u00bb. \u00ab\u00a0Nous partons pour l&rsquo;humanite\u0301 tout entie\u0300re\u00a0\u00bb, a de\u0301clare\u0301 dix minutes avant le de\u0301collage son coe\u0301quipier canadien Jeremy Hansen.<\/p>\n<p>A bord ont e\u0301galement pris place les Ame\u0301ricains Victor Glover et Christina Koch. Ils se sont envole\u0301s du me\u0302me pas de lancement le\u0301gendaire d&rsquo;ou\u0300 e\u0301taient partis les astronautes d&rsquo;Apollo, pour ce premier retour vers la Lune depuis la fin des vols Apollo en 1972. Leur capsule Orion s&rsquo;est de\u0301tache\u0301e comme pre\u0301vu huit minutes apre\u0300s le de\u0301collage du premier e\u0301tage qui l&rsquo;a propulse\u0301e dans l&rsquo;espace, puis elle s&rsquo;est place\u0301e en orbite terrestre.<\/p>\n<p>Ils feront plusieurs fois le tour de la Terre a\u0300 quelque 27.000 km\/h, en augmentant progressivement leur altitude, afin de ve\u0301rifier que les syste\u0300mes fonctionnent. La prochaine grande e\u0301tape aura lieu jeudi vers 23h30 GMT, lorsqu&rsquo;ils allumeront les moteurs pour prendre la direction de la Lune, dont ils feront le tour lundi, sans se poser, comme Apollo 8 en 1968.<\/p>\n<p>Dans la soire\u0301e, le pre\u0301sident Donald Trump a commence\u0301 son allocution sur l&rsquo;Iran en fe\u0301licitant les \u00ab\u00a0courageux astronautes\u00a0\u00bb pour leur lancement re\u0301ussi.<\/p>\n<p><b>Proble\u0300mes de toilettes<\/b><\/p>\n<p>Quelques impre\u0301vus techniques ont occupe\u0301 le centre de contro\u0302le de la Nasa a\u0300 Houston dans les premie\u0300res heures du vol: la communication avec les astronautes a brie\u0300vement e\u0301te\u0301 perdue, et les toilettes ne fonctionnent pas encore. \u00ab\u00a0C&rsquo;est juste le de\u0301but\u00a0\u00bb, a commente\u0301 Amit Kshatriya de la Nasa, avec le flegme typique des hauts responsables de l&rsquo;agence.<\/p>\n<p>Mais une man\u0153uvre en orbite, lors de laquelle Victor Glover a pris les commandes d&rsquo;Orion pour simuler un amarrage avec un autre appareil, s&rsquo;est de\u0301roule\u0301e parfaitement. \u00ab\u00a0C&rsquo;e\u0301tait bien de voler avec vous, Houston. Beau ve\u0301hicule\u00a0\u00bb, a-t-il lance\u0301 au centre de contro\u0302le.<\/p>\n<p>Au Centre spatial Kennedy, des ovations et cris de joie ont accompagne\u0301 l&rsquo;ascension de la fuse\u0301e dans un ciel radieux. \u00ab\u00a0Je suis tellement heureuse qu&rsquo;on retourne vers la Lune, tout le monde devrait e\u0302tre heureux et suivre les dix prochains jours, c&rsquo;est un grand pas pour l&rsquo;humanite\u0301\u00a0\u00bb, s&rsquo;exclame, comme sonne\u0301e, l&rsquo;ancienne astronaute Sian Proctor, pre\u0301sente sur place.<\/p>\n<p>Le programme Arte\u0301mis a cou\u0302te\u0301 des dizaines de milliards de dollars et pris des anne\u0301es de retard. \u00ab\u00a0La Nasa a vraiment besoin que cela marche\u00a0\u00bb, dit a\u0300 l&rsquo;AFP Casey Dreier, de The Planetary Society, rappelant que le moral au sein de l&rsquo;agence est en berne, a\u0300 cause de proble\u0300mes budge\u0301taires et de de\u0301parts en masse, notamment des chercheurs qui travaillent sur le climat.<\/p>\n<p><b>Et les Europe\u0301ens?<\/b><\/p>\n<p>A l&rsquo;origine, le programme Arte\u0301mis a e\u0301te\u0301 conc\u0327u pour symboliser un nouvel esprit de collaboration internationale et d&rsquo;inclusion. Son e\u0301quipage est ainsi le premier a\u0300 inclure une femme, un homme noir et un non Ame\u0301ricain ; les pionniers de l&rsquo;e\u0301poque d&rsquo;Apollo (1968 a\u0300 1972) e\u0301taient tous des hommes ame\u0301ricains blancs.<\/p>\n<p>Les Europe\u0301ens participent: ils ont fabrique\u0301 le module qui propulse Orion, et devaient envoyer leurs astronautes dans de futures missions, y compris sur la Lune. Mais la Nasa a re\u0301cemment modifie\u0301 en profondeur la suite du programme Artemis, annulant le projet de station en orbite lunaire, et n&rsquo;a pas clairement dit si les Europe\u0301ens garderaient leur billet pour la Lune.<\/p>\n<p>Pre\u0301sent au centre Kennedy, le directeur ge\u0301ne\u0301ral de l&rsquo;Agence spatiale europe\u0301enne, Josef Aschbacher, a confirme\u0301 a\u0300 l&rsquo;AFP qu&rsquo;il allait devoir s\u00a0\u00bb&lsquo;asseoir avec l&rsquo;administrateur, Jared Isaacman, et la Nasa, pour ne\u0301gocier\u00a0\u00bb les places.<\/p>\n<p><b>Doutes sur 2028<\/b><\/p>\n<p>La journe\u0301e a e\u0301te\u0301 longue jusqu&rsquo;a\u0300 allumage. Le remplissage des immenses re\u0301servoirs de millions de litres d&rsquo;oxyge\u0300ne et d&rsquo;hydroge\u0300ne liquides a dure\u0301 a\u0300 lui seul quatre heures. Puis, plusieurs heures avant le de\u0301collage, les astronautes se sont sangle\u0301s au sommet de la fuse\u0301e, dans Orion qui sera leur habitat jusqu&rsquo;a\u0300 leur retour au large de la Californie, dans le Pacifique, pre\u0301vu le 10 avril.<\/p>\n<p>Les astronautes devraient battre le record de l&rsquo;e\u0301quipage s&rsquo;e\u0301tant le plus e\u0301loigne\u0301 de la Terre, lundi prochain. Leur mission vise a\u0300 confirmer que cette fuse\u0301e haute de 98 me\u0300tres et non re\u0301utilisable pourra acheminer des astronautes sur la surface lunaire d&rsquo;ici 2028, avant la fin du mandat de Donald Trump.<\/p>\n<p>\u00ab\u00a0Arte\u0301mis 2 est le premier acte, c&rsquo;est la mission test, elle va pre\u0301parer le terrain pour les missions suivantes\u00a0\u00bb, a explique\u0301 Jared Isaacman. Mais la date de 2028 fait douter les experts car les astronautes auront besoin d&rsquo;un alunisseur&#8230; toujours en cours de de\u0301veloppement par les entreprises des milliardaires Elon Musk (SpaceX) et Jeff Bezos (Blue Origin).<\/p>\n<p class=\"ap-article-footer-note\">Retrouvez plus d\u2019actualit\u00e9s et d\u2019analyses sur <span class=\"ap-highlight-country\">Congo Brazzaville<\/span> sur le site <span class=\"ap-highlight-brand\">Africa Press<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Brazzaville. Les quatre astronautes de la mission Arte\u0301mis 2 de la Nasa se sont envole\u0301s le 1er avril 2026 pour un aller-retour de dix jours autour de la Lune, une mission test pour ouvrir la voie a\u0300 un retour sur le sol lunaire en 2028. \u00ab\u00a0Apre\u0300s une bre\u0300ve interruption de 54 ans, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":55071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[46],"class_list":["post-55073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-congo-brazzaville"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans - Congo Brazzaville<\/title>\n<meta name=\"description\" content=\"-article-header-tag&quot;&gt; Africa-Press - Congo Brazzaville. Les quatre astronaute ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans\" \/>\n<meta property=\"og:description\" content=\"-article-header-tag&quot;&gt; Africa-Press - Congo Brazzaville. Les quatre astronaute ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\" \/>\n<meta property=\"og:site_name\" content=\"Congo Brazzaville\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T11:41:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T12:21:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans\",\"datePublished\":\"2026-04-23T11:41:37+00:00\",\"dateModified\":\"2026-05-06T12:21:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\"},\"wordCount\":989,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg\",\"keywords\":[\"Congo Brazzaville\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\",\"url\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\",\"name\":\"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans - Congo Brazzaville\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg\",\"datePublished\":\"2026-04-23T11:41:37+00:00\",\"dateModified\":\"2026-05-06T12:21:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"-article-header-tag\\\"> Africa-Press - Congo Brazzaville. Les quatre astronaute ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg\",\"width\":800,\"height\":533,\"caption\":\"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/\",\"name\":\"Congo Brazzaville\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-brazzaville\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans - Congo Brazzaville","description":"-article-header-tag\"> Africa-Press - Congo Brazzaville. Les quatre astronaute ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans","og_locale":"fr_FR","og_type":"article","og_title":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans","og_description":"-article-header-tag\"> Africa-Press - Congo Brazzaville. Les quatre astronaute ...","og_url":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans","og_site_name":"Congo Brazzaville","article_published_time":"2026-04-23T11:41:37+00:00","article_modified_time":"2026-05-06T12:21:22+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans","datePublished":"2026-04-23T11:41:37+00:00","dateModified":"2026-05-06T12:21:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans"},"wordCount":989,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg","keywords":["Congo Brazzaville"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans","url":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans","name":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans - Congo Brazzaville","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg","datePublished":"2026-04-23T11:41:37+00:00","dateModified":"2026-05-06T12:21:22+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"-article-header-tag\"> Africa-Press - Congo Brazzaville. Les quatre astronaute ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#primaryimage","url":"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg","contentUrl":"https:\/\/static.africa-press.net\/congo-brazzaville\/sites\/51\/2026\/05\/sm_1778068559.812544.jpg","width":800,"height":533,"caption":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/toutes-les-actualites\/quatre-astronautes-vers-la-lune-apres-cinquante-ans#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-brazzaville\/"},{"@type":"ListItem","position":2,"name":"Quatre Astronautes Vers La Lune Apr\u00e8s Cinquante Ans"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/#website","url":"https:\/\/www.africa-press.net\/congo-brazzaville\/","name":"Congo Brazzaville","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-brazzaville\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-brazzaville\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/posts\/55073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/comments?post=55073"}],"version-history":[{"count":1,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/posts\/55073\/revisions"}],"predecessor-version":[{"id":55145,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/posts\/55073\/revisions\/55145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/media\/55071"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/media?parent=55073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/categories?post=55073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-brazzaville\/wp-json\/wp\/v2\/tags?post=55073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}