{"id":11052,"date":"2021-08-09T22:24:44","date_gmt":"2021-08-09T22:24:44","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/?p=11052"},"modified":"2021-08-09T22:17:55","modified_gmt":"2021-08-09T22:17:55","slug":"le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus","title":{"rendered":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>. <\/strong><\/span>\u00ab\u00a0Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n&rsquo;ont pas encore envoy\u00e9 les noms de leurs noms d\u00e9l\u00e9gu\u00e9s et certaines ont m\u00eame refus\u00e9 d&rsquo;envoyer leurs d\u00e9l\u00e9gu\u00e9s. Au regroupement politique Le Centre, nous disons que le r\u00e9sultat m\u00eame de la organique de la Commission \u00e9lectorale nationale ind\u00e9pendante (CENI) qui est le probl\u00e8me. Nous pensons que cette loi porte en elle m\u00eame les germes de cette impasse\u00a0\u00bb, estime, sur Top Congo FM, Docteur Rodrigue Mwamba, porte-parole du regroupement politique Le Centre de Germain Kambinga.<\/p>\n<p>\u00ab\u00a0Nous proposons qu&rsquo;on r\u00e9vise la loi organique de la CENI pour deux objectifs. Le premier, c&rsquo;est de rendre la gestion de la CENI coll\u00e9giale au lieu de concentrer tout le pouvoir sur le pr\u00e9sident. C&rsquo;est-\u00e0-dire que l&rsquo;on dilue les pouvoirs du pr\u00e9sident de la CENI pour rendre son r\u00f4le un peu plus administratif\u00a0\u00bb, explique Dr Rodrigue Muamba.<\/p>\n<p>\u00ab\u00a0Deuxi\u00e8mement, c&rsquo;est de permettre \u00e0 ce que la d\u00e9signation des r\u00f4les au sein de la CENI ne se fasse pas en amont, c&rsquo;est-\u00e0-dire \u00e0 la d\u00e9signation des personnalit\u00e9s qui vont repr\u00e9senter les diff\u00e9rentes composantes, mais que cela se passe sur le mod\u00e8le de la Cour constitutionnelle o\u00f9 chaque composante envoie ses d\u00e9l\u00e9gu\u00e9 mais ce sont ses d\u00e9l\u00e9gu\u00e9 qui d\u00e9cident en interne au travers d&rsquo;une \u00e9lection, qui sera pr\u00e9sident, vice-pr\u00e9sident etc. dans le but de neutraliser toutes les influences politique n\u00e9gatives\u00a0\u00bb.<\/p>\n<p><b>Dialogue pour un consensus<\/b><\/p>\n<p>Au moment o\u00f9 cette loi ne peut plus \u00eatre, car d\u00e9j\u00e0 au Parlement et promulgu\u00e9e par le Chef de l&rsquo;\u00c9tat, le Centre pense qu&rsquo;il faut \u00ab\u00a0mettre les gens autour d&rsquo;une table, faire un dialogue pour d\u00e9gager un consensus qui nous permette d&rsquo;aller aux \u00e9lections dans un climat apais\u00e9\u00a0\u00bb.<\/p>\n<p>Ce dialogue, souligne-t-il, \u00ab\u00a0ne va pas aboutir \u00e0 un partage des postes. Nous ne sommes pas dans ce sch\u00e9ma. Nous pensons que le gouvernement Sama doit rester en place jusqu&rsquo;en 2023\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. \u00ab\u00a0Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n&rsquo;ont pas encore envoy\u00e9 les noms de leurs noms d\u00e9l\u00e9gu\u00e9s et certaines ont m\u00eame refus\u00e9 d&rsquo;envoyer leurs d\u00e9l\u00e9gu\u00e9s. Au regroupement politique Le Centre, nous disons que le r\u00e9sultat m\u00eame de la organique de [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":11051,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,2,10],"tags":[36,47,46],"class_list":["post-11052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-politique","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"&quot;Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n&#039;ont pas ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus\" \/>\n<meta property=\"og:description\" content=\"&quot;Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n&#039;ont pas ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-09T22:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"416\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus\",\"datePublished\":\"2021-08-09T22:24:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\"},\"wordCount\":387,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"homepage-french\",\"Politique\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\",\"name\":\"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg\",\"datePublished\":\"2021-08-09T22:24:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"\\\"Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n'ont pas ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg\",\"width\":720,\"height\":416,\"caption\":\"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus - Congo-kinshasa","description":"\"Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n'ont pas ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus","og_locale":"fr_FR","og_type":"article","og_title":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus","og_description":"\"Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n'ont pas ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus","og_site_name":"Congo-kinshasa","article_published_time":"2021-08-09T22:24:44+00:00","og_image":[{"width":720,"height":416,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus","datePublished":"2021-08-09T22:24:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus"},"wordCount":387,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["homepage-french","Politique","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus","name":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg","datePublished":"2021-08-09T22:24:44+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"\"Il y a impasse (dans le processus de d\u00e9signation de nouveaux membres de la CENI). Les diff\u00e9rentes composantes n'ont pas ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6111a97aa7fcc.jpg","width":720,"height":416,"caption":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-centre-de-germain-kambinga-propose-de-reviser-la-loi-sur-la-ceni-ou-de-dialoguer-pour-un-consensus#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"Le Centre de Germain Kambinga propose de r\u00e9viser la loi sur la CENI ou de dialoguer pour un consensus"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/11052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=11052"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/11052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/11051"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=11052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=11052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=11052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}