{"id":11110,"date":"2021-08-10T16:58:45","date_gmt":"2021-08-10T16:58:45","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes"},"modified":"2021-08-10T18:31:57","modified_gmt":"2021-08-10T18:31:57","slug":"soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes","title":{"rendered":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>. <\/strong><\/span>L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au contraste de son ex\u00e9cution financi\u00e8re qui ne refl\u00e8te pas la r\u00e9alit\u00e9 de fonds d\u00e9caiss\u00e9s.<\/p>\n<p>D\u00e9cision salu\u00e9e par l\u2019Association Congolaise pour l\u2019acc\u00e8s \u00e0 la justice (ACAJ) par l\u2019entremise de son Coordonnateur, Georges Kapiamba, qui invite la justice \u00e0 diligenter le plus rapidement possible les enqu\u00eates contre tous les acteurs impliqu\u00e9s dans l\u2019ex\u00e9cution de ce projet.<\/p>\n<p>\u00ab La Justice doit amorcer une enqu\u00eate sur ces faits extr\u00eamement graves et entendre les plus hauts responsables de l\u2019OVD, UBA Bank, CREC 7 et Bureau de contr\u00f4le du Minist\u00e8re des ITPR doivent \u00eatre entendus. TROP C\u2019est TROP. Encore une fois F\u00e9licitations \u00e0 l\u2019IGF pour sa vigilance \u00bb, \u00e9crit Georges Kapiamba sur son compte Twitter.<\/p>\n<p>Et d\u2019ajouter : \u00ab Nous devons tous nous r\u00e9veiller et nous mobiliser contre la corruption et le d\u00e9tournement des deniers publics. Nous devons exiger haut et fort des enqu\u00eates ind\u00e9pendantes et le jugement des auteurs et leurs complices quels que soient leurs appartenances tribales ou politiques \u00bb<\/p>\n<p>Il faut signaler que le projet Tshilejelu financ\u00e9 par le gouvernement congolais \u00e0 travers le fonds national d\u2019entretien routier (Foner) consiste en la modernisation des voiries urbaines de la ville de Kinshasa, et des villes et territoires de l\u2019espace Grand Kasa\u00ef.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au contraste de son ex\u00e9cution financi\u00e8re qui ne refl\u00e8te pas la r\u00e9alit\u00e9 de fonds d\u00e9caiss\u00e9s. D\u00e9cision salu\u00e9e par l\u2019Association Congolaise pour l\u2019acc\u00e8s \u00e0 la justice (ACAJ) par l\u2019entremise de son Coordonnateur, Georges Kapiamba, qui invite la [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":11109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11,10],"tags":[36,47,46],"class_list":["post-11110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au c ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes\" \/>\n<meta property=\"og:description\" content=\"L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au c ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-10T16:58:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-10T18:31:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes\",\"datePublished\":\"2021-08-10T16:58:45+00:00\",\"dateModified\":\"2021-08-10T18:31:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\"},\"wordCount\":257,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\",\"name\":\"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg\",\"datePublished\":\"2021-08-10T16:58:45+00:00\",\"dateModified\":\"2021-08-10T18:31:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au c ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg\",\"width\":720,\"height\":432,\"caption\":\"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes - Congo-kinshasa","description":"L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au c ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes","og_locale":"fr_FR","og_type":"article","og_title":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes","og_description":"L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au c ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes","og_site_name":"Congo-kinshasa","article_published_time":"2021-08-10T16:58:45+00:00","article_modified_time":"2021-08-10T18:31:57+00:00","og_image":[{"width":720,"height":432,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes","datePublished":"2021-08-10T16:58:45+00:00","dateModified":"2021-08-10T18:31:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes"},"wordCount":257,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["Communaut\u00e9","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes","name":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg","datePublished":"2021-08-10T16:58:45+00:00","dateModified":"2021-08-10T18:31:57+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"L\u2019Inspection G\u00e9n\u00e9rale des Finances (IGF) vient de suspendre l\u2019approbation de financement du projet Tshilejelu suite au c ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-6112c6059e880.jpg","width":720,"height":432,"caption":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/soupcon-de-detournement-du-projet-tshilejelu-lacaj-exige-des-enquetes-urgentes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"Soup\u00e7on de d\u00e9tournement du projet Tshilejelu : l\u2019ACAJ exige des enqu\u00eates urgentes"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/11110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=11110"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/11110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/11109"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=11110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=11110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=11110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}