{"id":11333,"date":"2021-08-12T14:50:53","date_gmt":"2021-08-12T14:50:53","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/leuro-de-football-a-lheure-du-covid"},"modified":"2021-08-12T17:42:05","modified_gmt":"2021-08-12T17:42:05","slug":"leuro-de-football-a-lheure-du-covid","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid","title":{"rendered":"L\u2019Euro de football \u00e0 l\u2019heure du Covid"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>. <\/strong><\/span>Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9volutions successives de la pand\u00e9mie de Covid 19. Il n\u2019y a pas un endroit du monde qui soit \u00e9pargn\u00e9 et la tenue de grands \u00e9v\u00e9nements recevant du public est depuis un an, au pire en suspens, au mieux strictement encadr\u00e9 de r\u00e8gles sanitaires. On pense bien s\u00fbr aux Jeux Olympiques de Tokyo d\u00e9cal\u00e9s d\u2019un an et qui d\u00e9buteront finalement le 23 juillet prochain. Mais l\u2019autre \u00e9v\u00e9nement majeur de cet \u00e9t\u00e9 2021 c\u2019est bien \u00e9videmment l\u2019Euro 2021 de football qui a bel et bien lieu \u00e0 l\u2019heure o\u00f9 nous \u00e9crivons ces lignes. Mais quid des conditions sanitaires \u00e0 l\u2019heure du retour du public dans les stades? Qu\u2019en disent les autorit\u00e9s politiques, sportives et de sant\u00e9? Le point sur toutes ces questions.<\/p>\n<p><b>Le public finalement au rendez-vous de cet Euro 2021 de football<\/b><\/p>\n<p>Repouss\u00e9 d\u2019un an comme les JO de Tokyo, l\u2019Euro 2021 a finalement pu d\u00e9but\u00e9 au mois de juin dernier, un signe encourageant d\u2019un retour progressif \u00e0 la vie normale. N\u00e9anmoins pour \u00eatre pr\u00e9cis, nous devrions plut\u00f4t parler de retour \u00e0 la vie \u201cpresque normale\u201d car les conditions sanitaires dans lesquelles se d\u00e9roule cet Euro 2021 sont loin de pouvoir \u00eatre qualifi\u00e9es de normales. La tenue de la comp\u00e9tition \u00e9tait conditionn\u00e9e par le respect d\u2019un protocole sanitaire lourd, que nous allons d\u00e9tailler.<\/p>\n<p>Tout d\u2019abord, la grosse attente autour de cet Euro 2021 de football \u00e9tait \u00e9videmment le retour du public dans les stades. Le retour tant attendu des supporters a bel et bien eu lieu mais dans des proportions variables selon les r\u00e8gles sanitaires en vigueur dans chaque pays. Car l\u00e0 aussi, la grosse nouveaut\u00e9 de cette \u00e9dition 2021 c\u2019est qu\u2019il n\u2019y a pas de pays organisateur afin d\u2019\u00e9viter la concentration de public venu des quatres coins de l&rsquo;Europe dans une seul et m\u00eame pays. Ainsi, la Hongrie a par exemple autoris\u00e9 un remplissage de la Puskas Arena de Budapest \u00e0 100 % de ses capacit\u00e9s. La Russie s\u2019en tient quant \u00e0 elle \u00e0 une jauge de 50 % de la capacit\u00e9 du stade de Saint-P\u00e9tersbourg et enfin, les autres pays, \u00e0 une jauge comprise entre 22 et 33 % des capacit\u00e9s de leurs stades respectifs.<\/p>\n<p>L\u2019acc\u00e8s aux stades est lui aussi encadr\u00e9 par un protocole sanitaire propre \u00e0 chaque pays. Dans la plupart des pays, l\u2019acc\u00e8s aux stades est conditionn\u00e9 \u00e0 la pr\u00e9sentation d\u2019un des ces trois justificatifs:<\/p>\n<p>Dans certains pays les r\u00e8gles sont plus strictes, ainsi \u00e0 Amsterdam aux Pays Bas, m\u00eame en possession d\u2019une attestation de vaccination il faut \u00e9galement pr\u00e9senter un test PCR n\u00e9gatif datant de moins de 72 heures. En Hongrie, quel que soit les justificatifs fournis, un contr\u00f4le de temp\u00e9rature est effectu\u00e9 \u00e0 l\u2019entr\u00e9e des stades, l&rsquo;acc\u00e8s est refus\u00e9 \u00e0 toute personne pr\u00e9sentant une temp\u00e9rature sup\u00e9rieure \u00e0 37,8\u00b0C.<\/p>\n<p>Enfin, \u00e0 Munich en Allemagne, en plus des justificatifs mentionn\u00e9s pr\u00e9c\u00e9demment, seul le port de masques de type FFP2 permet l\u2019acc\u00e8s au stade. Autant dire que cet \u00e9t\u00e9 parier en ligne sera encore tr\u00e8s pertinent&#8230;<\/p>\n<p><b>Les joueurs dans une \u00ab\u00a0bulle sanitaire\u00a0\u00bb<\/b><\/p>\n<p>Les directives de l\u2019UEFA concernant les joueurs de 24 s\u00e9lections en lice sont encore plus strictes. En effet, les joueurs ainsi que la totalit\u00e9 du staff (entra\u00eeneurs, soignants, intendants, etc) sont tenus \u00e0 un isolement des plus stricts.<\/p>\n<p>En plus de cet isolement avec le monde ext\u00e9rieur, l\u2019ensemble des joueurs et les staffs techniques sont test\u00e9s r\u00e9guli\u00e8rement au Covid 19. Un seul test positif pourrait remettre en cause la participation de l\u2019\u00e9quipe toute enti\u00e8re \u00e0 la comp\u00e9tition. Autant dire que la vigilance est de mise au sein des s\u00e9lections.<\/p>\n<p>Mais malgr\u00e9 toutes ces mesures des cas de Covid 19 ont d\u00e9j\u00e0 \u00e9t\u00e9 signal\u00e9s aux seins de plusieurs s\u00e9lections. C\u2019est tout d\u2019abord le gardien des Pays-Bas, Jasper Cillessen, qui a \u00e9t\u00e9 \u00e9cart\u00e9 du groupe \u00e0 la fin du mois de mai apr\u00e8s avoir \u00e9t\u00e9 test\u00e9 positif au Covid 19. Puis ce fut au tour du milieu de terrain et capitaine espagnol Sergio Busquets de devoir quitter son \u00e9quipe le 6 juin dernier apr\u00e8s un test positif. Ce qui a entra\u00een\u00e9 sa mise \u00e0 l\u2019\u00e9cart mais aussi un entra\u00eenement des autres joueurs de l\u2019\u00e9quipe, d\u00e9sormais individuel jusqu\u2019\u00e0 l\u2019obtention de tests ult\u00e9rieurs attestant qu\u2019ils n\u2019ont pas eux aussi \u00e9t\u00e9 contamin\u00e9s.<\/p>\n<p>Mais que pr\u00e9voit l\u2019UEFA en cas de contamination de plusieurs joueurs au sein d\u2019une m\u00eame \u00e9quipe? Plusieurs options existent en fonction de plusieurs sc\u00e9narios. Dans le cas o\u00f9 une \u00e9quipe disposerait d\u2019au moins 13 joueurs valides dont au moins un gardien de but, elle serait tenue de disputer un match. Si l\u2019\u00e9quipe en question ne peut pas remplir ces conditions, alors l\u2019UEFA accorde un report du match de 48 heures maximum. Une fois ce d\u00e9lai expir\u00e9, si l\u2019\u00e9quipe ne peut toujours pas se pr\u00e9senter avec 13 joueurs valides, alors elle sera d\u00e9clar\u00e9e perdante par forfait (soit l\u2019\u00e9quivalent d\u2019une d\u00e9faite 3 buts \u00e0 0).<\/p>\n<p>Ce cas de figure ne s\u2019est pour l\u2019instant jamais pr\u00e9sent\u00e9 dans l\u2019histoire de la comp\u00e9tition, mais il reste encore pr\u00e8s de trois semaines de comp\u00e9tition dans un contexte in\u00e9dit \u00e0 plus d\u2019un titre. Ainsi, un retournement de situation historique comme le forfait d\u2019une \u00e9quipe majeure, ou une victoire finale par forfait li\u00e9 au Covid est de l\u2019ordre du possible. On imagine d\u00e9j\u00e0 les sueurs froides des parieurs \u00e0 l\u2019\u00e9vocation d\u2019un ou plusieurs cas positifs au sein de leur \u00e9quipe favorite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9volutions successives de la pand\u00e9mie de Covid 19. Il n\u2019y a pas un endroit du monde qui soit \u00e9pargn\u00e9 et la tenue de grands \u00e9v\u00e9nements recevant du public est depuis un an, au [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":11332,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,10],"tags":[36,47,46],"class_list":["post-11333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-homepage-french","category-sports","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u2019Euro de football \u00e0 l\u2019heure du Covid - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9vo ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Euro de football \u00e0 l\u2019heure du Covid\" \/>\n<meta property=\"og:description\" content=\"Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9vo ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-12T14:50:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-12T17:42:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"L\u2019Euro de football \u00e0 l\u2019heure du Covid\",\"datePublished\":\"2021-08-12T14:50:53+00:00\",\"dateModified\":\"2021-08-12T17:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\"},\"wordCount\":986,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"homepage-french\",\"Sports\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\",\"name\":\"L\u2019Euro de football \u00e0 l\u2019heure du Covid - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg\",\"datePublished\":\"2021-08-12T14:50:53+00:00\",\"dateModified\":\"2021-08-12T17:42:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9vo ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg\",\"width\":720,\"height\":393,\"caption\":\"L\u2019Euro de football \u00e0 l\u2019heure du Covid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Euro de football \u00e0 l\u2019heure du Covid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019Euro de football \u00e0 l\u2019heure du Covid - Congo-kinshasa","description":"Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9vo ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Euro de football \u00e0 l\u2019heure du Covid","og_description":"Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9vo ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid","og_site_name":"Congo-kinshasa","article_published_time":"2021-08-12T14:50:53+00:00","article_modified_time":"2021-08-12T17:42:05+00:00","og_image":[{"width":720,"height":393,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"L\u2019Euro de football \u00e0 l\u2019heure du Covid","datePublished":"2021-08-12T14:50:53+00:00","dateModified":"2021-08-12T17:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid"},"wordCount":986,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["homepage-french","Sports","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid","name":"L\u2019Euro de football \u00e0 l\u2019heure du Covid - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg","datePublished":"2021-08-12T14:50:53+00:00","dateModified":"2021-08-12T17:42:05+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Cela fait d\u00e9sormais plus d\u2019un an que la vie \u00e9conomique, culturelle, sportive, politique etc est \u00e9troitement li\u00e9e aux \u00e9vo ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/08\/img-61155d5677df1.jpg","width":720,"height":393,"caption":"L\u2019Euro de football \u00e0 l\u2019heure du Covid"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/sports\/leuro-de-football-a-lheure-du-covid#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"L\u2019Euro de football \u00e0 l\u2019heure du Covid"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/11333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=11333"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/11333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/11332"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=11333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=11333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=11333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}