{"id":17253,"date":"2021-10-24T17:43:32","date_gmt":"2021-10-24T17:43:32","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau"},"modified":"2021-10-24T17:48:00","modified_gmt":"2021-10-24T17:48:00","slug":"le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau","title":{"rendered":"Le coronavirus entraine l&rsquo;apparition de vaisseaux fant\u00f4mes dans le cerveau"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>. <\/strong><\/span>Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionnement du cerveau. \u00c0 partir de son propre mat\u00e9riel g\u00e9n\u00e9tique, il fait fabriquer des ciseaux mol\u00e9culaires par les cellules endoth\u00e9liales qu&rsquo;il infecte, transformant les vaisseaux sanguins en vaisseaux \u00ab fant\u00f4mes \u00bb.<\/p>\n<p><b>Quelles sont les cons\u00e9quences de cette mort cellulaire sur l&rsquo;irrigation du cerveau ?<\/b><\/p>\n<p>De nombreux chercheurs et chercheuses sont actuellement mobilis\u00e9s pour accro\u00eetre les connaissances relatives au virus du SARS-CoV-2, pour une meilleure prise en charge des patients infect\u00e9s, mais \u00e9galement pour essayer de pr\u00e9voir les cons\u00e9quences futures d&rsquo;une infection sur la sant\u00e9. Dans le cadre d&rsquo;une collaboration internationale, des chercheurs de l&rsquo;Inserm, de l&rsquo;Universit\u00e9, du CHU et de l&rsquo;Institut Pasteur de Lille, au sein du laboratoire \u00ab Lille neuroscience &amp; cognition \u00bb, et des coll\u00e8gues du CNRS, identifient pour la premi\u00e8re fois un effet direct du SARS-CoV-2 sur les vaisseaux sanguins du cerveau.<\/p>\n<p>Certaines cellules, les cellules endoth\u00e9liales vasculaires c\u00e9r\u00e9brales, composantes essentielles de la barri\u00e8re h\u00e9mato-enc\u00e9phalique qui prot\u00e8ge le cerveau, sont affect\u00e9es par un ph\u00e9nom\u00e8ne de mort cellulaire. Ces r\u00e9sultats, qui font l&rsquo;objet d&rsquo;une publication dans la revue Nature Neuroscience, interrogent notamment sur les cons\u00e9quences \u00e0 long terme de la maladie.<\/p>\n<p>Les vaisseaux sanguins sont compos\u00e9s de cellules endoth\u00e9liales. Parmi elles, les cellules endoth\u00e9liales vasculaires du cerveau qui composent la barri\u00e8re h\u00e9mato-enc\u00e9phalique (BHE). La fonction principale de la BHE est d&rsquo;isoler le syst\u00e8me nerveux central de la circulation sanguine, emp\u00eachant ainsi que des substances \u00e9trang\u00e8res ou mol\u00e9cules potentiellement toxiques ne p\u00e9n\u00e8trent dans le cerveau et la moelle \u00e9pini\u00e8re, tout en permettant le transfert de nutriments essentiels \u00e0 leur activit\u00e9. Participant \u00e0 cet effort, les cellules endoth\u00e9liales vasculaires du cerveau jouent donc un r\u00f4le primordial dans la bonne irrigation sanguine du cerveau et leur survie est essentielle \u00e0 son bon fonctionnement.<\/p>\n<p><b>Comment les ciseaux mol\u00e9culaires provoquent-ils la mort des cellules endoth\u00e9liales ?<\/b><\/p>\n<p>Dans le cadre d&rsquo;une collaboration internationale financ\u00e9e par le Conseil europ\u00e9en de la Recherche, les auteurs de l&rsquo;\u00e9tude se sont int\u00e9ress\u00e9s aux cellules endoth\u00e9liales vasculaires du cerveau et aux cons\u00e9quences d&rsquo;une infection par le SARS-CoV-2 sur leur fonctionnement. Gr\u00e2ce \u00e0 des mod\u00e8les d&rsquo;\u00e9tude pr\u00e9cliniques mais \u00e9galement en \u00e9tudiant le cortex de patients d\u00e9c\u00e9d\u00e9s des suites d&rsquo;une infection au SARS-CoV-2, les chercheurs montrent que l&rsquo;infection entrainerait la mort des cellules endoth\u00e9liales du cerveau, ce qui donnerait lieu \u00e0 l&rsquo;apparition de \u00ab vaisseaux fant\u00f4mes \u00bb dans le cerveau, c&rsquo;est-\u00e0-dire des tubes vides, sans cellules endoth\u00e9liales. En cons\u00e9quence, ces cellules essentielles ne pourraient plus assurer leur fonction au niveau de la barri\u00e8re h\u00e9mato-enc\u00e9phalique.<\/p>\n<p>Comment cette mort des cellules endoth\u00e9liales survient-elle ? Quels sont les m\u00e9canismes impliqu\u00e9s ? Gr\u00e2ce \u00e0 des techniques de pointes &#8212; telles que la transge\u0301ne\u0300se, le se\u0301quenc\u0327age de l&rsquo;ARN en cellule unique, la spectrome\u0301trie de masse et la microscopie a\u0300 super-re\u0301solution &#8211;, l&rsquo;\u00e9quipe a d\u00e9couvert que le SARS-CoV-2 fait fabriquer, \u00e0 partir de son propre mat\u00e9riel g\u00e9n\u00e9tique, des ciseaux mol\u00e9culaires par les cellules endoth\u00e9liales qu&rsquo;il infecte. Ces ciseaux vont couper une prot\u00e9ine appel\u00e9e Nemo, indispensable \u00e0 la survie des cellules endoth\u00e9liales qui vont donc mourir.<\/p>\n<p><b>Quelles cons\u00e9quences sur le fonctionnement du cerveau ?<\/b><\/p>\n<p>Selon les scientifiques, la mort des cellules endoth\u00e9liales vasculaires du cerveau peut entrainer deux cons\u00e9quences majeures :<\/p>\n<p>une rupture temporaire de la barri\u00e8re h\u00e9mato-enc\u00e9phalique provoquant des micro-h\u00e9morragies dans des r\u00e9gions o\u00f9 le sang n&rsquo;est pas cens\u00e9 acc\u00e9der librement.<\/p>\n<p>une hypoperfusion de certaines r\u00e9gions du cerveau (due \u00e0 la pr\u00e9sence de vaisseaux fant\u00f4mes non fonctionnels), c&rsquo;est-\u00e0-dire une diminution du d\u00e9bit sanguin pouvant entrainer le d\u00e9c\u00e8s des patients dans les cas les plus graves.<\/p>\n<p>L&rsquo;\u00e9tude r\u00e9v\u00e8le toutefois que la situation serait r\u00e9versible. Par ailleurs, les scientifiques s&rsquo;interrogent sur les cons\u00e9quences \u00e0 long terme de cette phase de vuln\u00e9rabilit\u00e9 au cours de laquelle le cerveau des patients est moins irrigu\u00e9. Selon eux, m\u00eame si cette hypoth\u00e8se reste encore \u00e0 v\u00e9rifier, cette fen\u00eatre de temps pourrait pr\u00e9disposer certaines personnes ayant contract\u00e9 la maladie \u00e0 d\u00e9velopper des troubles cognitifs, neuro-d\u00e9g\u00e9n\u00e9ratifs, voire des d\u00e9mences.<\/p>\n<p>\u00ab Cette prise de conscience de la gravit\u00e9 de l&rsquo;infection par le SARS-CoV-2 et ses cons\u00e9quences pour le bon fonctionnement de notre cerveau est capitale pour permettre la meilleure prise en charge possible des patients ayant \u00e9t\u00e9 infect\u00e9s dans les ann\u00e9es \u00e0 venir \u00bb, conclut Vincent Pr\u00e9vot, directeur de recherche \u00e0 l&rsquo;Inserm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionnement du cerveau. \u00c0 partir de son propre mat\u00e9riel g\u00e9n\u00e9tique, il fait fabriquer des ciseaux mol\u00e9culaires par les cellules endoth\u00e9liales qu&rsquo;il infecte, transformant les vaisseaux sanguins en vaisseaux \u00ab fant\u00f4mes \u00bb. Quelles sont [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":17252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[36,47,46,242,66],"class_list":["post-17253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa","tag-coronavirus","tag-covid-19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le coronavirus entraine l&#039;apparition de vaisseaux fant\u00f4mes dans le cerveau - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionn ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le coronavirus entraine l&#039;apparition de vaisseaux fant\u00f4mes dans le cerveau\" \/>\n<meta property=\"og:description\" content=\"Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionn ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-24T17:43:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-24T17:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"797\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Le coronavirus entraine l&rsquo;apparition de vaisseaux fant\u00f4mes dans le cerveau\",\"datePublished\":\"2021-10-24T17:43:32+00:00\",\"dateModified\":\"2021-10-24T17:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\"},\"wordCount\":835,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\",\"coronavirus\",\"Covid-19\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\",\"name\":\"Le coronavirus entraine l'apparition de vaisseaux fant\u00f4mes dans le cerveau - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg\",\"datePublished\":\"2021-10-24T17:43:32+00:00\",\"dateModified\":\"2021-10-24T17:48:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionn ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg\",\"width\":797,\"height\":718,\"caption\":\"Le coronavirus entraine l'apparition de vaisseaux fant\u00f4mes dans le cerveau\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le coronavirus entraine l&#8217;apparition de vaisseaux fant\u00f4mes dans le cerveau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le coronavirus entraine l'apparition de vaisseaux fant\u00f4mes dans le cerveau - Congo-kinshasa","description":"Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionn ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau","og_locale":"fr_FR","og_type":"article","og_title":"Le coronavirus entraine l'apparition de vaisseaux fant\u00f4mes dans le cerveau","og_description":"Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionn ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau","og_site_name":"Congo-kinshasa","article_published_time":"2021-10-24T17:43:32+00:00","article_modified_time":"2021-10-24T17:48:00+00:00","og_image":[{"width":797,"height":718,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Le coronavirus entraine l&rsquo;apparition de vaisseaux fant\u00f4mes dans le cerveau","datePublished":"2021-10-24T17:43:32+00:00","dateModified":"2021-10-24T17:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau"},"wordCount":835,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa","coronavirus","Covid-19"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau","name":"Le coronavirus entraine l'apparition de vaisseaux fant\u00f4mes dans le cerveau - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg","datePublished":"2021-10-24T17:43:32+00:00","dateModified":"2021-10-24T17:48:00+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Pour la premi\u00e8re fois, des chercheurs mettent en \u00e9vidence un effet direct, et redoutable, du SARS-CoV-2 sur le fonctionn ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/10\/img-61759c2111b9e.jpg","width":797,"height":718,"caption":"Le coronavirus entraine l'apparition de vaisseaux fant\u00f4mes dans le cerveau"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/le-coronavirus-entraine-lapparition-de-vaisseaux-fantomes-dans-le-cerveau#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"Le coronavirus entraine l&#8217;apparition de vaisseaux fant\u00f4mes dans le cerveau"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/17253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=17253"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/17253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/17252"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=17253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=17253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=17253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}