{"id":2899,"date":"2021-04-28T18:05:38","date_gmt":"2021-04-28T18:05:38","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques"},"modified":"2021-04-28T20:18:52","modified_gmt":"2021-04-28T20:18:52","slug":"bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques","title":{"rendered":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong><a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a> &#8211; <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>. <\/strong><\/span><b>En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement (FOFECEGDD) a dress\u00e9 le monitoring de plus de 500 cas des violences domestiques entre mars et novembre. Ce 27 avril, l\u2019organisation a r\u00e9uni des leaders sociaux et communautaires en faveur d\u2019un plaidoyer \u00e0 propos de la n\u00e9cessit\u00e9 et la rapidit\u00e9 des mesures \u00e0 prendre de le cadre de la pr\u00e9vention et de la lutte.<\/b><\/p>\n<p>\u00ab Nous proc\u00e9dons en 2021 \u00e0 la phase II du projet de lutte contre les violences domestiques \u00e0 Kinshasa. Apr\u00e8s r\u00e9colte des donn\u00e9es sur l&rsquo;existence effective des violences domestiques, cette phase consiste en un plaidoyer qui a pour mission d\u2019amener les d\u00e9cideurs \u00e0 prendre des mesures urgentes en vue de pr\u00e9venir et lutter contre ces formes de violences \u00bb, a expliqu\u00e9 Marie Lukusa, coordonnatrice du Forum.<\/p>\n<p>En effet, le code p\u00e9nal congolais n\u2019est pas sp\u00e9cifique en ce qui concerne les violences domestiques. L\u2019atelier, organis\u00e9 pour le renforcement des capacit\u00e9s des organisations de la soci\u00e9t\u00e9 civile, des d\u00e9fenseures des droits humains et des leaders communautaires aboutira \u00e0 un plan d&rsquo;actions du plaidoyer pour la mise en place des mesures sp\u00e9cifiques.<\/p>\n<p>\u00ab Nous envisageons \u00e9galement de tenir un atelier avec les parlementaires, car nous voulons des r\u00e9sultats \u00e0 court, moyen et long terme. Nous souhaitons avoir une loi sur les violences domestiques en RDC \u00bb, a-t-elle ajout\u00e9.<\/p>\n<p>Au cours de la p\u00e9riode de l\u2019\u00e9tat d\u2019urgence sanitaire, le centre hospitalier Arc-en-ciel, situ\u00e9 dans la commune de Bumbu a assur\u00e9 la prise en charge m\u00e9dicale des 20 victimes des violences domestiques. Maleka Musaka G\u00e9nial, m\u00e9decin dudit centre a partag\u00e9 l\u2019exp\u00e9rience avec les participants avant d\u2019aborder la n\u00e9cessit\u00e9 des soins holistiques.<\/p>\n<p>\u00a0\u00bb Nous avons re\u00e7u des cas au cours de l&rsquo;ann\u00e9e derni\u00e8re. Les violences domestiques n\u00e9cessitent une prise en charge optimale. Cependant, nos h\u00f4pitaux et centres de sant\u00e9 sont parfois limit\u00e9s. Nous avons fait ce qui \u00e9tait n\u00e9cessaire, offrir des soins aux victimes, proposer un suivi m\u00e9dical. Mais par manque de moyens, la plupart d&rsquo;entre elles ne pouvaient pas b\u00e9n\u00e9ficier de tous les services. Certaines victimes pr\u00e9sentaient des l\u00e9sions et des troubles psychiques (&#8230;) Je pense que si nous n&rsquo;agissons pas le plus vite possible, les violences domestiques peuvent se transformer en un r\u00e9el probl\u00e8me de sant\u00e9 publique. Il faut un soutien financier qui permette de couvrir tous les besoins de sant\u00e9, jusqu\u2019\u00e0 la gu\u00e9rison totale des victimes\u00a0\u00bb, a-t-il affirm\u00e9.<\/p>\n<p>La femme n\u2019est pas la seule victime des violences domestiques<\/p>\n<p>Les cons\u00e9quences socio-\u00e9conomiques des violences domestiques sur les victimes ont \u00e9t\u00e9 pr\u00e9sent\u00e9s l&rsquo;activiste Pascaline Zamuda. Durant son expos\u00e9 o\u00f9 elle a parl\u00e9 des statistiques, Jean Claude Mulamba, avocat au barreau de Kananga a soulev\u00e9 une probl\u00e9matique. \u00ab Pourquoi faut-il \u00e0 chaque fois faire croire que la femme est l\u2019unique victime de toutes formes de violences qui se commettent \u00e0 domicile ?.\u00bb<\/p>\n<p>Question \u00e0 laquelle a r\u00e9pondu Pascaline Zamuda en sp\u00e9cifiant que le concept de \u00ab violences domestiques \u00bb para\u00eet encore assez flou pour certaines personnes. L&rsquo;\u00e9ducation aux droits sp\u00e9cifiques, aux violences bas\u00e9es sur le genre (VBG) n\u2019a pas encore progress\u00e9 de fa\u00e7on particuli\u00e8re dans la soci\u00e9t\u00e9 congolaise. C\u2019est ainsi que de nombreux cas, ne sont pas d\u00e9nonc\u00e9s.<\/p>\n<p>\u00ab Ce n\u2019est pas pour victimiser la femme que l\u2019on parle assez souvent des cas f\u00e9minins enregistr\u00e9s. Ce sont les faits. Observons autour de nous, dans nos familles, dans notre soci\u00e9t\u00e9, dans nos communaut\u00e9s, dans notre environnement. Nous verrons que les femmes constituent assez souvent le plus grand nombre des victimes \u00bb.<\/p>\n<p>Les violences domestiques peuvent \u00eatre physiques, psychologiques, sexuelles, \u00e9conomiques, culturelles, institutionnelles et politiques. Parmi les cons\u00e9quences \u00e9conomiques, elles engendrent la pauvret\u00e9. Les femmes sont priv\u00e9es de leurs droits d&rsquo;exercer une activit\u00e9 \u00e9conomique ou un travail salari\u00e9. Ce qui entraine des frustrations, des probl\u00e8mes psychologiques ou conduisent \u00e0 la d\u00e9pression.<\/p>\n<p>Elle a par ailleurs soulign\u00e9 que la loi qui sera mise en place, va sanctionner les hommes au m\u00eame titre que les femmes qui se rendront coupables des violences domestiques.<\/p>\n<p>\u00ab Au-del\u00e0 des sanctions, il faut surtout une sensibilisation, penser \u00e0 une autre mani\u00e8re de socialiser les hommes et les femmes d\u00e8s la petite enfance, dans tous les milieux. Nous devons avoir des cadres qui permettent aux hommes et aux femmes victimes de ces formes de violences de s\u2019y rendre pour trouver des orientations et des premiers soins.\u00bb<\/p>\n<p>A la fin de la premi\u00e8re journ\u00e9e, Furaha Sa\u00efdi, charg\u00e9 du genre dans la conf\u00e9d\u00e9ration nationale de la Jeunesse Islamique au Congo (CNJIC) s\u2019est \u00e9galement exprim\u00e9 sur la th\u00e9matique. \u00ab\u00a0c&rsquo;est un atelier qui nous a permis de comprendre qu&rsquo;en fait il y a vraiment des femmes qui subissent des violences sous le toit conjugal, qu&rsquo;il y a \u00e9galement les hommes et les enfants qui peuvent en \u00eatre victimes. La communaut\u00e9 islamique \u00e9galement conna\u00eet ces cas de violences \u00e9tant donn\u00e9 que nous vivons dans la soci\u00e9t\u00e9. Il faut alors des mesures qui accompagnent les victimes\u00a0\u00bb<\/p>\n<p>Ouvert le 27 Avril, l\u2019atelier va se cl\u00f4turer ce mercredi \u00e0 15 heures.<\/p>\n<p><b>Prisca Lokale<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement (FOFECEGDD) a dress\u00e9 le monitoring de plus de 500 cas des violences domestiques entre mars et novembre. Ce 27 avril, l\u2019organisation a r\u00e9uni des leaders sociaux et communautaires en faveur d\u2019un plaidoyer [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":2898,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11,10],"tags":[36,47,46],"class_list":["post-2899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>bient\u00f4t un plaidoyer de lutte contre les violences domestiques - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bient\u00f4t un plaidoyer de lutte contre les violences domestiques\" \/>\n<meta property=\"og:description\" content=\"En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-28T18:05:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-28T20:18:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"bient\u00f4t un plaidoyer de lutte contre les violences domestiques\",\"datePublished\":\"2021-04-28T18:05:38+00:00\",\"dateModified\":\"2021-04-28T20:18:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\"},\"wordCount\":908,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\",\"name\":\"bient\u00f4t un plaidoyer de lutte contre les violences domestiques - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg\",\"datePublished\":\"2021-04-28T18:05:38+00:00\",\"dateModified\":\"2021-04-28T20:18:52+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg\",\"width\":720,\"height\":540,\"caption\":\"bient\u00f4t un plaidoyer de lutte contre les violences domestiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"bient\u00f4t un plaidoyer de lutte contre les violences domestiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques - Congo-kinshasa","description":"En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques","og_locale":"fr_FR","og_type":"article","og_title":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques","og_description":"En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques","og_site_name":"Congo-kinshasa","article_published_time":"2021-04-28T18:05:38+00:00","article_modified_time":"2021-04-28T20:18:52+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques","datePublished":"2021-04-28T18:05:38+00:00","dateModified":"2021-04-28T20:18:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques"},"wordCount":908,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["Communaut\u00e9","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques","name":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg","datePublished":"2021-04-28T18:05:38+00:00","dateModified":"2021-04-28T20:18:52+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"En 2020, un rapport du Forum des Femmes citoyennes et engag\u00e9es pour la gouvernance, la d\u00e9mocratie et le d\u00e9veloppement ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#primaryimage","url":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg","contentUrl":"https:\/\/static.africa-press.net\/centrafricaine\/sites\/49\/2021\/04\/img-6089c31040740.jpg","width":720,"height":540,"caption":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/bientot-un-plaidoyer-de-lutte-contre-les-violences-domestiques#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"bient\u00f4t un plaidoyer de lutte contre les violences domestiques"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/2899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=2899"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/2899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/2898"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=2899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=2899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=2899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}