{"id":79833,"date":"2023-11-30T12:10:24","date_gmt":"2023-11-30T12:10:24","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique"},"modified":"2023-11-30T12:57:06","modified_gmt":"2023-11-30T12:57:06","slug":"elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique","title":{"rendered":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Congo Kinshasa. <\/strong><\/span>Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes prioritaires. Pour eux, les prochains dirigeants doivent stabiliser l\u2019e\u0301conomique du pays.<\/p>\n<p>Le 20 de\u0301cembre, jour du scrutin en RDC, approche a\u0300 grands pas. A\u0300 Lubumbashi, les avis divergent sur ce que doivent e\u0302tre les priorite\u0301s de ces derniers sur le plan e\u0301conomique. La population attend, par exemple, la baisse du taux de change sur le marche\u0301, la rele\u0300ve des entreprises de l\u2019E\u0301tat et la cre\u0301ation d\u2019emplois.<\/p>\n<p>Taux de change et re\u0301duction du cho\u0302mage<\/p>\n<p>Depuis quelque temps, le taux de change peine a\u0300 se stabiliser. Par exemple, entre le mois de mai et juillet 2023, le franc congolais s\u2019est de\u0301pre\u0301cie\u0301 de 16 %. Gloire Mwamba est e\u0301tudiante en licence a\u0300 l\u2019universite\u0301 de Lubumbashi. Pour elle, les nouveaux e\u0301lus doivent se pencher sur cette question.<\/p>\n<p>\u00ab\u00a0Nous attendons des dirigeants qui tiennent compte de nos re\u0301alite\u0301s actuelles\u00a0\u00bb. Nous avons besoin qu\u2019ils baissent le taux de change sur le marche\u0301. Notre monnaie se de\u0301pre\u0301cie davantage et cela ne nous arrange pas. Et d\u2019ajouter, \u00ab\u00a0la de\u0301pre\u0301ciation de notre monnaie perturbe la vie sociale et notre e\u0301conomie\u00a0\u00bb. Tout est cher sur le marche\u0301 actuellement. La vie cou\u0302te cher. Il nous est difficile de subvenir a\u0300 nos besoins ces jours-ci\u00a0\u00bb.<\/p>\n<p>Pour d\u2019autres, la priorite\u0301 est de re\u0301sorber le cho\u0302mage. C\u2019est ce que pense Gabriel Kunda, conducteur de taxi moto a\u0300 Lubumbashi. \u00ab\u00a0En premie\u0300re position, ceux qui seront a\u0300 la te\u0302te du pays doivent re\u0301duire le taux de cho\u0302mage. Qu\u2019ils cre\u0301ent des emplois pour recruter des jeunes. La plupart de nos dirigeants ne prennent que les me\u0302mes personnes pour gouverner. Les jeunes ne sont pas nombreux dans les institutions publiques\u00a0\u00bb.<\/p>\n<p>Pour sa part, Prince Ngeleka, vendeur de charbon au quartier Karavia, pense que pour y arriver, il faut relever les entreprises publiques. \u00ab\u00a0Nous voulons voir la Miba et la Ge\u0301camines fonctionner comme il faut. Si les nouveaux dirigeants font de cela une priorite\u0301, les jeunes vont se retrouver. Le taux de cho\u0302mage va baisser au pays\u00a0\u00bb.<\/p>\n<p>Il faut noter que les priorite\u0301s sur le plan e\u0301conomique sont e\u0301normes. Et les prochains dirigeants auront du pain sur la planche.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes prioritaires. Pour eux, les prochains dirigeants doivent stabiliser l\u2019e\u0301conomique du pays. Le 20 de\u0301cembre, jour du scrutin en RDC, approche a\u0300 grands pas. A\u0300 Lubumbashi, les avis divergent sur ce que [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":79831,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[36,47,46],"class_list":["post-79833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ? - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes pr ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?\" \/>\n<meta property=\"og:description\" content=\"Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes pr ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T12:10:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-30T12:57:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?\",\"datePublished\":\"2023-11-30T12:10:24+00:00\",\"dateModified\":\"2023-11-30T12:57:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\"},\"wordCount\":435,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"\u00c9conomie\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\",\"name\":\"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ? - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg\",\"datePublished\":\"2023-11-30T12:10:24+00:00\",\"dateModified\":\"2023-11-30T12:57:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes pr ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg\",\"width\":720,\"height\":409,\"caption\":\"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ? - Congo-kinshasa","description":"Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes pr ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?","og_description":"Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes pr ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique","og_site_name":"Congo-kinshasa","article_published_time":"2023-11-30T12:10:24+00:00","article_modified_time":"2023-11-30T12:57:06+00:00","og_image":[{"width":720,"height":409,"url":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?","datePublished":"2023-11-30T12:10:24+00:00","dateModified":"2023-11-30T12:57:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique"},"wordCount":435,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["\u00c9conomie","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique","name":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ? - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg","datePublished":"2023-11-30T12:10:24+00:00","dateModified":"2023-11-30T12:57:06+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les Congolais espe\u0300rent voir l\u2019e\u0301conomie de la RDC e\u0302tre redresse\u0301e. La vie che\u0300re et le cho\u0302mage sont parmi les axes pr ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#primaryimage","url":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg","contentUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701336033.240788.jpg","width":720,"height":409,"caption":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/economie\/elections-rdc-quelles-sont-les-priorites-sur-le-plan-economique#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"\u00c9lections-RDC : quelles sont les priorit\u00e9s sur le plan \u00e9conomique ?"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/79833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=79833"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/79833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/79831"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=79833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=79833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=79833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}