{"id":79910,"date":"2023-11-30T16:35:57","date_gmt":"2023-11-30T16:35:57","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/?p=79910"},"modified":"2024-07-09T07:32:26","modified_gmt":"2024-07-09T07:32:26","slug":"helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars","title":{"rendered":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Congo Kinshasa. <\/strong><\/span>Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301ration capables de surpasser les performances d\u2019Ingenuity. Tandis que ce dernier continue d\u2019e\u0301tablir des records de vitesse et d\u2019altitude lors de ses explorations dans le crate\u0300re Jezero de la plane\u0300te rouge, des tests sur Terre visent en paralle\u0300le a\u0300 perfectionner des pales en fibre de carbone.<\/p>\n<p>Repousser les limites<\/p>\n<p>Les conditions atmosphe\u0301riques particulie\u0300res de Mars, caracte\u0301rise\u0301es par une pression atmosphe\u0301rique conside\u0301rablement re\u0301duite et une gravite\u0301 moindre par rapport a\u0300 la Terre, imposent des de\u0301fis significatifs pour la conception des engins spatiaux. Dans ce contexte, l\u2019he\u0301licopte\u0300re Ingenuity de la NASA, e\u0301quipe\u0301 de quatre pales en fibre de carbone organise\u0301es en deux rotors contrarotatifs, a re\u0301ussi a\u0300 ope\u0301rer avec succe\u0300s sur la plane\u0300te rouge. Ses rotations, variant entre 2 400 et 2 900 tr\/min, ont permis des vols efficaces malgre\u0301 les conditions martiennes uniques.<\/p>\n<p>De\u0301sormais, dans l\u2019optique de futures missions martiennes, les inge\u0301nieurs du Jet Propulsion Laboratory (JPL) de la NASA a\u0300 Pasadena travaillent sur des ve\u0301hicules e\u0301quipe\u0301s de pales plus longues. Ces ajustements visent a\u0300 maximiser les performances de vol dans l\u2019environnement spe\u0301cifique de Mars.<\/p>\n<p>Ces pales ont re\u0301cemment fait l\u2019objet de plusieurs essais au cours desquels elles ont e\u0301te\u0301 teste\u0301es jusqu\u2019a\u0300 3 500 tr\/min, soit 750 tr\/min de plus que celles d\u2019Ingenuity, le but e\u0301tant de repousser les limites actuelles et de pre\u0301parer le terrain pour des missions plus avance\u0301es, comme celle visant a\u0300 rapporter des e\u0301chantillons martiens sur Terre.<\/p>\n<p>Des appuis indispensables<\/p>\n<p>Pour rappel, le rover Perseverance, qui est au coeur de cette entreprise, a de\u0301ja\u0300 pre\u0301leve\u0301 plusieurs e\u0301chantillons rocheux lors de son exploration du crate\u0300re Jezero. Il se concentre de\u0301sormais sur un delta de rivie\u0300re asse\u0301che\u0301, un site prometteur pour la pre\u0301servation de signes de vie ancienne.<\/p>\n<p>Initialement, le plan impliquait l\u2019envoi d\u2019un rover de l\u2019agence spatiale europe\u0301enne (ESA) pour re\u0301cupe\u0301rer les e\u0301chantillons laisse\u0301s par Perseverance, puis les transporter vers un atterrisseur. Ces e\u0301chantillons devaient e\u0302tre charge\u0301s sur une petite fuse\u0301e et lance\u0301s en orbite martienne, ou\u0300 un autre vaisseau spatial les aurait re\u0301cupe\u0301re\u0301s pour les ramener sur Terre. Toutefois, des ajustements ont e\u0301te\u0301 apporte\u0301s re\u0301cemment, e\u0301liminant le rover de re\u0301cupe\u0301ration. De\u0301sormais, Perseverance prendra en charge la remise de ses e\u0301chantillons a\u0300 un atterrisseur qui les placera ensuite dans la fuse\u0301e de retour.<\/p>\n<p>La mission ne ne\u0301cessitera ainsi qu\u2019un seul atterrisseur, simplifiant l\u2019architecture. Cependant, pour garantir la re\u0301ussite de la mission, deux nouveaux he\u0301licopte\u0300res seront aussi probablement de\u0301ploye\u0301s en tant qu\u2019options de secours en cas de proble\u0300me avec Perseverance. Ces he\u0301licopte\u0300res, dont les pa\u0302les ont re\u0301cemment e\u0301te\u0301 teste\u0301es, seront e\u0301galement e\u0301quipe\u0301s de petites roues pour re\u0301cupe\u0301rer les e\u0301chantillons au sol en cas de besoin.<\/p>\n<p>Au-dela\u0300 de cette mission de re\u0301cupe\u0301ration, l\u2019envoi d\u2019he\u0301licopte\u0300res sur Mars pourrait avoir d\u2019autres avantages en matie\u0300re d\u2019exploration. Ces ve\u0301hicules pourront en effet surmonter les obstacles et les terrains difficiles plus facilement que les rovers. Ils pourront ainsi atteindre des zones autrement inaccessibles.<\/p>\n<p>Les he\u0301licopte\u0300res offrent e\u0301galement une vue d\u2019ensemble, permettant une reconnaissance ae\u0301rienne rapide des zones d\u2019inte\u0301re\u0302t. De cette manie\u0300re, ils pourraient servir de scouts en examinant les environs pour aider a\u0300 la planification des itine\u0301raires des rovers.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301ration capables de surpasser les performances d\u2019Ingenuity. Tandis que ce dernier continue d\u2019e\u0301tablir des records de vitesse et d\u2019altitude lors de ses explorations dans le crate\u0300re Jezero de la plane\u0300te rouge, des tests sur Terre visent en [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":79909,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[36,47,46],"class_list":["post-79910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301rati ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars\" \/>\n<meta property=\"og:description\" content=\"Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301rati ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T16:35:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-09T07:32:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"913\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars\",\"datePublished\":\"2023-11-30T16:35:57+00:00\",\"dateModified\":\"2024-07-09T07:32:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\"},\"wordCount\":671,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\",\"name\":\"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg\",\"datePublished\":\"2023-11-30T16:35:57+00:00\",\"dateModified\":\"2024-07-09T07:32:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301rati ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg\",\"width\":913,\"height\":620,\"caption\":\"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars - Congo-kinshasa","description":"Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301rati ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars","og_locale":"fr_FR","og_type":"article","og_title":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars","og_description":"Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301rati ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars","og_site_name":"Congo-kinshasa","article_published_time":"2023-11-30T16:35:57+00:00","article_modified_time":"2024-07-09T07:32:26+00:00","og_image":[{"width":913,"height":620,"url":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars","datePublished":"2023-11-30T16:35:57+00:00","dateModified":"2024-07-09T07:32:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars"},"wordCount":671,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars","name":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg","datePublished":"2023-11-30T16:35:57+00:00","dateModified":"2024-07-09T07:32:26+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les inge\u0301nieurs de la NASA travaillent activement sur le de\u0301veloppement d\u2019he\u0301licopte\u0300res martiens de nouvelle ge\u0301ne\u0301rati ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#primaryimage","url":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg","contentUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/11\/sm_1701351509.177373.jpg","width":913,"height":620,"caption":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/helicopteres-la-nasa-teste-ses-pales-de-nouvelle-generation-pour-survoler-mars#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"H\u00e9licopt\u00e8res : la NASA teste ses pales de nouvelle g\u00e9n\u00e9ration pour survoler Mars"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/79910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=79910"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/79910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/79909"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=79910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=79910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=79910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}