{"id":80225,"date":"2023-12-04T21:55:59","date_gmt":"2023-12-04T21:55:59","guid":{"rendered":"https:\/\/www.africa-press.net\/congo-kinshasa\/politique\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures"},"modified":"2023-12-04T21:59:56","modified_gmt":"2023-12-04T21:59:56","slug":"podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures","title":{"rendered":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&rsquo;est de la faute de nos chaussures"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; Congo Kinshasa. <\/strong><\/span>Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classique d\u2019appeler le mal du sie\u0300cle aligne toujours les me\u0302mes facteurs: la se\u0301dentarite\u0301, le stress, le surpoids&#8230; Mais on oublie souvent celles qui nous relient au sol, les chaussures. Bienvenue dans le monde des adeptes des chaussures dites minimalistes.<\/p>\n<p>Comment les chaussures finissent par affecter notre e\u0301quilibre<\/p>\n<p>Pour son 121e e\u0301pisode, Sixie\u0300me Science, le podcast scientifique de Sciences et Avenir et 20 minutes, vous explique comment celles que nous portons plus de 10 heures par jour finissent par affecter notre e\u0301quilibre. Au micro, Herve\u0301 Ratel, journaliste scientifique a\u0300 Sciences et Avenir, re\u0301pond aux questions de Romain Gouloume\u0300s de 20 minutes.<\/p>\n<p>Le journaliste vous raconte l&rsquo;origine d\u2019un mouvement ne\u0301 il y a une quinzaine d\u2019anne\u0301es, initie\u0301 par des sportifs qui se sont blesse\u0301s, et ont fini par s\u2019interroger sur ce qu\u2019ils portaient a\u0300 leurs pieds.<\/p>\n<p>En clair, les chaussures dites modernes (ou \u00ab\u00a0sneakers\u00a0\u00bb) souffrent de quatre faiblesses majeures: un talon inadapte\u0301, une pointe trop e\u0301trique\u0301e, une semelle qui, en nous isolant trop du sol, affaiblit nos capteurs dits proprioceptifs et enfin une rigidite\u0301 contraignant les mouvements. Comment s\u2019en sortir ? En optant pour les chaussures molles dites aussi minimalistes (\u00ab\u00a0barefoot\u00a0\u00bb).<\/p>\n<p>Elles inte\u0301ressent par exemple les Japonais qui, en 2021, ont suivi pendant quatre ans une centaine d\u2019enfants chausse\u0301s ou pas de ce type de chaussures. Apre\u0300s avoir surveille\u0301 attentivement leur de\u0301marche et leur course, ils ont fini par de\u0301montrer que les performances biome\u0301caniques du groupe ayant opte\u0301 pour les chaussures minimalistes e\u0301taient supe\u0301rieures a\u0300 l&rsquo;autre groupe.<\/p>\n<p>40% de la population souffrent de pieds plats<\/p>\n<p>En e\u0301coutant cet e\u0301pisode, vous saurez e\u0301galement tout des travaux de mode\u0301lisation mene\u0301s par d\u2019autres chercheurs qui eux e\u0301tudient le poids des pieds, le choc des talons. Et apprendrez, si vous souffrez de pieds plats comme 40% de la population, que l\u2019origine n\u2019est ge\u0301ne\u0301tique que dans 5%.<\/p>\n<p>En attendant de courir comme les Tarahumaras du Mexique, capables de parcourir l\u2019e\u0301quivalent de 12 marathons (500 km) en moins de 36 heures, vous pourrez trouver le temps de lire l\u2019article \u00ab\u00a0Mal de dos: la faute aux chaussures\u00a0\u00bb ou de consulter l\u2019inte\u0301gralite\u0301 des archives de Sixie\u0300me Science et vous abonner gratuitement sur Apple Podcast.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/congo-kinshasa\">Congo Kinshasa<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; Congo Kinshasa. Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classique d\u2019appeler le mal du sie\u0300cle aligne toujours les me\u0302mes facteurs: la se\u0301dentarite\u0301, le stress, le surpoids&#8230; Mais on oublie souvent celles qui nous relient au sol, les chaussures. Bienvenue [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":80224,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[36,47,46],"class_list":["post-80225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-congo-kinshasa","tag-congo-kinshasa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&#039;est de la faute de nos chaussures - Congo-kinshasa<\/title>\n<meta name=\"description\" content=\"Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classiqu ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&#039;est de la faute de nos chaussures\" \/>\n<meta property=\"og:description\" content=\"Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classiqu ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\" \/>\n<meta property=\"og:site_name\" content=\"Congo-kinshasa\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-04T21:55:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-04T21:59:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&rsquo;est de la faute de nos chaussures\",\"datePublished\":\"2023-12-04T21:55:59+00:00\",\"dateModified\":\"2023-12-04T21:59:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\"},\"wordCount\":445,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-Congo Kinshasa\",\"Congo Kinshasa\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\",\"name\":\"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c'est de la faute de nos chaussures - Congo-kinshasa\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg\",\"datePublished\":\"2023-12-04T21:55:59+00:00\",\"dateModified\":\"2023-12-04T21:59:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classiqu ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg\",\"width\":1200,\"height\":899,\"caption\":\"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c'est de la faute de nos chaussures\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&#8217;est de la faute de nos chaussures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#website\",\"url\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/\",\"name\":\"Congo-kinshasa\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c'est de la faute de nos chaussures - Congo-kinshasa","description":"Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classiqu ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures","og_locale":"fr_FR","og_type":"article","og_title":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c'est de la faute de nos chaussures","og_description":"Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classiqu ...","og_url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures","og_site_name":"Congo-kinshasa","article_published_time":"2023-12-04T21:55:59+00:00","article_modified_time":"2023-12-04T21:59:56+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&rsquo;est de la faute de nos chaussures","datePublished":"2023-12-04T21:55:59+00:00","dateModified":"2023-12-04T21:59:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures"},"wordCount":445,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg","keywords":["Africa Press","Africa Press-Congo Kinshasa","Congo Kinshasa"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures","name":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c'est de la faute de nos chaussures - Congo-kinshasa","isPartOf":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg","datePublished":"2023-12-04T21:55:59+00:00","dateModified":"2023-12-04T21:59:56+00:00","author":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Vous avez mal au dos ? Changez de chaussures. En effet, la liste des agents responsables de ce qu\u2019il est devenu classiqu ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#primaryimage","url":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg","contentUrl":"https:\/\/static.africa-press.net\/congo-kinshasa\/sites\/49\/2023\/12\/sm_1701714410.738032.jpg","width":1200,"height":899,"caption":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c'est de la faute de nos chaussures"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/toutes-les-actualites\/podcast-sixieme-science-episode-121-mal-de-dos-pourquoi-cest-de-la-faute-de-nos-chaussures#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/congo-kinshasa\/"},{"@type":"ListItem","position":2,"name":"PODCAST. Sixi\u00e8me Science, \u00e9pisode 121 : mal de dos, pourquoi c&#8217;est de la faute de nos chaussures"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#website","url":"https:\/\/www.africa-press.net\/congo-kinshasa\/","name":"Congo-kinshasa","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/congo-kinshasa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/congo-kinshasa\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/80225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/comments?post=80225"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/posts\/80225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media\/80224"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/media?parent=80225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/categories?post=80225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/congo-kinshasa\/wp-json\/wp\/v2\/tags?post=80225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}