{"id":20825,"date":"2021-11-22T18:26:24","date_gmt":"2021-11-22T18:26:24","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/?p=20825"},"modified":"2021-11-22T16:39:46","modified_gmt":"2021-11-22T16:39:46","slug":"cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes","title":{"rendered":"C\u00f4te d&rsquo;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>vue des rues de Yopougon de l&rsquo;int\u00e9rieur d&rsquo;un taxi-compteur ce lundi (Ph KOACI)<\/p>\n<p>Difficile de sortir de la plus grande commune d&rsquo;Abidjan ce lundi 22 novembre 2021.<\/p>\n<p>Pour cause, les chauffeurs de taxis communaux et les mini-cars de transport commun\u00e9ment appel\u00e9s \u00ab\u00a0Gbakas\u00a0\u00bb sont en gr\u00e8ve.<\/p>\n<p>Ils ont d\u00e9cid\u00e9 d&rsquo;observer un arr\u00eat de travail de 72 heures pour protester contre les taxes communaux exorbitants.<\/p>\n<p>Les responsables des gr\u00e9vistes d\u00e9noncent le fait qu&rsquo;en plus du co\u00fbt \u00e9lev\u00e9 de la carte de stationnement, des papillons, la mairie leur impose une taxe (papillon) qui varie entre 5000 FCFA et 50.000 FCFA.<\/p>\n<p>Ces chauffeurs de taxis communaux et \u00ab\u00a0Gbakas\u00a0\u00bb ont d\u00e9cid\u00e9 d&rsquo;observer un arr\u00eat de travail de 72 heures.<\/p>\n<p>Une situation de gr\u00e8ve g\u00e9n\u00e9ralement observ\u00e9e dans la commune de Yopougon qui fait que les usagers ont eu du mal \u00e0 regagner pour la plupart leurs lieux de travail ce jour.<\/p>\n<p>Cliquez pour agrandir l&rsquo;image<\/p>\n<p>Jean Chresus, Abidjan<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. vue des rues de Yopougon de l&rsquo;int\u00e9rieur d&rsquo;un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande commune d&rsquo;Abidjan ce lundi 22 novembre 2021. Pour cause, les chauffeurs de taxis communaux et les mini-cars de transport commun\u00e9ment appel\u00e9s \u00ab\u00a0Gbakas\u00a0\u00bb sont en gr\u00e8ve. Ils ont d\u00e9cid\u00e9 d&rsquo;observer un arr\u00eat [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":20824,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11,10],"tags":[56,63,978,29,2773,554,2772,2219,540],"class_list":["post-20825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-chauffeur","tag-cote-divoire","tag-gbaka","tag-greve","tag-taxe","tag-taxi","tag-yopougon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f4te d&#039;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"vue des rues de Yopougon de l&#039;int\u00e9rieur d&#039;un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande co ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f4te d&#039;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes\" \/>\n<meta property=\"og:description\" content=\"vue des rues de Yopougon de l&#039;int\u00e9rieur d&#039;un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande co ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-22T18:26:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"C\u00f4te d&rsquo;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes\",\"datePublished\":\"2021-11-22T18:26:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\"},\"wordCount\":209,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"chauffeur\",\"C\u00d4TE D'IVOIRE\",\"Gbaka\",\"gr\u00e8ve\",\"taxe\",\"taxi\",\"Yopougon\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\",\"name\":\"C\u00f4te d'Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg\",\"datePublished\":\"2021-11-22T18:26:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"vue des rues de Yopougon de l'int\u00e9rieur d'un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande co ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg\",\"width\":720,\"height\":540,\"caption\":\"C\u00f4te d'Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f4te d&#8217;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f4te d'Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes - C\u00f4te d&#039;Ivoire","description":"vue des rues de Yopougon de l'int\u00e9rieur d'un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande co ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f4te d'Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes","og_description":"vue des rues de Yopougon de l'int\u00e9rieur d'un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande co ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2021-11-22T18:26:24+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"C\u00f4te d&rsquo;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes","datePublished":"2021-11-22T18:26:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes"},"wordCount":209,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","chauffeur","C\u00d4TE D'IVOIRE","Gbaka","gr\u00e8ve","taxe","taxi","Yopougon"],"articleSection":["Communaut\u00e9","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes","url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes","name":"C\u00f4te d'Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg","datePublished":"2021-11-22T18:26:24+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"vue des rues de Yopougon de l'int\u00e9rieur d'un taxi-compteur ce lundi (Ph KOACI) Difficile de sortir de la plus grande co ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/11\/img-619bc7a2dd52f.jpg","width":720,"height":540,"caption":"C\u00f4te d'Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/cote-divoire-yopougon-greve-des-taxis-communaux-et-des-mini-cars-gbakas-pour-protester-contre-les-taxes-communales-exorbitantes#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"C\u00f4te d&#8217;Ivoire : Yopougon, gr\u00e8ve des taxis communaux et des mini-cars (Gbakas) pour protester contre les taxes communales exorbitantes"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/20825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=20825"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/20825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/20824"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=20825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=20825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=20825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}