{"id":21909,"date":"2021-12-02T13:49:33","date_gmt":"2021-12-02T13:49:33","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/des-fissures-decouvertes-sur-un-module-russe-de-liss"},"modified":"2021-12-02T16:10:15","modified_gmt":"2021-12-02T16:10:15","slug":"des-fissures-decouvertes-sur-un-module-russe-de-liss","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss","title":{"rendered":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres fissures pourtant superficielles ont \u00e9t\u00e9 d\u00e9couvertes dans le module Zarya, le plus ancien du segment russe de l\u2019ISS.<\/p>\n<p>\u00abL\u2019\u00e9tat actuel du segment russe de l&rsquo;ISS soul\u00e8ve des inqui\u00e9tudes\u00bb, a d\u00e9clar\u00e9 \u00e0 Sputnik le 30 ao\u00fbt Vladimir Soloviev, directeur de vol de ce segment et ing\u00e9nieur en chef de RKK Energuia, qui pointe la n\u00e9cessit\u00e9 de construire une nouvelle station spatiale russe. Il a notamment \u00e9voqu\u00e9 pour la premi\u00e8re fois la pr\u00e9sence \u00abde quelques fissures superficielles\u00bb dans le module Zarya qui date de 1998.<\/p>\n<p>En r\u00e9action le directeur g\u00e9n\u00e9ral de Roscosmos Dmitri Rogozine a pr\u00e9cis\u00e9 sur Twitter que les cosmonautes avaient d\u00e9j\u00e0 re\u00e7u l&rsquo;\u00e9quipement pour \u00abmener une \u00e9tude de l&rsquo;\u00e9tat de la coque du segment russe et d\u00e9terminer si ce dont parle Soloviev est des \u00ab\u00a0fissures superficielles\u00a0\u00bb ou simplement des \u00e9gratignures r\u00e9colt\u00e9es au fil des ann\u00e9es de fonctionnement\u00bb.<\/p>\n<p>Parlant de la fuite d\u2019oxyg\u00e8ne d\u00e9couverte en septembre 2019 dans le module Zvezda, Vladimir Soloviev a indiqu\u00e9 que son origine pr\u00e9cise n\u2019a pas \u00e9t\u00e9 d\u00e9termin\u00e9e. Selon lui, il est tr\u00e8s probable que lors de la construction du module la technologie de soudage n\u2019a pas \u00e9t\u00e9 respect\u00e9e.<\/p>\n<p>\u00ab\u00c0 l\u2019\u00e9poque tout \u00e9tait soud\u00e9 \u00e0 la main, et quelque part le soudeur pouvait s&rsquo;arr\u00eater, s&rsquo;attarder, puis, comme l&rsquo;alliage aluminium-magn\u00e9sium se trouve dans le vide depuis longtemps, les jointures peuvent devenir poreuses. Ajoutons \u00e0 cela les vibrations internes [\u2026] et des ph\u00e9nom\u00e8nes de r\u00e9sonance\u00bb, a-t-il expliqu\u00e9.<\/p>\n<p>Il a d\u2019ailleurs confirm\u00e9 qu\u2019environ 80% des syst\u00e8mes du module Zvezda avaient d\u00e9pass\u00e9 leur dur\u00e9e de service, l&rsquo;exploitation de la station apr\u00e8s 2025 devenant \u00abune entreprise tr\u00e8s risqu\u00e9e\u00bb. Et d\u2019ajouter:<\/p>\n<p>En octobre 2020, Vladimir Soloviev avait d\u00e9j\u00e0 signal\u00e9 que des sp\u00e9cialistes pr\u00e9voyaient \u00abune avalanche de d\u00e9faillances\u00bb \u00e0 bord de l&rsquo;ISS apr\u00e8s 2025. Le 20 avril Dmitri Rogozine a annonc\u00e9 que la Russie proc\u00e9dait \u00e0 la construction du premier module de sa future station orbitale.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres fissures pourtant superficielles ont \u00e9t\u00e9 d\u00e9couvertes dans le module Zarya, le plus ancien du segment russe de l\u2019ISS. \u00abL\u2019\u00e9tat actuel du segment russe de l&rsquo;ISS soul\u00e8ve des inqui\u00e9tudes\u00bb, a d\u00e9clar\u00e9 \u00e0 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":21908,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,11,10],"tags":[56,63,29,3062],"class_list":["post-21909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-cote-divoire","tag-fissures"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS\" \/>\n<meta property=\"og:description\" content=\"Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T13:49:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T16:10:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS\",\"datePublished\":\"2021-12-02T13:49:33+00:00\",\"dateModified\":\"2021-12-02T16:10:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\"},\"wordCount\":403,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"C\u00d4TE D'IVOIRE\",\"fissures\"],\"articleSection\":[\"Divers\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\",\"name\":\"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg\",\"datePublished\":\"2021-12-02T13:49:33+00:00\",\"dateModified\":\"2021-12-02T16:10:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS - C\u00f4te d&#039;Ivoire","description":"Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss","og_locale":"fr_FR","og_type":"article","og_title":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS","og_description":"Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2021-12-02T13:49:33+00:00","article_modified_time":"2021-12-02T16:10:15+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS","datePublished":"2021-12-02T13:49:33+00:00","dateModified":"2021-12-02T16:10:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss"},"wordCount":403,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","C\u00d4TE D'IVOIRE","fissures"],"articleSection":["Divers","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss","url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss","name":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg","datePublished":"2021-12-02T13:49:33+00:00","dateModified":"2021-12-02T16:10:15+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Alors que la fuite d\u2019air d\u00e9tect\u00e9 dans le module russe Zvezda ne stoppe pas malgr\u00e9 les efforts des cosmonautes, d\u2019autres ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2021\/12\/img-61a8efb357a42.jpg","width":1920,"height":1080,"caption":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-fissures-decouvertes-sur-un-module-russe-de-liss#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Des fissures d\u00e9couvertes sur un module russe de l\u2019ISS"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/21909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=21909"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/21909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/21908"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=21909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=21909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=21909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}