{"id":31062,"date":"2022-03-25T18:26:37","date_gmt":"2022-03-25T18:26:37","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/?p=31062"},"modified":"2022-03-25T17:28:16","modified_gmt":"2022-03-25T17:28:16","slug":"polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais","title":{"rendered":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&rsquo;id\u00e9e de ce d\u00e9cret n&rsquo;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span><b>Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI)<\/b><\/p>\n<p>Les d\u00e9tenteurs de droit d\u2019attribution ou de concession provisoire sur les terrains urbains non immatricul\u00e9s, non mis en valeur ou insuffisamment mis en valeur, doivent \u00e0 compter de l\u2019entr\u00e9e en vigueur de la loi n\u00b0624 du 14 ao\u00fbt 2020 instituant Code de l\u2019Urbanisme et du Domaine Foncier Urbain, au titre des dispositions transitoires, proc\u00e9der \u00e0 leur immatriculation et\/ou mise en valeur, sous peine de d\u00e9ch\u00e9ance de leurs droits. Cette disposition de la loi est pr\u00e9vue par les articles 295 \u00e0 299.<\/p>\n<p>C\u2019est pour encadrer les contours de cette loi que le d\u00e9cret n\u00b02021-783 du 08 d\u00e9cembre 2021 est intervenu pour d\u00e9terminer la proc\u00e9dure et les modalit\u00e9s de la d\u00e9ch\u00e9ance et de l\u2019acquisition des terrains concern\u00e9s. Ainsi, en vertu de l\u2019article 1 dudit d\u00e9cret d\u2019application, la proc\u00e9dure concerne les parcelles de terrains du domaine priv\u00e9 de l\u2019Etat ayant conf\u00e9r\u00e9 des droits d\u2019attribution ou de concession provisoires (lettres d\u2019attribution et arr\u00eat\u00e9s de concession provisoire), non mis en valeur ou insuffisamment mis en valeur.<\/p>\n<p>Depuis quelques jours, ce d\u00e9cret suscite des pol\u00e9miques au sein de l\u2019opinion publique, car il s\u2019agirait pour plusieurs observateurs d\u2019une ruse de l\u2019Etat pour d\u00e9poss\u00e9der des citoyens de leurs biens.<\/p>\n<p>Face \u00e0 ces pol\u00e9miques incessantes entretenues sur Internet et dans certains m\u00e9dias, Bruno Kon\u00e9, Ministre de la Construction, du Logement et de l\u2019Urbanisme (MCLU) a voulu lever un coin de voile sur cette affaire.<\/p>\n<p>Lors de la c\u00e9r\u00e9monie de remise des engins roulants aux agents r\u00e9gionaux et d\u00e9partementaux du MCLU le mercredi 23 mars 2022 au Plateau, comme sur place constat\u00e9 par KOACI, le Ministre Bruno Kon\u00e9 s\u2019est p\u00e9dagogiquement \u00e9vertu\u00e9 \u00e0 expliquer les dispositions de ce d\u00e9cret pour mettre fin \u00e0 toutes les interpr\u00e9tations erron\u00e9es.<\/p>\n<p>Ainsi, pour le d\u00e9put\u00e9 de Kouto, sont exclus du champ d\u2019application de ces textes les terrains urbains d\u00e9tenus en pleine propri\u00e9t\u00e9 (objet d\u2019ACD, de CPF, de CMPF) ainsi que les terrains urbains d\u00e9j\u00e0 b\u00e2tis.<\/p>\n<p>Il a indiqu\u00e9 que ne sont pas concern\u00e9s par cette proc\u00e9dure les terrains urbains sur lesquels s\u2019exercent des droits coutumiers d\u2019usage dans les centres urbains ou leur zone d\u2019am\u00e9nagement diff\u00e9r\u00e9 et n\u2019ayant pas fait l\u2019objet d\u2019acte administratif cr\u00e9ateur de droit pr\u00e9caire.<\/p>\n<p>\u00ab Il s\u2019agit premi\u00e8rement des terrains sur lesquels aucune d\u00e9marche n\u2019a \u00e9t\u00e9 entam\u00e9e depuis 2013, pour une demande d\u2019Acd , de terrains sur lesquels aucun d\u00e9but de mise en valeur n\u2019a \u00e9t\u00e9 constat\u00e9 depuis 2013, autrement dit tous les terrains sur lesquels des demandes d\u2019actes de propri\u00e9t\u00e9 ont \u00e9t\u00e9 faites depuis cette \u00e9poque et que ces actes aient \u00e9t\u00e9 obtenus ou pas, ces parcelles ne sont pas concern\u00e9es par la mesure. L\u2019id\u00e9e de ce d\u00e9cret n\u2019est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais plut\u00f4t de les inciter d\u2019une part, \u00e0 solliciter les actes de propri\u00e9t\u00e9s pour aider l\u2019Etat \u00e0 r\u00e9aliser la mise en \u0153uvre du Syst\u00e8me de Gestion Int\u00e9gr\u00e9 du Foncier Urbain et d\u2019autre part, pour les conduire \u00e0 mettre ces parcelles en valeur pour respecter la coh\u00e9rence des plans d\u2019urbanisme ; et \u00e9viter de cr\u00e9er des poches d\u2019ins\u00e9curit\u00e9 dans les villes concern\u00e9es \u00bb, a expliqu\u00e9 Bruno Kon\u00e9.<\/p>\n<p>Pour le Ministre, ce d\u00e9cret vise plut\u00f4t \u00e0 \u00ab inciter les d\u00e9tenteurs de lettres d\u2019attributions et d\u2019arr\u00eat\u00e9s de concession provisoire \u00e0 initier la proc\u00e9dure de d\u00e9livrance de l\u2019Arr\u00eat\u00e9 de Concession D\u00e9finitive afin de s\u00e9curiser leurs biens immobiliers ; rem\u00e9dier \u00e0 la disharmonie urbaine provoqu\u00e9e par la pr\u00e9sence de b\u00e2timents inachev\u00e9s et de parcelles non mises en valeur jouxtant des constructions achev\u00e9es et habit\u00e9es et constituant un risque sanitaire et une source d\u2019ins\u00e9curit\u00e9 pour les riverains ; analyser et \u00e9ventuellement faire droit aux requ\u00eates l\u00e9gitimes adress\u00e9es par des personnes ayant int\u00e9r\u00eat \u00e0 la mise en \u0153uvre de la proc\u00e9dure de d\u00e9ch\u00e9ance aux fins d\u2019actualisation de la base de donn\u00e9es domaniales et enfin \u00e0 favoriser une urbanisation coh\u00e9rente et ma\u00eetris\u00e9e \u00bb.<\/p>\n<p>Aussi, faut-il savoir qu\u2019aux termes du d\u00e9cret, la d\u00e9ch\u00e9ance est soumise au strict respect des conditions cumulatives, apr\u00e8s v\u00e9rification de l\u2019\u00e9tat foncier. Ces conditions, expliqua le Ministre Bruno Kon\u00e9 sont : \u00ab Le constat de non mise en valeur ou d\u2019insuffisance de mise en valeur ; la mise en demeure de d\u00e9ch\u00e9ance impartissant au titulaire de droits un nouveau d\u00e9lai de mise en valeur de douze mois au plus ; le constat du non-respect de l\u2019injonction de mise en valeur dans le nouveau d\u00e9lai imparti. \u00bb.<\/p>\n<p>Enfin, notons que la d\u00e9cision de d\u00e9ch\u00e9ance visant \u00e0 l\u2019an\u00e9antissement ou \u00e0 l\u2019annulation d\u2019un acte administratif, est susceptible de porter grief, et peut th\u00e9oriquement faire l\u2019objet d\u2019un recours pour exc\u00e8s de pouvoir par le d\u00e9chu devant le Conseil d\u2019Etat apr\u00e8s un recours gracieux exerc\u00e9 devant l\u2019auteur de l\u2019acte ou son sup\u00e9rieur hi\u00e9rarchique, en cas de vice de proc\u00e9dure.<\/p>\n<p><b>Jean Chr\u00e9sus, Abidjan<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ou de concession provisoire sur les terrains urbains non immatricul\u00e9s, non mis en valeur ou insuffisamment mis en valeur, doivent \u00e0 compter de l\u2019entr\u00e9e en vigueur de la loi n\u00b0624 du 14 ao\u00fbt [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":31061,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11],"tags":[674,56,63,1713,29,5165,1746,1749,527,713,1933],"class_list":["post-31062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","tag-acd","tag-africa-press","tag-africa-press-cote-divoire","tag-bruno-kone","tag-cote-divoire","tag-decheance","tag-decret","tag-mclu","tag-plateau","tag-procedure","tag-terrain"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&#039;id\u00e9e de ce d\u00e9cret n&#039;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&#039;id\u00e9e de ce d\u00e9cret n&#039;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb\" \/>\n<meta property=\"og:description\" content=\"Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T18:26:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&rsquo;id\u00e9e de ce d\u00e9cret n&rsquo;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb\",\"datePublished\":\"2022-03-25T18:26:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\"},\"wordCount\":973,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg\",\"keywords\":[\"ACD\",\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"Bruno Kon\u00e9\",\"C\u00d4TE D'IVOIRE\",\"d\u00e9ch\u00e9ance\",\"d\u00e9cret\",\"MCLU\",\"Plateau\",\"proc\u00e9dure\",\"terrain\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\",\"name\":\"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL'id\u00e9e de ce d\u00e9cret n'est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg\",\"datePublished\":\"2022-03-25T18:26:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg\",\"width\":720,\"height\":480,\"caption\":\"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL'id\u00e9e de ce d\u00e9cret n'est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&#8217;id\u00e9e de ce d\u00e9cret n&#8217;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL'id\u00e9e de ce d\u00e9cret n'est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb - C\u00f4te d&#039;Ivoire","description":"Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais","og_locale":"fr_FR","og_type":"article","og_title":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL'id\u00e9e de ce d\u00e9cret n'est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb","og_description":"Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2022-03-25T18:26:37+00:00","og_image":[{"width":720,"height":480,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&rsquo;id\u00e9e de ce d\u00e9cret n&rsquo;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb","datePublished":"2022-03-25T18:26:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais"},"wordCount":973,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg","keywords":["ACD","Africa Press","Africa Press-C\u00f4te d'Ivoire","Bruno Kon\u00e9","C\u00d4TE D'IVOIRE","d\u00e9ch\u00e9ance","d\u00e9cret","MCLU","Plateau","proc\u00e9dure","terrain"],"articleSection":["Communaut\u00e9","homepage-french"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais","url":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais","name":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL'id\u00e9e de ce d\u00e9cret n'est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg","datePublished":"2022-03-25T18:26:37+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Bruno Kon\u00e9 dans le jardin de la cit\u00e9 administrative au Plateau (Ph KOACI) Les d\u00e9tenteurs de droit d\u2019attribution ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/03\/img-623dfb29d656d.jpg","width":720,"height":480,"caption":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL'id\u00e9e de ce d\u00e9cret n'est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/homepage-french\/polemiques-sur-la-procedure-de-decheance-des-droits-sur-des-parcelles-de-terrain-bruno-kone-formel-lidee-de-ce-decret-nest-pas-de-deposseder-les-citoyens-de-leurs-biens-mais#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Pol\u00e9miques sur la proc\u00e9dure de d\u00e9ch\u00e9ance des droits sur des parcelles de terrain, Bruno Kon\u00e9 formel \u00abL&#8217;id\u00e9e de ce d\u00e9cret n&#8217;est pas de d\u00e9poss\u00e9der les citoyens de leurs biens, mais\u2026 \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/31062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=31062"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/31062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/31061"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=31062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=31062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=31062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}