{"id":35282,"date":"2022-05-13T17:05:49","date_gmt":"2022-05-13T17:05:49","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone"},"modified":"2022-05-13T17:42:05","modified_gmt":"2022-05-13T17:42:05","slug":"soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone","title":{"rendered":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span><b> <\/b>Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la purge des droits coutumiers sur la parcelle de 940 ha couvrant la zone industrielle d\u2019Akoup\u00e9-Zeudji PK 24 d\u00e9fraie pr\u00e9sentement la chronique. Au point o\u00f9 un quotidien proche de Laurent Gbagbo ait \u00e9voqu\u00e9 dans ces colonnes cette affaire.<\/p>\n<p>Des \u00ab soup\u00e7ons de d\u00e9tournements de centaines de millions de FCFA par des agents du minist\u00e8re de la Construction, du Logement et de l\u2019Urbanisme (MCLU) \u00bb de quoi \u00e0 susciter une r\u00e9action des services de Bruno Kon\u00e9.<\/p>\n<p>Pour cette affaire qui touche au paiement de la purge des droits coutumiers sur la parcelle de 940 ha couvrant la zone industrielle d\u2019Akoup\u00e9-Zeudji PK 24 et face aux all\u00e9gations qui incriminent certains responsables du MCLU, les services du Minist\u00e8re de la Construction, du Logement et de l\u2019Urbanisme ont tenu \u00e0 faire quelques pr\u00e9cisons.<\/p>\n<p>Dans une note parvenue ce jour \u00e0 KOACI, les services de Bruno Kon\u00e9 affirment que le 11 mai 2015, une convention de purge des droits coutumiers de la parcelle d\u2019une contenance de 940 ha couvrant la zone industrielle d\u2019Akoup\u00e9-Zeudji PK 24 a \u00e9t\u00e9 sign\u00e9e entre le collectif des d\u00e9tenteurs de droits d\u2019usage coutumiers des villages d\u2019Akoup\u00e9-Zeudji, d\u2019Allokoi, d\u2019Attingu\u00e9 et l\u2019Etat de C\u00f4te d\u2019Ivoire, repr\u00e9sent\u00e9 par les Minist\u00e8res de l\u2019Int\u00e9rieur, de la Construction et de l\u2019Urbanisme ainsi que de l\u2019Industrie et des Mines.<\/p>\n<p>Contre toute attente, dans le cadre des paiements de la purge, Monsieur le Ministre de la Construction, du Logement et de l\u2019Urbanisme a \u00e9t\u00e9 saisi par des d\u00e9tenteurs de droits coutumiers, concernant le pr\u00e9l\u00e8vement, sans leur accord, de la somme de 300 francs par m\u00e8tre carr\u00e9, sur le montant de leur purge, au profit de la soci\u00e9t\u00e9 \u00ab Anouanz\u00e8 Ivoire \u00bb.<\/p>\n<p>Le MCLU pr\u00e9cise que dans la signature de cet accord, nulle part dans cette convention, la soci\u00e9t\u00e9 \u00ab Anouanz\u00e8 Ivoire \u00bb n\u2019a \u00e9t\u00e9 identifi\u00e9e comme d\u00e9tentrice de droits d\u2019usage coutumiers, b\u00e9n\u00e9ficiaire de la purge convenue.<\/p>\n<p>Ainsi, en vue de clarifier ces affirmations, les services comp\u00e9tents du minist\u00e8re ont r\u00e9alis\u00e9 une enqu\u00eate fonci\u00e8re aupr\u00e8s de la communaut\u00e9 villageoise d\u2019Akoup\u00e9-Zeudji.<\/p>\n<p>Cette enqu\u00eate a permis de mettre en lumi\u00e8re le fait que, d\u2019une part, les d\u00e9tenteurs de droits coutumiers, dans leur majorit\u00e9, n\u2019ont aucun lien avec la soci\u00e9t\u00e9 \u00ab Anouanz\u00e8 Ivoire \u00bb et n\u2019ont jamais conclu de contrat avec elle. De plus, les documents fournis par la soci\u00e9t\u00e9, en date du 18 janvier 2021, ne mentionnent nulle part une quelconque convention liant les deux entit\u00e9s. Aussi, l\u2019enqu\u00eate a r\u00e9v\u00e9l\u00e9 que deux agents de cette soci\u00e9t\u00e9 se sont octroy\u00e9s, frauduleusement, le titre de d\u00e9tenteur de droits coutumiers, afin de percevoir des paiements.<\/p>\n<p>D\u2019autres parts, les documents comptables fournis par le Fonds de D\u00e9veloppement des Infrastructures Industrielles (FODI), le 19 juillet 2021, \u00e0 la demande du Cabinet du minist\u00e8re de la Construction, du Logement et de l\u2019Urbanisme, r\u00e9v\u00e8lent que huit d\u00e9tenteurs de droits coutumiers n\u2019ont jamais per\u00e7u le montant de leur purge, estim\u00e9 \u00e0 900.637.500 FCFA pour une superficie de 360 255 m\u00b2, \u00e0 raison de 2500 f\/m\u00b2 ;<\/p>\n<p>Aussi, il est \u00e0 noter un pr\u00e9l\u00e8vement abusif, au profit de la soci\u00e9t\u00e9 \u00ab Anouanz\u00e8 Ivoire \u00bb de la somme de 2.035.878.000 pour une superficie de 6 786 206 m\u00b2, \u00e0 raison de 300 F\/m\u00b2.<\/p>\n<p>Les plaintes des d\u00e9tenteurs de droits coutumiers \u00e9tant donc justifi\u00e9es et dans l\u2019optique d\u2019apporter une r\u00e9ponse aux requ\u00e9rants, les services de Bruno Kon\u00e9 affirment avoir pris des mesures de la suspension des paiements en cours dans l\u2019attente d\u2019une clarification des conditions des paiements effectu\u00e9s au profit des deux agents de la soci\u00e9t\u00e9 \u00ab Anouanz\u00e8 Ivoire \u00bb incrimin\u00e9s ; la transmission au FODI, organisme en charge des paiements, des listes des d\u00e9tenteurs des droits d\u2019usage coutumiers abusivement pr\u00e9lev\u00e9s, pour paiement des sommes dues.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la purge des droits coutumiers sur la parcelle de 940 ha couvrant la zone industrielle d\u2019Akoup\u00e9-Zeudji PK 24 d\u00e9fraie pr\u00e9sentement la chronique. Au point o\u00f9 un quotidien proche de Laurent Gbagbo ait \u00e9voqu\u00e9 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":35281,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11,10],"tags":[56,63,4425,1713,29,3121,4456,1749,6069,6068],"class_list":["post-35282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-homepage-french","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-akoupe","tag-bruno-kone","tag-cote-divoire","tag-droit","tag-fodi","tag-mclu","tag-purge","tag-zeudji"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9 - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la p ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9\" \/>\n<meta property=\"og:description\" content=\"Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la p ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-13T17:05:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-13T17:42:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9\",\"datePublished\":\"2022-05-13T17:05:49+00:00\",\"dateModified\":\"2022-05-13T17:42:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\"},\"wordCount\":736,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"Akoup\u00e9\",\"Bruno Kon\u00e9\",\"C\u00d4TE D'IVOIRE\",\"Droit\",\"FODI\",\"MCLU\",\"purge\",\"Zeudji\"],\"articleSection\":[\"Communaut\u00e9\",\"homepage-french\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\",\"name\":\"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9 - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg\",\"datePublished\":\"2022-05-13T17:05:49+00:00\",\"dateModified\":\"2022-05-13T17:42:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la p ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg\",\"width\":720,\"height\":367,\"caption\":\"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9 - C\u00f4te d&#039;Ivoire","description":"Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la p ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone","og_locale":"fr_FR","og_type":"article","og_title":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9","og_description":"Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la p ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2022-05-13T17:05:49+00:00","article_modified_time":"2022-05-13T17:42:05+00:00","og_image":[{"width":720,"height":367,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9","datePublished":"2022-05-13T17:05:49+00:00","dateModified":"2022-05-13T17:42:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone"},"wordCount":736,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","Akoup\u00e9","Bruno Kon\u00e9","C\u00d4TE D'IVOIRE","Droit","FODI","MCLU","purge","Zeudji"],"articleSection":["Communaut\u00e9","homepage-french","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone","url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone","name":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9 - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg","datePublished":"2022-05-13T17:05:49+00:00","dateModified":"2022-05-13T17:42:05+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Une affaire de soup\u00e7ons de d\u00e9tournements de plus d\u2019une centaine de millions de FCFA touchant au paiement de la p ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2022\/05\/postQueueImg_23-627e98478cda2.jpg","width":720,"height":367,"caption":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/soupcons-de-detournements-de-plus-de-100-millions-de-fcfa-portant-sur-le-paiement-de-la-purge-des-droits-coutumiers-sur-une-parcelle-de-940-ha-la-reaction-des-services-de-bruno-kone#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Soup\u00e7ons de d\u00e9tournements de plus de 100 millions de FCFA portant sur le paiement de la purge des droits coutumiers sur une parcelle de 940 ha, la r\u00e9action des services de Bruno Kon\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/35282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=35282"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/35282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/35281"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=35282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=35282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=35282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}