{"id":56464,"date":"2023-04-12T18:38:36","date_gmt":"2023-04-12T18:38:36","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba"},"modified":"2023-04-12T19:30:05","modified_gmt":"2023-04-12T19:30:05","slug":"lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba","title":{"rendered":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&rsquo;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement du terrorisme et de la prolife\u0301ration (LBC\/FTP) exige des pays qu\u2019ils se dotent, entre autres, de politiques nationales de LBC\/FTP.<\/p>\n<p>Afin donc de renforcer les capacite\u0301s des Comite\u0301s interministe\u0301riels \/ Comite\u0301s nationaux de coordination de LBC\/FTP a\u0300 remplir efficacement leurs ro\u0302les et fonctions de coordination, le Groupe Intergouvernemental d\u2019Action contre le Blanchiment d\u2019Argent en Afrique de l\u2019Ouest (GIABA) institution spe\u0301cialise\u0301e de la CEDEAO tient depuis ce mercredi 12 avril et ce jusqu\u2019au 14 avril 2023, un atelier re\u0301gional a\u0300 Abidjan-Plateau.<\/p>\n<p>Cet atelier s\u2019appuie sur les re\u0301sultats du Forum des CIM\/CNC qui s\u2019est tenu a\u0300 Saly, au Se\u0301ne\u0301gal, du 31 octobre au 2 novembre 2022, au cours duquel un Rapport d\u2019e\u0301valuation sur le fonctionnement des CIM\/CNC a e\u0301te\u0301 examine\u0301 et des recommandations ont e\u0301te\u0301 formule\u0301es sur la voie a\u0300 suivre.<\/p>\n<p>A terme, les travaux permettront a\u0300 la quarantaine de hauts repre\u0301sentants des CIM\/CNC des E\u0301tats membres du GIABA de comprendre (i) l&rsquo;e\u0301laboration et e\u0301valuation des politiques de LBC\/FT\/FP ; (ii) la coordination de l&rsquo;E\u0301valuation Nationale des Risques ; la Coordination de l&rsquo;e\u0301laboration de la Strate\u0301gie\/du Plan d&rsquo;Action National(e) ; (iii) la coordination des E\u0301valuations Mutuelles ; (iv) les e\u0301change d&rsquo;informations aux niveaux national et international ainsi que les questions relatives a\u0300 la Mobilisation des ressources pour renforcer le fonctionnement des CIM\/CNC.<\/p>\n<p>Dans son discours d\u2019ouverture, le Directeur ge\u0301ne\u0301ral de la Giaba Edwin W. Harris Junior a assure\u0301 que l\u2019institution \u00ab fournira continuellement un soutien technique aux E\u0301tats membres dans le cadre du mandat Giaba pour s\u2019assurer que l&rsquo;e\u0301conomie des E\u0301tats membres est prote\u0301ge\u0301e, mais les moteurs de la protection des e\u0301conomies des E\u0301tats membres reposent sur le pays et c\u2019est la\u0300 que l&rsquo;IMC \/ NCC devrait assumer le ro\u0302le de leadership significatif.\u00bb<\/p>\n<p>Il a appele\u0301 les membres a\u0300 \u00ab enque\u0302ter sur les questions des sanctions financie\u0300res cible\u0301es contre les terroristes, afin de mieux pre\u0301parer \u00bb leur pays \u00ab a\u0300 la prochaine se\u0301rie d&rsquo;e\u0301valuations mutuelles. \u00bb<\/p>\n<p>Cet atelier vise a\u0300 renforcer leur capacite\u0301 a\u0300 demeurer le sommet au niveau des politiques et de la coordination dans la lutte contre le blanchiment d&rsquo;argent, le financement des activite\u0301s terroristes et la prolife\u0301ration du financement.<\/p>\n<p>\u00ab Nous attendons avec inte\u0301re\u0302t votre engagement conforme\u0301ment a\u0300 la recommandation 2 de la norme du GAFI avec toutes les autorite\u0301s compe\u0301tentes de votre pays pour ame\u0301liorer et rendre votre re\u0301gime efficace tant au niveau politique qu&rsquo;ope\u0301rationnel. A\u0300 cette fin, la coope\u0301ration, le re\u0301seautage, le partage de l&rsquo;information et la collaboration harmonieuse demeurent essentiels pour atteindre vos objectifs de protection de votre syste\u0300me financier et de votre e\u0301conomie contre les abus des criminels a\u0300 des fins e\u0301goi\u0308stes.\u00bb, a-t-il indique\u0301.<\/p>\n<p>Pre\u0301sent aux re\u0301unions de printemps du FMI et du groupe de la Banque mondiale, le ministre de l\u2019Economie et des finances, Adama Coulibaly, a e\u0301te\u0301 repre\u0301sente\u0301 par son Directeur de cabinet adjoint Bamba Vassogbo.<\/p>\n<p>Il a rappele\u0301 que la de\u0301cision d\u2019organiser cette session a\u0300 Abidjan, intervient au moment ou\u0300 le dispositif de lutte contre le blanchissement de capitaux et le financement du terrorisme fait l\u2019objet d\u2019e\u0301valuation par les experts e\u0301valuateurs du FMI et du Giaba.<\/p>\n<p>Bamba Vassogbo a fait savoir par ailleurs que depuis que la Co\u0302te d\u2019Ivoire s\u2019est dote\u0301e d\u2019un comite\u0301 national de coordination des politiques de LBC\/FT en 2014, \u00ab le gouvernement n&rsquo;a me\u0301nage\u0301 aucun effort pour lui permettre de mener les actions visant a\u0300 endiguer le phe\u0301nome\u0300ne de blanchiment de capitaux et de financement du terrorisme. \u00bb<\/p>\n<p>\u00ab A ce jour, le Comite\u0301 est dote\u0301 d&rsquo;un sie\u0300ge, avec un personnel dont l&rsquo;expertise est ave\u0301re\u0301e dans les questions de politiques de LBC\/FT. En termes de re\u0301sultats, faut indiquer, entre autres, que le Comite\u0301 a conduit sur la pe\u0301riode 2019-2020, l&rsquo;Evaluation nationale des Risques de blanchiment de capitaux et de financement du terrorisme la Co\u0302te d&rsquo;Ivoire, dont les re\u0301sultats ont permis d&rsquo;approfondir notre compre\u0301hension des risques en matie\u0300re de LBC\/FT. \u00bb, a-t-il ajoute\u0301.<\/p>\n<p>Le Directeur de cabinet adjoint a en outre assure\u0301 que les efforts se poursuivront avec pour finalite\u0301 de doter la Co\u0302te d\u2019Ivoire d\u2019un dispositif de LBC\/FT cohe\u0301rent, robuste et efficace, qui ne\u0301cessite l\u2019accompagnement du Giaba dont les actions sont a\u0300 saluer.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"bin\/Users\/MiladFR\/postMediaimg_30_1.jpg\" width=\"480\" height=\"360\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"bin\/Users\/MiladFR\/postMediaimg_30_2.jpg\" width=\"480\" height=\"360\" \/><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement du terrorisme et de la prolife\u0301ration (LBC\/FTP) exige des pays qu\u2019ils se dotent, entre autres, de politiques nationales de LBC\/FTP. Afin donc de renforcer les capacite\u0301s des Comite\u0301s interministe\u0301riels \/ Comite\u0301s nationaux de [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":56463,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,8,10],"tags":[56,63,590,29,3692,1670,9740,166],"class_list":["post-56464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-photo","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-blanchiment","tag-cote-divoire","tag-financement","tag-fmi","tag-groupe-daction-financiere","tag-terrorisme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&#039;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&#039;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA\" \/>\n<meta property=\"og:description\" content=\"La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-12T18:38:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-12T19:30:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&rsquo;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA\",\"datePublished\":\"2023-04-12T18:38:36+00:00\",\"dateModified\":\"2023-04-12T19:30:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\"},\"wordCount\":851,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"Blanchiment\",\"C\u00d4TE D'IVOIRE\",\"Financement\",\"FMI\",\"Groupe d\u2019Action Financi\u00e8re\",\"Terrorisme\"],\"articleSection\":[\"\u00c9conomie\",\"Photo\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\",\"name\":\"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d'\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg\",\"datePublished\":\"2023-04-12T18:38:36+00:00\",\"dateModified\":\"2023-04-12T19:30:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg\",\"width\":720,\"height\":540,\"caption\":\"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d'\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&#8217;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d'\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA - C\u00f4te d&#039;Ivoire","description":"La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba","og_locale":"fr_FR","og_type":"article","og_title":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d'\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA","og_description":"La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2023-04-12T18:38:36+00:00","article_modified_time":"2023-04-12T19:30:05+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&rsquo;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA","datePublished":"2023-04-12T18:38:36+00:00","dateModified":"2023-04-12T19:30:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba"},"wordCount":851,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","Blanchiment","C\u00d4TE D'IVOIRE","Financement","FMI","Groupe d\u2019Action Financi\u00e8re","Terrorisme"],"articleSection":["\u00c9conomie","Photo","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba","url":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba","name":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d'\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg","datePublished":"2023-04-12T18:38:36+00:00","dateModified":"2023-04-12T19:30:05+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"La recommandation 2 du Groupe d\u2019Action Financie\u0300re (GAFI) sur la lutte contre le blanchiment de capitaux, le financement ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/04\/postQueueImg_1681308549.33.jpg","width":720,"height":540,"caption":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d'\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/lutte-contre-le-blanchissement-de-capitaux-et-le-financement-du-terrorisme-le-dispositif-ivoirien-objet-devaluation-par-les-experts-evaluateurs-du-fmi-et-du-giaba#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Lutte contre le blanchissement de capitaux et le financement du terrorisme, le dispositif ivoirien objet d&#8217;\u00e9valuation par les experts \u00e9valuateurs du FMI et du GIABA"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/56464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=56464"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/56464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/56463"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=56464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=56464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=56464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}