{"id":59338,"date":"2023-06-05T10:32:49","date_gmt":"2023-06-05T10:32:49","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer"},"modified":"2023-06-05T11:01:03","modified_gmt":"2023-06-05T11:01:03","slug":"en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer","title":{"rendered":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb"},"content":{"rendered":"<p><b> A\u00efssatou Diallo<\/b><\/p>\n<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Le pr\u00e9sident ex\u00e9cutif du PPA-CI tentera de prendre la t\u00eate du conseil r\u00e9gional du Cavally, dans l\u2019ouest du pays, dirig\u00e9 par la ministre de la Fonction publique depuis 2018.<br \/>\nLa campagne n\u2019a pas encore officiellement e\u0301te\u0301 lance\u0301e mais, depuis la publication des listes des candidats aux e\u0301lections locales \u2013 re\u0301gionales et municipales \u2013 du 2 septembre par les principaux partis, l\u2019effervescence se fait sentir. Ministres, e\u0301lus et autres te\u0302tes d\u2019affiche ont commence\u0301 a\u0300 sillonner le pays pour rencontrer leurs e\u0301lecteurs.<\/p>\n<p>Apre\u0300s plusieurs anne\u0301es de boycott des e\u0301lections, le Parti des peuples africains \u2013 Co\u0302te d\u2019Ivoire (PPA-CI, de Laurent Gbagbo) participera au scrutin. Pour l\u2019ancien pre\u0301sident, rentre\u0301 en Co\u0302te d\u2019Ivoire en 2021 apre\u0300s son acquittement par la Cour pe\u0301nale internationale (CPI), ces locales seront un premier grand test permettant de jauger l\u2019implantation de sa nouvelle formation.<\/p>\n<p>L\u2019une des affiches phares de ces r\u00e9gionales se tiendra dans le Cavally, dans l\u2019ouest du pays, o\u00f9 le pr\u00e9sident ex\u00e9cutif du PPA-CI, Hubert Oulaye, se pr\u00e9sentera face \u00e0 la pr\u00e9sidente sortante du conseil r\u00e9gional, Anne D\u00e9sir\u00e9e Ouloto.<\/p>\n<p>Seule candidate du Rassemblement des houphou\u00ebtistes pour la d\u00e9mocratie et la paix (RHDP) aux r\u00e9gionales, la ministre de la Fonction publique, 57 ans, tentera de conserver son si\u00e8ge. Membre du RDR d\u00e8s les ann\u00e9es 1990, puis du RHDP, elle a occup\u00e9 plusieurs postes minist\u00e9riels et est un poids lourd du parti pr\u00e9sidentiel.<\/p>\n<p><b>\u00ab Maman Bulldozer \u00bb<\/b><br \/>\nEn 2010, alors cheffe de cabinet d\u2019Ibrahim Ciss\u00e9 Bacongo, ministre de l\u2019Enseignement sup\u00e9rieur, c\u2019est elle qui est choisie pour devenir la porte-parole d\u2019Alassane Ouattara lors de la pr\u00e9sidentielle. Elle contribue \u00e0 mobiliser l\u2019\u00e9lectorat de l\u2019ouest du pays, dont elle est originaire.<\/p>\n<p>Lorsque son mentor arrive au pouvoir apr\u00e8s la crise post\u00e9lectorale l\u2019ayant oppos\u00e9 \u00e0 Laurent Gbagbo, il lui confie le portefeuille de la Salubrit\u00e9 urbaine en 2011. Elle lance alors des op\u00e9rations de d\u00e9guerpissement et de destruction des installations anarchiques. M\u00eame s\u2019il n\u2019a dur\u00e9 qu\u2019environ un an, cet \u00e9pisode suffit \u00e0 lui valoir le surnom de \u00ab maman bulldozer \u00bb. Elle a depuis assum\u00e9 plusieurs autres fonctions au sein de gouvernements successifs, jusqu\u2019\u00e0 sa nomination, en avril 2021, comme ministre de la Fonction publique et de la Modernisation de l\u2019administration.<\/p>\n<p>D\u00e9put\u00e9e de Toulepleu depuis 2011, Anne D\u00e9sir\u00e9e Ouloto est \u00e9lue pr\u00e9sidente du conseil r\u00e9gional du Cavally en 2018. Cinq ans plus tard, \u00e0 l\u2019heure de remettre son fauteuil en jeu, elle compte mettre en avant ses r\u00e9alisations dans la r\u00e9gion.<\/p>\n<p>\u00ab Nous partons favoris parce que notre bilan parle pour nous, estime Hippolyte Bayalla, maire RHDP de Tha\u00ef, une ville de la r\u00e9gion, \u00e9galement candidat aux municipales. \u00c0 notre arriv\u00e9e, le taux d\u2019\u00e9lectrification \u00e9tait d\u2019environ 33,5 %. Aujourd\u2019hui, il est de 99 %. Nous avons aussi un grand chantier de pont en cours de finition. Le bitumage de plusieurs axes a \u00e9t\u00e9 achev\u00e9 et d\u2019autres doivent l\u2019\u00eatre dans les mois \u00e0 venir \u00bb, \u00e9num\u00e8re l\u2019\u00e9lu, qui rejette les critiques de l\u2019opposition bas\u00e9es sur le manque d\u2019ancrage local d\u2019Ouloto.<\/p>\n<p><b>Oulaye, un enfant de la r\u00e9gion<\/b><br \/>\nEn plus du conseil r\u00e9gional, le RHDP a conquis trois des quatre mairies du p\u00e9rim\u00e8tre aux derni\u00e8res municipales. Il tient aussi les deux postes de s\u00e9nateurs du Cavally. Si Anne Ouloto a ind\u00e9niablement contribu\u00e9 \u00e0 installer le parti au pouvoir dans ce bastion de l\u2019opposition au fil des ans, les r\u00e9gionales du 2 septembre s\u2019annoncent ardues. Cette fois, c\u2019est une personnalit\u00e9 bien connue de la r\u00e9gion qui lui tiendra t\u00eate : Hubert Oulaye, 68 ans.<\/p>\n<p>En mars 2021, ce fid\u00e8le de Laurent Gbagbo avait r\u00e9ussi un coup de force aux l\u00e9gislatives en remportant six des sept si\u00e8ges de la r\u00e9gion \u00e0 la t\u00eate de la liste Ensemble pour la d\u00e9mocratie et la souverainet\u00e9 (EDS). Au terme d\u2019un scrutin tr\u00e8s disput\u00e9, seule Anne Ouloto avait r\u00e9ussi \u00e0 conserver son si\u00e8ge, \u00e0 Toulepleu. Pr\u00e9sident du groupe parlementaire EDS \u00e0 l\u2019Assembl\u00e9e nationale jusqu\u2019au retour de Gbagbo, Hubert Oulaye, devenu d\u00e9put\u00e9 de Guiglo, \u00e9tait alors consid\u00e9r\u00e9 comme l\u2019un des meneurs des \u00ab GOR \u00bb (les \u00ab Gbagbo ou rien \u00bb). C\u2019est donc sans surprise \u00e0 ce compagnon de longue date que Laurent Gbagbo a d\u00e9cid\u00e9 de confier la pr\u00e9sidence du PPA-CI, en octobre 2021.<\/p>\n<p>Directeur de cabinet de l\u2019ancien pr\u00e9sident \u00e0 la fin des ann\u00e9es 1990 puis ministre de l\u2019Emploi et de la Fonction publique durant la d\u00e9cennie du pouvoir de Gbagbo (de 2000 \u00e0 2010), Hubert Oulaye s\u2019est un temps exil\u00e9 au Ghana apr\u00e8s la crise post\u00e9lectorale de 2010-2011. \u00ab M\u00eame si elle a un bon bilan \u00e0 d\u00e9fendre, Anne Ouloto fera face \u00e0 une ic\u00f4ne de la r\u00e9gion. N\u2019importe quel W\u00e8 le conna\u00eet. Lorsqu\u2019il \u00e9tait aux affaires, il a fait la promotion de beaucoup de personnes et a soutenu les jeunes cadres. Les gens se cotisaient pour subvenir \u00e0 ses besoins quand il \u00e9tait en prison [de 2015 \u00e0 2017]. C\u2019est un f\u00e9tiche ! \u00bb explique un d\u00e9put\u00e9 de l\u2019opposition.<\/p>\n<p>D\u00e9but mai, le d\u00e9put\u00e9 de Guiglo a effectu\u00e9 une tourn\u00e9e dans quelques villes de la r\u00e9gion. Il a demand\u00e9 au peuple W\u00e8 son appui et a dit compter sur l\u2019aura de Laurent Gbagbo pour emporter la victoire.<\/p>\n<p>Lors de ce scrutin, Hubert Oulaye devrait \u00e9galement b\u00e9n\u00e9ficier du soutien du Parti d\u00e9mocratique de C\u00f4te d\u2019Ivoire (PDCI), avec qui EDS avait nou\u00e9 des alliances aux derni\u00e8res l\u00e9gislatives. Des discussions entre les cadres des deux formations sont en cours pour ces locales. Sauf grande surprise, dans le Cavally, le candidat du PPA-CI sera soutenu par le PDCI. En contrepartie, l\u2019ancien parti unique devrait conserver une autre r\u00e9gion de l\u2019Ouest, le Gu\u00e9mon, o\u00f9 le pr\u00e9sident de son groupe parlementaire, Simon Doho, est candidat.<\/p>\n<p><b>La Source: JeuneAfrique.com<\/b><\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00efssatou Diallo Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Le pr\u00e9sident ex\u00e9cutif du PPA-CI tentera de prendre la t\u00eate du conseil r\u00e9gional du Cavally, dans l\u2019ouest du pays, dirig\u00e9 par la ministre de la Fonction publique depuis 2018. La campagne n\u2019a pas encore officiellement e\u0301te\u0301 lance\u0301e mais, depuis la publication des listes des candidats aux e\u0301lections locales \u2013 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":59337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,20,10],"tags":[56,63,29],"class_list":["post-59338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossiers","category-top-nouvelles","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-cote-divoire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Le pre\u0301sident exe\u0301cutif du PPA-CI tentera de prendre la te\u0302te du conseil re\u0301gional du Cavally, dans l\u2019ouest du pays, dirige\u0301 ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb\" \/>\n<meta property=\"og:description\" content=\"Le pre\u0301sident exe\u0301cutif du PPA-CI tentera de prendre la te\u0302te du conseil re\u0301gional du Cavally, dans l\u2019ouest du pays, dirige\u0301 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T10:32:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T11:01:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1256\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb\",\"datePublished\":\"2023-06-05T10:32:49+00:00\",\"dateModified\":\"2023-06-05T11:01:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\"},\"wordCount\":1060,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"C\u00d4TE D'IVOIRE\"],\"articleSection\":[\"Dossiers\",\"Top Nouvelles\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\",\"name\":\"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg\",\"datePublished\":\"2023-06-05T10:32:49+00:00\",\"dateModified\":\"2023-06-05T11:01:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le pre\u0301sident exe\u0301cutif du PPA-CI tentera de prendre la te\u0302te du conseil re\u0301gional du Cavally, dans l\u2019ouest du pays, dirige\u0301 ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg\",\"width\":1256,\"height\":628,\"caption\":\"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb - C\u00f4te d&#039;Ivoire","description":"Le pre\u0301sident exe\u0301cutif du PPA-CI tentera de prendre la te\u0302te du conseil re\u0301gional du Cavally, dans l\u2019ouest du pays, dirige\u0301 ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer","og_locale":"fr_FR","og_type":"article","og_title":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb","og_description":"Le pre\u0301sident exe\u0301cutif du PPA-CI tentera de prendre la te\u0302te du conseil re\u0301gional du Cavally, dans l\u2019ouest du pays, dirige\u0301 ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2023-06-05T10:32:49+00:00","article_modified_time":"2023-06-05T11:01:03+00:00","og_image":[{"width":1256,"height":628,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb","datePublished":"2023-06-05T10:32:49+00:00","dateModified":"2023-06-05T11:01:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer"},"wordCount":1060,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","C\u00d4TE D'IVOIRE"],"articleSection":["Dossiers","Top Nouvelles","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer","url":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer","name":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg","datePublished":"2023-06-05T10:32:49+00:00","dateModified":"2023-06-05T11:01:03+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le pre\u0301sident exe\u0301cutif du PPA-CI tentera de prendre la te\u0302te du conseil re\u0301gional du Cavally, dans l\u2019ouest du pays, dirige\u0301 ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685950179.578427.jpg","width":1256,"height":628,"caption":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/dossiers\/en-cote-divoire-hubert-oulaye-defie-anne-desiree-ouloto-alias-maman-bulldozer#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"En C\u00f4te d\u2019Ivoire, Hubert Oulaye d\u00e9fie Anne D\u00e9sir\u00e9e Ouloto, alias \u00ab\u00a0maman Bulldozer\u00a0\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/59338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=59338"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/59338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/59337"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=59338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=59338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=59338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}