{"id":59341,"date":"2023-06-05T11:47:04","date_gmt":"2023-06-05T11:47:04","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables"},"modified":"2023-06-05T11:57:53","modified_gmt":"2023-06-05T11:57:53","slug":"long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables","title":{"rendered":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des personnes vulne\u0301rables ope\u0301rant dans la ville de Bouake\u0301 par le biais d\u2019une caravane baptise\u0301e \u00ab caravane de l\u2019espoir, de la solidarite\u0301 et du partage \u00bb.<\/p>\n<p>Il s\u2019agit, notamment, de la Maison des be\u0301be\u0301s de N\u2019Gattakro, de l\u2019Orphelinat Notre Dames des sources d\u2019Air France 3-Socopao, du Centre d\u2019observation des mineurs de Bouake\u0301 (MACOB) et de l\u2019Association St Camille, qui a en charge l\u2019ho\u0302pital St Camille de Bouake\u0301-Nimbo.<\/p>\n<p>Ces trois structures ont rec\u0327u de la part de l\u2019AFES des vivres et non vivres compose\u0301s de riz, de pommes de terre, d\u2019huiles de table, de sucres, de sels, de pa\u0302tes alimentaires, de plateaux d\u2019\u0153ufs, d\u2019oignons, de mate\u0301riels sportifs (poteaux, ballons), de ve\u0302tements, de se\u0301choirs et d\u2019ustensiles de cuisine, des sceaux d\u2019un cou\u0302t global d\u2019environ 2 millions FCFA.<\/p>\n<p>\u00ab Ayant fait le constat que tous ces enfants orphelins qui sont dans les orphelinats, tous ces mineurs qui sont au centre d\u2019observation et toutes ces personnes qui sont interne\u0301es a\u0300 l\u2019ho\u0302pital psychiatrique St Camille, ont quelque peu perdu l\u2019espoir de vivre. Nous avons de\u0301cide\u0301 a\u0300 notre fac\u0327on de leur redonner cet espoir perdu. Nous voulons leur dire qu\u2019ils ne sont pas oublie\u0301s. C\u2019est le sens de ce don \u00bb, a indique\u0301 le pre\u0301sident du conseil d\u2019administration (PCA) de l\u2019AFES, Dr. Kouame\u0301 Marcelin.<\/p>\n<p>Ce dernier a traduit ses remerciements a\u0300 tous ceux qui ont contribue\u0301 de quelque manie\u0300re que ce soit a\u0300 re\u0301unir ces vivres et non vivres destine\u0301s a\u0300 soulager un tant soit peu ces personnes vulne\u0301rables. Ces remerciements s\u2019adressent a\u0300 la direction et aux e\u0301le\u0300ves des e\u0301tablissements Henri Point Carre\u0301, partenaires de l\u2019AFES, et a\u0300 toutes les personnes de bonne volonte\u0301 qui se sont associe\u0301es a\u0300 ce projet.<\/p>\n<p>Ce geste de \u00ab haute porte\u0301e sociale \u00bb de l\u2019AFES a e\u0301te\u0301 appre\u0301cie\u0301 a\u0300 sa juste valeur par les repre\u0301sentants des structures be\u0301ne\u0301ficiaires qui ont exprime\u0301 la gratitude des pensionnaires a\u0300 ces membres. \u00ab Merci a\u0300 tous les membres de l\u2019ONG Afrique Espoir qui font l\u2019\u0153uvre de Dieu. Sachez, chers membres, que Dieu se trouve au-dedans de chacun de vous \u00bb, a dit la directrice du centre d\u2019observation des mineurs de Bouake\u0301, Le\u0301a Kouassi, au nom de tous les repre\u0301sentants des structures be\u0301ne\u0301ficiaires.<\/p>\n<p>Cre\u0301e\u0301e en fe\u0301vrier 2021, l\u2019ONG Afrique Espoir \u0153uvre dans les domaines de la cohe\u0301sion sociale, de la de\u0301mocratie, de la sante\u0301 maternelle, du sondage d\u2019opinion et de l\u2019e\u0301ducation. Ces premie\u0300res actions ont concerne\u0301 ce dernier domaine d\u2019action avec l\u2019e\u0301quipe de la bibliothe\u0300que Jacques Aka de Bouake\u0301 en ouvrages et le don de kits scolaires et la remise de bon de re\u0301duction de la scolarite\u0301 a\u0300 plusieurs e\u0301le\u0300ves de familles de\u0301munies de la ville de Bouake\u0301.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des personnes vulne\u0301rables ope\u0301rant dans la ville de Bouake\u0301 par le biais d\u2019une caravane baptise\u0301e \u00ab caravane de l\u2019espoir, de la solidarite\u0301 et du partage \u00bb. Il s\u2019agit, notamment, de la Maison des be\u0301be\u0301s [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":59340,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,10],"tags":[56,63,29],"class_list":["post-59341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communaute","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-cote-divoire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des perso ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables\" \/>\n<meta property=\"og:description\" content=\"L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des perso ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T11:47:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T11:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"825\" \/>\n\t<meta property=\"og:image:height\" content=\"371\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables\",\"datePublished\":\"2023-06-05T11:47:04+00:00\",\"dateModified\":\"2023-06-05T11:57:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\"},\"wordCount\":564,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"C\u00d4TE D'IVOIRE\"],\"articleSection\":[\"Communaut\u00e9\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\",\"name\":\"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg\",\"datePublished\":\"2023-06-05T11:47:04+00:00\",\"dateModified\":\"2023-06-05T11:57:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des perso ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg\",\"width\":825,\"height\":371,\"caption\":\"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables - C\u00f4te d&#039;Ivoire","description":"L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des perso ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables","og_description":"L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des perso ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2023-06-05T11:47:04+00:00","article_modified_time":"2023-06-05T11:57:53+00:00","og_image":[{"width":825,"height":371,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables","datePublished":"2023-06-05T11:47:04+00:00","dateModified":"2023-06-05T11:57:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables"},"wordCount":564,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","C\u00d4TE D'IVOIRE"],"articleSection":["Communaut\u00e9","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables","url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables","name":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg","datePublished":"2023-06-05T11:47:04+00:00","dateModified":"2023-06-05T11:57:53+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"L\u2019ONG Afrique Espoir (AFES) a apporte\u0301 samedi 03 juin 2023 un soutien mate\u0301riel a\u0300 quatre structures d\u2019accueil des perso ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685953646.636921.jpg","width":825,"height":371,"caption":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/long-afrique-espoir-apporte-un-soutien-materiel-a-quatre-structures-daccueil-des-personnes-vulnerables#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"L\u2019ONG Afrique Espoir apporte un soutien mat\u00e9riel \u00e0 quatre structures d\u2019accueil des personnes vuln\u00e9rables"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/59341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=59341"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/59341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/59340"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=59341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=59341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=59341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}