{"id":59361,"date":"2023-06-05T13:02:30","date_gmt":"2023-06-05T13:02:30","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante"},"modified":"2023-06-05T14:15:14","modified_gmt":"2023-06-05T14:15:14","slug":"les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante","title":{"rendered":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Les paranthropes, cette presque humanite\u0301 qui s&rsquo;est e\u0301teinte il y a 1,5 a\u0300 1,2 million d&rsquo;anne\u0301es, avaient des enfants qui grandissaient bien plus rapidement que ceux des humains, avec notamment un cerveau qui atteignait sa taille adulte de\u0300s l&rsquo;a\u0302ge de trois ans. \u00ab\u00a0Une surprise\u00a0\u00bb, souligne Jose\u0301 Braga, professeur de pale\u0301oanthropologie a\u0300 l\u2019universite\u0301 Toulouse III \u2013 Paul Sabatier et au Centre d\u2019anthropobiologie et de ge\u0301nomique de Toulouse. \u00ab\u00a0En effet, s&rsquo;ils e\u0301taient toujours en vie, les paranthropes seraient les plus proches parents des humains et on s&rsquo;attendrait donc a\u0300 une vitesse de croissance proche\u00a0\u00bb, explique-t-il. Mais l&rsquo;examen de quatre fossiles partiels de cra\u0302nes d&rsquo;enfants paranthropes, a\u0302ge\u0301s de moins de trois ans, de\u0301montre le contraire.<\/p>\n<p><b>Les paranthropes sont bien plus proches des humains que les australopithe\u0300ques<\/b><\/p>\n<p>Le pale\u0301ontologue a de\u0301couvert les fossiles, vieux de deux millions d&rsquo;anne\u0301es, dans deux grottes en Afrique du Sud, situe\u0301es dans les localite\u0301s de Kromdraai et Drimolen, dans les environs de Johannesburg et de Pretoria. Aucun des quatre cra\u0302nes n&rsquo;est entier, mais des fragments de mandibules, de maxillaires, de boi\u0302te cra\u0302nienne et des dents, ont permis de reconstituer et d&rsquo;analyser pour la premie\u0300re fois le cra\u0302ne d&rsquo;un enfant paranthrope. \u00ab\u00a0Une avance\u0301e conside\u0301rable qui permet d&rsquo;e\u0301tudier la croissance d&rsquo;une espe\u0300ce proche des humains. Avec des caracte\u0301ristiques bien plus humaines que celles des australopithe\u0300ques qui vivaient durant la me\u0302me pe\u0301riode\u00a0\u00bb, pre\u0301cise-t-il. Les pale\u0301ontologues savaient de\u0301ja\u0300 que la morphologie cra\u0302nienne des adultes des deux genres (Paranthropus et Homo) e\u0301tait globalement similaire avec ne\u0301anmoins quelques diffe\u0301rences bien visibles comme de tre\u0300s grosses dents jugales (molaires et pre\u0301-molaires) et des ma\u0302choires massives pour le paranthrope.<\/p>\n<p>La question e\u0301tait de savoir si ces similarite\u0301s relevaient d&rsquo;une e\u0301volution convergente ou de raisons e\u0301volutives bien plus profondes. \u00ab\u00a0Gra\u0302ce a\u0300 cette e\u0301tude, on peut enfin trancher : de\u0300s l&rsquo;a\u0302ge de deux ans, il est fascinant de constater a\u0300 quel point les enfants paranthropes partagent des similarite\u0301s avec les humains et sont a\u0300 des anne\u0301es-lumie\u0300re, en termes de modernite\u0301, des jeunes australopithe\u0300ques repre\u0301sente\u0301s par un fossile emble\u0301matique, celui de l&rsquo;enfant de Taung\u00a0\u00bb, insiste Jose\u0301 Braga.<\/p>\n<p>En particulier, l&rsquo;arrie\u0300re du cra\u0302ne (la partie occipitale), qui conditionne l&rsquo;anatomie du lobe poste\u0301rieur et du cervelet, et la face ont un de\u0301veloppement analogue a\u0300 celui des humains et tre\u0300s e\u0301loigne\u0301e des australopithe\u0300ques. L&rsquo;analyse comple\u0300te du cra\u0302ne composite, qui a e\u0301te\u0301 re\u0301alise\u0301e avec des techniques innovantes d\u2019imagerie et notamment la morphome\u0301trie 3D, est publie\u0301e dans la revue Science Advances.<\/p>\n<p><b> Une dure\u0301e de vie plus courte<\/b><\/p>\n<p>Ce qui a e\u0301galement frappe\u0301 les chercheurs, et qui pour le coup diffe\u0300re vraiment de l&rsquo;ontoge\u0301nie humaine, c&rsquo;est la rapide croissance des jeunes paranthropes. \u00ab\u00a0Certaines caracte\u0301ristiques de la face et du cra\u0302ne ont une forme, voire une taille adulte de\u0300s trois ans. C&rsquo;est le cas du cerveau dont le volume, autour de 400 centime\u0300tres-cube, est celui d&rsquo;un adulte alors que chez l&rsquo;humain, le cerveau n&rsquo;atteint sa taille adulte qu&rsquo;a\u0300 l&rsquo;a\u0302ge de six ans \u00a0\u00bb pre\u0301cise Jose\u0301 Braga. Cela signifie que l&rsquo;enfance des paranthropes e\u0301tait tre\u0300s bre\u0300ve et qu&rsquo;ils devaient probablement e\u0302tre tre\u0300s rapidement aptes a\u0300 la mastication.<\/p>\n<p><b>Enfants humains et paranthropes e\u0301taient des proies<\/b><\/p>\n<p>De\u0301couvert il y a 50 ans dans la grotte de Swartkrans, en Afrique du Sud, le spe\u0301cimen SK 54 est un fossile tre\u0300s ce\u0301le\u0300bre. Il s&rsquo;agit en effet d&rsquo;un cra\u0302ne qui porte les marques de deux crocs. Longtemps, les pale\u0301ontologues ont cru qu&rsquo;il appartenait a\u0300 un be\u0301be\u0301 paranthrope chasse\u0301 par un le\u0301opard. Cette nouvelle e\u0301tude indique que le cra\u0302ne, qui pre\u0301sente des caracte\u0301ristiques plus \u00ab\u00a0modernes\u00a0\u00bb, correspond en fait a\u0300 celui d&rsquo;un petit humain. Les enfants de ces deux groupes e\u0301taient donc la proie des grands fe\u0301lins de la re\u0301gion.<\/p>\n<p>La maturation pre\u0301coce des jeunes paranthropes sugge\u0300re e\u0301galement que la vie de ce genre e\u0301tait sans doute plus courte que celle des humains et que celle qu&rsquo;on pouvait projeter en se basant sur sa taille corporelle, autour de 35 a\u0300 40 kilos maximum. Sans doute, les premiers atteignaient une vingtaine d&rsquo;anne\u0301es contre une trentaine pour les humains.<\/p>\n<p>Pour mieux comprendre la croissance dans les premiers jours et semaines des paranthropes et avoir des informations plus comple\u0300tes sur la taille et la forme du cerveau a\u0300 la naissance ou le degre\u0301 de de\u0301pendance aux parents, il manque encore l&rsquo;e\u0301tude d&rsquo;un fossile cle\u0301 : celui d&rsquo;un nouveau-ne\u0301 paranthrope. Une analyse qui ne devrait pas tarder puisque Jose\u0301 Braga a de\u0301niche\u0301 un tel fossile au cours de ses dernie\u0300res fouilles.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Les paranthropes, cette presque humanite\u0301 qui s&rsquo;est e\u0301teinte il y a 1,5 a\u0300 1,2 million d&rsquo;anne\u0301es, avaient des enfants qui grandissaient bien plus rapidement que ceux des humains, avec notamment un cerveau qui atteignait sa taille adulte de\u0300s l&rsquo;a\u0302ge de trois ans. \u00ab\u00a0Une surprise\u00a0\u00bb, souligne Jose\u0301 Braga, professeur de pale\u0301oanthropologie a\u0300 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":59360,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[56,63,29],"class_list":["post-59361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-cote-divoire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Les paranthropes, cette presque humanite\u0301 qui s&#039;est e\u0301teinte il y a 1,5 a\u0300 1,2 million d&#039;anne\u0301es, avaient des enfants qu ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante\" \/>\n<meta property=\"og:description\" content=\"Les paranthropes, cette presque humanite\u0301 qui s&#039;est e\u0301teinte il y a 1,5 a\u0300 1,2 million d&#039;anne\u0301es, avaient des enfants qu ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-05T13:02:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T14:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante\",\"datePublished\":\"2023-06-05T13:02:30+00:00\",\"dateModified\":\"2023-06-05T14:15:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\"},\"wordCount\":899,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"C\u00d4TE D'IVOIRE\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\",\"name\":\"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg\",\"datePublished\":\"2023-06-05T13:02:30+00:00\",\"dateModified\":\"2023-06-05T14:15:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Les paranthropes, cette presque humanite\u0301 qui s'est e\u0301teinte il y a 1,5 a\u0300 1,2 million d'anne\u0301es, avaient des enfants qu ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg\",\"width\":1200,\"height\":899,\"caption\":\"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante - C\u00f4te d&#039;Ivoire","description":"Les paranthropes, cette presque humanite\u0301 qui s'est e\u0301teinte il y a 1,5 a\u0300 1,2 million d'anne\u0301es, avaient des enfants qu ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante","og_locale":"fr_FR","og_type":"article","og_title":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante","og_description":"Les paranthropes, cette presque humanite\u0301 qui s'est e\u0301teinte il y a 1,5 a\u0300 1,2 million d'anne\u0301es, avaient des enfants qu ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2023-06-05T13:02:30+00:00","article_modified_time":"2023-06-05T14:15:14+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante","datePublished":"2023-06-05T13:02:30+00:00","dateModified":"2023-06-05T14:15:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante"},"wordCount":899,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","C\u00d4TE D'IVOIRE"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante","url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante","name":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg","datePublished":"2023-06-05T13:02:30+00:00","dateModified":"2023-06-05T14:15:14+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Les paranthropes, cette presque humanite\u0301 qui s'est e\u0301teinte il y a 1,5 a\u0300 1,2 million d'anne\u0301es, avaient des enfants qu ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1685961812.315019.jpg","width":1200,"height":899,"caption":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/les-enfants-des-paranthropes-les-plus-proches-parents-des-humains-grandissaient-a-une-vitesse-surprenante#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Les enfants des paranthropes, les plus proches parents des humains, grandissaient \u00e0 une vitesse surprenante"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/59361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=59361"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/59361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/59360"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=59361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=59361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=59361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}