{"id":60169,"date":"2023-06-18T14:57:05","date_gmt":"2023-06-18T14:57:05","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2"},"modified":"2023-06-18T15:22:59","modified_gmt":"2023-06-18T15:22:59","slug":"aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2","title":{"rendered":"A\u00e9rohub, AGL livre les travaux d&rsquo;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301e) dans son entrepo\u0302t de logistique contractuelle, l\u2019Ae\u0301rohub situe\u0301e a\u0300 proximite\u0301 de l&rsquo;Ae\u0301roport International Fe\u0301lix Houphoue\u0308t Boigny d&rsquo;Abidjan, dans la commune de Port Boue\u0308t, apprend KOACI de l&rsquo;ope\u0301rateur majeur de la logistique sur le territoire.<\/p>\n<p>Il nous pre\u0301cise que ces travaux ont e\u0301te\u0301 re\u0301alise\u0301s sur la plus grande base de logistique contractuelle d\u2019Afrique de l\u2019Ouest avec l&rsquo;expertise des entreprises locales ARIC, 2I IVOIRE INGENIERIE et INSTAFRIC, dans le respect des normes et standards internationaux.<\/p>\n<p>Nous apprenons qu&rsquo;ils ont permis de tripler la capacite\u0301 de la zone a\u0300 tempe\u0301rature dirige\u0301e qui est passe\u0301e de 600 m2 a\u0300 1800 m2, afin de re\u0301pondre aux exigences croissantes des clients et d\u2019anticiper leurs besoins sur les marche\u0301s ivoirien et ouest-africain.<\/p>\n<p>\u00ab Cette extension de nos infrastructures de production permettra a\u0300 AGL Co\u0302te d\u2019Ivoire de re\u0301pondre de manie\u0300re plus efficace aux besoins e\u0301volutifs de nos clients. Notre objectif est d&rsquo;anticiper les attentes du marche\u0301 ivoirien et international dans le domaine de la logistique contractuelle \u00bb, a de\u0301clare\u0301 Claude Aman, Directeur des Solutions Logistiques de AGL Co\u0302te d\u2019Ivoire.<\/p>\n<p>Pour rappel, l\u2019Ae\u0301rohub, base de logistique contractuelle de 6.000 m2, a pour vocation de recevoir, stocker et distribuer au sein de sa plateforme tri-tempe\u0301rature (surgele\u0301, froid positif, tempe\u0301rature ambiante), des marchandises destine\u0301es au marche\u0301 ivoirien et sous re\u0301gional.<\/p>\n<p>Cette plateforme a traite\u0301 en 2022, 1491 conteneurs EVP, de marchandises, soit environ 6 096 000 colis rec\u0327us et 3 424 680 colis expe\u0301die\u0301s.<\/p>\n<p>\u00ab Nous sommes tre\u0300s satisfaits du partenariat en cours avec l\u2019Ae\u0301rohub de AGL Co\u0302te d\u2019Ivoire, pour l\u2019entreposage a\u0300 valeur ajoute\u0301e et la gestion de nos stocks de produits surgele\u0301s. Gra\u0302ce a\u0300 ce service, nos produits sont bien conserve\u0301s et livre\u0301s en temps re\u0301el, nous permettant, ainsi, d\u2019offrir a\u0300 nos clients un service de qualite\u0301. L\u2019accroissement de la chambre froide de cette infrastructure vient e\u0301galement re\u0301pondre a\u0300 la croissance de nos activite\u0301s, sur le marche\u0301 ivoirien et sous re\u0301gional \u00bb, explique Faustin Karamoko, Country Manager Danone EDP \/ FAN MILK Co\u0302te d\u2019Ivoire.<\/p>\n<p>Gra\u0302ce a\u0300 une architecture technique de pointe, la nouvelle zone de froid entend, pour AGL, accompagner les clients des secteurs pharmaceutiques, de la grande distribution et de la restauration, dans leur croissance, tout en maintenant les engagements de sa qualite\u0301 en matie\u0300re de gestion de la chai\u0302ne du froid.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301e) dans son entrepo\u0302t de logistique contractuelle, l\u2019Ae\u0301rohub situe\u0301e a\u0300 proximite\u0301 de l&rsquo;Ae\u0301roport International Fe\u0301lix Houphoue\u0308t Boigny d&rsquo;Abidjan, dans la commune de Port Boue\u0308t, apprend KOACI de l&rsquo;ope\u0301rateur majeur de la logistique [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":60168,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,10],"tags":[10394,56,63,9613,10395,10396,29,10398,10397],"class_list":["post-60169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie","category-toutes-les-actualites","tag-aerohub","tag-africa-press","tag-africa-press-cote-divoire","tag-agl","tag-chambre-froide","tag-claude-aman","tag-cote-divoire","tag-danone","tag-faustin-karamoko"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A\u00e9rohub, AGL livre les travaux d&#039;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2 - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301 ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00e9rohub, AGL livre les travaux d&#039;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2\" \/>\n<meta property=\"og:description\" content=\"AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-18T14:57:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-18T15:22:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"296\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"A\u00e9rohub, AGL livre les travaux d&rsquo;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2\",\"datePublished\":\"2023-06-18T14:57:05+00:00\",\"dateModified\":\"2023-06-18T15:22:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\"},\"wordCount\":489,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg\",\"keywords\":[\"A\u00e9rohub\",\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"AGL\",\"chambre froide\",\"Claude Aman\",\"C\u00d4TE D'IVOIRE\",\"Danone\",\"Faustin Karamoko\"],\"articleSection\":[\"\u00c9conomie\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\",\"name\":\"A\u00e9rohub, AGL livre les travaux d'extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2 - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg\",\"datePublished\":\"2023-06-18T14:57:05+00:00\",\"dateModified\":\"2023-06-18T15:22:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301 ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg\",\"width\":719,\"height\":296,\"caption\":\"A\u00e9rohub, AGL livre les travaux d'extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00e9rohub, AGL livre les travaux d&#8217;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A\u00e9rohub, AGL livre les travaux d'extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2 - C\u00f4te d&#039;Ivoire","description":"AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301 ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2","og_locale":"fr_FR","og_type":"article","og_title":"A\u00e9rohub, AGL livre les travaux d'extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2","og_description":"AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301 ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2023-06-18T14:57:05+00:00","article_modified_time":"2023-06-18T15:22:59+00:00","og_image":[{"width":719,"height":296,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"A\u00e9rohub, AGL livre les travaux d&rsquo;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2","datePublished":"2023-06-18T14:57:05+00:00","dateModified":"2023-06-18T15:22:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2"},"wordCount":489,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg","keywords":["A\u00e9rohub","Africa Press","Africa Press-C\u00f4te d'Ivoire","AGL","chambre froide","Claude Aman","C\u00d4TE D'IVOIRE","Danone","Faustin Karamoko"],"articleSection":["\u00c9conomie","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2","url":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2","name":"A\u00e9rohub, AGL livre les travaux d'extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2 - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg","datePublished":"2023-06-18T14:57:05+00:00","dateModified":"2023-06-18T15:22:59+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"AGL Co\u0302te d\u2019Ivoire a livre\u0301 le 15 avril 2023, les travaux d\u2019extension de sa chambre froide (zone a\u0300 tempe\u0301rature dirige\u0301 ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/06\/sm_1687088933.866741.jpg","width":719,"height":296,"caption":"A\u00e9rohub, AGL livre les travaux d'extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/economie\/aerohub-agl-livre-les-travaux-dextension-de-sa-chambre-froide-aux-standards-internationaux-elle-passe-de-de-600-m2-a-1800-m2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"A\u00e9rohub, AGL livre les travaux d&#8217;extension de sa chambre froide aux standards internationaux, elle passe de de 600 m2 \u00e0 1800 m2"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/60169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=60169"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/60169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/60168"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=60169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=60169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=60169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}