{"id":70827,"date":"2023-12-05T14:33:27","date_gmt":"2023-12-05T14:33:27","guid":{"rendered":"https:\/\/www.africa-press.net\/cotedivoire\/politique\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia"},"modified":"2023-12-05T15:15:59","modified_gmt":"2023-12-05T15:15:59","slug":"des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia","status":"publish","type":"post","link":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia","title":{"rendered":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA"},"content":{"rendered":"<p><span style=\"color: #ff6600\"><strong>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. <\/strong><\/span>Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301liorer ces technologies, il est primordial de de\u0301velopper de nouveaux mate\u0301riaux aux proprie\u0301te\u0301s variables.<b> <\/b>C&rsquo;est pour re\u0301pondre a\u0300 ce besoin que DeepMind, la socie\u0301te\u0301 de Google spe\u0301cialise\u0301e dans l\u2019intelligence artificielle (IA), a de\u0301veloppe\u0301 une IA pour aider les chercheurs dans leur recherche de mate\u0301riaux innovants : nomme\u0301e GNoME (pour Re\u0301seau de Graphes pour l\u2019Exploration des Mate\u0301riaux), elle a e\u0301te\u0301 conc\u0327ue pour explorer le vaste champ des mate\u0301riaux possibles, selon une publication scientifique parue dans la revue Nature le 29 novembre 2023.<\/p>\n<p><b>Le de\u0301veloppement de nouveaux mate\u0301riaux, un processus long<\/b><\/p>\n<p>Pour concevoir de nouveaux mate\u0301riaux, les chercheurs ne partent pas de rien, ils vont se baser sur les structures de mate\u0301riaux de\u0301ja\u0300 connus et la modifier le\u0301ge\u0300rement, souvent en substituant un atome par un atome similaire. Une fois une structure de\u0301termine\u0301e, il faut ve\u0301rifier sa stabilite\u0301. Pour ce faire, les chercheurs utilisent des me\u0301thodes de simulations ne pouvant tourner en un temps raisonnable que sur des supercalculateurs (serveurs, aux capacite\u0301s e\u0301normes, utilise\u0301s par les chercheurs pour faire tourner des algorithmes demandeurs en ressources).<\/p>\n<p>A\u0300 ces calculs the\u0301oriques s\u2019ajoute la recherche d\u2019une synthe\u0300se permettant d\u2019obtenir le mate\u0301riau souhaite\u0301. Lors de cette phase, chaque e\u0301chantillon obtenu par un protocole de synthe\u0300se teste\u0301 se doit d\u2019e\u0302tre caracte\u0301rise\u0301 (il faut de\u0301terminer la nature et la position des atomes qui le constitue). C\u2019est une fois la caracte\u0301risation faite que le chercheur peut analyser les re\u0301sultats et choisir quelles sont les modifications a\u0300 apporter a\u0300 la synthe\u0300se. En suivant ces e\u0301tapes, cela peut prendre plusieurs mois a\u0300 un physicien pour concevoir un nouveau mate\u0301riau et de\u0301terminer une proce\u0301dure de synthe\u0300se.<\/p>\n<p><b>Plus de 2,2 millions de nouvelles structures cristallines<\/b><\/p>\n<p>Or GNoME est parvenu rapidement a\u0300 de\u0301terminer plus de 2,2 millions de nouvelles structures cristallines (structures internes des mate\u0301riaux) pre\u0301sentant une certaine stabilite\u0301.<\/p>\n<p>Parmi la mine de mate\u0301riaux sugge\u0301re\u0301s par l\u2019intelligence artificielle, plus de 380.000 vont enrichir la base de donne\u0301es The Materials Project, fonde\u0301e par des chercheurs de l\u2019universite\u0301 ame\u0301ricaine de Berkeley et servant de grande bibliothe\u0300que des mate\u0301riaux. Cette grande base de donne\u0301es permet aux chercheurs de cataloguer les mate\u0301riaux ainsi que leur proprie\u0301te\u0301 (s&rsquo;ils sont conducteurs ou isolants, leurs proprie\u0301te\u0301s magne\u0301tiques, ou encore s\u2019ils ont de\u0301ja\u0300 e\u0301te\u0301 observe\u0301s expe\u0301rimentalement) mais e\u0301galement de les calculer automatiquement par simulation quand cela est ne\u0301cessaire.<\/p>\n<p><b>Un re\u0301seau de neurones<\/b><\/p>\n<p>L\u2019approche par intelligence artificielle GNoME se base sur une cate\u0301gorie de re\u0301seaux de neurones spe\u0301cialise\u0301s dans le traitement d\u2019informations pouvant e\u0302tre repre\u0301sente\u0301es par un graphe. Ce dernier est un objet mathe\u0301matique constitue\u0301 de n\u0153uds relie\u0301s entre eux par des are\u0302tes, ce qui est le cas d\u2019une structure cristalline.<\/p>\n<p>L\u2019IA a e\u0301te\u0301 entrai\u0302ne\u0301e a\u0300 partir des donne\u0301es de The Materials Project<b> <\/b>en 2018, soit l\u2019e\u0301quivalent de 69.000 mate\u0301riaux diffe\u0301rents. Le re\u0301seau de neurones est ainsi capable de proposer des structures cristallines en les de\u0301rivant de la base donne\u0301e. Une des caracte\u0301ristiques principales de leur technologie est qu\u2019elle est capable d\u2019apprendre de ses erreurs (et de ses re\u0301ussites). Chaque cristal propose\u0301 passe par un ensemble de simulation (similaire a\u0300 celle de The Materials Project), les informations re\u0301cupe\u0301re\u0301es de cette simulation sont ensuite fournies en donne\u0301es d\u2019entre\u0301e et d\u2019apprentissage pour l\u2019IA. C\u2019est gra\u0302ce a\u0300 ce proce\u0301de\u0301 d\u2019apprentissage actif que GNoME re\u0301ussit a\u0300 s\u2019ame\u0301liorer au-dela\u0300 me\u0302me des donne\u0301es fournies initialement.<\/p>\n<p><b>Un laboratoire automatique pour acce\u0301le\u0301rer le test de ces mate\u0301riaux<\/b><\/p>\n<p>Le 29 novembre 2023 e\u0301galement, ces chercheurs de Berkeley ont publie\u0301, dans Nature, les premiers re\u0301sultats de leur laboratoire automatise\u0301 fonctionnant en partie gra\u0302ce a\u0300 l\u2019intelligence artificielle, le A-Lab. Ce laboratoire est capable de de\u0301terminer des proce\u0301dures de synthe\u0300se des mate\u0301riaux en se basant sur la litte\u0301rature scientifique et sur les expe\u0301riences qu\u2019il a effectue\u0301es.<\/p>\n<p>Le labo est donc constitue\u0301 de plusieurs parties : des bras robotiques, des fours contro\u0302lables par ordinateur, pouvant chauffer de 600\u00b0C a\u0300 1100\u00b0C<b>, <\/b>ou encore d&rsquo;un analyseur a\u0300 rayons X<b>, <\/b>appareil capable de de\u0301terminer la structure interne d&rsquo;un mate\u0301riau a\u0300 l&rsquo;aide des rayons X. Tous ces appareils de pointe sont dirige\u0301s par une intelligence artificielle. Cette dernie\u0300re a e\u0301te\u0301 entrai\u0302ne\u0301e sur une base de donne\u0301es regroupant des protocoles de synthe\u0300se re\u0301cupe\u0301re\u0301s dans pre\u0300s de 25.000 publications.<\/p>\n<p>Pour re\u0301cupe\u0301rer les informations importantes de ces articles, les chercheurs ont utilise\u0301 une autre intelligence artificielle spe\u0301cialise\u0301e dans le langage naturel<b>,<\/b> c&rsquo;est-a\u0300-dire capable d&rsquo;interpre\u0301ter des textes e\u0301crits par l&rsquo;humain sans avoir besoin d&rsquo;intervention humaine pre\u0301alable sur le texte. L\u2019intelligence artificielle est ensuite capable de de\u0301tecter les similarite\u0301s entre le mate\u0301riau cible et ceux de la litte\u0301rature pour de\u0301terminer les poudres a\u0300 me\u0301langer, leur proportion et les tempe\u0301ratures des fours ne\u0301cessaires.<\/p>\n<p><b>100 e\u0301chantillons par jour<\/b><\/p>\n<p>La fabrication est ope\u0301re\u0301e automatiquement par les robots. Une fois celle-ci termine\u0301e, les bras robotiques pulve\u0301risent le solide obtenu et l\u2019ame\u0300ne a\u0300 l\u2019analyseur a\u0300 rayons X. Ce dernier utilise le phe\u0301nome\u0300ne de diffraction (de\u0301viation des rayons lumineux par la pre\u0301sence d\u2019objets de petite taille, ici les atomes constituant le cristal). A\u0300 partir des re\u0301sultats de la diffraction, il est possible de de\u0301terminer la nature et la position des atomes dans le cristal analyse\u0301. Ces re\u0301sultats sont ensuite, a\u0300 l\u2019instar des simulations pour GNoME, utilise\u0301s pour re\u0301entrai\u0302ner le mode\u0300le et re\u0301ajuster les fabrications propose\u0301es.<\/p>\n<p>Gra\u0302ce a\u0300 cette automatisation, le laboratoire a re\u0301ussi a\u0300 de\u0301terminer en 17 jours la synthe\u0300se de 41 mate\u0301riaux (sur les 58 analyse\u0301s), a\u0300 un rythme de 100 e\u0301chantillons par jour. Ce rythme d\u2019environ deux mate\u0301riaux par jour permet une acce\u0301le\u0301ration dans la recherche de mate\u0301riaux innovants &#8211; rappelons qu\u2019un humain peut mettre plusieurs mois pour un seul mate\u0301riau.<\/p>\n<p><strong>Pour plus d&rsquo;informations et d&rsquo;analyses sur la <a href=\"https:\/\/www.africa-press.net\/cotedivoire\">C\u00f4te d&rsquo;Ivoire<\/a>, suivez <a href=\"https:\/\/www.africa-press.net\/\">Africa-Press<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Africa-Press &#8211; C\u00f4te d&rsquo;Ivoire. Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301liorer ces technologies, il est primordial de de\u0301velopper de nouveaux mate\u0301riaux aux proprie\u0301te\u0301s variables. C&rsquo;est pour re\u0301pondre a\u0300 ce besoin que DeepMind, la socie\u0301te\u0301 de Google spe\u0301cialise\u0301e dans l\u2019intelligence artificielle (IA), a de\u0301veloppe\u0301 [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":70826,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,10],"tags":[56,63,29],"class_list":["post-70827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divers","category-toutes-les-actualites","tag-africa-press","tag-africa-press-cote-divoire","tag-cote-divoire"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA - C\u00f4te d&#039;Ivoire<\/title>\n<meta name=\"description\" content=\"Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301li ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA\" \/>\n<meta property=\"og:description\" content=\"Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301li ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\" \/>\n<meta property=\"og:site_name\" content=\"C\u00f4te d&#039;Ivoire\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-05T14:33:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T15:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cfeditorfr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"cfeditorfr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\"},\"author\":{\"name\":\"cfeditorfr\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"headline\":\"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA\",\"datePublished\":\"2023-12-05T14:33:27+00:00\",\"dateModified\":\"2023-12-05T15:15:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\"},\"wordCount\":1166,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg\",\"keywords\":[\"Africa Press\",\"Africa Press-C\u00f4te d'Ivoire\",\"C\u00d4TE D'IVOIRE\"],\"articleSection\":[\"Divers\",\"Toutes les actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\",\"name\":\"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA - C\u00f4te d&#039;Ivoire\",\"isPartOf\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage\"},\"thumbnailUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg\",\"datePublished\":\"2023-12-05T14:33:27+00:00\",\"dateModified\":\"2023-12-05T15:15:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\"},\"description\":\"Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301li ...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage\",\"url\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg\",\"contentUrl\":\"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg\",\"width\":1200,\"height\":899,\"caption\":\"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africa-press.net\/cotedivoire\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#website\",\"url\":\"https:\/\/www.africa-press.net\/cotedivoire\/\",\"name\":\"C\u00f4te d&#039;Ivoire\",\"description\":\"Just another Africa News Agency Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1\",\"name\":\"cfeditorfr\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA - C\u00f4te d&#039;Ivoire","description":"Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301li ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia","og_locale":"fr_FR","og_type":"article","og_title":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA","og_description":"Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301li ...","og_url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia","og_site_name":"C\u00f4te d&#039;Ivoire","article_published_time":"2023-12-05T14:33:27+00:00","article_modified_time":"2023-12-05T15:15:59+00:00","og_image":[{"width":1200,"height":899,"url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg","type":"image\/jpeg"}],"author":"cfeditorfr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"cfeditorfr","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#article","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia"},"author":{"name":"cfeditorfr","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"headline":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA","datePublished":"2023-12-05T14:33:27+00:00","dateModified":"2023-12-05T15:15:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia"},"wordCount":1166,"commentCount":0,"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg","keywords":["Africa Press","Africa Press-C\u00f4te d'Ivoire","C\u00d4TE D'IVOIRE"],"articleSection":["Divers","Toutes les actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia","url":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia","name":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA - C\u00f4te d&#039;Ivoire","isPartOf":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage"},"image":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage"},"thumbnailUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg","datePublished":"2023-12-05T14:33:27+00:00","dateModified":"2023-12-05T15:15:59+00:00","author":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1"},"description":"Le besoin d\u2019innovation en matie\u0300re de batteries ou d\u2019e\u0301nergies vertes est de plus en plus important. Pour pouvoir ame\u0301li ...","breadcrumb":{"@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#primaryimage","url":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg","contentUrl":"https:\/\/static.africa-press.net\/cote\/sites\/43\/2023\/12\/sm_1701774502.583155.jpg","width":1200,"height":899,"caption":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.africa-press.net\/cotedivoire\/toutes-les-actualites\/des-robots-pilotes-par-ia-testent-des-nouveaux-materiaux-obtenus-tres-rapidement-par-une-autre-ia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africa-press.net\/cotedivoire\/"},{"@type":"ListItem","position":2,"name":"Des robots, pilot\u00e9s par IA, testent des nouveaux mat\u00e9riaux obtenus tr\u00e8s rapidement par une autre IA"}]},{"@type":"WebSite","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#website","url":"https:\/\/www.africa-press.net\/cotedivoire\/","name":"C\u00f4te d&#039;Ivoire","description":"Just another Africa News Agency Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africa-press.net\/cotedivoire\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.africa-press.net\/cotedivoire\/#\/schema\/person\/2b1cf3cd81a31e3cd26889ca66d677f1","name":"cfeditorfr"}]}},"_links":{"self":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/70827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/comments?post=70827"}],"version-history":[{"count":0,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/posts\/70827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media\/70826"}],"wp:attachment":[{"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/media?parent=70827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/categories?post=70827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africa-press.net\/cotedivoire\/wp-json\/wp\/v2\/tags?post=70827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}